{"id":99993,"date":"2026-03-08T22:06:23","date_gmt":"2026-03-08T20:06:23","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/"},"modified":"2026-03-08T22:06:23","modified_gmt":"2026-03-08T20:06:23","slug":"und-merkel-geistert-durch-hamburg","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/","title":{"rendered":"Und Merkel geistert durch Hamburg &#8230;"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/69ac563948fbef36a75c934c.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Im Hamburger Rathaus gibt es ein j\u00e4hrliches Festmahl, eine jahrhundertealte Tradition: das Matthiae-Mahl. Nicht zum ersten Mal trat dort Ex-Kanzlerin Angela Merkel als Rednerin auf. Und obwohl sie nur eine Viertelstunde sprach, weckte es viele schlechte Erinnerungen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Dagmar Henn<\/em><\/p>\n<p>So vieles von dem, was uns heute schwer im Magen liegt, hat sie einger\u00fchrt. Und immer noch schafft sie es, sich hinzustellen und zu tun, als sei alles bestens und als k\u00f6nne sie kein W\u00e4sserchen tr\u00fcben \u2026 und r\u00fchrt weiter, selbst noch vom Spielfeldrand.<\/p>\n<p>Im R\u00fcckblick tut das wirklich weh. Ihre Heuchelei rund um die Minsker Vereinbarungen etwa. Diese immer leicht arrogant-angemuffelte Haltung, mit der sie sich dar\u00fcber beschwerte, dass Russland die Vereinbarung nicht einhalte, wo doch sie es war, die von Anfang an damit betrogen hatte. Die den Brand in der Ukraine, der sp\u00e4ter ausbrach, also mitgelegt hat.<\/p>\n<p>Oder diese unertr\u00e4gliche EU mit ihrer Leidenschaft f\u00fcr Sanktionen und Zensur, ihrer Kriegsl\u00fcsternheit. Heute schaut man sich das alte, inszenierte Foto an, als die ganzen Staatschefs damals nach dem Anschlag auf Charlie Hebdo auf einer Pariser Stra\u00dfe standen und so taten, als w\u00e4ren sie Teil einer Demonstration, obwohl weit und breit au\u00dfer ihren Bodyguards kein Mensch war \u2026 und von den &#8220;europ\u00e4ischen Werten&#8221; tr\u00f6teten. Man h\u00e4tte es damals schon erkennen m\u00fcssen, worauf das hinauslief. Dass diese \u00dcberheblichkeit immer ins Unheil f\u00fchrt. Und mittendrin Merkel.<\/p>\n<p>Wie nat\u00fcrlich auch bei den Bestrebungen, allgegenw\u00e4rtige Zensur zu etablieren. Ach ja, und die gro\u00dfen Stadtbildspenden, die folgen sollten. Wertvoller als Goldst\u00fccke. Nichts davon wirklich demokratisch diskutiert, immer nur h\u00fcbsch angestrichen und dann dem B\u00fcrger zum Schlucken ins Maul gedr\u00fcckt.<\/p>\n<p>Die EU, so <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.hamburg.de\/politik-und-verwaltung\/senat\/rathaus-hamburg\/matthiae-mahl\/rede-von-bundeskanzlerin-a-d-dr-angela-merkel\">t\u00f6nte<\/a> sie in Hamburg, bei ihrem mindestens dritten Auftritt beim Matthiae-Mahl, m\u00fcsse &#8220;ihr Schicksal in die eigenen H\u00e4nde nehmen&#8221;. Und das, was etwa in der <em>Hamburger Morgenpost<\/em> zitiert wird, klingt ganz typisch nach Merkel:<\/p>\n<p><em>&#8220;Ein geeint handelndes Europa bedeute Eintreten f\u00fcr Demokratie, Rechtsstaat, Menschenw\u00fcrde, Wohlstand, Arbeitspl\u00e4tze, aber auch den Schutz der Au\u00dfengrenzen, der kulturellen Identit\u00e4t und der gemeinsamen Sch\u00f6pfung.&#8221;<\/em><\/p>\n<p>Ja, genau. Demokratie, Rechtsstaat, Menschenw\u00fcrde \u2026 Lasst hundert Zensoren verbieten, verfolgt Worte statt Straft\u00e4ter und sorgt daf\u00fcr, dass die Eingeborenen immer weiter verarmen. Wenn es bei ihr wie im M\u00e4rchen w\u00e4re (zugegeben, das ist ein franz\u00f6sisches) und ihr bei jedem Wort eine Kr\u00f6te aus dem Mund springen w\u00fcrde \u2026 das w\u00e4re die angemessene Begleitung. Wobei: &#8220;Schutz der Au\u00dfengrenzen&#8221; ist schon eine Art von Humor.<\/p>\n<p>Eine gemeinsame Haltung der EU gegen\u00fcber den USA? Das w\u00e4re in vielen Momenten keine schlechte Idee gewesen, aber die Haltung, die eine Angela Merkel will, ist immer mindestens so schlimm wie jene aus Washington. Denn wenn sie von einer &#8220;gemeinsamen Politik \u00fcber Russland&#8221; spricht, dann meint sie letztlich genau das, was derzeit passiert, nur vielleicht noch ein wenig effizienter. Sie meint kein Ende des Krieges, keine ernsthaften Verhandlungen. Sie hat bestenfalls Sorgen, dass andere weniger b\u00f6sartig sein k\u00f6nnten als sie selbst. &#8220;Das, was wir wollen, dass Russland den Krieg nicht gewinnt&#8221; \u2013 da ist sie, die Formel f\u00fcr die unbegrenzte Fortsetzung des Gemetzels, mit der eigentlich alles gesagt ist.<\/p>\n<p>Ihr Bekenntnis zur Zensur tarnt sie sehr geschickt. &#8220;Neue technische M\u00f6glichkeiten wie die sogenannten sozialen Medien sowie die Entwicklung im Bereich der KI f\u00fchren dazu, dass Wahrheiten L\u00fcgen und L\u00fcgen Wahrheiten genannt werden k\u00f6nnen.&#8221; Sie muss sich ja auskennen mit der L\u00fcge. Au\u00dfer Minsk waren da noch &#8220;Wir schaffen das&#8221; und &#8220;Die bleiben nur vor\u00fcbergehend&#8221; im Angebot, nicht zu vergessen Werte, Werte, Werte. Als kr\u00f6nenden Abschluss legte sie dann noch die Grundsteine des Corona-Terrors.<\/p>\n<p>&#8220;Verantwortung f\u00fcr die internationale Gemeinschaft&#8221; \u2013 die Phrasendreschmaschine l\u00e4uft noch immer wie geschmiert. Der n\u00f6lende Ton ist immer noch da. Dieses eigenartige Neben-der-Wirklichkeit-Stehen, als s\u00e4he man eine schlechte Amateurschauspielerin. Kein Gef\u00fchl, kein Gedanke scheint echt. Aber die Tr\u00fcmmerw\u00fcste, die sie \u00fcberall hinterlassen hat, die ist echt. Wenn sie sich ausl\u00e4sst \u00fcber den &#8220;russischen Angriffskrieg&#8221; \u2013 sie, die den durch die Minsker Vereinbarungen m\u00f6glichen Frieden sabotiert hat \u2013, denkt sie dann an das wirkliche Gesicht ihrer Handlungen? Man m\u00f6chte ihr w\u00fcnschen, dass die Toten, f\u00fcr die sie verantwortlich ist, sie umgeben, nicht in Gestalt, nur im Geruch, tagein, tagaus. Vielleicht sogar, dass sie diesen Geruch ausstr\u00f6mt, damit jeder wei\u00df, womit er es zu tun hat.<\/p>\n<p>Denn dass Gef\u00fchle in sie eindringen, ist unwahrscheinlich. Auch die toten Kinder von Gaza werden nicht zu ihr vordringen. Merkels Pers\u00f6nlichkeit ist so, dass man an die alten Sagen vom Wechselbalg erinnert wird. In denen das Menschenkind geraubt und durch einen Holzscheit ersetzt wird.<\/p>\n<p>Immerhin, dieses Gastmahl im Hamburger Rathaus hat schon fast sieben Jahrhunderte \u00fcberstanden, da wird es auch diesen Auftritt von Merkel \u00fcberstehen. Ansonsten bleibt nur die Hoffnung, sie m\u00f6ge das Land, dem sie solchen Schaden zugef\u00fcgt hat, nur noch m\u00f6glichst selten mit ihren Auftritten qu\u00e4len.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211;\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/meinung\/264475-merkel-und-kretschmann-zwei-boesartige\/\">Merkel und Kretschmann \u2013 zwei b\u00f6sartige dunkle Seelen Seit an Seit <\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v740l78\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/272477-und-merkel-geistert-durch-hamburg\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Hamburger Rathaus gibt es ein j\u00e4hrliches Festmahl, eine jahrhundertealte Tradition: das Matthiae-Mahl. Nicht zum ersten Mal trat dort Ex-Kanzlerin Angela Merkel als Rednerin auf. Und obwohl sie nur eine Viertelstunde sprach, weckte es viele schlechte Erinnerungen. Von Dagmar Henn So vieles von dem, was uns heute schwer im Magen liegt, hat sie einger\u00fchrt. Und [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":99994,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1773000893"],"wp_automatic_camp":["217"],"29f843dedb5c95d553975794c8c34333":["Und Merkel geistert durch Hamburg ..."],"original_link":["https:\/\/de.rt.com\/meinung\/272477-und-merkel-geistert-durch-hamburg\/"],"_thumbnail_id":["99994"],"jnews_social_counter_last_update":["1778595607"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-03-08 22:15:49\";}"]},"categories":[19,23],"tags":[1024,71667,26091,55,140],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Und Merkel geistert durch Hamburg ... - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Und Merkel geistert durch Hamburg ...\" \/>\n<meta property=\"og:description\" content=\"Im Hamburger Rathaus gibt es ein j\u00e4hrliches Festmahl, eine jahrhundertealte Tradition: das Matthiae-Mahl. Nicht zum ersten Mal trat dort Ex-Kanzlerin Angela Merkel als Rednerin auf. Und obwohl sie nur eine Viertelstunde sprach, weckte es viele schlechte Erinnerungen. Von Dagmar Henn So vieles von dem, was uns heute schwer im Magen liegt, hat sie einger\u00fchrt. Und [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-03-08T20:06:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/69ac563948fbef36a75c934c.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Und Merkel geistert durch Hamburg &#8230;\",\"datePublished\":\"2026-03-08T20:06:23+00:00\",\"dateModified\":\"2026-03-08T20:06:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/\"},\"wordCount\":868,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/Und-Merkel-geistert-durch-Hamburg.jpg\",\"keywords\":[\"durch\",\"geistert\",\"Hamburg\",\"Merkel\",\"und\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/\",\"name\":\"Und Merkel geistert durch Hamburg ... - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/Und-Merkel-geistert-durch-Hamburg.jpg\",\"datePublished\":\"2026-03-08T20:06:23+00:00\",\"dateModified\":\"2026-03-08T20:06:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/Und-Merkel-geistert-durch-Hamburg.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/Und-Merkel-geistert-durch-Hamburg.jpg\",\"width\":460,\"height\":259,\"caption\":\"Und Merkel geistert durch Hamburg ...\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Und Merkel geistert durch Hamburg &#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Und Merkel geistert durch Hamburg ... - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/","og_locale":"de_DE","og_type":"article","og_title":"Und Merkel geistert durch Hamburg ...","og_description":"Im Hamburger Rathaus gibt es ein j\u00e4hrliches Festmahl, eine jahrhundertealte Tradition: das Matthiae-Mahl. Nicht zum ersten Mal trat dort Ex-Kanzlerin Angela Merkel als Rednerin auf. Und obwohl sie nur eine Viertelstunde sprach, weckte es viele schlechte Erinnerungen. Von Dagmar Henn So vieles von dem, was uns heute schwer im Magen liegt, hat sie einger\u00fchrt. Und [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-03-08T20:06:23+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/69ac563948fbef36a75c934c.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Und Merkel geistert durch Hamburg &#8230;","datePublished":"2026-03-08T20:06:23+00:00","dateModified":"2026-03-08T20:06:23+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/"},"wordCount":868,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/Und-Merkel-geistert-durch-Hamburg.jpg","keywords":["durch","geistert","Hamburg","Merkel","und"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/","url":"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/","name":"Und Merkel geistert durch Hamburg ... - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/Und-Merkel-geistert-durch-Hamburg.jpg","datePublished":"2026-03-08T20:06:23+00:00","dateModified":"2026-03-08T20:06:23+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/Und-Merkel-geistert-durch-Hamburg.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/03\/Und-Merkel-geistert-durch-Hamburg.jpg","width":460,"height":259,"caption":"Und Merkel geistert durch Hamburg ..."},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/und-merkel-geistert-durch-hamburg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Und Merkel geistert durch Hamburg &#8230;"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/99993"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=99993"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/99993\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/99994"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=99993"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=99993"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=99993"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}