{"id":98920,"date":"2026-02-15T22:11:13","date_gmt":"2026-02-15T20:11:13","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/"},"modified":"2026-02-15T22:11:13","modified_gmt":"2026-02-15T20:11:13","slug":"polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/","title":{"rendered":"Polens Pr\u00e4sident Nawrocki will eigene Atomwaffen entwickeln lassen"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/69920e1848fbef77a947178f.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Der US-Sender Bloomberg berichtet \u00fcber eine Erkl\u00e4rung von Pr\u00e4sident Karol Nawrocki zu m\u00f6glichen polnischen Atomwaffen. Auch ukrainische Politiker und Medien berichten, dass in Europa immer mehr Stimmen laut werden, die neben dem US-amerikanischen &#8220;Atomschirm&#8221; den Aufbau eines eigenen &#8220;Verteidigungssystems&#8221; fordern.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Polens Pr\u00e4sident Karol Nawrocki hat auf <em>Polsat News<\/em> erkl\u00e4rt, er sei ein gro\u00dfer Bef\u00fcrworter\u00a0eines polnischen Atomprogramms. Er glaube, Warschau solle den Weg der Entwicklung seines eigenen Nuklearpotenzials beschreiten und dabei alle internationalen Bestimmungen respektieren, da es sich &#8220;am Rande eines bewaffneten Konflikts&#8221; befinde. Der rechte Politiker sagte:<\/p>\n<blockquote>\n<p><em>&#8220;Wir kennen die Haltung der aggressiven, imperialistischen Russischen F\u00f6deration gegen\u00fcber Polen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Auf die Frage, ob die Vereinigten Staaten Polen erlauben w\u00fcrden, in diese Richtung zu gehen, da Warschau Unterzeichnerstaat des Atomwaffensperrvertrags ist, antwortete Nawrocki: &#8220;Ich wei\u00df es nicht, aber wir m\u00fcssen uns in diese Richtung bewegen, damit wir mit der Arbeit beginnen k\u00f6nnen.&#8221;<\/p>\n<p><em>Bloomberg<\/em> merkte an, dass Nawrockis \u00c4u\u00dferungen erfolgten, nachdem Bundeskanzler Friedrich Merz auf der M\u00fcnchner Sicherheitskonferenz angek\u00fcndigt hatte, Gespr\u00e4che mit Frankreich \u00fcber eine m\u00f6gliche europ\u00e4ische Nuklearverteidigung zu f\u00fchren. Merz hatte angesichts der Turbulenzen w\u00e4hrend Donald Trumps zweiter Amtszeit eine Neuordnung der transatlantischen Beziehungen gefordert.<\/p>\n<p>Zudem erinnert<em> Bloomberg<\/em> daran, dass Warschau im Jahr 2025 ein Abkommen mit Frankreich unterzeichnet hat, das, wie Premierminister Donald Tusk erkl\u00e4rte, den Weg f\u00fcr eine m\u00f6gliche gemeinsame Nutzung des Schutzes vor franz\u00f6sischen Raketen durch Polen ebnen soll. Nawrocki erkl\u00e4rte gegen\u00fcber <em>Polsat News<\/em>, es sei noch zu fr\u00fch, um zu sagen, ob er das Gesetz in dieser Angelegenheit unterzeichnen werde.\u00a0Weiterhin antwortete Nawrocki auf die Frage von <em>Polsat News<\/em>, wie Moskau auf Polens Atomwaffenprogramm reagieren k\u00f6nnte, mit der Behauptung, dass &#8220;Russland auf alles aggressiv reagieren kann&#8221;.<\/p>\n<p>Anton Heraschtschenko vom ukrainischen Innenministerium merkte im Zusammenhang mit Nawrockis \u00c4u\u00dferungen an, dass &#8220;in Europa die Diskussionen \u00fcber die Schaffung einer eigenen nuklearen Abschreckung, die den amerikanischen &#8216;nuklearen Schutzschirm&#8217; erg\u00e4nzen w\u00fcrde, intensiviert wurden&#8221;.<\/p>\n<p>Nawrockis \u00c4u\u00dferungen blieben auch in Russland nicht ungeh\u00f6rt. So berichtete die Nachrichtenagentur\u00a0<em>RIA Nowosti<\/em> bereits, Pr\u00e4sident Nawrocki habe sich &#8220;f\u00fcr die Stationierung von Atomwaffen in Polen ausgesprochen&#8221;.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2013\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/europa\/269901-rueckschlag-fuer-us-regierung-polen\/\">R\u00fcckschlag f\u00fcr US-Regierung: Polen und Italien wollen Trumps &#8220;Friedensrat&#8221; nicht beitreten<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/270263-polens-praesident-nawrocki-will-eigene\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der US-Sender Bloomberg berichtet \u00fcber eine Erkl\u00e4rung von Pr\u00e4sident Karol Nawrocki zu m\u00f6glichen polnischen Atomwaffen. Auch ukrainische Politiker und Medien berichten, dass in Europa immer mehr Stimmen laut werden, die neben dem US-amerikanischen &#8220;Atomschirm&#8221; den Aufbau eines eigenen &#8220;Verteidigungssystems&#8221; fordern. Polens Pr\u00e4sident Karol Nawrocki hat auf Polsat News erkl\u00e4rt, er sei ein gro\u00dfer Bef\u00fcrworter\u00a0eines polnischen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":98921,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1771186441"],"wp_automatic_camp":["217"],"30729235a8646c1a88366c85cd74ff1e":["Polens Pr\u00e4sident Nawrocki will eigene Atomwaffen entwickeln lassen"],"original_link":["https:\/\/de.rt.com\/international\/270263-polens-praesident-nawrocki-will-eigene\/"],"_thumbnail_id":["98921"],"jnews_social_counter_last_update":["1784114754"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-02-15 22:14:59\";}"]},"categories":[19,23],"tags":[7620,20241,10044,3340,65411,14418,3464],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Polens Pr\u00e4sident Nawrocki will eigene Atomwaffen entwickeln lassen - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Polens Pr\u00e4sident Nawrocki will eigene Atomwaffen entwickeln lassen\" \/>\n<meta property=\"og:description\" content=\"Der US-Sender Bloomberg berichtet \u00fcber eine Erkl\u00e4rung von Pr\u00e4sident Karol Nawrocki zu m\u00f6glichen polnischen Atomwaffen. Auch ukrainische Politiker und Medien berichten, dass in Europa immer mehr Stimmen laut werden, die neben dem US-amerikanischen &#8220;Atomschirm&#8221; den Aufbau eines eigenen &#8220;Verteidigungssystems&#8221; fordern. Polens Pr\u00e4sident Karol Nawrocki hat auf Polsat News erkl\u00e4rt, er sei ein gro\u00dfer Bef\u00fcrworter\u00a0eines polnischen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-15T20:11:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/69920e1848fbef77a947178f.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Polens Pr\u00e4sident Nawrocki will eigene Atomwaffen entwickeln lassen\",\"datePublished\":\"2026-02-15T20:11:13+00:00\",\"dateModified\":\"2026-02-15T20:11:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/\"},\"wordCount\":391,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/Polens-Praesident-Nawrocki-will-eigene-Atomwaffen-entwickeln-lassen.jpg\",\"keywords\":[\"Atomwaffen\",\"eigene\",\"entwickeln\",\"lassen\",\"Nawrocki\",\"Polens\",\"Pr\u00e4sident\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/\",\"name\":\"Polens Pr\u00e4sident Nawrocki will eigene Atomwaffen entwickeln lassen - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/Polens-Praesident-Nawrocki-will-eigene-Atomwaffen-entwickeln-lassen.jpg\",\"datePublished\":\"2026-02-15T20:11:13+00:00\",\"dateModified\":\"2026-02-15T20:11:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/Polens-Praesident-Nawrocki-will-eigene-Atomwaffen-entwickeln-lassen.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/Polens-Praesident-Nawrocki-will-eigene-Atomwaffen-entwickeln-lassen.jpg\",\"width\":460,\"height\":259,\"caption\":\"Polens Pr\u00e4sident Nawrocki will eigene Atomwaffen entwickeln lassen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Polens Pr\u00e4sident Nawrocki will eigene Atomwaffen entwickeln lassen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Polens Pr\u00e4sident Nawrocki will eigene Atomwaffen entwickeln lassen - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/","og_locale":"de_DE","og_type":"article","og_title":"Polens Pr\u00e4sident Nawrocki will eigene Atomwaffen entwickeln lassen","og_description":"Der US-Sender Bloomberg berichtet \u00fcber eine Erkl\u00e4rung von Pr\u00e4sident Karol Nawrocki zu m\u00f6glichen polnischen Atomwaffen. Auch ukrainische Politiker und Medien berichten, dass in Europa immer mehr Stimmen laut werden, die neben dem US-amerikanischen &#8220;Atomschirm&#8221; den Aufbau eines eigenen &#8220;Verteidigungssystems&#8221; fordern. Polens Pr\u00e4sident Karol Nawrocki hat auf Polsat News erkl\u00e4rt, er sei ein gro\u00dfer Bef\u00fcrworter\u00a0eines polnischen [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-02-15T20:11:13+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/69920e1848fbef77a947178f.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Polens Pr\u00e4sident Nawrocki will eigene Atomwaffen entwickeln lassen","datePublished":"2026-02-15T20:11:13+00:00","dateModified":"2026-02-15T20:11:13+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/"},"wordCount":391,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/Polens-Praesident-Nawrocki-will-eigene-Atomwaffen-entwickeln-lassen.jpg","keywords":["Atomwaffen","eigene","entwickeln","lassen","Nawrocki","Polens","Pr\u00e4sident"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/","url":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/","name":"Polens Pr\u00e4sident Nawrocki will eigene Atomwaffen entwickeln lassen - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/Polens-Praesident-Nawrocki-will-eigene-Atomwaffen-entwickeln-lassen.jpg","datePublished":"2026-02-15T20:11:13+00:00","dateModified":"2026-02-15T20:11:13+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/Polens-Praesident-Nawrocki-will-eigene-Atomwaffen-entwickeln-lassen.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/Polens-Praesident-Nawrocki-will-eigene-Atomwaffen-entwickeln-lassen.jpg","width":460,"height":259,"caption":"Polens Pr\u00e4sident Nawrocki will eigene Atomwaffen entwickeln lassen"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/polens-praesident-nawrocki-will-eigene-atomwaffen-entwickeln-lassen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Polens Pr\u00e4sident Nawrocki will eigene Atomwaffen entwickeln lassen"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/98920"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=98920"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/98920\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/98921"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=98920"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=98920"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=98920"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}