{"id":98288,"date":"2026-02-03T14:59:34","date_gmt":"2026-02-03T12:59:34","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/"},"modified":"2026-02-03T14:59:34","modified_gmt":"2026-02-03T12:59:34","slug":"moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/","title":{"rendered":"&quot;Moralisch degeniert&quot; &#8211; Kiew attackiert FIFA-Pr\u00e4sident Infantino"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/6981c207b480cc78b05d2def.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Der ukrainische Au\u00dfenminister Andrei Sibiga hat FIFA-Pr\u00e4sident Gianni Infantino als &#8220;moralischen Degeneraten&#8221; bezeichnet. Anlass sind Infantinos Forderungen, Sperren gegen russische Athleten zu \u00fcberdenken. Der Fu\u00dfballfunktion\u00e4r h\u00e4lt Boykotte f\u00fcr wirkungslos und pl\u00e4diert f\u00fcr Jugendteilnahmen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em><\/em>Andrei Sibiga, seines Zeichens ukrainischer Au\u00dfenminister, bezeichnete FIFA-Pr\u00e4sident Gianni Infantino als &#8220;moralischen Degeneraten&#8221;, nachdem dieser Kritik an den Teilnahmeverboten f\u00fcr russische Athleten bei zahlreichen internationalen Sportwettk\u00e4mpfen ge\u00fcbt hatte.<\/p>\n<p>Infantino hatte zu diesem Thema am Montag gegen\u00fcber dem Fernsehsender <em>Sky News<\/em>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/news.sky.com\/story\/infantino-is-controversial-but-consistent-the-fifa-boss-places-football-above-politics-13502330\">festgestellt<\/a>, die bisherigen Verbote und Boykotte haben &#8220;nichts gebracht&#8221; und &#8220;lediglich zu noch mehr Frust und Hass gef\u00fchrt&#8221;. Man werde daher wohl die Teilnahme russischer Mannschaften an Wettbewerben unter der \u00c4gide des Verbandes wieder erlauben m\u00fcssen.\u00a0Russen sollten jedenfalls &#8220;zumindest im Jugendbereich&#8221; an Wettk\u00e4mpfen teilnehmen d\u00fcrfen.\u00a0<\/p>\n<p>Aus derselben \u00dcberlegung heraus erkl\u00e4rte er sich dagegen, etwa Israel f\u00fcr dessen Vorgehen gegen pal\u00e4stinensische Zivilisten oder die USA f\u00fcr deren aktuelles Verhalten in der internationalen Arena und Vorgehen gegen Einwanderer von internationalen Sportwettbewerben auszuschlie\u00dfen.\u00a0Zugleich bekundete er\u00a0den Wunsch, das Regelwerk der FIFA dergestalt zu \u00e4ndern, dass politisch motivierte Ausschl\u00fcsse von Sportlern jeglicher L\u00e4nder grunds\u00e4tzlich ausdr\u00fccklich verboten w\u00e4ren.\u00a0<\/p>\n<p><em>Sky News<\/em> fasste die Haltung des FIFA-Vorsitzenden wie folgt zusammen:<\/p>\n<blockquote>\n<p><em>&#8220;Was man von Infantino auch halten mag \u2013 er bleibt konsequent. Er glaubt daran, dass Fu\u00dfball \u00fcber der Politik stehen sollte.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Die Reaktion auf Infantinos Vorsto\u00df brachte der ukrainische Au\u00dfenminister auf seiner Internet-Pr\u00e4senz im sozialen Netzwerk X (vormals Twitter) an \u2013 und warf im selben Atemzug Russland vor, Kinder in der ehemaligen Ukrainischen Sowjetrepublik zu t\u00f6ten:<\/p>\n<p><em>&#8220;Und es t\u00f6tet immer weiter, w\u00e4hrend moralische Degeneraten vorschlagen, die Verbote aufzuheben \u2013 obwohl Russland seinen Krieg nicht beendet hat.&#8221;<\/em><\/p>\n<p>Sibiga lie\u00df sich au\u00dferdem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.nytimes.com\/athletic\/7016812\/2026\/02\/02\/russia-ukraine-football-ban-fifa-infantino\/\">zur Weissagung verleiten<\/a>, zuk\u00fcnftige Generationen w\u00fcrden Infantinos \u00c4u\u00dferungen als besch\u00e4mend empfinden, und erkl\u00e4rte schlie\u00dflich,\u00a0Infantinos Haltung erinnere ihn an die Olympischen Spiele 1936, die von Nazi-Deutschland ausgerichtet wurden.<\/p>\n<p>Russland betonte in der Vergangenheit wiederholt, dass seine Truppen ausschlie\u00dflich milit\u00e4rische Ziele in der Ukraine angreifen \u2013 und nicht Zivilisten. Demgegen\u00fcber ist es gerade die ukrainische Seite selbst, die sich an Zivilisten vergeht, und zwar nicht nur <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/russland\/268187-ukrainische-massaker-im-gebiet-kursk\/\">an russischen Staatsb\u00fcrgern<\/a>, sondern auch <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/europa\/267322-kriegsverbrechen-ukrainischen-militaers-ungesuehnt-bei\/\">an ukrainischen<\/a>.<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v72ufp8\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<p>Seit der Eskalation des zuvor schwelenden Ukraine-Konflikts im Jahr 2022 sind russische und wei\u00dfrussische Athleten und Nationalmannschaften von den meisten internationalen Sportwettbewerben, darunter FIFA- und UEFA-Spiele sowie die Olympischen Spiele, ausgeschlossen.<\/p>\n<p>Die Ukraine hat zudem eigene Sanktionen gegen einzelne russische Athleten verh\u00e4ngt, denen sie vorwirft, &#8220;Aggression und Propaganda&#8221; zu unterst\u00fctzen.<\/p>\n<p>Mehrere internationale Sportorganisationen haben die Beschr\u00e4nkungen in letzter Zeit gelockert. So ermutigte das Internationale Olympische Komitee (IOC) die nationalen Verb\u00e4nde Ende letzten Jahres, Athleten aus Russland und Wei\u00dfrussland die Teilnahme an Juniorenwettbewerben unter ihren Nationalflaggen und -hymnen zu erm\u00f6glichen.<\/p>\n<p>Russische Beamte und Sportfunktion\u00e4re kritisierten die Boykotte als &#8220;Politisierung&#8221; des Sports; Michail Degtjarjow, Pr\u00e4sident des Russischen Olympischen Komitees, verurteilte den Ausschluss der Athleten von internationalen Wettbewerben als &#8220;politische Diskriminierung&#8221; und Versto\u00df gegen die Olympische Charta.<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/europa\/263910-kiew-spricht-von-verrat-europameisterin\/\">Kiew spricht von &#8220;Verrat&#8221;: Europameisterin im Turmspringen nimmt russische Staatsb\u00fcrgerschaft an<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v730gvs\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/269159-wegen-kritik-an-ausschluss-sportler-russlands-kiew-schimpft-fifa-prasident-degenerat\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der ukrainische Au\u00dfenminister Andrei Sibiga hat FIFA-Pr\u00e4sident Gianni Infantino als &#8220;moralischen Degeneraten&#8221; bezeichnet. Anlass sind Infantinos Forderungen, Sperren gegen russische Athleten zu \u00fcberdenken. Der Fu\u00dfballfunktion\u00e4r h\u00e4lt Boykotte f\u00fcr wirkungslos und pl\u00e4diert f\u00fcr Jugendteilnahmen. Andrei Sibiga, seines Zeichens ukrainischer Au\u00dfenminister, bezeichnete FIFA-Pr\u00e4sident Gianni Infantino als &#8220;moralischen Degeneraten&#8221;, nachdem dieser Kritik an den Teilnahmeverboten f\u00fcr russische Athleten [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":98289,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1770123950"],"wp_automatic_camp":["217"],"c3f24d10d87477dcdc95145884653717":["&quot;Moralisch degeniert&quot; - Kiew attackiert FIFA-Pr\u00e4sident Infantino"],"original_link":["https:\/\/de.rt.com\/international\/269159-wegen-kritik-an-ausschluss-sportler-russlands-kiew-schimpft-fifa-prasident-degenerat\/"],"_thumbnail_id":["98289"],"jnews_social_counter_last_update":["1784061652"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-02-03 15:06:52\";}"]},"categories":[19,23],"tags":[19082,70975,70976,50276,1025,70974],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Moralisch degeniert&quot; - Kiew attackiert FIFA-Pr\u00e4sident Infantino - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Moralisch degeniert&quot; - Kiew attackiert FIFA-Pr\u00e4sident Infantino\" \/>\n<meta property=\"og:description\" content=\"Der ukrainische Au\u00dfenminister Andrei Sibiga hat FIFA-Pr\u00e4sident Gianni Infantino als &#8220;moralischen Degeneraten&#8221; bezeichnet. Anlass sind Infantinos Forderungen, Sperren gegen russische Athleten zu \u00fcberdenken. Der Fu\u00dfballfunktion\u00e4r h\u00e4lt Boykotte f\u00fcr wirkungslos und pl\u00e4diert f\u00fcr Jugendteilnahmen. Andrei Sibiga, seines Zeichens ukrainischer Au\u00dfenminister, bezeichnete FIFA-Pr\u00e4sident Gianni Infantino als &#8220;moralischen Degeneraten&#8221;, nachdem dieser Kritik an den Teilnahmeverboten f\u00fcr russische Athleten [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-03T12:59:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/6981c207b480cc78b05d2def.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"&quot;Moralisch degeniert&quot; &#8211; Kiew attackiert FIFA-Pr\u00e4sident Infantino\",\"datePublished\":\"2026-02-03T12:59:34+00:00\",\"dateModified\":\"2026-02-03T12:59:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/\"},\"wordCount\":540,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/quotMoralisch-degeniertquot-Kiew-attackiert-FIFA-Praesident-Infantino.jpg\",\"keywords\":[\"attackiert\",\"degeniertquot\",\"FIFAPr\u00e4sident\",\"Infantino\",\"Kiew\",\"quotMoralisch\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/\",\"name\":\"&quot;Moralisch degeniert&quot; - Kiew attackiert FIFA-Pr\u00e4sident Infantino - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/quotMoralisch-degeniertquot-Kiew-attackiert-FIFA-Praesident-Infantino.jpg\",\"datePublished\":\"2026-02-03T12:59:34+00:00\",\"dateModified\":\"2026-02-03T12:59:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/quotMoralisch-degeniertquot-Kiew-attackiert-FIFA-Praesident-Infantino.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/quotMoralisch-degeniertquot-Kiew-attackiert-FIFA-Praesident-Infantino.jpg\",\"width\":460,\"height\":259,\"caption\":\"&quot;Moralisch degeniert&quot; - Kiew attackiert FIFA-Pr\u00e4sident Infantino\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&quot;Moralisch degeniert&quot; &#8211; Kiew attackiert FIFA-Pr\u00e4sident Infantino\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"&quot;Moralisch degeniert&quot; - Kiew attackiert FIFA-Pr\u00e4sident Infantino - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/","og_locale":"de_DE","og_type":"article","og_title":"&quot;Moralisch degeniert&quot; - Kiew attackiert FIFA-Pr\u00e4sident Infantino","og_description":"Der ukrainische Au\u00dfenminister Andrei Sibiga hat FIFA-Pr\u00e4sident Gianni Infantino als &#8220;moralischen Degeneraten&#8221; bezeichnet. Anlass sind Infantinos Forderungen, Sperren gegen russische Athleten zu \u00fcberdenken. Der Fu\u00dfballfunktion\u00e4r h\u00e4lt Boykotte f\u00fcr wirkungslos und pl\u00e4diert f\u00fcr Jugendteilnahmen. Andrei Sibiga, seines Zeichens ukrainischer Au\u00dfenminister, bezeichnete FIFA-Pr\u00e4sident Gianni Infantino als &#8220;moralischen Degeneraten&#8221;, nachdem dieser Kritik an den Teilnahmeverboten f\u00fcr russische Athleten [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-02-03T12:59:34+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/6981c207b480cc78b05d2def.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"&quot;Moralisch degeniert&quot; &#8211; Kiew attackiert FIFA-Pr\u00e4sident Infantino","datePublished":"2026-02-03T12:59:34+00:00","dateModified":"2026-02-03T12:59:34+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/"},"wordCount":540,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/quotMoralisch-degeniertquot-Kiew-attackiert-FIFA-Praesident-Infantino.jpg","keywords":["attackiert","degeniertquot","FIFAPr\u00e4sident","Infantino","Kiew","quotMoralisch"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/","url":"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/","name":"&quot;Moralisch degeniert&quot; - Kiew attackiert FIFA-Pr\u00e4sident Infantino - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/quotMoralisch-degeniertquot-Kiew-attackiert-FIFA-Praesident-Infantino.jpg","datePublished":"2026-02-03T12:59:34+00:00","dateModified":"2026-02-03T12:59:34+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/quotMoralisch-degeniertquot-Kiew-attackiert-FIFA-Praesident-Infantino.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/quotMoralisch-degeniertquot-Kiew-attackiert-FIFA-Praesident-Infantino.jpg","width":460,"height":259,"caption":"&quot;Moralisch degeniert&quot; - Kiew attackiert FIFA-Pr\u00e4sident Infantino"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/moralisch-degeniert-kiew-attackiert-fifa-praesident-infantino\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"&quot;Moralisch degeniert&quot; &#8211; Kiew attackiert FIFA-Pr\u00e4sident Infantino"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/98288"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=98288"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/98288\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/98289"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=98288"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=98288"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=98288"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}