{"id":98275,"date":"2026-02-03T10:02:23","date_gmt":"2026-02-03T08:02:23","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\/"},"modified":"2026-02-03T10:02:23","modified_gmt":"2026-02-03T08:02:23","slug":"deutsche-kriegstuechtigkeit-der-ton-wird-schriller","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\/","title":{"rendered":"Deutsche Kriegst\u00fcchtigkeit: Der Ton wird schriller"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/6980da68b480cc49d77c1dd4.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die Wehrpflicht f\u00fcr Frauen sowie die vollst\u00e4ndige Einbeziehung der Zivilbev\u00f6lkerung in die Kriegsf\u00fchrung k\u00fcndigen sich in Deutschland an. Und wer immer noch nicht mental auf Krieg eingestellt ist, dem droht die Presse den Genozid durch die Russen an.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Astrid Sigena<\/em><\/p>\n<p>Vor dem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.cdu.de\/38-parteitag\/\">CDU-Parteitag<\/a> Ende Februar \u00fcberbieten sich die verschiedenen Parteigruppierungen mit Grausamkeiten gegen\u00fcber dem B\u00fcrger, durch die Deutschland wieder fit gemacht werden soll. So sprach die Bundestagsabgeordnete Gitta Connemann von der Mittelstands- und Wirtschaftsunion von der Gefahr einer sogenannten &#8220;Lifestyle-Teilzeit&#8221; und <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/268373-cdu-wirtschaftsfluegel-will-recht-auf\/\">forderte<\/a> eine Einschr\u00e4nkung der M\u00f6glichkeit, lediglich auf Teilzeitbasis zu arbeiten. Ins gleiche Horn blies der &#8220;Wirtschaftsrat der CDU e. V.&#8221; und verlangte \u2013 neben der Abschaffung weiterer Sozialleistungen \u2013, dass die Krankenkassen in Zukunft nicht mehr die Kosten von Zahnbehandlungen tragen sollten (<em>RT DE<\/em>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/269042-deutschland-lobbyverband-fordert-steuersenkungen-und\/\">berichtete<\/a>).<\/p>\n<p>Die Frauenunion wollte bei diesem \u00dcberbietungswettbewerb nicht abseits stehen und wagte sich auf das Feld der Verteidigungspolitik. In einem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/web.de\/magazine\/politik\/inland\/frauen-union-frauen-ausfuellen-wehrdienst-fragebogens-verpflichten-41847332\">Antrag<\/a> f\u00fcr den Bundesparteitag m\u00f6chte sie die verpflichtende briefliche Musterung auch f\u00fcr junge Frauen (derzeit sind nur junge M\u00e4nner der Alterskohorte ab 18 Jahren verpflichtet, diese Briefe auszuf\u00fcllen). Der Fragebogen soll nach dem Willen der Unionsfrauen au\u00dferdem erweitert werden: Wer ankreuzt, dass er Interesse an einem Einsatz im sozialen Bereich oder im Zivil- oder Katastrophenschutz habe, soll in Zukunft gezielt Post von Wohlt\u00e4tigkeitsverb\u00e4nden und Blaulichtorganisationen bekommen.<\/p>\n<p>Letztendlich zielt der Antrag der Christdemokratinnen aber auf ein verpflichtendes Gesellschaftsjahr f\u00fcr alle Geschlechter ab, also eine Wehrpflicht beziehungsweise einen Ersatzdienst auch f\u00fcr Frauen. Dazu m\u00fcsste man dann allerdings das Grundgesetz \u00e4ndern, denn dort ist bisher nur eine Wehrpflicht f\u00fcr M\u00e4nner vorgesehen. Da die Linke gegen die Wiedereinf\u00fchrung der Wehrpflicht und erst recht gegen ein verpflichtendes Gesellschaftsjahr ist, bleibt zur n\u00f6tigen Zweidrittelmehrheit f\u00fcr die Verfassungs\u00e4nderung nur ein Zusammengehen mit der AfD-Fraktion \u00fcbrig. Derzeit pl\u00e4diert die AfD in ihrem Grundsatzprogramm f\u00fcr eine Wiedereinf\u00fchrung der Wehrpflicht nur f\u00fcr M\u00e4nner. Das Grundsatzprogramm wird allerdings derzeit \u00fcberarbeitet und offenbar spekuliert die Frauenunion auf einen Gesinnungswandel der AfD zugunsten einer Dienstpflicht f\u00fcr beide Geschlechter.<\/p>\n<p>Der Vorsto\u00df der Frauenunion ist allerdings nur ein Anfang. Man verf\u00e4hrt nach dem Prinzip &#8220;Steter Tropfen h\u00f6hlt den Stein&#8221; und hofft auf die zerm\u00fcrbende Wirkung steter medialer Aufbereitung des Themas. Geschickt wird dabei eine Debatte \u00fcber die Frage vermieden, ob eine Wiederaufr\u00fcstung Deutschlands sowie eine Ausweitung der Wehrpflicht \u00fcberhaupt notwendig sind und ob sie nicht vielmehr fragw\u00fcrdigen Zwecken dienen.<\/p>\n<p>Stattdessen wird eine Ausweitung der Wehrpflicht auf junge Frauen zur Angelegenheit von Feminismus und Geschlechtergerechtigkeit \u2013 eigentlich Nebenkriegsschaupl\u00e4tze im Vergleich zur zentralen Frage von Krieg und Frieden, um die es hier tats\u00e4chlich geht. So zum Beispiel die Historikerin Karen Hagemann, deren Hauptsorge die Bek\u00e4mpfung &#8220;toxischer M\u00e4nnlichkeit&#8221; im Milit\u00e4r zu sein scheint. Auch Hagemann <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.deutschlandfunkkultur.de\/neue-wehrhaftigkeit-was-militarisierung-mit-der-gesellschaft-macht-100.html\">sieht<\/a> eine &#8220;geschlechtergerechte Form&#8221; der Wehrpflicht kommen sowie &#8220;in einer kriegsnahen Situation&#8221; eine Mobilisierung der Zivilbev\u00f6lkerung (Minute 17 f.).<\/p>\n<p>Allerdings haben die Verfechter der Kriegst\u00fcchtigkeit ein Problem: Noch gilt das Recht auf Kriegsdienstverweigerung aus Gewissensgr\u00fcnden \u2013 noch, denn es mehren sich juristische Stimmen, die f\u00fcr eine Einschr\u00e4nkung oder gar Abschaffung dieses Rechts <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.deutschlandfunk.de\/krieg-deutschland-verteidigungsfall-ausnahmezustand-wehrpflicht-grundrechte-100.html\">pl\u00e4dieren<\/a>. Administrativ lie\u00dfe es sich auch ohne Gesetzes\u00e4nderung einrichten, die M\u00f6glichkeiten f\u00fcr potenzielle Verweigerer einzuschr\u00e4nken: Kriegsdienstverweigerer aus den 1950ern und 1960ern k\u00f6nnen noch aus eigener leidvoller Erfahrung berichten, welche Verh\u00f6re sie bis zur endg\u00fcltigen Anerkennung durchstehen mussten.<\/p>\n<p>Durch die k\u00fcrzliche Versch\u00e4rfung des Arbeitssicherstellungsgesetzes hat der Staat im Spannungs- und Verteidigungsfall erweiterte M\u00f6glichkeiten, auch Zivilisten zu einer T\u00e4tigkeit in kriegswichtigen Bereichen zu <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.abendblatt.de\/hamburg\/politik\/article409581120\/arbeitsagentur-und-bundeswehr-ueben-gemeinsam-im-krisenfall-muessen-auch-zivilisten-ran-3.html\">verpflichten<\/a>: So etwa zur Arbeit in R\u00fcstungsunternehmen oder bei der Versorgung von Bundeswehrsoldaten oder verb\u00fcndeter Truppen. F\u00fcr Frauen <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/perspektive-online.net\/2025\/08\/aus-dem-buero-an-die-front-arbeitszwang-im-kriegsfall-per-gesetz\/\">besteht<\/a> bisher nur die M\u00f6glichkeit einer Dienstverpflichtung im Lazarett \u2013 bei 1.000 hereinstr\u00f6menden verletzten Soldaten (so die <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.thetimes.com\/world\/europe\/article\/germany-russia-attacks-nato-commander-preparing-lhjdtzsmm\">Prognose<\/a> des Bundeswehrgenerals Gerald Funke) kein Zuckerschlecken.<\/p>\n<p>Man kann angesichts des voraussichtlichen Mangels an Arbeitskr\u00e4ften f\u00fcr kriegswichtige Betriebe davon ausgehen, dass beim Thema Dienstpflicht f\u00fcr Frauen nicht locker gelassen wird. Milit\u00e4rs wie Generalleutnant Funke gehen jedenfalls f\u00fcr den Ernstfall von einer Einbeziehung der Zivilbev\u00f6lkerung aus: &#8220;Es muss ganz klar gesagt werden, dass wir ohne die Unterst\u00fctzung der Zivilbev\u00f6lkerung im Rahmen eines Gesamtverteidigungskonzepts nicht in der Lage w\u00e4ren, uns zu verteidigen.&#8221;<\/p>\n<p>Lieber ist es jedoch den Verfechtern der Kriegst\u00fcchtigkeit, die Bev\u00f6lkerung w\u00fcrde freiwillig mitmachen, wenn es wieder gegen Russland geht. Immerhin kostet es auch den Staat Nerven und Aufwand, Unwillige zu Dienstleistungen zu zwingen. Umso besser, wenn sie mental so gepolt sind, dass sie aus Angst vor &#8220;dem Russen&#8221; freiwillig mitmachen. Noch immer sehen allerdings f\u00fcr den Geschmack der Bellizisten zu viele Deutsche nicht ein, warum ausgerechnet sie pers\u00f6nlich sich an einer solch gewagten Unternehmung wie einem Krieg gegen Russland beteiligen sollen.<\/p>\n<p>Es ist daher kein Wunder, dass sich in den letzten Tagen der mediale Ton nochmals versch\u00e4rft hat. Den kriegsunwilligen Deutschen wird das Schlimmste angedroht: den Genozid durch die Russen. So <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.welt.de\/politik\/ausland\/plus68e3738d1642fe56b7eda508\/ukraine-krieg-die-russen-denken-dass-ihr-alle-nazis-seid-denkt-ihr-wirklich-dass-sie-euch-leben-lassen.html\">warnt<\/a> Florian S\u00e4dler in der <em>Welt<\/em>\u00a0vor den Gefahren einer Kapitulation (die noch gar nicht zur Debatte steht) sowie einer anschlie\u00dfenden Besatzung und zitiert zur Bekr\u00e4ftigung seiner Warnung einen Ukrainer, der als Partisan gegen die russische Armee gek\u00e4mpft hat: &#8220;Die Russen denken, dass ihr alle Nazis seid. Denkt ihr wirklich, dass sie euch einfach leben lassen? Nein.&#8221; Wer sich nicht gegen die Russen wehre, dem drohe der sichere Tod. Ein neuer Tiefstand der propagandistischen Angstmache.<\/p>\n<p>Ein weiteres Beispiel: Estlands Au\u00dfenminister Margus Tsahkna <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.24rhein.de\/welt\/politik\/putin-wird-tausende-kriminelle-entsenden-um-in-ganz-europa-verwuestung-anzurichten-zr-94149791.html?utm_term=Autofeed&amp;utm_campaign=24rhein&amp;utm_medium=Social&amp;utm_source=Facebook&amp;fbclid=IwY2xjawPtIz1leHRuA2FlbQIxMABicmlkETFNaUFqdHk1cElEVG1IWVRtc3J0YwZhcHBfaWQQMjIyMDM5MTc4ODIwMDg5MgABHnAPu8Mp4YT4AUaWXw01rpgzO7qb0oJpgSPFM9xP7A-1naudzYE3Y8rnmUOl_aem_2rm1pu4alxZPSA0uPtzC9Q\">sieht<\/a> zwar nicht die v\u00f6llige Ausl\u00f6schung Deutschlands kommen, daf\u00fcr jedoch hunderttausende russische Soldaten, die nach einem m\u00f6glichen Friedensabkommen die Reiselust Richtung Europa packen k\u00f6nnte. Putin w\u00fcrde dann Ex-H\u00e4ftlinge, M\u00f6rder und Vergewaltiger in die EU schicken, so Tsahkna: &#8220;Und sie kommen ganz bestimmt nicht mit guten Pl\u00e4nen, um ihren Lebensunterhalt zu verdienen und Steuern zu zahlen. Sie kommen mit wirklich schlechten Pl\u00e4nen.&#8221; Deshalb m\u00fcssten die Einreiseregelungen f\u00fcr Russen weiter versch\u00e4rft werden.<\/p>\n<p>Der Historiker Ilko-Sascha Kowalczuk wiederum <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.nzz.ch\/nzz-am-sonntag\/report-und-debatte\/woher-ruehrt-deutschlands-naehe-zu-russland-ein-ostdeutscher-historiker-erklaert-ld.1922284\">beklagt<\/a> eine mangelnde Kampfwilligkeit der Deutschen mit den Worten: &#8220;Wenn Putins Armee morgen vor Warschau st\u00fcnde, h\u00e4tte Deutschland ein Riesenproblem. Die Mehrheit w\u00fcrde kapitulieren und wei\u00dfe Flaggen hissen. Und diejenigen, die Widerstand leisteten, w\u00fcrden gehasst.&#8221; (auch hier muss wieder ein noch nicht eingetretener Kriegsfall \u2013 diesmal in Polen \u2013 herhalten, um kriegsunwillige Deutsche als Def\u00e4tisten zu brandmarken).<\/p>\n<p>Zus\u00e4tzlich problematisiert Kowalczuk ein angebliches Schuldgef\u00fchl der Deutschen gegen\u00fcber den Russen: &#8220;Aber die entscheidende Rolle spielt das Schuldgef\u00fchl wegen des Vernichtungsfeldzugs der Deutschen gegen die Sowjetunion im Zweiten Weltkrieg. Man spricht von 27 Millionen ermordeten Sowjetb\u00fcrgern und meint damit die Russen. Dabei waren die meisten Opfer Ukrainer und Wei\u00dfrussen! Aber das wird alles ausgeblendet und nicht differenziert.&#8221;\u00a0Klar, ein etwa noch vorhandenes Schuldgef\u00fchl der Deutschen wegen des vergangenen Krieges w\u00e4re aus Sicht der Kriegstreiber wirklich hinderlich bei einem robusten Vorgehen gegen\u00fcber Russland.<\/p>\n<p>Wer Kriegstreiberei und Hetze entgegentreten m\u00f6chte, sollte das tun und widersprechen, solange er noch die Gelegenheit dazu hat. Etwa beim n\u00e4chsten &#8220;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/schulstreikgegenwehrpflicht.com\/\">Schulstreik gegen Wehrpflicht<\/a>&#8221;\u00a0am 5. M\u00e4rz 2026 oder bei den Osterm\u00e4rschen Anfang April. Die Kriegshetzer sind auf das Mittun einer in Russenpanik versetzten Bev\u00f6lkerung angewiesen, das wissen sie genau. W\u00e4re es nicht gro\u00dfartig, wenn das Volk &#8220;Nein&#8221; sagte?<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/262743-gegen-drill-gehorsam-und-toeten-initiative-plant-bundesweite-schulstreiks-gegen-wehrpflicht\/\">Gegen &#8220;Drill, Gehorsam und T\u00f6ten&#8221;: Initiative plant bundesweite Schulstreiks gegen Wehrpflicht<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6vy8xs\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/269108-deutsche-kriegstuechtigkeit-ton-wird-schriller\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Wehrpflicht f\u00fcr Frauen sowie die vollst\u00e4ndige Einbeziehung der Zivilbev\u00f6lkerung in die Kriegsf\u00fchrung k\u00fcndigen sich in Deutschland an. Und wer immer noch nicht mental auf Krieg eingestellt ist, dem droht die Presse den Genozid durch die Russen an. Von Astrid Sigena Vor dem CDU-Parteitag Ende Februar \u00fcberbieten sich die verschiedenen Parteigruppierungen mit Grausamkeiten gegen\u00fcber dem [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":98276,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1770108518"],"wp_automatic_camp":["217"],"a9d278797caf9aa7edfe277faa4241e4":["Deutsche Kriegst\u00fcchtigkeit: Der Ton wird schriller"],"original_link":["https:\/\/de.rt.com\/meinung\/269108-deutsche-kriegstuechtigkeit-ton-wird-schriller\/"],"_thumbnail_id":["98276"],"jnews_social_counter_last_update":["1788238227"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-02-03 10:49:47\";}"]},"categories":[19,23],"tags":[82,2374,53113,70964,23507,374],"class_list":["post-98275","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-der","tag-deutsche","tag-kriegstuechtigkeit","tag-schriller","tag-ton","tag-wird"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Deutsche Kriegst\u00fcchtigkeit: Der Ton wird schriller - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Deutsche Kriegst\u00fcchtigkeit: Der Ton wird schriller\" \/>\n<meta property=\"og:description\" content=\"Die Wehrpflicht f\u00fcr Frauen sowie die vollst\u00e4ndige Einbeziehung der Zivilbev\u00f6lkerung in die Kriegsf\u00fchrung k\u00fcndigen sich in Deutschland an. Und wer immer noch nicht mental auf Krieg eingestellt ist, dem droht die Presse den Genozid durch die Russen an. Von Astrid Sigena Vor dem CDU-Parteitag Ende Februar \u00fcberbieten sich die verschiedenen Parteigruppierungen mit Grausamkeiten gegen\u00fcber dem [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-02-03T08:02:23+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/6980da68b480cc49d77c1dd4.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Deutsche Kriegst\u00fcchtigkeit: Der Ton wird schriller\",\"datePublished\":\"2026-02-03T08:02:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\\\/\"},\"wordCount\":1250,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/02\\\/Deutsche-Kriegstuechtigkeit-Der-Ton-wird-schriller.jpg\",\"keywords\":[\"der\",\"Deutsche\",\"Kriegst\u00fcchtigkeit\",\"schriller\",\"Ton\",\"wird\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\\\/\",\"name\":\"Deutsche Kriegst\u00fcchtigkeit: Der Ton wird schriller - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/02\\\/Deutsche-Kriegstuechtigkeit-Der-Ton-wird-schriller.jpg\",\"datePublished\":\"2026-02-03T08:02:23+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/02\\\/Deutsche-Kriegstuechtigkeit-Der-Ton-wird-schriller.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/02\\\/Deutsche-Kriegstuechtigkeit-Der-Ton-wird-schriller.jpg\",\"width\":460,\"height\":259,\"caption\":\"Deutsche Kriegst\u00fcchtigkeit: Der Ton wird schriller\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Deutsche Kriegst\u00fcchtigkeit: Der Ton wird schriller\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Deutsche Kriegst\u00fcchtigkeit: Der Ton wird schriller - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\/","og_locale":"de_DE","og_type":"article","og_title":"Deutsche Kriegst\u00fcchtigkeit: Der Ton wird schriller","og_description":"Die Wehrpflicht f\u00fcr Frauen sowie die vollst\u00e4ndige Einbeziehung der Zivilbev\u00f6lkerung in die Kriegsf\u00fchrung k\u00fcndigen sich in Deutschland an. Und wer immer noch nicht mental auf Krieg eingestellt ist, dem droht die Presse den Genozid durch die Russen an. Von Astrid Sigena Vor dem CDU-Parteitag Ende Februar \u00fcberbieten sich die verschiedenen Parteigruppierungen mit Grausamkeiten gegen\u00fcber dem [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-02-03T08:02:23+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/6980da68b480cc49d77c1dd4.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Deutsche Kriegst\u00fcchtigkeit: Der Ton wird schriller","datePublished":"2026-02-03T08:02:23+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\/"},"wordCount":1250,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/Deutsche-Kriegstuechtigkeit-Der-Ton-wird-schriller.jpg","keywords":["der","Deutsche","Kriegst\u00fcchtigkeit","schriller","Ton","wird"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\/","url":"https:\/\/now-news.de\/de\/deutschland\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\/","name":"Deutsche Kriegst\u00fcchtigkeit: Der Ton wird schriller - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/Deutsche-Kriegstuechtigkeit-Der-Ton-wird-schriller.jpg","datePublished":"2026-02-03T08:02:23+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/Deutsche-Kriegstuechtigkeit-Der-Ton-wird-schriller.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/02\/Deutsche-Kriegstuechtigkeit-Der-Ton-wird-schriller.jpg","width":460,"height":259,"caption":"Deutsche Kriegst\u00fcchtigkeit: Der Ton wird schriller"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/deutsche-kriegstuechtigkeit-der-ton-wird-schriller\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Deutsche Kriegst\u00fcchtigkeit: Der Ton wird schriller"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/98275","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=98275"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/98275\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/98276"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=98275"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=98275"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=98275"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}