{"id":97539,"date":"2026-01-20T11:02:20","date_gmt":"2026-01-20T09:02:20","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/"},"modified":"2026-01-20T11:02:20","modified_gmt":"2026-01-20T09:02:20","slug":"ausschreitungen-bei-anti-wef-demonstration-in-zuerich","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/","title":{"rendered":"Ausschreitungen bei Anti-WEF-Demonstration in Z\u00fcrich"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/696f3cc448fbef4ae63f71ae.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Mehrere Tausend Menschen protestierten in Z\u00fcrich gegen den Auftritt von Donald Trump am WEF in Davos. W\u00e4hrend der Demonstrationszug anf\u00e4nglich geordnet verlief, eskalierte die Lage im Bereich der Kasernenstra\u00dfe. Barrikaden, Br\u00e4nde und Angriffe auf Einsatzkr\u00e4fte f\u00fchrten zu einem Gro\u00dfaufgebot der Polizei.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p data-start=\"42\" data-end=\"416\">Am Montagabend ist es in Z\u00fcrich am Rande einer Demonstration gegen das Weltwirtschaftsforum zu schweren Ausschreitungen gekommen. Mehrere Tausend Menschen folgten dem Aufruf unter dem Motto &#8220;Trump still not welcome&#8221; und zogen ab 19 Uhr von der Stadthausanlage durch die Innenstadt in Richtung Helvetiaplatz. Der gr\u00f6\u00dfte Teil des Umzugs verlief zun\u00e4chst geordnet.<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\" data-media-max-width=\"560\">\n<p lang=\"de\" dir=\"ltr\">Bewilligte Anti-WEF-Demo in Z\u00fcrich mit mehreren Tausend Teilnehmenden <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/hashtag\/ZH1901?src=hash&amp;ref_src=twsrc%5Etfw\">#ZH1901<\/a><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/hashtag\/WEF?src=hash&amp;ref_src=twsrc%5Etfw\">#WEF<\/a><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/hashtag\/AntiWEF?src=hash&amp;ref_src=twsrc%5Etfw\">#AntiWEF<\/a><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/R5TE0C5AW5\">pic.twitter.com\/R5TE0C5AW5<\/a><\/p>\n<p>\u2014 R L (@RaimondLueppken) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/RaimondLueppken\/status\/2013332621078544440?ref_src=twsrc%5Etfw\">January 19, 2026<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Entlang der Route \u00fcber Limmatquai, Bahnhofstra\u00dfe und Rudolf-Brun-Br\u00fccke z\u00fcndeten Teilnehmende jedoch wiederholt B\u00f6ller, Rauchpetarden und Feuerwerksk\u00f6rper. Zudem kam es laut Angaben der Stadtpolizei zu Sprayereien sowie zu Farbbeutelw\u00fcrfen gegen Fassaden. An der Kreuzung Bahnhofstra\u00dfe und Uraniastra\u00dfe wurden Schaufensterscheiben besch\u00e4digt. Die H\u00f6he des Sachschadens ist bislang offen.<\/p>\n<p>W\u00e4hrend ein Teil der Demonstranten gegen 20.30 Uhr zur Abschlusskundgebung auf dem Helvetiaplatz eintraf, spaltete sich eine Gruppe ab, darunter Angeh\u00f6rige des sogenannten Schwarzen Blocks. Sie verlie\u00dfen die bewilligte Route und blockierten im Bereich der Milit\u00e4r- und Kasernenstra\u00dfe den Verkehr. Der \u00f6ffentliche Verkehr rund um die Kaserne kam zeitweise vollst\u00e4ndig zum Stillstand.<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"de\" dir=\"ltr\">Die Antifa ist eine Terrororganisation eine radikale, militante Struktur, die mit gezielter Gewalt gegen Andersdenkende vorgeht und politische Gegner jagt, geh\u00f6rt nicht auf die Strasse \u2013 sondern vor Gericht. <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/ppk5JKQThb\">https:\/\/t.co\/ppk5JKQThb<\/a><\/p>\n<p>\u2014 Manuel Cadonau \ud83c\udde8\ud83c\udded (@mcpolitik) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/mcpolitik\/status\/2013493334757589254?ref_src=twsrc%5Etfw\">January 20, 2026<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p data-start=\"810\" data-end=\"1198\">Nachdem die Blockade trotz mehrfacher Aufforderung nicht aufgehoben wurde, griff die Stadtpolizei kurz nach 21.30 Uhr ein. Mit Wasserwerfern versuchten die Einsatzkr\u00e4fte, die Gruppe auseinanderzutreiben.<\/p>\n<p>In der Folge flogen Steine und Feuerwerksk\u00f6rper in Richtung der Polizei. Diese setzte Reizstoff sowie Gummischrot ein, um die Lage unter Kontrolle zu bringen.<\/p>\n<p>Auf dem R\u00fcckweg zum Helvetiaplatz kam es zu weiteren Sachbesch\u00e4digungen. Scheiben einer Tramhaltestelle wurden eingeschlagen, Barrikaden errichtet und mehrere Abfallcontainer angez\u00fcndet. Die Feuerwehr musste ausr\u00fccken, um die Br\u00e4nde zu l\u00f6schen. Gegen 23 Uhr l\u00f6ste sich die Demonstration auf, Stra\u00dfen und Tramgleise wurden schrittweise wieder freigegeben.<\/p>\n<p>Zwei Polizisten wurden von Steinen getroffen, blieben jedoch unverletzt. Die Stadtpolizei meldete zun\u00e4chst keine verletzten Demonstranten, w\u00e4hrend ein Sanit\u00e4tsdienst aus dem Umfeld der Kundgebung von mehreren Verletzten sprach.<\/p>\n<p>Zur Demonstration aufgerufen hatte die linke Gruppierung &#8220;Bewegung f\u00fcr den Sozialismus&#8221;. Anlass war die Teilnahme von Donald Trump am Weltwirtschaftsforum in Davos. Die Veranstalter kritisierten den Auftritt des US-Pr\u00e4sidenten als Symbol einer aus ihrer Sicht militarisierten und machtpolitisch gepr\u00e4gten Weltordnung.<\/p>\n<p>Die Stadt Z\u00fcrich war w\u00e4hrend des Abends mit einem Gro\u00dfaufgebot der Stadtpolizei Z\u00fcrich pr\u00e4sent. Der Verkehr in weiten Teilen der Innenstadt blieb bis sp\u00e4t in die Nacht eingeschr\u00e4nkt.<\/p>\n<p data-start=\"2574\" data-end=\"2775\" data-is-last-node=\"\" data-is-only-node=\"\"><strong>Mehr zum Thema \u2013<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/meinung\/192872-davos-ist-nicht-wie-frueher\/\">Davos ist nicht wie fr\u00fcher: Die geopolitischen Pfaue haben den Kampf verloren<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v69y76j\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/schweiz\/267754-ausschreitungen-bei-anti-wef-demonstration\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mehrere Tausend Menschen protestierten in Z\u00fcrich gegen den Auftritt von Donald Trump am WEF in Davos. W\u00e4hrend der Demonstrationszug anf\u00e4nglich geordnet verlief, eskalierte die Lage im Bereich der Kasernenstra\u00dfe. Barrikaden, Br\u00e4nde und Angriffe auf Einsatzkr\u00e4fte f\u00fchrten zu einem Gro\u00dfaufgebot der Polizei. Am Montagabend ist es in Z\u00fcrich am Rande einer Demonstration gegen das Weltwirtschaftsforum zu [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":97540,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1768900443"],"wp_automatic_camp":["217"],"cf5245a5e0b896b4689f26e541e34976":["Ausschreitungen bei Anti-WEF-Demonstration in Z\u00fcrich"],"original_link":["https:\/\/de.rt.com\/schweiz\/267754-ausschreitungen-bei-anti-wef-demonstration\/"],"_thumbnail_id":["97540"],"jnews_social_counter_last_update":["1784015051"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-01-20 11:15:10\";}"]},"categories":[19,23],"tags":[70665,598,363,53356],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ausschreitungen bei Anti-WEF-Demonstration in Z\u00fcrich - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ausschreitungen bei Anti-WEF-Demonstration in Z\u00fcrich\" \/>\n<meta property=\"og:description\" content=\"Mehrere Tausend Menschen protestierten in Z\u00fcrich gegen den Auftritt von Donald Trump am WEF in Davos. W\u00e4hrend der Demonstrationszug anf\u00e4nglich geordnet verlief, eskalierte die Lage im Bereich der Kasernenstra\u00dfe. Barrikaden, Br\u00e4nde und Angriffe auf Einsatzkr\u00e4fte f\u00fchrten zu einem Gro\u00dfaufgebot der Polizei. Am Montagabend ist es in Z\u00fcrich am Rande einer Demonstration gegen das Weltwirtschaftsforum zu [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-20T09:02:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/696f3cc448fbef4ae63f71ae.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Ausschreitungen bei Anti-WEF-Demonstration in Z\u00fcrich\",\"datePublished\":\"2026-01-20T09:02:20+00:00\",\"dateModified\":\"2026-01-20T09:02:20+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/\"},\"wordCount\":513,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Ausschreitungen-bei-Anti-WEF-Demonstration-in-Zuerich.jpg\",\"keywords\":[\"AntiWEFDemonstration\",\"Ausschreitungen\",\"bei\",\"Z\u00fcrich\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/\",\"name\":\"Ausschreitungen bei Anti-WEF-Demonstration in Z\u00fcrich - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Ausschreitungen-bei-Anti-WEF-Demonstration-in-Zuerich.jpg\",\"datePublished\":\"2026-01-20T09:02:20+00:00\",\"dateModified\":\"2026-01-20T09:02:20+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Ausschreitungen-bei-Anti-WEF-Demonstration-in-Zuerich.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Ausschreitungen-bei-Anti-WEF-Demonstration-in-Zuerich.jpg\",\"width\":460,\"height\":259,\"caption\":\"Ausschreitungen bei Anti-WEF-Demonstration in Z\u00fcrich\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ausschreitungen bei Anti-WEF-Demonstration in Z\u00fcrich\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ausschreitungen bei Anti-WEF-Demonstration in Z\u00fcrich - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/","og_locale":"de_DE","og_type":"article","og_title":"Ausschreitungen bei Anti-WEF-Demonstration in Z\u00fcrich","og_description":"Mehrere Tausend Menschen protestierten in Z\u00fcrich gegen den Auftritt von Donald Trump am WEF in Davos. W\u00e4hrend der Demonstrationszug anf\u00e4nglich geordnet verlief, eskalierte die Lage im Bereich der Kasernenstra\u00dfe. Barrikaden, Br\u00e4nde und Angriffe auf Einsatzkr\u00e4fte f\u00fchrten zu einem Gro\u00dfaufgebot der Polizei. Am Montagabend ist es in Z\u00fcrich am Rande einer Demonstration gegen das Weltwirtschaftsforum zu [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-01-20T09:02:20+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/696f3cc448fbef4ae63f71ae.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Ausschreitungen bei Anti-WEF-Demonstration in Z\u00fcrich","datePublished":"2026-01-20T09:02:20+00:00","dateModified":"2026-01-20T09:02:20+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/"},"wordCount":513,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Ausschreitungen-bei-Anti-WEF-Demonstration-in-Zuerich.jpg","keywords":["AntiWEFDemonstration","Ausschreitungen","bei","Z\u00fcrich"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/","url":"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/","name":"Ausschreitungen bei Anti-WEF-Demonstration in Z\u00fcrich - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Ausschreitungen-bei-Anti-WEF-Demonstration-in-Zuerich.jpg","datePublished":"2026-01-20T09:02:20+00:00","dateModified":"2026-01-20T09:02:20+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Ausschreitungen-bei-Anti-WEF-Demonstration-in-Zuerich.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Ausschreitungen-bei-Anti-WEF-Demonstration-in-Zuerich.jpg","width":460,"height":259,"caption":"Ausschreitungen bei Anti-WEF-Demonstration in Z\u00fcrich"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/ausschreitungen-bei-anti-wef-demonstration-in-zuerich\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Ausschreitungen bei Anti-WEF-Demonstration in Z\u00fcrich"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/97539"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=97539"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/97539\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/97540"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=97539"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=97539"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=97539"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}