{"id":97525,"date":"2026-01-19T22:50:07","date_gmt":"2026-01-19T20:50:07","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/freispruch-im-prozess-zum-garmischer-zugunglueck\/"},"modified":"2026-01-19T22:50:07","modified_gmt":"2026-01-19T20:50:07","slug":"freispruch-im-prozess-zum-garmischer-zugunglueck","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/freispruch-im-prozess-zum-garmischer-zugunglueck\/","title":{"rendered":"Freispruch im Prozess zum Garmischer Zugungl\u00fcck"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/696e7294b480cc751041cf9c.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Vier Frauen und ein 13-j\u00e4hriger Junge starben und weitere 72 Fahrg\u00e4ste wurden teils schwer verletzt, als am 3. Juni 2022 ein doppelst\u00f6ckiger Regionalzug kurz vor Garmisch-Partenkirchen entgleiste. Jetzt sprach ein M\u00fcnchner Gericht sein Urteil.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>F\u00fcnf Fahrg\u00e4ste hatte es im Sommer 2022 das Leben gekostet, als ein Zug auf dem Weg nach Garmisch-Partenkirchen bei Burgrain entgleiste. Nun hat das Landgericht M\u00fcnchen II sein Urteil gesprochen: Die beiden Angeklagten, der verantwortliche Bezirksleiter f\u00fcr die Fahrbahn und der zust\u00e4ndige Fahrdienstleiter, wurden freigesprochen.<\/p>\n<p>Die Staatsanwaltschaft hatte f\u00fcr beide Haftstrafen gefordert. Ein Jahr auf Bew\u00e4hrung f\u00fcr den Fahrdienstleiter und zwei Jahre f\u00fcr den Bezirksleiter. Der Verantwortliche f\u00fcr die Fahrbahn habe, so die Argumentation der Staatsanwaltschaft, Instandsetzungsma\u00dfnahmen immer wieder verz\u00f6gert, was ein &#8220;wiederholtes und systematisches Versagen&#8221; darstelle. Der Fahrdienstleiter h\u00e4tte sich dadurch, dass er eine Meldung eines Lokf\u00fchrers \u00fcber Auff\u00e4lligkeiten auf der Strecke am Vortag nicht weitergab, schuldig gemacht. Das Gericht sah bei beiden kein strafbares Verhalten.<\/p>\n<p>Der Zug von M\u00fcnchen nach Garmisch war in einer Kurve entgleist, eine B\u00f6schung heruntergerutscht und auf den Unterbau der Bundesstra\u00dfe geprallt. Diese B\u00f6schung entstand erst durch eine Erweiterung der Bundesstra\u00dfe etwa 20 Jahre vor dem Ungl\u00fcck. Sicherungsma\u00dfnahmen, um die durch die B\u00f6schung entstandene Gefahr auszugleichen, hatten nicht stattgefunden.<\/p>\n<p>Ein weiterer Faktor bei diesem Ungl\u00fcck war der Zustand der Bahnschwellen. Die Betonschwellen waren im Inneren verrottet, was aber durch Augenschein nicht zu erkennen war. Den Verantwortlichen der DB Netz sei, so ergab der Untersuchungsbericht der Bundesstelle f\u00fcr Eisenbahnunfalluntersuchung, der Zustand der Schwellen bekannt gewesen, sie h\u00e4tten aber daraufhin keine Ma\u00dfnahmen ergriffen. Auch ein schon 2022 erstellter Bericht der Gewerkschaft der Lokf\u00fchrer zum Ungl\u00fcck kam zu diesem Schluss.<\/p>\n<p>\u00dcber Jahrzehnte hinweg, so die Kritik, die auch von der Fahrgastvereinigung Pro Bahn geteilt wird, habe die Bahn m\u00f6glichst wenig ins Netz investiert. Bis zum Verkauf an den d\u00e4nischen Logistikkonzern DSV hatte der Konzern Deutsche Bahn AG viel in den Ausbau der Logistiktochter Schenker investiert, die weltweit t\u00e4tig ist, und weniger in die Infrastruktur der Eisenbahn.<\/p>\n<p>Allerdings standen weder die Chefs der DB Netz noch die der DB insgesamt in M\u00fcnchen vor Gericht, und der Handlungsspielraum der \u00f6rtlichen Untergebenen war begrenzt. Wesentlich mehr, als eventuell eine weitere Langsamfahrstrecke einzurichten, w\u00e4re vermutlich auch dem Bezirksleiter Fahrbahn nicht m\u00f6glich gewesen.<\/p>\n<p>Inzwischen wurden bundesweit zwei Millionen der betroffenen Betonschwellen ausgetauscht. Die Infrastruktur der Bahn sollte durch Mittel aus der Billionenschuld endlich wieder funktionst\u00fcchtig gemacht werden, zumindest insoweit, dass fertig geplante Projekte umgesetzt werden. Zuletzt wurde aber bekannt, dass schon jetzt einige dieser Projekte gestrichen wurden.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2012 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/254860-interner-bericht-zugunglueck-von-garmisch-partenkirchen\/\">Interner Bericht: Zugungl\u00fcck von Garmisch-Partenkirchen auf Personalversagen zur\u00fcckzuf\u00fchren <\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-vk\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/vk.com\/video_ext.php?oid=-134310637&amp;id=456254300\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/267722-freispruch-im-prozess-zum-garmischer\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vier Frauen und ein 13-j\u00e4hriger Junge starben und weitere 72 Fahrg\u00e4ste wurden teils schwer verletzt, als am 3. Juni 2022 ein doppelst\u00f6ckiger Regionalzug kurz vor Garmisch-Partenkirchen entgleiste. Jetzt sprach ein M\u00fcnchner Gericht sein Urteil. F\u00fcnf Fahrg\u00e4ste hatte es im Sommer 2022 das Leben gekostet, als ein Zug auf dem Weg nach Garmisch-Partenkirchen bei Burgrain entgleiste. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":97526,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1768856215"],"wp_automatic_camp":["217"],"0c1cfaa74cfe2791f5aec43bc0948bcf":["Freispruch im Prozess zum Garmischer Zugungl\u00fcck"],"original_link":["https:\/\/de.rt.com\/inland\/267722-freispruch-im-prozess-zum-garmischer\/"],"_thumbnail_id":["97526"],"jnews_social_counter_last_update":["1788349398"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-01-19 22:57:55\";}"]},"categories":[19,23],"tags":[44036,70660,19590,22978,565],"class_list":["post-97525","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-freispruch","tag-garmischer","tag-prozess","tag-zugunglueck","tag-zum"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Freispruch im Prozess zum Garmischer Zugungl\u00fcck - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/freispruch-im-prozess-zum-garmischer-zugunglueck\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Freispruch im Prozess zum Garmischer Zugungl\u00fcck\" \/>\n<meta property=\"og:description\" content=\"Vier Frauen und ein 13-j\u00e4hriger Junge starben und weitere 72 Fahrg\u00e4ste wurden teils schwer verletzt, als am 3. Juni 2022 ein doppelst\u00f6ckiger Regionalzug kurz vor Garmisch-Partenkirchen entgleiste. Jetzt sprach ein M\u00fcnchner Gericht sein Urteil. F\u00fcnf Fahrg\u00e4ste hatte es im Sommer 2022 das Leben gekostet, als ein Zug auf dem Weg nach Garmisch-Partenkirchen bei Burgrain entgleiste. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/freispruch-im-prozess-zum-garmischer-zugunglueck\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-19T20:50:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/696e7294b480cc751041cf9c.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/freispruch-im-prozess-zum-garmischer-zugunglueck\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/freispruch-im-prozess-zum-garmischer-zugunglueck\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Freispruch im Prozess zum Garmischer Zugungl\u00fcck\",\"datePublished\":\"2026-01-19T20:50:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/freispruch-im-prozess-zum-garmischer-zugunglueck\\\/\"},\"wordCount\":467,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/freispruch-im-prozess-zum-garmischer-zugunglueck\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/01\\\/Freispruch-im-Prozess-zum-Garmischer-Zugunglueck.jpg\",\"keywords\":[\"Freispruch\",\"Garmischer\",\"Prozess\",\"Zugungl\u00fcck\",\"zum\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/freispruch-im-prozess-zum-garmischer-zugunglueck\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/freispruch-im-prozess-zum-garmischer-zugunglueck\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/freispruch-im-prozess-zum-garmischer-zugunglueck\\\/\",\"name\":\"Freispruch im Prozess zum Garmischer Zugungl\u00fcck - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/freispruch-im-prozess-zum-garmischer-zugunglueck\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/freispruch-im-prozess-zum-garmischer-zugunglueck\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/01\\\/Freispruch-im-Prozess-zum-Garmischer-Zugunglueck.jpg\",\"datePublished\":\"2026-01-19T20:50:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/freispruch-im-prozess-zum-garmischer-zugunglueck\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/freispruch-im-prozess-zum-garmischer-zugunglueck\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/freispruch-im-prozess-zum-garmischer-zugunglueck\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/01\\\/Freispruch-im-Prozess-zum-Garmischer-Zugunglueck.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/01\\\/Freispruch-im-Prozess-zum-Garmischer-Zugunglueck.jpg\",\"width\":460,\"height\":259,\"caption\":\"Freispruch im Prozess zum Garmischer Zugungl\u00fcck\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/freispruch-im-prozess-zum-garmischer-zugunglueck\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Freispruch im Prozess zum Garmischer Zugungl\u00fcck\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Freispruch im Prozess zum Garmischer Zugungl\u00fcck - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/freispruch-im-prozess-zum-garmischer-zugunglueck\/","og_locale":"de_DE","og_type":"article","og_title":"Freispruch im Prozess zum Garmischer Zugungl\u00fcck","og_description":"Vier Frauen und ein 13-j\u00e4hriger Junge starben und weitere 72 Fahrg\u00e4ste wurden teils schwer verletzt, als am 3. Juni 2022 ein doppelst\u00f6ckiger Regionalzug kurz vor Garmisch-Partenkirchen entgleiste. Jetzt sprach ein M\u00fcnchner Gericht sein Urteil. F\u00fcnf Fahrg\u00e4ste hatte es im Sommer 2022 das Leben gekostet, als ein Zug auf dem Weg nach Garmisch-Partenkirchen bei Burgrain entgleiste. [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/freispruch-im-prozess-zum-garmischer-zugunglueck\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-01-19T20:50:07+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/696e7294b480cc751041cf9c.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/freispruch-im-prozess-zum-garmischer-zugunglueck\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/freispruch-im-prozess-zum-garmischer-zugunglueck\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Freispruch im Prozess zum Garmischer Zugungl\u00fcck","datePublished":"2026-01-19T20:50:07+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/freispruch-im-prozess-zum-garmischer-zugunglueck\/"},"wordCount":467,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/freispruch-im-prozess-zum-garmischer-zugunglueck\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Freispruch-im-Prozess-zum-Garmischer-Zugunglueck.jpg","keywords":["Freispruch","Garmischer","Prozess","Zugungl\u00fcck","zum"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/freispruch-im-prozess-zum-garmischer-zugunglueck\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/freispruch-im-prozess-zum-garmischer-zugunglueck\/","url":"https:\/\/now-news.de\/de\/deutschland\/freispruch-im-prozess-zum-garmischer-zugunglueck\/","name":"Freispruch im Prozess zum Garmischer Zugungl\u00fcck - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/freispruch-im-prozess-zum-garmischer-zugunglueck\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/freispruch-im-prozess-zum-garmischer-zugunglueck\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Freispruch-im-Prozess-zum-Garmischer-Zugunglueck.jpg","datePublished":"2026-01-19T20:50:07+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/freispruch-im-prozess-zum-garmischer-zugunglueck\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/freispruch-im-prozess-zum-garmischer-zugunglueck\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/freispruch-im-prozess-zum-garmischer-zugunglueck\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Freispruch-im-Prozess-zum-Garmischer-Zugunglueck.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Freispruch-im-Prozess-zum-Garmischer-Zugunglueck.jpg","width":460,"height":259,"caption":"Freispruch im Prozess zum Garmischer Zugungl\u00fcck"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/freispruch-im-prozess-zum-garmischer-zugunglueck\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Freispruch im Prozess zum Garmischer Zugungl\u00fcck"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/97525","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=97525"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/97525\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/97526"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=97525"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=97525"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=97525"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}