{"id":96788,"date":"2026-01-04T11:57:15","date_gmt":"2026-01-04T09:57:15","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/venezuela-und-der-us-imperialismus\/"},"modified":"2026-01-04T11:57:15","modified_gmt":"2026-01-04T09:57:15","slug":"venezuela-und-der-us-imperialismus","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/venezuela-und-der-us-imperialismus\/","title":{"rendered":"Venezuela und der US-Imperialismus"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/6959676a48fbef3fab37645e.png\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Mit ihrem Krieg gegen Venezuela und der Entf\u00fchrung von Pr\u00e4sident Nicol\u00e1s Maduro eskalieren die USA ihren Machtkampf um globale Vorherrschaft weiter. Das war abzusehen und ist Ausdruck sich zuspitzender imperialistischer Konkurrenz. Die EU ist dabei keineswegs nur Zuschauer.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><strong><\/strong><em>Eine<\/em><strong>\u00a0<\/strong><em>Analyse von Alexandra Nollok<\/em><\/p>\n<p>Mit ihren brutalen Angriffen auf Venezuela und der Verschleppung von Pr\u00e4sident Nicol\u00e1s Maduro haben die USA ihre imperialistische Aggression nun\u00a0\u2013 wie erwartet\u00a0\u2013 weiter eskaliert. Unter wachsender Erkl\u00e4rungsnot <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.n-tv.de\/mediathek\/videos\/politik\/Was-hinter-Trumps-Angriff-auf-Venezuela-steckt-id30199099.html\">r\u00e4tselten anschlie\u00dfend deutsche Leitmedien dar\u00fcber<\/a>,\u00a0welche Rechtsgrundlagen US-Pr\u00e4sident Donald Trump wohl sp\u00e4ter vortragen werde. Man k\u00f6nnte fast dar\u00fcber lachen.<\/p>\n<p>Denn der westliche &#8220;Werte&#8221;-Kanon zieht nicht mehr, es ist l\u00e4ngst un\u00fcbersehbar: Es geht den USA nicht um ein &#8220;b\u00f6ses sozialistisches Regime&#8221;, sondern um billigen Zugriff auf \u00d6l, Gas, Seltene Erden und andere Ressourcen Venezuelas. Die USA eskalieren ihre imperialistische Standortpolitik zunehmend kriegerisch auf einem Weltmarkt, der mit China, Russland, einigen arabischen und anderen Staaten m\u00e4chtige Konkurrenz hervorgebracht hat und sich gerade neu sortiert.<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-vk\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/vk.com\/video_ext.php?oid=-134310637&amp;id=456288971\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<p>Die EU schaut dabei keineswegs nur zu.<\/p>\n<\/p>\n<p><strong>Moderner Imperialismus<\/strong><\/p>\n<p>\u00dcber den modernen Imperialismus lernt man in b\u00fcrgerlichen M\u00e4rchenb\u00fcchern leider nichts. Dort wird so getan, als geh\u00f6re dieser einer grauen Vergangenheit des territorialen Kolonialismus an, die man l\u00e4ngst \u00fcberwunden habe. Doch moderne Imperialisten m\u00fcssen heute nicht mehr andere L\u00e4nder besetzen, um sie \u00f6konomisch und politisch zu beherrschen. Es &#8220;reicht&#8221;, Vasallenregime unter fadenscheinigen Begr\u00fcndungen notfalls herbeizubomben, die sich auf Knebel-Freihandelsvertr\u00e4ge einlassen, dazu noch Kapitalexport und viele Milit\u00e4rbasen in Reichweite. So lassen sich die L\u00e4nder (und ihre Arbeiter) vortrefflich ausbeuten.<\/p>\n<p>Kurz gesagt: Imperialisten m\u00fcssen fremde M\u00e4rkte und Rohstoffe unter ihre Kontrolle bringen, um die tendenziell sinkenden Profite ihrer Gro\u00dfkonzerne hochzuhalten und ihre globale politische und wirtschaftliche Macht zu sichern. Sie k\u00f6nnen unter Konkurrenzdruck gar nicht anders, da Konkurrenten das gleiche Interesse haben. Ohne Krieg gelingt das nur bei unterw\u00fcrfigen Staaten, die sich &#8220;freiwillig&#8221; unterordnen. Ein Beispiel daf\u00fcr ist die NATO-Osterweiterung. Verweigern Konkurrenten aber ihre Unterordnung, kommt es fr\u00fcher oder sp\u00e4ter zum Krieg. Manchmal benutzen Imperialisten daf\u00fcr Stellvertreter, wie aktuell die Ukraine, die\u00a0\u2013 ganz &#8220;wertewestlich&#8221;\u00a0\u2013 Russland schw\u00e4chen soll.<\/p>\n<p>Wie viel imperialistische Macht ein Staat oder Staatenverbund, wie die EU, global tats\u00e4chlich hat, l\u00e4sst sich nur schwer genau beziffern. Wesentlich daf\u00fcr sind mehrere Kriterien. Dazu geh\u00f6rt zum Beispiel das Volumen des Exports von Waren und Kapital, also eigene Konzerne, die in anderen L\u00e4ndern Ressourcen und Arbeitskraft besonders billig ausbeuten. Auch das Volumen von Freihandelsvertr\u00e4gen, die Anzahl von Milit\u00e4rbasen in aller Welt, die Einbindung in multinationale Milit\u00e4rb\u00fcndnisse (wie die NATO)\u00a0sowie die mediale (Propaganda-)Macht spielen eine wesentliche Rolle.<\/p>\n<\/p>\n<p><strong>Fehlkalkulation Russland<\/strong><\/p>\n<p>In vielen der genannten Punkte stehen die USA noch immer ganz weit oben. Dennoch bahnt sich seit etwa 30\u00a0Jahren eine Machtverschiebung an: China, Russland, aber auch viele L\u00e4nder des &#8220;Globalen S\u00fcdens&#8221; sind zu ernsthaften wirtschaftlichen und milit\u00e4rischen Konkurrenten aufgestiegen, die die Dominanz der USA in Frage stellen. So schl\u00e4gt der Westen unter US-Vorherrschaft immer kriegerischer um sich.<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v71lgdy\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<p>Ziel des imperialistischen NATO-B\u00fcndnisses unter F\u00fchrung der USA war es zun\u00e4chst, den Konkurrenten Russland vom Weltmarkt abzuschneiden, bestenfalls in kleine Vasallenstaaten zu zersplittern, zu schw\u00e4chen und damit zugleich den Aufstieg Chinas zur\u00fcckzudr\u00e4ngen. Daf\u00fcr st\u00e4rkte der Westen die rechten Nationalisten in der Westukraine mit Geld, Waffen und politischer Einflussnahme und kalkulierte den Stellvertreterkrieg eindeutig ein. Offensichtlich hatten die Imperialisten die St\u00e4rke der russischen Wirtschaft und die europ\u00e4ische Abh\u00e4ngigkeit von selbiger massiv untersch\u00e4tzt.<\/p>\n<\/p>\n<p><strong>EU unter Konkurrenzdruck<\/strong><\/p>\n<p>Die USA unter Trump versuchen inzwischen, dies f\u00fcr ihre eigenen Interessen zu nutzen. Sie wollen ihren angeblichen &#8220;Wertepartner&#8221;, die EU, abh\u00e4ngiger von ihren eigenen Rohstoffen und ihrer Industrie machen, sie also niederkonkurrieren. Daf\u00fcr setzten sie erfolgreich auf das Feindbild Russland. Die EU hat mitgespielt: W\u00e4hrend ihre Industrie zerbricht, r\u00fcstet sie wie wild unter diesem Vorwand auf\u00a0\u2013 nicht zuletzt, um die Profitraten ihrer R\u00fcstungs- und Finanzkonzerne im Fluss zu halten und k\u00fcnstlich ihr Bruttoinlandsprodukt zu pushen. Derweil bem\u00fcht sich Trump um lukrative &#8220;Deals&#8221; mit Russland.<\/p>\n<\/p>\n<p><strong>Zielscheibe Venezuela<\/strong><\/p>\n<p>Venezuela ist f\u00fcr die USA einerseits ein Meilenstein im Kampf um imperialistische Vorherrschaft, der sich\u00a0insbesondere gegen China richtet. Andererseits ist Venezuela mit seinen reichen Rohstoffvorkommen, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/amerika\/258204-medien-trump-kuendigt-versuche-diplomatischer-versuche-konfliktbeilegung-venezuela-auf\/\">vor allem Erd\u00f6l<\/a>, Gas, Seltene Erden und weitere wichtige Metalle wie Gold und Eisen, ein eigenst\u00e4ndig wichtiges Angriffsziel. Ein Dorn im Auge des US-Imperiums ist das Land schon lange, da es sich seiner Einflussnahme seit vielen Jahren politisch widersetzt.\u00a0Die kriegerischen Ambitionen der USA in S\u00fcdamerika werden wohl nicht bei Venezuela haltmachen.<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v71muy0\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<p>Alle Staaten, in denen sich gegnerische Regierungen etablieren, m\u00fcssen in den n\u00e4chsten Jahren mit einer solchen &#8220;Intervention&#8221; rechnen. Es gibt nat\u00fcrlich Ausnahmen, wie derzeit etwa Argentinien. Mit Javier Milei konnten die USA dort ganz &#8220;demokratisch&#8221; einen Vasallen an die Macht bringen. Das r\u00e4cht sich nun f\u00fcr die Bev\u00f6lkerung: durch Privatisierung staatlicher Industrien, massive Lohndr\u00fcckerei und Sozialabbau, was bereits zu weiterer Verarmung wachsender Bev\u00f6lkerungsteile f\u00fchrt.<\/p>\n<\/p>\n<p><strong>Imperialistische Innenpolitik<\/strong><\/p>\n<p>Womit wir bei den innenpolitischen Auswirkungen imperialistischer Machtk\u00e4mpfe angekommen w\u00e4ren. Diese sind gravierend, wie sich in den USA sehr deutlich zeigt: Trump treibt gleichzeitig massiven Sozialabbau voran. Millionen US-Amerikaner verlieren beispielsweise derzeit ihre Krankenversicherung, weil die Regierung die Subventionen im Rahmen des sogenannten &#8220;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/archive.is\/ytHb6\">Affordable Care Act<\/a>&#8221; (Obamacare) gestrichen hat.\u00a0<\/p>\n<p>Die <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.tagesschau.de\/ausland\/amerika\/usa-new-york-obdachlosigkeit-trump-100.html\">Obdachlosen<\/a>&#8211;\u00a0und <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.spiegel.de\/wirtschaft\/usa-arbeitslosenzahlen-in-den-usa-auf-hoechstem-stand-seit-vier-jahren-a-e42d5080-25ad-4697-a9cc-e196a405d06a\">Arbeitslosenzahlen<\/a>\u00a0erreichen derweil st\u00e4ndig neue Rekordwerte in den USA. Hinzu kommt eine zunehmend autorit\u00e4re Politik gegen die eigene Bev\u00f6lkerung: Dissidenten,\u00a0besonders bez\u00fcglich der Israel-Politik des Imperiums, verlieren ihre Jobs, werden abgeschoben, sanktioniert oder verlassen aus Angst vor politischer Verfolgung die USA. Israel ist ein wichtiger Vasall des Imperiums, um dessen Macht und Einfluss in Nahost milit\u00e4risch abzusichern.<\/p>\n<\/p>\n<p><strong>Aufr\u00fcstung und Sozialkahlschlag: EU zieht mit<\/strong><\/p>\n<p>Beides, Sozialabbau und autorit\u00e4re politische Entwicklungen, erleben auch die Menschen in Europa. W\u00e4hrend die EU immer mehr Steuergeld in die R\u00fcstung pumpt, &#8220;begr\u00fcndet&#8221; mit dem Feindbild Russland und begleitet von einer seit 80\u00a0Jahren nicht mehr dagewesenen Kriegsrhetorik, treiben zahlreiche Regierungen, darunter die deutsche, den Sozialkahlschlag massiv voran und stampfen Arbeitnehmerrechte in einer Gr\u00f6\u00dfenordnung ein, die an den neoliberalen R\u00fcckbau der USA in den 1970er-Jahren erinnert.<\/p>\n<p>Die Bundesregierung will\u00a0beispielsweise das B\u00fcrgergeld in ein Repressionsinstrument umbauen, das Hartz\u00a0IV noch \u00fcbertrifft. Was daf\u00fcr sorgen wird, dass sich ein Hungerlohnsektor ungeahnter Gr\u00f6\u00dfe ausbreitet. Dazu passt, dass Kanzler Friedrich Merz und seine Regierung die Arbeitszeit ausweiten und weitere Arbeitsrechte drastisch schleifen wollen. Die Sozialversicherungskosten steigen weiter, das Gesundheitssystem erodiert, der ohnehin schon kaum noch nutzbare \u00f6ffentliche Nahverkehr, darunter die Bahn, verrottet weiter.<\/p>\n<\/p>\n<p><strong>Politische Faschisierung<\/strong><\/p>\n<p>Auch der Autoritarismus <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/gesellschaft\/262863-internet-soll-pro-westlich-sein\/\">nimmt zunehmend gef\u00e4hrliche Gestalt an<\/a>, wie die brutalen, existenzvernichtenden EU-Sanktionen gegen eigene Privatb\u00fcrger unter dem Label &#8220;russische Desinformation&#8221; belegen. Manche sprechen bereits von einer Faschisierung. Kurzum: Wer nicht spurt, wird plattgemacht\u00a0\u2013 zunehmend in den USA wie auch in der EU. Menschenrechtsverletzungen spielen dabei keine Rolle mehr, es gelingt den Herrschenden immer schwerer, sie in einen &#8220;demokratischen&#8221; Deckmantel zu h\u00fcllen.<\/p>\n<p>Sowohl die zunehmenden kriegerischen Aggressionen der USA und des gesamten Westens als auch der innenpolitische Sozialkahlschlag und die politische Faschisierung sind Ausdruck des imperialistischen Machtkampfes um die politische, \u00f6konomische und milit\u00e4rische Vorherrschaft im globalen kapitalistischen Wahnsinn, der starke Konkurrenten hervorgebracht hat, die sich nicht l\u00e4nger dem westlichen Diktat zu beugen gedenken.<\/p>\n<p>Schon jetzt ist abzusehen: Die Machtk\u00e4mpfe, ob wirtschaftlich oder mit Waffengewalt, brutalisieren sich zunehmend, dies freilich zulasten aller betroffenen Bev\u00f6lkerungen im In- und Ausland. Wer verhindern will, dass es so weitergeht, dem bleibt nur eines: Er muss sich mit anderen zusammentun\u00a0\u2013 gegen die \u00f6konomischen Eigentums- und Machtverh\u00e4ltnisse, gegen Sozialabbau, Krieg, Aufr\u00fcstung und Faschismus.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/257337-lawrow-deutsche-politiker-teilen-hitlers\/\">Lawrow: Deutsche Politiker teilen Hitlers Ziele \u2013 Anzeichen f\u00fcr Renazifizierung<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6r4qm3\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/266447-venezuela-und-der-us-imperialismus\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mit ihrem Krieg gegen Venezuela und der Entf\u00fchrung von Pr\u00e4sident Nicol\u00e1s Maduro eskalieren die USA ihren Machtkampf um globale Vorherrschaft weiter. Das war abzusehen und ist Ausdruck sich zuspitzender imperialistischer Konkurrenz. Die EU ist dabei keineswegs nur Zuschauer. Eine\u00a0Analyse von Alexandra Nollok Mit ihren brutalen Angriffen auf Venezuela und der Verschleppung von Pr\u00e4sident Nicol\u00e1s Maduro [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":96789,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1767520783"],"wp_automatic_camp":["217"],"df5243d46d1ddb0fa59e3f6d2ad7c62c":["Venezuela und der US-Imperialismus"],"original_link":["https:\/\/de.rt.com\/meinung\/266447-venezuela-und-der-us-imperialismus\/"],"_thumbnail_id":["96789"],"jnews_social_counter_last_update":["1788288519"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2026-01-04 12:00:51\";}"]},"categories":[19,23],"tags":[82,140,42711,18708],"class_list":["post-96788","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-der","tag-und","tag-usimperialismus","tag-venezuela"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Venezuela und der US-Imperialismus - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/venezuela-und-der-us-imperialismus\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Venezuela und der US-Imperialismus\" \/>\n<meta property=\"og:description\" content=\"Mit ihrem Krieg gegen Venezuela und der Entf\u00fchrung von Pr\u00e4sident Nicol\u00e1s Maduro eskalieren die USA ihren Machtkampf um globale Vorherrschaft weiter. Das war abzusehen und ist Ausdruck sich zuspitzender imperialistischer Konkurrenz. Die EU ist dabei keineswegs nur Zuschauer. Eine\u00a0Analyse von Alexandra Nollok Mit ihren brutalen Angriffen auf Venezuela und der Verschleppung von Pr\u00e4sident Nicol\u00e1s Maduro [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/venezuela-und-der-us-imperialismus\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2026-01-04T09:57:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/6959676a48fbef3fab37645e.png\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/venezuela-und-der-us-imperialismus\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/venezuela-und-der-us-imperialismus\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Venezuela und der US-Imperialismus\",\"datePublished\":\"2026-01-04T09:57:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/venezuela-und-der-us-imperialismus\\\/\"},\"wordCount\":1311,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/venezuela-und-der-us-imperialismus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/01\\\/Venezuela-und-der-US-Imperialismus.png\",\"keywords\":[\"der\",\"und\",\"USImperialismus\",\"Venezuela\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/venezuela-und-der-us-imperialismus\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/venezuela-und-der-us-imperialismus\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/venezuela-und-der-us-imperialismus\\\/\",\"name\":\"Venezuela und der US-Imperialismus - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/venezuela-und-der-us-imperialismus\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/venezuela-und-der-us-imperialismus\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/01\\\/Venezuela-und-der-US-Imperialismus.png\",\"datePublished\":\"2026-01-04T09:57:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/venezuela-und-der-us-imperialismus\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/venezuela-und-der-us-imperialismus\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/venezuela-und-der-us-imperialismus\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/01\\\/Venezuela-und-der-US-Imperialismus.png\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2026\\\/01\\\/Venezuela-und-der-US-Imperialismus.png\",\"width\":460,\"height\":259,\"caption\":\"Venezuela und der US-Imperialismus\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/venezuela-und-der-us-imperialismus\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Venezuela und der US-Imperialismus\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Venezuela und der US-Imperialismus - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/venezuela-und-der-us-imperialismus\/","og_locale":"de_DE","og_type":"article","og_title":"Venezuela und der US-Imperialismus","og_description":"Mit ihrem Krieg gegen Venezuela und der Entf\u00fchrung von Pr\u00e4sident Nicol\u00e1s Maduro eskalieren die USA ihren Machtkampf um globale Vorherrschaft weiter. Das war abzusehen und ist Ausdruck sich zuspitzender imperialistischer Konkurrenz. Die EU ist dabei keineswegs nur Zuschauer. Eine\u00a0Analyse von Alexandra Nollok Mit ihren brutalen Angriffen auf Venezuela und der Verschleppung von Pr\u00e4sident Nicol\u00e1s Maduro [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/venezuela-und-der-us-imperialismus\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2026-01-04T09:57:15+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/6959676a48fbef3fab37645e.png","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/venezuela-und-der-us-imperialismus\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/venezuela-und-der-us-imperialismus\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Venezuela und der US-Imperialismus","datePublished":"2026-01-04T09:57:15+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/venezuela-und-der-us-imperialismus\/"},"wordCount":1311,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/venezuela-und-der-us-imperialismus\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Venezuela-und-der-US-Imperialismus.png","keywords":["der","und","USImperialismus","Venezuela"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/venezuela-und-der-us-imperialismus\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/venezuela-und-der-us-imperialismus\/","url":"https:\/\/now-news.de\/de\/deutschland\/venezuela-und-der-us-imperialismus\/","name":"Venezuela und der US-Imperialismus - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/venezuela-und-der-us-imperialismus\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/venezuela-und-der-us-imperialismus\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Venezuela-und-der-US-Imperialismus.png","datePublished":"2026-01-04T09:57:15+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/venezuela-und-der-us-imperialismus\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/venezuela-und-der-us-imperialismus\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/venezuela-und-der-us-imperialismus\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Venezuela-und-der-US-Imperialismus.png","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2026\/01\/Venezuela-und-der-US-Imperialismus.png","width":460,"height":259,"caption":"Venezuela und der US-Imperialismus"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/venezuela-und-der-us-imperialismus\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Venezuela und der US-Imperialismus"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/96788","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=96788"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/96788\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/96789"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=96788"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=96788"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=96788"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}