{"id":96628,"date":"2025-12-30T20:28:45","date_gmt":"2025-12-30T18:28:45","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/"},"modified":"2025-12-30T20:28:45","modified_gmt":"2025-12-30T18:28:45","slug":"putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/","title":{"rendered":"Putin t\u00f6ten zu wollen war eine schlechte Idee: Welche Folgen wird Selenskijs letzter Fehler haben?"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/6954194bb480cc33e93a785a.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Abgesehen von &#8220;Zugest\u00e4ndnissen&#8221; sei man sich in den Verhandlungen mit den USA einig gewesen, hie\u00df es. Nach dem ukrainischen Drohnenangriff auf die Residenz des russischen Pr\u00e4sidenten und der Reaktion des Kreml ist nun endg\u00fcltig klar, was unter &#8220;Zugest\u00e4ndnissen&#8221; zu verstehen war und wie es nun damit weitergehen wird.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/ria.ru\/20251230\/zelenskiy-2065561750.html\"><\/a><em>Von Kirill Strelnikow<\/em><\/p>\n<p>Sowohl die heimischen &#8220;Pessimisten&#8221; als auch die westlichen Russophoben waren sich von Anfang an in ihrer Interpretation der Lecks \u00fcber die sogenannten &#8220;Zugest\u00e4ndnisse&#8221; Russlands im Rahmen der Verhandlungen mit den US-Amerikanern praktisch einig\u00a0\u2013 der Unterschied bestand lediglich in den Details und den Epitheta, wobei die einen von einem &#8220;manipulierten Spiel&#8221; heulten, w\u00e4hrend die anderen von einer &#8220;schwachen Position Russlands&#8221; sprachen.<\/p>\n<p><a><\/a> Angesichts der Reaktion der russischen Staatsf\u00fchrung auf den Angriff ukrainischer Drohnen auf die Residenz des russischen Pr\u00e4sidenten Wladimir Putin in Waldai ist nun endg\u00fcltig klar, was unter &#8220;Zugest\u00e4ndnissen&#8221; zu verstehen war und wie es nun damit weitergehen wird.<\/p>\n<p>Es ist vielen aufgefallen, dass Wladimir Selenskij bereits am 25.\u00a0Dezember\u00a0\u2013 w\u00e4hrend des westlichen Weihnachtsfests\u00a0\u2013 ganz unverhohlen seinen Todeswunsch gegen\u00fcber dem russischen Pr\u00e4sidenten ausgedr\u00fcckt hat. Der gestrige Angriff ist nun der Beweis daf\u00fcr, dass die Entscheidung \u00fcber das Attentat auf Putin bereits damals von der Kiewer Clique getroffen wurde.<\/p>\n<p>Mehr noch: Berechnungen zufolge wurde der ukrainische Drohnenangriff bereits einige Stunden vor Beginn des Treffens von US-Pr\u00e4sident Donald Trump und Selenskij in Trumps Residenz in Mar-a-Lago eingeleitet, da das Ergebnis dieses Treffens bereits im Voraus bekannt war.<\/p>\n<p>Von Anfang an hatte Selenskij keine Chance, seinen &#8220;Friedensplan&#8221; zu &#8220;verkaufen&#8221;: Er bekr\u00e4ftigte erneut, dass die ukrainischen Streitkr\u00e4fte nicht aus dem Donbass abziehen w\u00fcrden, dass in der Ukraine die Pr\u00e4senz von NATO-Truppen vorgesehen sei, dass von Russland ein langfristiger Waffenstillstand gefordert werde\u00a0\u2013 angeblich, um ein Referendum durchzuf\u00fchren\u00a0\u2013 und so weiter. Das hei\u00dft, es wurden erneut Bedingungen gestellt, die f\u00fcr unsere Seite von vornherein inakzeptabel sind.<\/p>\n<p>Obwohl Trump die Ergebnisse dieses Treffens als positiv bezeichnete, war allen klar, dass er zutiefst entt\u00e4uscht und ver\u00e4rgert \u00fcber die Versuche Selenskijs war, Zeit zu gewinnen. Laut dem US-Pr\u00e4sidenten &#8220;wurde Kiew empfohlen, nicht zu versuchen, eine vor\u00fcbergehende Atempause zu erlangen, sondern sich auf das Erreichen einer umfassenden Vereinbarung zu konzentrieren&#8221;.<\/p>\n<p>Und Selenskij entschied sich\u00a0\u2013 nachdem er von seinen Kumpels in London gr\u00fcnes Licht bekommen hatte\u00a0\u2013, proaktiv vorzugehen: Der Plan war, dass es in Russland zu politischem Chaos kommen w\u00fcrde, wenn Putin bei diesem Angriff get\u00f6tet w\u00fcrde. Wenn nicht, w\u00e4re Russland gezwungen, \u00fcbertrieben scharf zu reagieren (laut Selenskij war angeblich ein Angriff auf das Regierungszentrum in Kiew geplant), und man k\u00f6nnte es beschuldigen, die Friedensverhandlungen sabotiert zu haben.<\/p>\n<p>Aber alles ging schief. Das Attentat auf Putin ist gescheitert. Doch statt mit den von allen prognostizierten Drohungen zu reagieren, formulierten russische Offizielle fast wortw\u00f6rtlich folgende sachliche Thesen:<\/p>\n<p>\u2013 Der gestrige Angriff sei ein Akt des Staatsterrorismus, f\u00fcr den Selenskij pers\u00f6nlich verantwortlich sei.<\/p>\n<p>\u2013 Der Angriff sei inmitten des Friedensprozesses erfolgt und stelle einen Schlag ins Gesicht des US-Pr\u00e4sidenten dar, der bis zuletzt auf die Vernunft Kiews gehofft habe.<\/p>\n<p>\u2013 Die Handlungen des Kiewer Regimes w\u00fcrden nicht unbeantwortet bleiben, und diese Antwort werde nicht diplomatischer Natur sein.<\/p>\n<p>\u2013 Die Verhandlungsposition Russlands werde hinsichtlich &#8220;einer ganzen Reihe bereits erzielter Vereinbarungen und sich abzeichnender L\u00f6sungen&#8221; zweifellos revidiert werden, wobei Russland auf das Verst\u00e4ndnis seiner US-Partner hoffe.<\/p>\n<p><a><\/a> Zur Erinnerung: Noch bis vor Kurzem hatte die US-Seite nach jedem Kontakt mit den russischen Verhandlungspartnern in ungew\u00f6hnlich konsequenter Weise unterstrichen, dass &#8220;Russland eindeutig zum Frieden bereit&#8221; und &#8220;auf eine konstruktive L\u00f6sung des Konflikts ausgerichtet&#8221; sei.<\/p>\n<p>Der gestrige Angriff macht unsere Zugest\u00e4ndnisse zunichte, da selbst den US-Amerikanern klar geworden ist, dass die derzeitige terroristische Formation namens Ukraine, angef\u00fchrt von einem wahnsinnigen Schakal, per definitionem nicht mehr als Verhandlungspartner in Frage kommen kann.<\/p>\n<p>Wie Trump nach dem Angriff erkl\u00e4rte, er sei \u00e4u\u00dferst ver\u00e4rgert dar\u00fcber, dass die Provokation Kiews &#8220;zu einem v\u00f6llig unpassenden Zeitpunkt&#8221; stattgefunden habe, und dass er kategorisch gegen einen Angriff auf &#8220;Putins Haus&#8221; sei und sich &#8220;solch verr\u00fcckte Handlungen&#8221; nicht einmal vorstellen k\u00f6nne. Der US-Pr\u00e4sident teilte Putin mit, er danke Gott daf\u00fcr, dass er der Ukraine seinerzeit keine Tomahawk-Flugk\u00f6rper geliefert habe, und dass &#8220;der Versuch eines Angriffs auf Putins Residenz die Ans\u00e4tze der USA in Bezug auf die Zusammenarbeit mit Selenskij beeinflussen&#8221; werde.<\/p>\n<p>Es spielt nun keine Rolle mehr, wie Trump mit Selenskij verfahren wird. Wichtig ist vielmehr, wie Russland darauf reagieren wird.<\/p>\n<p>Im Westen geht man mit hundertprozentiger Wahrscheinlichkeit davon aus, dass wir demonstrativ etwas in Schutt und Asche legen werden (das w\u00e4re ganz im Stil Trumps): Man k\u00f6nnte beispielsweise das gesamte Regierungsviertel in Kiew in Staub und kraterf\u00f6rmige Landschaften verwandeln. Diesbez\u00fcglich hegt auch Selenskij gro\u00dfe Hoffnungen.<\/p>\n<p><a><\/a> Doch die russische F\u00fchrung handelt nicht nach dem Paradigma &#8220;verletzter Eitelkeit&#8221;. Es wird also keine demonstrative Bombardierung erfolgen. Denn alles, was geschehen musste, ist bereits eingetreten: Alles deutet darauf hin, dass es f\u00fcr uns nun v\u00f6llig undenkbar ist, Vertreter des derzeitigen ukrainischen Regimes als Verhandlungspartner zu akzeptieren, ebenso wie es angesichts des Vormarsches der russischen Armee sinnlos geworden ist, den Abzug der ukrainischen Streitkr\u00e4fte aus dem Donbass \u00fcberhaupt noch zur Debatte zu stellen.<\/p>\n<p>Die Gegenseite bestehe aus Terroristen. Mit ihnen k\u00f6nne man keine Verhandlungen mehr f\u00fchren. Die derzeitige Regierung in Kiew sei terroristisch und d\u00fcrfe nicht an der Macht bleiben. Punkt.<\/p>\n<p>Von nun an ist v\u00f6llig unerheblich, was in Kiew gesagt wird und welche Papiere dort vorgelegt werden: Diese Personen sind bereits &#8220;tot&#8221;\u00a0\u2013 ebenso wie ihr &#8220;Staat&#8221;.<\/p>\n<p>Wie der russische Au\u00dfenminister Sergei Lawrow pr\u00e4zisierte, werden wir jedoch nicht aus den Verhandlungen mit den USA aussteigen: Denn zu zweit ist es immer leichter, ein Grab zuzusch\u00fctten.<\/p>\n<p><em>\u00dcbersetzt aus dem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/ria.ru\/20251230\/zelenskiy-2065561750.html\">Russischen<\/a>. Der Artikel ist am 30.\u00a0Dezember 2025 zuerst bei RIA\u00a0Nowosti erschienen.<\/em><\/p>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/russland\/266086-lawrow-ukraine-griff-putin-residenz-an\/\">Ukraine greift Putin-Residenz mit 91 Drohnen an \u2013 Trump zeigt sich &#8220;schockiert und emp\u00f6rt&#8221;<\/a><em><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/russland\/266086-lawrow-ukraine-griff-putin-residenz-an\/\"><\/a><\/em><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v71fgfm\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/266191-welche-folgen-wird-selenskijs-letzter-fehler-haben\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Abgesehen von &#8220;Zugest\u00e4ndnissen&#8221; sei man sich in den Verhandlungen mit den USA einig gewesen, hie\u00df es. Nach dem ukrainischen Drohnenangriff auf die Residenz des russischen Pr\u00e4sidenten und der Reaktion des Kreml ist nun endg\u00fcltig klar, was unter &#8220;Zugest\u00e4ndnissen&#8221; zu verstehen war und wie es nun damit weitergehen wird. Von Kirill Strelnikow Sowohl die heimischen &#8220;Pessimisten&#8221; [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":96629,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1767119583"],"wp_automatic_camp":["217"],"c7081431c6a5db1dd559d9b9387911bb":["Putin t\u00f6ten zu wollen war eine schlechte Idee: Welche Folgen wird Selenskijs letzter Fehler haben?"],"original_link":["https:\/\/de.rt.com\/europa\/266191-welche-folgen-wird-selenskijs-letzter-fehler-haben\/"],"_thumbnail_id":["96629"],"jnews_social_counter_last_update":["1778520011"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-12-30 20:34:09\";}"]},"categories":[19,23],"tags":[275,1936,2378,771,24748,19895,125,20133,1290,2564,2223,4503,374,1050],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Putin t\u00f6ten zu wollen war eine schlechte Idee: Welche Folgen wird Selenskijs letzter Fehler haben? - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Putin t\u00f6ten zu wollen war eine schlechte Idee: Welche Folgen wird Selenskijs letzter Fehler haben?\" \/>\n<meta property=\"og:description\" content=\"Abgesehen von &#8220;Zugest\u00e4ndnissen&#8221; sei man sich in den Verhandlungen mit den USA einig gewesen, hie\u00df es. Nach dem ukrainischen Drohnenangriff auf die Residenz des russischen Pr\u00e4sidenten und der Reaktion des Kreml ist nun endg\u00fcltig klar, was unter &#8220;Zugest\u00e4ndnissen&#8221; zu verstehen war und wie es nun damit weitergehen wird. Von Kirill Strelnikow Sowohl die heimischen &#8220;Pessimisten&#8221; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-30T18:28:45+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/6954194bb480cc33e93a785a.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Putin t\u00f6ten zu wollen war eine schlechte Idee: Welche Folgen wird Selenskijs letzter Fehler haben?\",\"datePublished\":\"2025-12-30T18:28:45+00:00\",\"dateModified\":\"2025-12-30T18:28:45+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/\"},\"wordCount\":1021,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/Putin-toeten-zu-wollen-war-eine-schlechte-Idee-Welche-Folgen.jpg\",\"keywords\":[\"eine\",\"Fehler\",\"Folgen\",\"haben\",\"Idee\",\"Letzter\",\"putin\",\"schlechte\",\"Selenskijs\",\"Toten\",\"War\",\"Welche\",\"wird\",\"wollen\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/\",\"name\":\"Putin t\u00f6ten zu wollen war eine schlechte Idee: Welche Folgen wird Selenskijs letzter Fehler haben? - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/Putin-toeten-zu-wollen-war-eine-schlechte-Idee-Welche-Folgen.jpg\",\"datePublished\":\"2025-12-30T18:28:45+00:00\",\"dateModified\":\"2025-12-30T18:28:45+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/Putin-toeten-zu-wollen-war-eine-schlechte-Idee-Welche-Folgen.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/Putin-toeten-zu-wollen-war-eine-schlechte-Idee-Welche-Folgen.jpg\",\"width\":460,\"height\":259,\"caption\":\"Putin t\u00f6ten zu wollen war eine schlechte Idee: Welche Folgen wird Selenskijs letzter Fehler haben?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Putin t\u00f6ten zu wollen war eine schlechte Idee: Welche Folgen wird Selenskijs letzter Fehler haben?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Putin t\u00f6ten zu wollen war eine schlechte Idee: Welche Folgen wird Selenskijs letzter Fehler haben? - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/","og_locale":"de_DE","og_type":"article","og_title":"Putin t\u00f6ten zu wollen war eine schlechte Idee: Welche Folgen wird Selenskijs letzter Fehler haben?","og_description":"Abgesehen von &#8220;Zugest\u00e4ndnissen&#8221; sei man sich in den Verhandlungen mit den USA einig gewesen, hie\u00df es. Nach dem ukrainischen Drohnenangriff auf die Residenz des russischen Pr\u00e4sidenten und der Reaktion des Kreml ist nun endg\u00fcltig klar, was unter &#8220;Zugest\u00e4ndnissen&#8221; zu verstehen war und wie es nun damit weitergehen wird. Von Kirill Strelnikow Sowohl die heimischen &#8220;Pessimisten&#8221; [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-12-30T18:28:45+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/6954194bb480cc33e93a785a.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Putin t\u00f6ten zu wollen war eine schlechte Idee: Welche Folgen wird Selenskijs letzter Fehler haben?","datePublished":"2025-12-30T18:28:45+00:00","dateModified":"2025-12-30T18:28:45+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/"},"wordCount":1021,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/Putin-toeten-zu-wollen-war-eine-schlechte-Idee-Welche-Folgen.jpg","keywords":["eine","Fehler","Folgen","haben","Idee","Letzter","putin","schlechte","Selenskijs","Toten","War","Welche","wird","wollen"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/","url":"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/","name":"Putin t\u00f6ten zu wollen war eine schlechte Idee: Welche Folgen wird Selenskijs letzter Fehler haben? - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/Putin-toeten-zu-wollen-war-eine-schlechte-Idee-Welche-Folgen.jpg","datePublished":"2025-12-30T18:28:45+00:00","dateModified":"2025-12-30T18:28:45+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/Putin-toeten-zu-wollen-war-eine-schlechte-Idee-Welche-Folgen.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/Putin-toeten-zu-wollen-war-eine-schlechte-Idee-Welche-Folgen.jpg","width":460,"height":259,"caption":"Putin t\u00f6ten zu wollen war eine schlechte Idee: Welche Folgen wird Selenskijs letzter Fehler haben?"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/putin-toeten-zu-wollen-war-eine-schlechte-idee-welche-folgen-wird-selenskijs-letzter-fehler-haben\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Putin t\u00f6ten zu wollen war eine schlechte Idee: Welche Folgen wird Selenskijs letzter Fehler haben?"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/96628"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=96628"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/96628\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/96629"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=96628"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=96628"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=96628"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}