{"id":95372,"date":"2025-12-08T10:08:51","date_gmt":"2025-12-08T08:08:51","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/"},"modified":"2025-12-08T10:08:51","modified_gmt":"2025-12-08T08:08:51","slug":"russen-in-westeuropa-beklagen-atmosphaere-der-angst","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/","title":{"rendered":"Russen in Westeuropa beklagen &quot;Atmosph\u00e4re der Angst&quot;"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/6932e628b480cc1cf87eb168.JPG\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                In Europa lebende Russen geraten wegen ihrer Herkunft und gesch\u00e4ftlicher Kontakte ins Heimatland seit dem Beginn des Ukrainekriegs zunehmend ins Visier der Geheimdienste. Ein aktuelles Urteil in Schweden zeigt die Fragw\u00fcrdigkeit so mancher Vorw\u00fcrfe, doch Recht zu bekommen sei selten \u2013 Europa schaffe bewusst eine &#8220;Atmosph\u00e4re der Angst&#8221;, so Experten.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Stanislaw Leschtschenko<\/em><\/p>\n<p>Der &#8220;Spionagefall&#8221; Sergei Skworzow machte vor drei Jahren Schlagzeilen in der schwedischen Presse. Der aus Perm stammende Skworzow, heute 62 Jahre alt, lebte seit Ende der 1990er Jahre in Schweden und war im Import-Export-Gesch\u00e4ft t\u00e4tig. 1999 erhielten er und seine Frau Jelena Kulkowa eine Aufenthaltsgenehmigung in Schweden und 2013 die Staatsb\u00fcrgerschaft dieses Landes.<\/p>\n<p>Ihr ruhiges Leben wurde am 22. November 2022 unterbrochen: Zwei Hubschrauber schwebten \u00fcber ihrem Haus im Stockholmer Vorort Nacka, Spezialeinheiten seilten sich ab und nahmen das \u00e4ltere Ehepaar fest.<\/p>\n<p><a><\/a>&#8220;Ich war gerade aufgestanden, als ich einen Hubschrauber h\u00f6rte, der ganz in der N\u00e4he vorbeiflog. Als ich aus dem Fenster schaute, sah ich bereits zwei Hubschrauber, die sehr tief \u00fcber dem Boden schwebten. Sie hatten keine Lichter an. Das Licht war komplett ausgeschaltet&#8221;, berichtete ihr Nachbar, der Zeuge dieses Vorfalls war. Zun\u00e4chst wurde sogar vermutet, dass es sich um einen Rettungshubschrauber handelte, der einen Patienten mit Herzinfarkt notfallm\u00e4\u00dfig evakuieren sollte. Erst als maskierte Sicherheitskr\u00e4fte aus dem Hubschrauber landeten, wurde klar, dass es sich um eine Operation der Spezialeinheiten handelte.<\/p>\n<p>Skworzow musste fast ein Jahr im Untersuchungsgef\u00e4ngnis verbringen. Seine Frau wurde kurz darauf ohne Anklage freigelassen. Nach Ansicht der Staatsanwaltschaft war Skworzow heimlich im Interesse des russischen Staates t\u00e4tig \u2013 sowohl gegen Schweden als auch gegen die USA.<\/p>\n<p>Skworzow &#8220;ist ein Beschaffungsagent f\u00fcr den russischen Milit\u00e4rkomplex und dessen Nachrichtendienst GRU. Russland hat Bedarf an elektronischen Technologien. In Russland existiert ein entsprechendes Beschaffungssystem, das von den Geheimdiensten kontrolliert wird\u00a0\u2026 Skworzow und seine beiden Unternehmen sind Teil dieses Systems&#8221;, argumentierte Staatsanwalt Henrik Olin.<\/p>\n<p>Laut der schwedischen Staatsanwaltschaft sollte Sergei Skworzow \u00fcber seine schwedische Firma sanktionierte Produkte in die Stadt Sneschinsk (Gebiet Tscheljabinsk) liefern, wo sich das F\u00f6derale Nuklearzentrum Russlands befindet. Dar\u00fcber hinaus wurde Skworzow vorgeworfen, als Vermittler bei der Lieferung von sanktionierten Ausr\u00fcstungsg\u00fctern aus den Niederlanden an die russische Schiffsreparaturwerft &#8220;Swesdotschka&#8221; mitgewirkt zu haben.<\/p>\n<p>Ferner\u00a0habe das Unternehmen des Verd\u00e4chtigen nach Ansicht der schwedischen Staatsanwaltschaft eine Vereinbarung \u00fcber die Lieferung von Ausr\u00fcstung aus Schweden f\u00fcr das russische Projekt zur Entwicklung eines Spionagesatelliten namens &#8220;Kanopus&#8221; unterzeichnet. Die Ermittler seien angeblich im Besitz von Kopien der vom russischen Verteidigungsministerium an Skworzow gesendeten E-Mails.<\/p>\n<p><a><\/a> Die schwedische Staatsanwaltschaft beantragte f\u00fcr Skworzow f\u00fcnf Jahre Freiheitsstrafe. Angesichts der Aufregung, die von den Beh\u00f6rden und der Presse ausgel\u00f6st wurde, schien es so, als sei ein Schuldspruch bereits beschlossene Sache.<\/p>\n<p>Im Oktober 2023 wurde dieser Gesch\u00e4ftsmann jedoch freigesprochen. Es stellte sich heraus, dass die &#8220;Beweislage&#8221; nicht ausreichte.<\/p>\n<p>&#8220;Um entsprechend der erhobenen Anklage strafrechtlich verfolgt zu werden, h\u00e4tte die T\u00e4tigkeit darauf abzielen m\u00fcssen, geheime Informationen von hohem Sicherheitswert f\u00fcr Schweden und die USA zu beschaffen, und zwar zum Zwecke der Spionage. Dem Staatsanwalt gelang es nicht nachzuweisen, dass das Ziel der Handlungen in der Beschaffung solcher Informationen bestand&#8221;, stellte Richter Jakob Hedenmo fest. In den Gerichtsunterlagen hie\u00df es:<\/p>\n<p><em>&#8220;Die Handlungen von Skworzow waren ausschlie\u00dflich auf den Kauf von Technologien im Westen ausgerichtet und nicht auf die Beschaffung von Informationen \u00fcber Schweden oder die USA.&#8221;<\/em><\/p>\n<p>F\u00fcr Staatsanwalt Henrik Olin und die Sicherheitspolizei stellte dieses Urteil ein v\u00f6lliges Fiasko dar. Sie versuchten, den Fall neu aufzurollen, legten Berufung ein und suchten gleichzeitig nach neuen Beweisen gegen Skworzow. Ihre Bem\u00fchungen waren jedoch erfolglos: Ende November 2025 best\u00e4tigte das Berufungsgericht des schwedischen Bezirks Svea das Freispruchurteil. &#8220;Es kann zwar angenommen werden, dass Skworzow bestimmte Informationen \u00fcber Unternehmen gesammelt hat, aber diese Daten sind nicht geheim&#8221;, erkl\u00e4rte H\u00e5kan Sellman, Berater des Berufungsgerichts.<\/p>\n<p>Dieser &#8220;Spionagefall&#8221; Skworzow ist ein typisches Beispiel f\u00fcr die im Westen verbreitete Spionagehysterie. Da die Propaganda behauptet, dass \u00fcberall russische Spione zu finden seien, m\u00fcssen diese nun aufgesp\u00fcrt, gefasst und der \u00d6ffentlichkeit pr\u00e4sentiert werden.<\/p>\n<p><a><\/a> Dabei sind es oft unbeteiligte Menschen, deren einzige Schuld darin besteht, dass sie ethnische Russen sind und gesch\u00e4ftliche Beziehungen zu Russland unterhalten. Ein anschauliches Beispiel daf\u00fcr ereignete sich k\u00fcrzlich in der Republik Estland: Sie lieferte ihren russischsprachigen Staatsb\u00fcrger Andrei Schewljakow an die USA aus, da ihm vorgeworfen wurde, sanktionierte Technologien an Russland weitergegeben zu haben.<\/p>\n<p><a><\/a> Diese Anschuldigungen basierten darauf, dass Andrei Schewljakow, ein Einwohner von Tallinn, sich seit vielen Jahren mit dem Kauf und Verkauf von Elektronik und Elektronikkomponenten befasste. Das Gesch\u00e4ftsmodell war einfach: Andrei nahm Bestellungen von Privatpersonen oder Unternehmen entgegen, suchte dann weltweit nach den bestellten Artikeln und lieferte sie an die angegebene Adresse. Die geografische Reichweite seiner T\u00e4tigkeit war \u00e4u\u00dferst gro\u00df: Amerika, Europa, Russland \u2013 wobei der russische Markt etwa 60 Prozent seiner gesamten Kundschaft ausmachte. Da es sich um Einzelst\u00fccke handelte, transportierte er die Waren nicht mit Lastwagen, sondern pers\u00f6nlich mit seinem Pkw \u00fcber die Grenze.<\/p>\n<p>Der Anklage zufolge habe Schewljakow zehn Jahre lang unter Versto\u00df gegen die Exportkontrollvorschriften bei US-Herstellern gekaufte Elektronik nach Russland verschickt. Sollte Schewljakow f\u00fcr schuldig erkl\u00e4rt werden, drohen ihm bis zu zwanzig Jahre Freiheitsstrafe. Er selbst versteht nicht, warum ihm illegale Handlungen vorgeworfen werden. Der Unternehmer kontrollierte st\u00e4ndig, ob die von seinen Kunden bestellten Waren Sanktionen und Beschr\u00e4nkungen unterliegen.<\/p>\n<p><a><\/a><a><\/a><a><\/a> &#8220;Wir haben die Lage st\u00e4ndig beobachtet und versucht, die Nuancen dieser Sanktionen zu verstehen. Im Nachhinein ist es f\u00fcr mich schwer zu sagen, ob etwas Verbotenes dabei war oder nicht. Aber ich bin der Meinung, dass, wenn die Ware korrekt deklariert wurde, wenn sie die Zollkontrolle passiert hat, wenn sie vom Zoll freigegeben wurde \u2013 welches Problem k\u00f6nnte es dann noch im Nachhinein geben?&#8221;, stellt Schewljakow\u00a0als rhetorische Frage in den Raum.<\/p>\n<p>Er weist darauf hin, dass &#8220;elektronische Komponenten&#8221;, deren Einfuhr in die Russische F\u00f6deration ihm vorgeworfen wird, ein weit gefasster Begriff sind: Solche Komponenten werden sowohl in Fernsehern als auch in Haushaltsger\u00e4ten und sogar in Beleuchtungsger\u00e4ten verwendet. Selbst die estnische Staatsanwaltschaft hatte Zweifel an den gegen Schewljakow erhobenen Vorw\u00fcrfen \u2013 in Tallinn z\u00f6gerte man mehr als zwei Jahre lang, ob man ihn an die USA ausliefern sollte, und tat dies schlie\u00dflich nur, um den &#8220;amerikanischen Herrn&#8221; nicht zu ver\u00e4rgern. Jetzt befindet sich Schewljakow in einem US-Gef\u00e4ngnis in Erwartung seines Urteils.<\/p>\n<p>Natalja Jeremina, Doktor der Politikwissenschaften und Professorin an der Sankt Petersburger Staatlichen Universit\u00e4t, ist der Ansicht, dass das Ziel der Attacken auf Personen wie Skworzow und Schewljakow darin besteht, die westliche Unternehmerschaft einzusch\u00fcchtern und sie dazu zu bewegen, von jeglichen Gesch\u00e4ften mit Russland Abstand zu nehmen. Sie erkl\u00e4rt:<\/p>\n<p><em>&#8220;Es gibt einen klaren politischen Auftrag, die antirussische Hysterie anzuheizen \u2013 und solche Methoden, die mit der Verhaftung von Gesch\u00e4ftsleuten einhergehen, tragen sehr dazu bei, eine Atmosph\u00e4re der Angst zu schaffen. Man k\u00f6nnte davon ausgehen, dass man legale Gesch\u00e4fte mit Russland t\u00e4tigt, doch dann kommt es zu einer Festnahme, man wird inhaftiert und erf\u00e4hrt, dass man trotzdem illegale Gesch\u00e4fte betrieben habe. Aus diesem Grund werden viele Unternehmer \u2013 nachdem sie von der Festnahme eines ihrer Kollegen erfahren haben \u2013 zweimal \u00fcberlegen, ob es sich \u00fcberhaupt lohnt, mit Russen Gesch\u00e4fte zu machen. Schlie\u00dflich ist Freiheit wichtiger als Geld.&#8221;<\/em><\/p>\n<p>Nach Ansicht der Expertin fallen westliche Regierungen der eigenen Propaganda zum Opfer und verkennen, dass Russland eine hochtechnologische Gro\u00dfmacht ist, die keine Chips aus importierten K\u00fchlschr\u00e4nken und Waschmaschinen &#8220;herauskratzen&#8221; muss.<\/p>\n<p>Abschlie\u00dfend bemerkt Natalja Jeremina:<\/p>\n<p><em><a><\/a> &#8220;Diejenigen, die die Gesch\u00e4ftsleute verhaften, greifen auf genau diese Art von Rhetorik zur\u00fcck \u2013 sie behaupten, dass diese Lieferungen f\u00fcr die Russen \u2013 auch wenn es sich nur um Unterhaltungselektronik handelt \u2013 von enormer Bedeutung seien, da sie selbst nichts herstellen k\u00f6nnten. F\u00fcr uns klingt das insgesamt v\u00f6llig absurd. Im Westen jedoch werden solche propagandistischen Thesen zum Axiom erhoben.&#8221;<\/em><\/p>\n<p><em>\u00dcbersetzt aus dem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/vz.ru\/world\/2025\/12\/4\/1378370.html\">Russischen<\/a>. Der Artikel ist am 4. Dezember 2025 zuerst auf der Homepage der Zeitung &#8220;Wsgljad&#8221; erschienen.<\/em><\/p>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/263782-merz-imperialistische-russland-strebt-danach\/\">Merz: &#8220;Das imperialistische Russland strebt danach seine Einflusszone in Europa auszuweiten&#8221;<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v70g4hm\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/russland\/263882-in-europa-verdichtet-sich-atmosphaere\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Europa lebende Russen geraten wegen ihrer Herkunft und gesch\u00e4ftlicher Kontakte ins Heimatland seit dem Beginn des Ukrainekriegs zunehmend ins Visier der Geheimdienste. Ein aktuelles Urteil in Schweden zeigt die Fragw\u00fcrdigkeit so mancher Vorw\u00fcrfe, doch Recht zu bekommen sei selten \u2013 Europa schaffe bewusst eine &#8220;Atmosph\u00e4re der Angst&#8221;, so Experten. Von Stanislaw Leschtschenko Der &#8220;Spionagefall&#8221; [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":95373,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1765181357"],"wp_automatic_camp":["217"],"d0d94101b42edc6c9e786f1ba45de5ff":["Russen in Westeuropa beklagen &quot;Atmosph\u00e4re der Angst&quot;"],"original_link":["https:\/\/de.rt.com\/russland\/263882-in-europa-verdichtet-sich-atmosphaere\/"],"_thumbnail_id":["95373"],"jnews_social_counter_last_update":["1784088230"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-12-08 10:10:19\";}"]},"categories":[19,23],"tags":[39615,744,82,69725,4405,42201],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Russen in Westeuropa beklagen &quot;Atmosph\u00e4re der Angst&quot; - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Russen in Westeuropa beklagen &quot;Atmosph\u00e4re der Angst&quot;\" \/>\n<meta property=\"og:description\" content=\"In Europa lebende Russen geraten wegen ihrer Herkunft und gesch\u00e4ftlicher Kontakte ins Heimatland seit dem Beginn des Ukrainekriegs zunehmend ins Visier der Geheimdienste. Ein aktuelles Urteil in Schweden zeigt die Fragw\u00fcrdigkeit so mancher Vorw\u00fcrfe, doch Recht zu bekommen sei selten \u2013 Europa schaffe bewusst eine &#8220;Atmosph\u00e4re der Angst&#8221;, so Experten. Von Stanislaw Leschtschenko Der &#8220;Spionagefall&#8221; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-08T08:08:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/6932e628b480cc1cf87eb168.JPG\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Russen in Westeuropa beklagen &quot;Atmosph\u00e4re der Angst&quot;\",\"datePublished\":\"2025-12-08T08:08:51+00:00\",\"dateModified\":\"2025-12-08T08:08:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/\"},\"wordCount\":1367,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/Russen-in-Westeuropa-beklagen-quotAtmosphaere-der-Angstquot.JPG\",\"keywords\":[\"Angstquot\",\"beklagen\",\"der\",\"quotAtmosph\u00e4re\",\"Russen\",\"Westeuropa\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/\",\"name\":\"Russen in Westeuropa beklagen &quot;Atmosph\u00e4re der Angst&quot; - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/Russen-in-Westeuropa-beklagen-quotAtmosphaere-der-Angstquot.JPG\",\"datePublished\":\"2025-12-08T08:08:51+00:00\",\"dateModified\":\"2025-12-08T08:08:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/Russen-in-Westeuropa-beklagen-quotAtmosphaere-der-Angstquot.JPG\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/Russen-in-Westeuropa-beklagen-quotAtmosphaere-der-Angstquot.JPG\",\"width\":460,\"height\":259,\"caption\":\"Russen in Westeuropa beklagen &quot;Atmosph\u00e4re der Angst&quot;\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Russen in Westeuropa beklagen &quot;Atmosph\u00e4re der Angst&quot;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Russen in Westeuropa beklagen &quot;Atmosph\u00e4re der Angst&quot; - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/","og_locale":"de_DE","og_type":"article","og_title":"Russen in Westeuropa beklagen &quot;Atmosph\u00e4re der Angst&quot;","og_description":"In Europa lebende Russen geraten wegen ihrer Herkunft und gesch\u00e4ftlicher Kontakte ins Heimatland seit dem Beginn des Ukrainekriegs zunehmend ins Visier der Geheimdienste. Ein aktuelles Urteil in Schweden zeigt die Fragw\u00fcrdigkeit so mancher Vorw\u00fcrfe, doch Recht zu bekommen sei selten \u2013 Europa schaffe bewusst eine &#8220;Atmosph\u00e4re der Angst&#8221;, so Experten. Von Stanislaw Leschtschenko Der &#8220;Spionagefall&#8221; [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-12-08T08:08:51+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/6932e628b480cc1cf87eb168.JPG"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Russen in Westeuropa beklagen &quot;Atmosph\u00e4re der Angst&quot;","datePublished":"2025-12-08T08:08:51+00:00","dateModified":"2025-12-08T08:08:51+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/"},"wordCount":1367,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/Russen-in-Westeuropa-beklagen-quotAtmosphaere-der-Angstquot.JPG","keywords":["Angstquot","beklagen","der","quotAtmosph\u00e4re","Russen","Westeuropa"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/","url":"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/","name":"Russen in Westeuropa beklagen &quot;Atmosph\u00e4re der Angst&quot; - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/Russen-in-Westeuropa-beklagen-quotAtmosphaere-der-Angstquot.JPG","datePublished":"2025-12-08T08:08:51+00:00","dateModified":"2025-12-08T08:08:51+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/Russen-in-Westeuropa-beklagen-quotAtmosphaere-der-Angstquot.JPG","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/Russen-in-Westeuropa-beklagen-quotAtmosphaere-der-Angstquot.JPG","width":460,"height":259,"caption":"Russen in Westeuropa beklagen &quot;Atmosph\u00e4re der Angst&quot;"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/russen-in-westeuropa-beklagen-atmosphaere-der-angst\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Russen in Westeuropa beklagen &quot;Atmosph\u00e4re der Angst&quot;"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/95372"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=95372"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/95372\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/95373"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=95372"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=95372"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=95372"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}