{"id":95051,"date":"2025-12-02T16:31:57","date_gmt":"2025-12-02T14:31:57","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\/"},"modified":"2025-12-02T16:31:57","modified_gmt":"2025-12-02T14:31:57","slug":"rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\/","title":{"rendered":"&quot;RT India&quot; geht auf Sendung: Nachrichten und Shows aus Fernsehstudio in Neu-Delhi"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/692eb5b9b480cc5a951340b9.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                &#8220;RT&#8221; baut sein Netzwerk in Indien aus. In dieser Woche geht die \u00f6rtliche Redaktion des russischen Auslandssenders von einem TV-Studio in Neu-Delhi aus auf Sendung. Das Programm umfasst Nachrichten und Analysen. Eine Show wird von Ex-Au\u00dfenminister Salman Khurshid moderiert.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Es ist eine gro\u00dfartige Nachricht f\u00fcr alle <em>RT<\/em>-Fans: Am 5. Dezember 2025 geht der Fernsehsender <em>RT India <\/em>auf Sendung. Das Programm wird aus einem Studio in der indischen Hauptstadt Neu-Delhi ausgestrahlt. Anfangs sollen t\u00e4glich im modernen Fernsehkomplex bis zu vier Nachrichtensendungen auf Englisch produziert werden, die sich an ein breites Publikum im bev\u00f6lkerungsreichsten Land der Welt richten. In diesen Sendungen will <em>RT <\/em>den Schwerpunkt auf die wichtigsten Richtlinien der russisch-indischen Beziehungen und die Schl\u00fcsselrolle der beiden L\u00e4nder in der multipolaren Welt legen.<\/p>\n<p><em>RT India<\/em> besch\u00e4ftigt sich au\u00dferdem mit analytischen Sendungen zu verschiedenen Themen. Eine Show, die das aktuelle internationale Tagesgeschehen beleuchtet, wird vom fr\u00fcheren indischen Au\u00dfenminister Salman Khurshid moderiert. Runjhun Sharma, Leiterin der News-Abteilung von <em>RT India<\/em> und preisgekr\u00f6nte Journalistin, berichtet in ihrer allw\u00f6chentlichen Sendung extra \u00fcber das russisch-indische Verh\u00e4ltnis.<\/p>\n<p>Im Vorfeld des Sendestarts von <em>RT India<\/em> hat der russische Auslandssender eine gro\u00df angelegte Werbekampagne in vielen indischen Gro\u00dfst\u00e4dten lanciert, welche die lange Geschichte der russisch-indischen Beziehungen thematisiert. So verkehrt in der U-Bahn der Hauptstadt Neu-Delhi ein in <em>RT<\/em>-Farben geschm\u00fcckter Zug, dessen acht Waggons die Bereiche der bilateralen Zusammenarbeit von Raumfahrt \u00fcber Verteidigung bis hin zu Kultur und Sport abdecken. Ein Video mit dem Zug ist im asiatischen Land viral gegangen.<\/p>\n<p>Schon jetzt strahlen die 18 gr\u00f6\u00dften TV-Anbieter des asiatischen Landes mit einem Publikum von insgesamt 675 Millionen Zuschauern englischsprachige Inhalte des Senders <em>RT International<\/em> aus. Au\u00dferdem werden <em>RT<\/em>-Inhalte regelm\u00e4\u00dfig von lokalen Nachrichtensendern wie <em>NDTV<\/em>, <em>India Today<\/em> und <em>Republic TV<\/em> genutzt. <em>RT<\/em>-Reporter werden dar\u00fcber hinaus von f\u00fchrenden Zeitungen wie <em>Times of India<\/em>, <em>Economic Times<\/em> und <em>Hindustan Times<\/em> als Experten und Beobachter eingeladen und zitiert. F\u00fcr das Jahr 2026 bereitet <em>RT<\/em> au\u00dferdem die Er\u00f6ffnung einer Nachrichtenseite auf Hindi vor, da sich \u00fcber 500 Millionen Menschen in Indien in dieser Sprache verst\u00e4ndigen.<\/p>\n<p>Zuvor hat die Abgeordnete Sagarika Ghose den\u00a0indischen Medien <em>RT<\/em> als Vorbild pr\u00e4sentiert. Bei einer Parlamentssitzung sagte die Politikerin, dass sich der russische Auslandssender schnell erweitere und den Gesichtspunkt der F\u00fchrung in Moskau f\u00fcr die ganze Welt verst\u00e4ndlich mache. Auch indische Medien sollten ein solch hohes internationales Niveau anstreben, betonte Ghose.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2013\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/262303-indien-vertieft-seine-beziehung-zu\/\">Indien vertieft seine Beziehungen zu Russland und er\u00f6ffnet zwei Konsulate<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/asien\/263565-rt-india-geht-auf-sendung\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;RT&#8221; baut sein Netzwerk in Indien aus. In dieser Woche geht die \u00f6rtliche Redaktion des russischen Auslandssenders von einem TV-Studio in Neu-Delhi aus auf Sendung. Das Programm umfasst Nachrichten und Analysen. Eine Show wird von Ex-Au\u00dfenminister Salman Khurshid moderiert. Es ist eine gro\u00dfartige Nachricht f\u00fcr alle RT-Fans: Am 5. Dezember 2025 geht der Fernsehsender RT [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":95052,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1764686869"],"wp_automatic_camp":["217"],"760f7a327a47a7c7e1e5eaddb4d6df41":["&quot;RT India&quot; geht auf Sendung: Nachrichten und Shows aus Fernsehstudio in Neu-Delhi"],"original_link":["https:\/\/de.rt.com\/asien\/263565-rt-india-geht-auf-sendung\/"],"_thumbnail_id":["95052"],"jnews_social_counter_last_update":["1788316794"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-12-02 16:48:48\";}"]},"categories":[19,23],"tags":[133,679,69599,1673,69598,8975,35539,28370,27322,8383,140],"class_list":["post-95051","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-auf","tag-aus","tag-fernsehstudio","tag-geht","tag-indiaquot","tag-nachrichten","tag-neudelhi","tag-quotrt","tag-sendung","tag-shows","tag-und"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>&quot;RT India&quot; geht auf Sendung: Nachrichten und Shows aus Fernsehstudio in Neu-Delhi - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;RT India&quot; geht auf Sendung: Nachrichten und Shows aus Fernsehstudio in Neu-Delhi\" \/>\n<meta property=\"og:description\" content=\"&#8220;RT&#8221; baut sein Netzwerk in Indien aus. In dieser Woche geht die \u00f6rtliche Redaktion des russischen Auslandssenders von einem TV-Studio in Neu-Delhi aus auf Sendung. Das Programm umfasst Nachrichten und Analysen. Eine Show wird von Ex-Au\u00dfenminister Salman Khurshid moderiert. Es ist eine gro\u00dfartige Nachricht f\u00fcr alle RT-Fans: Am 5. Dezember 2025 geht der Fernsehsender RT [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-12-02T14:31:57+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/692eb5b9b480cc5a951340b9.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"&quot;RT India&quot; geht auf Sendung: Nachrichten und Shows aus Fernsehstudio in Neu-Delhi\",\"datePublished\":\"2025-12-02T14:31:57+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\\\/\"},\"wordCount\":435,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/12\\\/quotRT-Indiaquot-geht-auf-Sendung-Nachrichten-und-Shows-aus-Fernsehstudio.jpg\",\"keywords\":[\"AUF\",\"aus\",\"Fernsehstudio\",\"Geht\",\"Indiaquot\",\"Nachrichten\",\"NeuDelhi\",\"quotRT\",\"Sendung\",\"shows\",\"und\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\\\/\",\"name\":\"&quot;RT India&quot; geht auf Sendung: Nachrichten und Shows aus Fernsehstudio in Neu-Delhi - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/12\\\/quotRT-Indiaquot-geht-auf-Sendung-Nachrichten-und-Shows-aus-Fernsehstudio.jpg\",\"datePublished\":\"2025-12-02T14:31:57+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/12\\\/quotRT-Indiaquot-geht-auf-Sendung-Nachrichten-und-Shows-aus-Fernsehstudio.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/12\\\/quotRT-Indiaquot-geht-auf-Sendung-Nachrichten-und-Shows-aus-Fernsehstudio.jpg\",\"width\":460,\"height\":259,\"caption\":\"&quot;RT India&quot; geht auf Sendung: Nachrichten und Shows aus Fernsehstudio in Neu-Delhi\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&quot;RT India&quot; geht auf Sendung: Nachrichten und Shows aus Fernsehstudio in Neu-Delhi\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"&quot;RT India&quot; geht auf Sendung: Nachrichten und Shows aus Fernsehstudio in Neu-Delhi - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\/","og_locale":"de_DE","og_type":"article","og_title":"&quot;RT India&quot; geht auf Sendung: Nachrichten und Shows aus Fernsehstudio in Neu-Delhi","og_description":"&#8220;RT&#8221; baut sein Netzwerk in Indien aus. In dieser Woche geht die \u00f6rtliche Redaktion des russischen Auslandssenders von einem TV-Studio in Neu-Delhi aus auf Sendung. Das Programm umfasst Nachrichten und Analysen. Eine Show wird von Ex-Au\u00dfenminister Salman Khurshid moderiert. Es ist eine gro\u00dfartige Nachricht f\u00fcr alle RT-Fans: Am 5. Dezember 2025 geht der Fernsehsender RT [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-12-02T14:31:57+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/692eb5b9b480cc5a951340b9.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"&quot;RT India&quot; geht auf Sendung: Nachrichten und Shows aus Fernsehstudio in Neu-Delhi","datePublished":"2025-12-02T14:31:57+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\/"},"wordCount":435,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/quotRT-Indiaquot-geht-auf-Sendung-Nachrichten-und-Shows-aus-Fernsehstudio.jpg","keywords":["AUF","aus","Fernsehstudio","Geht","Indiaquot","Nachrichten","NeuDelhi","quotRT","Sendung","shows","und"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\/","url":"https:\/\/now-news.de\/de\/deutschland\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\/","name":"&quot;RT India&quot; geht auf Sendung: Nachrichten und Shows aus Fernsehstudio in Neu-Delhi - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/quotRT-Indiaquot-geht-auf-Sendung-Nachrichten-und-Shows-aus-Fernsehstudio.jpg","datePublished":"2025-12-02T14:31:57+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/quotRT-Indiaquot-geht-auf-Sendung-Nachrichten-und-Shows-aus-Fernsehstudio.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/12\/quotRT-Indiaquot-geht-auf-Sendung-Nachrichten-und-Shows-aus-Fernsehstudio.jpg","width":460,"height":259,"caption":"&quot;RT India&quot; geht auf Sendung: Nachrichten und Shows aus Fernsehstudio in Neu-Delhi"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/rt-india-geht-auf-sendung-nachrichten-und-shows-aus-fernsehstudio-in-neu-delhi\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"&quot;RT India&quot; geht auf Sendung: Nachrichten und Shows aus Fernsehstudio in Neu-Delhi"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/95051","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=95051"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/95051\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/95052"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=95051"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=95051"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=95051"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}