{"id":94480,"date":"2025-11-22T18:28:46","date_gmt":"2025-11-22T16:28:46","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/"},"modified":"2025-11-22T18:28:46","modified_gmt":"2025-11-22T16:28:46","slug":"puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/","title":{"rendered":"Puschkow: Worte von JD Vance entlarven Scheitern des US-Kurses in der Ukraine"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/69216b7cb480cc22a375ffcb.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Der russische Senator Puschkow wertet die Kritik von JD Vance an den Sanktionen und der Milit\u00e4rhilfe f\u00fcr die Ukraine als offenes Eingest\u00e4ndnis: Der fr\u00fchere US-Kurs habe sich als wirkungslos erwiesen. Nun drohen die USA der Ukraine sogar mit einem Stopp von Waffen und Geheimdienstinformationen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p data-start=\"309\" data-end=\"638\">Nach Einsch\u00e4tzung des russischen Senators Alexei Puschkow markieren die j\u00fcngsten \u00c4u\u00dferungen von US-Vizepr\u00e4sident JD Vance zum amerikanischen Friedensplan f\u00fcr die Ukraine einen Wendepunkt in der Washingtoner Politik. Vance habe offen zugegeben, dass die bisherigen Ans\u00e4tze der USA im Umgang mit dem Konflikt gescheitert seien.\u00a0Auf seinem Telegram-Kanal schrieb Puschkow:<\/p>\n<p data-start=\"309\" data-end=\"638\"><em data-start=\"685\" data-end=\"962\">&#8220;JD Vance nannte es eine Fantasie zu glauben, dass Sanktionen, Geld und Waffen aus den USA den Konflikt in der Ukraine l\u00f6sen k\u00f6nnten. Diese Aussage ist heute das vollst\u00e4ndigste Eingest\u00e4ndnis der Unhaltbarkeit des gesamten bisherigen US-Kurses im ukrainischen Krisenmanagement.&#8221;<\/em><\/p>\n<p>Puschkow erinnerte daran, dass Vance erst vor Kurzem die Sinnlosigkeit weiterer Strafma\u00dfnahmen gegen Russland und die Zwecklosigkeit fortgesetzter Waffenlieferungen an Kiew betont hatte. Die US-Regierung\u00a0beginne daher, sich schrittweise von der bisherigen Rhetorik zu l\u00f6sen. Diese Neubewertung habe auch politische Folgen im Umfeld von Pr\u00e4sident Donald Trump.<\/p>\n<p data-start=\"1341\" data-end=\"1804\">So f\u00fchrte der Senator aus, dass der erwartete R\u00fcckzug des Sondergesandten des US-Pr\u00e4sidenten f\u00fcr die Ukraine, Keith Kellogg, unmittelbar mit der Kurskorrektur zusammenh\u00e4nge.<\/p>\n<p data-start=\"1341\" data-end=\"1804\"><em data-start=\"1517\" data-end=\"1642\">&#8220;Sein Ansatz, der dem der EU-F\u00fchrung \u00e4hnelte, f\u00fcgt sich nicht in den von Trump gew\u00e4hlten Kurs und dessen Friedensplan ein.&#8221;<\/em><\/p>\n<p data-start=\"1341\" data-end=\"1804\">Bislang war Kelloggs Konzept st\u00e4rker auf eine enge Abstimmung mit Br\u00fcssel ausgerichtet und unterschied sich damit deutlich von\u00a0der Linie, die JD Vance vertritt. Nach Einsch\u00e4tzung des Senators setzen die USA nun auf ein h\u00e4rteres Vorgehen gegen\u00fcber Kiew. Washington mache deutlich, dass die Ukraine zur Zustimmung zum amerikanischen Friedensplan gedr\u00e4ngt werden solle. Puschkow betonte:<\/p>\n<p data-start=\"1341\" data-end=\"1804\"><em data-start=\"2032\" data-end=\"2234\">&#8220;Die USA\u00a0haben\u00a0den Weg eines sch\u00e4rferen &#8216;Friedenszwangs&#8217; der Ukraine eingeschlagen. Deshalb droht Washington Kiew offen mit der Einstellung der Waffenlieferungen und Geheimdienstunterst\u00fctzung.&#8221;<\/em><\/p>\n<p data-start=\"2236\" data-end=\"2527\">Vance selbst hatte die Vorstellung, eine Ausweitung der Milit\u00e4rhilfe oder eine Versch\u00e4rfung der Sanktionen k\u00f6nnten Kiew einen Sieg im Konflikt erm\u00f6glichen, als &#8220;Fantasie&#8221; bezeichnet. Nur &#8220;kluge Menschen, die in der realen Welt leben&#8221;, seien in der Lage, eine L\u00f6sung zu finden, sagte er. Kritik am US-Plan f\u00fcr die Ukraine zeige lediglich ein &#8220;Nichtverstehen der Realit\u00e4t vor Ort&#8221;.<\/p>\n<p data-start=\"2529\" data-end=\"2851\">Die Kurs\u00e4nderung Washingtons sorgt unterdessen auch in Europa f\u00fcr Nervosit\u00e4t. Der Kolumnist der Zeitung <em>Komsomolskaja Prawda<\/em>, Jewgeni Umerenkow, erkl\u00e4rte, der neue US-Ansatz sei ein &#8220;Schlag f\u00fcr Europa&#8221;. Besonders deutlich werde dies an der Reaktion der EU-Au\u00dfenbeauftragten Kaja Kallas, die angesichts der neuen Lage &#8220;f\u00f6rmlich in eine Starre verfiel&#8221;.<\/p>\n<p data-start=\"2853\" data-end=\"3173\" data-is-last-node=\"\" data-is-only-node=\"\">Mit den Aussagen von Vance und den Verschiebungen in Washington sieht Puschkow die bisherige US-Linie endg\u00fcltig widerlegt. Seiner Ansicht nach habe sich in der Trump-Administration nun jene Position durchgesetzt, die den Konflikt nicht durch Druck auf Russland, sondern durch politischen Zwang gegen\u00fcber Kiew l\u00f6sen will.<\/p>\n<p>Kremlsprecher Dmitri Peskow erkl\u00e4rte, Russland bleibe vollst\u00e4ndig offen f\u00fcr Friedensgespr\u00e4che und orientiere sich weiterhin an den Ergebnissen des Treffens der Pr\u00e4sidenten Russlands und der USA in Anchorage. Er betonte zudem, dass das Kiewer Regime eine verantwortliche Entscheidung treffen und mit Verhandlungen beginnen m\u00fcsse. Je mehr Territorium die Ukraine verliere, desto kleiner werde ihr Handlungsspielraum.<\/p>\n<p>Abschlie\u00dfend sagte er zu den Aktionen der russischen Streitkr\u00e4fte, diese seien ein &#8220;Zwang f\u00fcr Wladimir Selenskij und sein Regime zu einer friedlichen L\u00f6sung&#8221;. Eine Fortsetzung des Konflikts sei f\u00fcr Kiew &#8220;sinnlos und gef\u00e4hrlich&#8221;.<\/p>\n<p><strong>Mehr zum Thema\u00a0<\/strong>\u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/131481-liveticker-ukraine-krieg\/\">Liveticker Ukraine-Krieg \u2013 Trump sieht nur eine Option: Selenskij muss US-Friedensplan akzeptieren<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6zvgeg\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/262564-puschkow-vances-worte-entlarven-scheitern-des-us-kurses-in-der-ukraine\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der russische Senator Puschkow wertet die Kritik von JD Vance an den Sanktionen und der Milit\u00e4rhilfe f\u00fcr die Ukraine als offenes Eingest\u00e4ndnis: Der fr\u00fchere US-Kurs habe sich als wirkungslos erwiesen. Nun drohen die USA der Ukraine sogar mit einem Stopp von Waffen und Geheimdienstinformationen. Nach Einsch\u00e4tzung des russischen Senators Alexei Puschkow markieren die j\u00fcngsten \u00c4u\u00dferungen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":94481,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1763829138"],"wp_automatic_camp":["217"],"970edeb32572a4233863766f1883ae09":["Puschkow: Worte von JD Vance entlarven Scheitern des US-Kurses in der Ukraine"],"original_link":["https:\/\/de.rt.com\/international\/262564-puschkow-vances-worte-entlarven-scheitern-des-us-kurses-in-der-ukraine\/"],"_thumbnail_id":["94481"],"jnews_social_counter_last_update":["1778622331"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-11-22 18:33:22\";}"]},"categories":[19,23],"tags":[82,583,23751,64148,11272,127,69384,18340,50,6314],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Puschkow: Worte von JD Vance entlarven Scheitern des US-Kurses in der Ukraine - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Puschkow: Worte von JD Vance entlarven Scheitern des US-Kurses in der Ukraine\" \/>\n<meta property=\"og:description\" content=\"Der russische Senator Puschkow wertet die Kritik von JD Vance an den Sanktionen und der Milit\u00e4rhilfe f\u00fcr die Ukraine als offenes Eingest\u00e4ndnis: Der fr\u00fchere US-Kurs habe sich als wirkungslos erwiesen. Nun drohen die USA der Ukraine sogar mit einem Stopp von Waffen und Geheimdienstinformationen. Nach Einsch\u00e4tzung des russischen Senators Alexei Puschkow markieren die j\u00fcngsten \u00c4u\u00dferungen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-22T16:28:46+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/69216b7cb480cc22a375ffcb.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Puschkow: Worte von JD Vance entlarven Scheitern des US-Kurses in der Ukraine\",\"datePublished\":\"2025-11-22T16:28:46+00:00\",\"dateModified\":\"2025-11-22T16:28:46+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/\"},\"wordCount\":627,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Puschkow-Worte-von-JD-Vance-entlarven-Scheitern-des-US-Kurses-in.jpg\",\"keywords\":[\"der\",\"des\",\"entlarven\",\"Puschkow\",\"Scheitern\",\"ukraine\",\"USKurses\",\"Vance\",\"von\",\"Worte\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/\",\"name\":\"Puschkow: Worte von JD Vance entlarven Scheitern des US-Kurses in der Ukraine - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Puschkow-Worte-von-JD-Vance-entlarven-Scheitern-des-US-Kurses-in.jpg\",\"datePublished\":\"2025-11-22T16:28:46+00:00\",\"dateModified\":\"2025-11-22T16:28:46+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Puschkow-Worte-von-JD-Vance-entlarven-Scheitern-des-US-Kurses-in.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Puschkow-Worte-von-JD-Vance-entlarven-Scheitern-des-US-Kurses-in.jpg\",\"width\":460,\"height\":259,\"caption\":\"Puschkow: Worte von JD Vance entlarven Scheitern des US-Kurses in der Ukraine\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Puschkow: Worte von JD Vance entlarven Scheitern des US-Kurses in der Ukraine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Puschkow: Worte von JD Vance entlarven Scheitern des US-Kurses in der Ukraine - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/","og_locale":"de_DE","og_type":"article","og_title":"Puschkow: Worte von JD Vance entlarven Scheitern des US-Kurses in der Ukraine","og_description":"Der russische Senator Puschkow wertet die Kritik von JD Vance an den Sanktionen und der Milit\u00e4rhilfe f\u00fcr die Ukraine als offenes Eingest\u00e4ndnis: Der fr\u00fchere US-Kurs habe sich als wirkungslos erwiesen. Nun drohen die USA der Ukraine sogar mit einem Stopp von Waffen und Geheimdienstinformationen. Nach Einsch\u00e4tzung des russischen Senators Alexei Puschkow markieren die j\u00fcngsten \u00c4u\u00dferungen [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-11-22T16:28:46+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/69216b7cb480cc22a375ffcb.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Puschkow: Worte von JD Vance entlarven Scheitern des US-Kurses in der Ukraine","datePublished":"2025-11-22T16:28:46+00:00","dateModified":"2025-11-22T16:28:46+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/"},"wordCount":627,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Puschkow-Worte-von-JD-Vance-entlarven-Scheitern-des-US-Kurses-in.jpg","keywords":["der","des","entlarven","Puschkow","Scheitern","ukraine","USKurses","Vance","von","Worte"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/","url":"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/","name":"Puschkow: Worte von JD Vance entlarven Scheitern des US-Kurses in der Ukraine - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Puschkow-Worte-von-JD-Vance-entlarven-Scheitern-des-US-Kurses-in.jpg","datePublished":"2025-11-22T16:28:46+00:00","dateModified":"2025-11-22T16:28:46+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Puschkow-Worte-von-JD-Vance-entlarven-Scheitern-des-US-Kurses-in.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Puschkow-Worte-von-JD-Vance-entlarven-Scheitern-des-US-Kurses-in.jpg","width":460,"height":259,"caption":"Puschkow: Worte von JD Vance entlarven Scheitern des US-Kurses in der Ukraine"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/puschkow-worte-von-jd-vance-entlarven-scheitern-des-us-kurses-in-der-ukraine\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Puschkow: Worte von JD Vance entlarven Scheitern des US-Kurses in der Ukraine"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/94480"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=94480"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/94480\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/94481"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=94480"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=94480"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=94480"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}