{"id":94136,"date":"2025-11-17T20:58:29","date_gmt":"2025-11-17T18:58:29","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/"},"modified":"2025-11-17T20:58:29","modified_gmt":"2025-11-17T18:58:29","slug":"nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/","title":{"rendered":"Nach Sabotageakt: Polnischer Generalstab meldet Vorbereitung eines Angriffs auf das Land"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/691b614848fbef69255761de.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Polens Generalstab behauptete, dass auf das Land ein Angriff vorbereitet werde. Derzeit versuche der Gegner angeblich, das Vertrauen der B\u00fcrger in die staatlichen Strukturen zu untergraben. Diese Erkl\u00e4rung folgte auf die zweite Besch\u00e4digung einer Eisenbahnstrecke.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Auf Polen wird mutma\u00dflich ein bewaffneter Angriff vorbereitet. Dies behauptete der Chef des Generalstabs der polnischen Streitkr\u00e4fte, General Wies\u0142aw Kukula. Im Radiosender\u00a0<em>Jedynka<\/em> wurde der General gebeten, die \u00c4u\u00dferungen des Pentagon-Chefs Peter Hegseth zu kommentieren, wonach sich die Welt in einer \u00e4hnlichen Situation wie 1939 und 1981 befinde. Kukula antwortete:<\/p>\n<blockquote>\n<p><em>&#8220;Das ist ein sehr guter Vergleich, denn heute h\u00e4ngt alles von unserer Position ab, davon, ob wir den Gegner zur\u00fcckhalten k\u00f6nnen oder ihn im Gegenteil zur Aggression provozieren.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Anschlie\u00dfend wurde der General gefragt, was es mit der Reihe von Cyberangriffen und Sabotageakten auf sich habe, von denen die Beh\u00f6rden berichten. Kukula \u00e4u\u00dferte sich wie folgt:<\/p>\n<blockquote>\n<p><em>&#8220;Der Gegner hat mit den Vorbereitungen f\u00fcr einen Krieg begonnen. Er schafft hier eine bestimmte Situation, deren Ziel es ist, das Vertrauen der \u00d6ffentlichkeit in die Regierung und in wichtige Institutionen wie die Streitkr\u00e4fte und die Polizei zu untergraben und Bedingungen zu schaffen, die eine potenzielle Aggression auf polnischem Gebiet beg\u00fcnstigen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Die Eisenbahnstrecke Warschau-Lublin, die in Richtung Ukraine f\u00fchrt, wurde am 17. November zum zweiten Mal innerhalb eines Tages besch\u00e4digt. Der polnische Premierminister Donald Tusk erkl\u00e4rte, dass die Zerst\u00f6rung eines Teils der Eisenbahnstrecke auf dieser Linie das Ergebnis einer Sabotageaktion sei. Er pr\u00e4zisierte, dass die Strecke f\u00fcr die Lieferung von Hilfsg\u00fctern in die Ukraine von entscheidender Bedeutung sei, und versprach, die T\u00e4ter zur Rechenschaft zu ziehen. Das polnische Innenministerium best\u00e4tigte jedoch zun\u00e4chst nicht die Berichte \u00fcber einen Sprengsatz, der auf der Eisenbahnstrecke angebracht worden sein soll.<\/p>\n<p>Im Oktober gab Tusk bekannt, dass acht Personen, die der Vorbereitung von Sabotageakten verd\u00e4chtigt werden, im Land festgenommen worden seien. Dies ist nicht der erste Fall dieser Art \u2013 zuvor hatten die polnischen Beh\u00f6rden wiederholt erkl\u00e4rt, Sabotageakte verhindert zu haben, die ihrer Aussage nach &#8220;im Auftrag ausl\u00e4ndischer Geheimdienste&#8221; vorbereitet worden seien. Insbesondere im August beschuldigte Tusks Regierung Russland direkt, B\u00fcrger der Ukraine und Wei\u00dfrusslands f\u00fcr Sabotageakte auf polnischem Territorium rekrutiert zu haben. Die russische Seite wies diese Vorw\u00fcrfe zur\u00fcck.<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/europa\/261997-polens-premier-tusk-bezeichnet-eisenba\">Polens Premier Tusk: Eisenbahnsprengung &#8220;beispielloser Sabotageakt&#8221;<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6xun7u\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/262056-nach-sabotageakt-polnischer-generalstab-meldet\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Polens Generalstab behauptete, dass auf das Land ein Angriff vorbereitet werde. Derzeit versuche der Gegner angeblich, das Vertrauen der B\u00fcrger in die staatlichen Strukturen zu untergraben. Diese Erkl\u00e4rung folgte auf die zweite Besch\u00e4digung einer Eisenbahnstrecke. Auf Polen wird mutma\u00dflich ein bewaffneter Angriff vorbereitet. Dies behauptete der Chef des Generalstabs der polnischen Streitkr\u00e4fte, General Wies\u0142aw Kukula. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":94137,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1763406526"],"wp_automatic_camp":["217"],"38868187841d4cbeb3eef1ce59b27698":["Nach Sabotageakt: Polnischer Generalstab meldet Vorbereitung eines Angriffs auf das Land"],"original_link":["https:\/\/de.rt.com\/europa\/262056-nach-sabotageakt-polnischer-generalstab-meldet\/"],"_thumbnail_id":["94137"],"jnews_social_counter_last_update":["1784095684"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-11-17 21:09:47\";}"]},"categories":[19,23],"tags":[21409,133,427,2111,489,7414,272,979,19459,33287,1020],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Nach Sabotageakt: Polnischer Generalstab meldet Vorbereitung eines Angriffs auf das Land - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Nach Sabotageakt: Polnischer Generalstab meldet Vorbereitung eines Angriffs auf das Land\" \/>\n<meta property=\"og:description\" content=\"Polens Generalstab behauptete, dass auf das Land ein Angriff vorbereitet werde. Derzeit versuche der Gegner angeblich, das Vertrauen der B\u00fcrger in die staatlichen Strukturen zu untergraben. Diese Erkl\u00e4rung folgte auf die zweite Besch\u00e4digung einer Eisenbahnstrecke. Auf Polen wird mutma\u00dflich ein bewaffneter Angriff vorbereitet. Dies behauptete der Chef des Generalstabs der polnischen Streitkr\u00e4fte, General Wies\u0142aw Kukula. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-17T18:58:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/691b614848fbef69255761de.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Nach Sabotageakt: Polnischer Generalstab meldet Vorbereitung eines Angriffs auf das Land\",\"datePublished\":\"2025-11-17T18:58:29+00:00\",\"dateModified\":\"2025-11-17T18:58:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/\"},\"wordCount\":409,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Nach-Sabotageakt-Polnischer-Generalstab-meldet-Vorbereitung-eines-Angriffs-auf-das.jpg\",\"keywords\":[\"Angriffs\",\"AUF\",\"das\",\"eines\",\"Generalstab\",\"Land\",\"meldet\",\"nach\",\"Polnischer\",\"Sabotageakt\",\"Vorbereitung\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/\",\"name\":\"Nach Sabotageakt: Polnischer Generalstab meldet Vorbereitung eines Angriffs auf das Land - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Nach-Sabotageakt-Polnischer-Generalstab-meldet-Vorbereitung-eines-Angriffs-auf-das.jpg\",\"datePublished\":\"2025-11-17T18:58:29+00:00\",\"dateModified\":\"2025-11-17T18:58:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Nach-Sabotageakt-Polnischer-Generalstab-meldet-Vorbereitung-eines-Angriffs-auf-das.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Nach-Sabotageakt-Polnischer-Generalstab-meldet-Vorbereitung-eines-Angriffs-auf-das.jpg\",\"width\":460,\"height\":259,\"caption\":\"Nach Sabotageakt: Polnischer Generalstab meldet Vorbereitung eines Angriffs auf das Land\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Nach Sabotageakt: Polnischer Generalstab meldet Vorbereitung eines Angriffs auf das Land\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Nach Sabotageakt: Polnischer Generalstab meldet Vorbereitung eines Angriffs auf das Land - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/","og_locale":"de_DE","og_type":"article","og_title":"Nach Sabotageakt: Polnischer Generalstab meldet Vorbereitung eines Angriffs auf das Land","og_description":"Polens Generalstab behauptete, dass auf das Land ein Angriff vorbereitet werde. Derzeit versuche der Gegner angeblich, das Vertrauen der B\u00fcrger in die staatlichen Strukturen zu untergraben. Diese Erkl\u00e4rung folgte auf die zweite Besch\u00e4digung einer Eisenbahnstrecke. Auf Polen wird mutma\u00dflich ein bewaffneter Angriff vorbereitet. Dies behauptete der Chef des Generalstabs der polnischen Streitkr\u00e4fte, General Wies\u0142aw Kukula. [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-11-17T18:58:29+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/691b614848fbef69255761de.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Nach Sabotageakt: Polnischer Generalstab meldet Vorbereitung eines Angriffs auf das Land","datePublished":"2025-11-17T18:58:29+00:00","dateModified":"2025-11-17T18:58:29+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/"},"wordCount":409,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Nach-Sabotageakt-Polnischer-Generalstab-meldet-Vorbereitung-eines-Angriffs-auf-das.jpg","keywords":["Angriffs","AUF","das","eines","Generalstab","Land","meldet","nach","Polnischer","Sabotageakt","Vorbereitung"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/","url":"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/","name":"Nach Sabotageakt: Polnischer Generalstab meldet Vorbereitung eines Angriffs auf das Land - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Nach-Sabotageakt-Polnischer-Generalstab-meldet-Vorbereitung-eines-Angriffs-auf-das.jpg","datePublished":"2025-11-17T18:58:29+00:00","dateModified":"2025-11-17T18:58:29+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Nach-Sabotageakt-Polnischer-Generalstab-meldet-Vorbereitung-eines-Angriffs-auf-das.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Nach-Sabotageakt-Polnischer-Generalstab-meldet-Vorbereitung-eines-Angriffs-auf-das.jpg","width":460,"height":259,"caption":"Nach Sabotageakt: Polnischer Generalstab meldet Vorbereitung eines Angriffs auf das Land"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/nach-sabotageakt-polnischer-generalstab-meldet-vorbereitung-eines-angriffs-auf-das-land\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Nach Sabotageakt: Polnischer Generalstab meldet Vorbereitung eines Angriffs auf das Land"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/94136"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=94136"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/94136\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/94137"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=94136"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=94136"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=94136"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}