{"id":93280,"date":"2025-11-03T19:55:02","date_gmt":"2025-11-03T17:55:02","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/"},"modified":"2025-11-03T19:55:02","modified_gmt":"2025-11-03T17:55:02","slug":"rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/","title":{"rendered":"Rente nicht mehr sicher: Bundesbankchef Nagel fordert l\u00e4ngere Lebensarbeitszeit"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/69089b6f48fbef13214fa413.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Um den verbliebenen geringen Wohlstand zu sichern, m\u00fcssten die Deutschen noch l\u00e4nger als ohnehin schon arbeiten, meint Bundesbank-Pr\u00e4sident Joachim Nagel. Ohne daf\u00fcr eine konkrete Begr\u00fcndung zu nennen, sieht er dar\u00fcber hinaus einen &#8220;moderaten Wachstumspfad&#8221; mit Blick auf die deutsche Wirtschaft f\u00fcr 2026.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p data-external=\"Article.FirstParagraph\">Bundesbank-Pr\u00e4sident Joachim Nagel fordert eine l\u00e4ngere Lebensarbeitszeit f\u00fcr die Deutschen. Laut einem Bericht von <em>Table Briefings<\/em> sagte er:<\/p>\n<blockquote>\n<p data-external=\"Article.FirstParagraph\"><em>&#8220;Wir m\u00fcssen uns ehrlich machen. Wir sind eine alternde Gesellschaft. Wir m\u00fcssen l\u00e4nger arbeiten, um uns den Wohlstand zu erhalten, den die Generationen nach dem Krieg aufgebaut haben.&#8221;<\/em><\/p>\n<\/blockquote>\n<p data-external=\"Article.FirstParagraph\">Schwammig erg\u00e4nzte er: &#8220;Man muss den Menschen zutrauen, zu verstehen, wo die Herausforderungen liegen.&#8221; Das berichtet unter anderem die <em>Welt<\/em> am Montag. Wenn zur Erhaltung der Wettbewerbsf\u00e4higkeit nicht auch unangenehme Fragen beantwortet w\u00fcrden, fielen Deutschland und Europa zur\u00fcck. Dabei <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/easyfolio.de\/aktuelles\/details\/renteneintrittsalter-europa-tabelle\">stehen<\/a> die Deutschen zusammen mit Schweden und Niederl\u00e4ndern mit einem abschlagsfreien Renteneintrittsalter von 67 Jahren ohnehin an der Spitze der &#8220;Langzeitarbeiter&#8221; innerhalb der EU, deutlich vor Franzosen, Griechen, Polen oder Italienern.<\/p>\n<p>Wie andere\u00a0\u2012 wohlgemerkt staatsnahe \u2012 \u00d6konomen \u00e4u\u00dferte sich Nagel zuversichtlich \u00fcber die wirtschaftliche Entwicklung im kommenden Jahr. &#8220;Die deutsche Wirtschaft kann jetzt auf einen moderaten Wachstumspfad einschwenken. Wir werden im n\u00e4chsten Jahr mehr Wachstum sehen, wenn die Zukunftsausgaben richtig gesetzt werden. Dann kann aus dem zarten Pfl\u00e4nzlein mehr werden.&#8221;<\/p>\n<p>Woher er diese Zuversicht nimmt, bleibt unklar: Seit der Einf\u00fchrung des Euros 2002 sank der Anteil der EU am weltweiten kaufkraftbereinigten globalen Bruttoinlandsprodukt (BIP) von \u00fcber 21 auf derzeit nur noch 14 Prozent. Besonders die negative Entwicklung Deutschlands h\u00e4ngt damit zusammen: Die unumkehrbare Deindustrialisierung des Landes seit 2022, die Flucht von echten Fachkr\u00e4ften ins Ausland und die weiterhin ungebremste Einwanderung von schlecht qualifizierten Menschen in das deutsche Sozialsystem sollten eher die Abw\u00e4rtsspirale weiter beschleunigen.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2012\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/kurzclips\/video\/258648-afd-politiker-springer-hoeheres-rentenalter\/\">AfD-Politiker Springer: H\u00f6heres Rentenalter l\u00f6st Personalprobleme nicht<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/260679-rente-ist-nicht-mehr-sicher\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Um den verbliebenen geringen Wohlstand zu sichern, m\u00fcssten die Deutschen noch l\u00e4nger als ohnehin schon arbeiten, meint Bundesbank-Pr\u00e4sident Joachim Nagel. Ohne daf\u00fcr eine konkrete Begr\u00fcndung zu nennen, sieht er dar\u00fcber hinaus einen &#8220;moderaten Wachstumspfad&#8221; mit Blick auf die deutsche Wirtschaft f\u00fcr 2026. Bundesbank-Pr\u00e4sident Joachim Nagel fordert eine l\u00e4ngere Lebensarbeitszeit f\u00fcr die Deutschen. Laut einem Bericht [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":93281,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1762192683"],"wp_automatic_camp":["217"],"956de3a80e9c13ebec39f47b60d688aa":["Rente nicht mehr sicher: Bundesbankchef Nagel fordert l\u00e4ngere Lebensarbeitszeit"],"original_link":["https:\/\/de.rt.com\/inland\/260679-rente-ist-nicht-mehr-sicher\/"],"_thumbnail_id":["93281"],"jnews_social_counter_last_update":["1778622287"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-11-03 19:59:03\";}"]},"categories":[19,23],"tags":[59767,355,28451,68889,2063,18659,800,20697,22337],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rente nicht mehr sicher: Bundesbankchef Nagel fordert l\u00e4ngere Lebensarbeitszeit - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rente nicht mehr sicher: Bundesbankchef Nagel fordert l\u00e4ngere Lebensarbeitszeit\" \/>\n<meta property=\"og:description\" content=\"Um den verbliebenen geringen Wohlstand zu sichern, m\u00fcssten die Deutschen noch l\u00e4nger als ohnehin schon arbeiten, meint Bundesbank-Pr\u00e4sident Joachim Nagel. Ohne daf\u00fcr eine konkrete Begr\u00fcndung zu nennen, sieht er dar\u00fcber hinaus einen &#8220;moderaten Wachstumspfad&#8221; mit Blick auf die deutsche Wirtschaft f\u00fcr 2026. Bundesbank-Pr\u00e4sident Joachim Nagel fordert eine l\u00e4ngere Lebensarbeitszeit f\u00fcr die Deutschen. Laut einem Bericht [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-03T17:55:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/69089b6f48fbef13214fa413.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Rente nicht mehr sicher: Bundesbankchef Nagel fordert l\u00e4ngere Lebensarbeitszeit\",\"datePublished\":\"2025-11-03T17:55:02+00:00\",\"dateModified\":\"2025-11-03T17:55:02+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/\"},\"wordCount\":324,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Rente-nicht-mehr-sicher-Bundesbankchef-Nagel-fordert-laengere-Lebensarbeitszeit.jpg\",\"keywords\":[\"BundesbankChef\",\"fordert\",\"l\u00e4ngere\",\"Lebensarbeitszeit\",\"mehr\",\"N\u00e4gel\",\"nicht\",\"Rente\",\"sicher\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/\",\"name\":\"Rente nicht mehr sicher: Bundesbankchef Nagel fordert l\u00e4ngere Lebensarbeitszeit - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Rente-nicht-mehr-sicher-Bundesbankchef-Nagel-fordert-laengere-Lebensarbeitszeit.jpg\",\"datePublished\":\"2025-11-03T17:55:02+00:00\",\"dateModified\":\"2025-11-03T17:55:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Rente-nicht-mehr-sicher-Bundesbankchef-Nagel-fordert-laengere-Lebensarbeitszeit.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Rente-nicht-mehr-sicher-Bundesbankchef-Nagel-fordert-laengere-Lebensarbeitszeit.jpg\",\"width\":460,\"height\":259,\"caption\":\"Rente nicht mehr sicher: Bundesbankchef Nagel fordert l\u00e4ngere Lebensarbeitszeit\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rente nicht mehr sicher: Bundesbankchef Nagel fordert l\u00e4ngere Lebensarbeitszeit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rente nicht mehr sicher: Bundesbankchef Nagel fordert l\u00e4ngere Lebensarbeitszeit - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/","og_locale":"de_DE","og_type":"article","og_title":"Rente nicht mehr sicher: Bundesbankchef Nagel fordert l\u00e4ngere Lebensarbeitszeit","og_description":"Um den verbliebenen geringen Wohlstand zu sichern, m\u00fcssten die Deutschen noch l\u00e4nger als ohnehin schon arbeiten, meint Bundesbank-Pr\u00e4sident Joachim Nagel. Ohne daf\u00fcr eine konkrete Begr\u00fcndung zu nennen, sieht er dar\u00fcber hinaus einen &#8220;moderaten Wachstumspfad&#8221; mit Blick auf die deutsche Wirtschaft f\u00fcr 2026. Bundesbank-Pr\u00e4sident Joachim Nagel fordert eine l\u00e4ngere Lebensarbeitszeit f\u00fcr die Deutschen. Laut einem Bericht [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-11-03T17:55:02+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/69089b6f48fbef13214fa413.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Rente nicht mehr sicher: Bundesbankchef Nagel fordert l\u00e4ngere Lebensarbeitszeit","datePublished":"2025-11-03T17:55:02+00:00","dateModified":"2025-11-03T17:55:02+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/"},"wordCount":324,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Rente-nicht-mehr-sicher-Bundesbankchef-Nagel-fordert-laengere-Lebensarbeitszeit.jpg","keywords":["BundesbankChef","fordert","l\u00e4ngere","Lebensarbeitszeit","mehr","N\u00e4gel","nicht","Rente","sicher"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/","url":"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/","name":"Rente nicht mehr sicher: Bundesbankchef Nagel fordert l\u00e4ngere Lebensarbeitszeit - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Rente-nicht-mehr-sicher-Bundesbankchef-Nagel-fordert-laengere-Lebensarbeitszeit.jpg","datePublished":"2025-11-03T17:55:02+00:00","dateModified":"2025-11-03T17:55:02+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Rente-nicht-mehr-sicher-Bundesbankchef-Nagel-fordert-laengere-Lebensarbeitszeit.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Rente-nicht-mehr-sicher-Bundesbankchef-Nagel-fordert-laengere-Lebensarbeitszeit.jpg","width":460,"height":259,"caption":"Rente nicht mehr sicher: Bundesbankchef Nagel fordert l\u00e4ngere Lebensarbeitszeit"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/rente-nicht-mehr-sicher-bundesbankchef-nagel-fordert-laengere-lebensarbeitszeit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Rente nicht mehr sicher: Bundesbankchef Nagel fordert l\u00e4ngere Lebensarbeitszeit"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/93280"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=93280"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/93280\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/93281"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=93280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=93280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=93280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}