{"id":93204,"date":"2025-11-01T22:45:13","date_gmt":"2025-11-01T20:45:13","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\/"},"modified":"2025-11-01T22:45:13","modified_gmt":"2025-11-01T20:45:13","slug":"slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\/","title":{"rendered":"Slowakei wird Idee eines antiukrainischen Blocks mit Ungarn und Tschechien unterst\u00fctzen"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/6905de69b480cc18334a02db.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Bratislava, Budapest und Prag k\u00f6nnten einen Ukraine-skeptischen Block bilden und gemeinsam gegen die EU-Milit\u00e4rhilfe auftreten, meint Lubo\u0161 Blaha, stellvertretender Vorsitzender der regierenden slowakischen Partei Smer. Die Idee eines solchen Blocks wird von Ungarn vorangetrieben, berichtete &#8220;Politico&#8221;.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die Slowakei werde die Idee eines Anti-Ukraine-Blocks mit Ungarn und Tschechien unterst\u00fctzen. Dies <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/iz.ru\/1982788\/daniil-sechkin\/vnutrisoyuznyj-dogovor-slovakiya-podderzhit-ideyu-antiukrainskogo-bloka-s-vengriej-i-chekhiej\">erkl\u00e4rte<\/a> Lubo\u0161 Blaha, der Abgeordnete des slowakischen Nationalrats und stellvertretende Vorsitzende der regierenden Partei Smer, gegen\u00fcber der Zeitung <em>Iswestija<\/em>. Er sagte:<\/p>\n<p><em>&#8220;Gemeinsame Handlungen von denen, die in Europa noch bei vollem Verstand sind, sind nicht nur m\u00f6glich, sondern auch wahrscheinlich.\u00a0Abgesehen davon, dass Europa nach Jahrzehnten erneut von einem kollektiven Wahnsinn erfasst ist, der uns alle zum Krieg, Niedergang und Chaos f\u00fchrt.&#8221;<\/em><\/p>\n<p>Bratislava, Budapest und Prag verst\u00fcnden, dass die heutige Politik Br\u00fcssels sch\u00e4dlich und anti-europ\u00e4isch sei und dass das Beste, was sie f\u00fcr ihre Staaten und V\u00f6lker tun k\u00f6nnten, darin bestehe, sich mit allen m\u00f6glichen Mitteln zu verteidigen, betonte Blaha.<\/p>\n<p><em>&#8220;Nat\u00fcrlich werden sie viel st\u00e4rker sein, wenn sie sich zusammentun.\u00a0Deshalb ist genau dieses Szenario zu erwarten.\u00a0Man muss darin keine Verschw\u00f6rung oder keinen hybriden Krieg Russlands sehen, denn es wird lediglich ein Ausdruck von gesundem Menschenverstand und politischem Realismus sein&#8221;,<\/em><\/p>\n<p>f\u00fcgte der Politiker hinzu.<\/p>\n<p><strong><\/strong>In ihrer Au\u00dfenpolitik seien sich die Slowakei, Tschechien und Ungarn nicht vollkommen einig, aber die Staatschefs dieser drei L\u00e4nder und offensichtlich eine Reihe von anderen einflussreichen Politikern in Europa h\u00e4tten \u00e4hnliche Positionen in der Ukraine-Frage, so Blaha weiter.\u00a0&#8220;Unabh\u00e4ngig voneinander sind sie zu \u00e4hnlichen Schlussfolgerungen gekommen&#8221;.<\/p>\n<p><strong><\/strong>Die antirussische Milit\u00e4rhysterie in Europa f\u00fchre nur zur Katastrophe, ist Blacha \u00fcberzeugt.\u00a0Trotz Sanktionen sei es Europa nicht gelungen, Russland zu brechen, und neue Pakete w\u00fcrden keine Auswirkung haben. &#8220;Es ist unm\u00f6glich, Russland ohne einen Atomkrieg zu besiegen (\u2026) und der Verzicht auf russische Energietr\u00e4ger f\u00fcr die europ\u00e4ische Wirtschaft ist so \u00e4hnlich wie den Ast abzus\u00e4gen, auf dem man sitzt&#8221;, glaubt der slowakische Politiker. Seiner Meinung nach sei die Subventionierung der korrupten oligarchischen F\u00fchrung der Ukraine der Weg in die H\u00f6lle.<\/p>\n<p>Ungarns Regierungschef Viktor Orb\u00e1n plane, eine ukrainische Skeptikerallianz innerhalb der EU unter Beteiligung der Slowakei und Tschechiens zu formen. Dies <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.politico.eu\/article\/hungary-anti-ukraine-bloc-czechia-slovakia-viktor-orban-andrej-babis-robert-fico\/\">berichtete<\/a>\u00a0<em>Politico<\/em> am Dienstag unter Berufung auf Bal\u00e1zs Orb\u00e1n, einen hochrangigen politischen Berater des ungarischen Ministerpr\u00e4sidenten.<\/p>\n<p>Viktor Orb\u00e1n hoffe, sich mit dem slowakischen Regierungschef Robert Fico sowie mit Andrej Babi\u0161, dessen ANO-Partei die j\u00fcngsten Parlamentswahlen in Tschechien gewonnen hat und noch eine Regierung bilden muss, zusammenzutun, um eine gemeinsame Position im Vorfeld der Treffen der EU-Staats- und Regierungschefs zu vereinbaren, so der Berater.<\/p>\n<p>Obwohl die Bildung einer festen politischen Allianz noch in weiter Ferne liege, so <em>Politico<\/em>, k\u00f6nnte diese Initiative die finanzielle und milit\u00e4rische Hilfe f\u00fcr die Ukraine seitens der EU erheblich erschweren.\u00a0<\/p>\n<p><strong>Mehr zum Thema <\/strong>\u2013<strong><\/strong><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/europa\/260118-bericht-ungarn-will-anti-ukraine\/\">Bericht: Ungarn will Anti-Ukraine-Block mit Tschechien und Slowakei bilden<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6ycxta\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/260557-slowakei-wird-idee-antiukrainischen-blocks\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bratislava, Budapest und Prag k\u00f6nnten einen Ukraine-skeptischen Block bilden und gemeinsam gegen die EU-Milit\u00e4rhilfe auftreten, meint Lubo\u0161 Blaha, stellvertretender Vorsitzender der regierenden slowakischen Partei Smer. Die Idee eines solchen Blocks wird von Ungarn vorangetrieben, berichtete &#8220;Politico&#8221;. Die Slowakei werde die Idee eines Anti-Ukraine-Blocks mit Ungarn und Tschechien unterst\u00fctzen. Dies erkl\u00e4rte Lubo\u0161 Blaha, der Abgeordnete des [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":93205,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1762030712"],"wp_automatic_camp":["217"],"7a57425a5d95791d242847994d99a4ed":["Slowakei wird Idee eines antiukrainischen Blocks mit Ungarn und Tschechien unterst\u00fctzen"],"original_link":["https:\/\/de.rt.com\/europa\/260557-slowakei-wird-idee-antiukrainischen-blocks\/"],"_thumbnail_id":["93205"],"jnews_social_counter_last_update":["1788332035"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-11-01 22:59:32\";}"]},"categories":[19,23],"tags":[68862,48241,2111,24748,419,41775,32609,140,11664,1190,374],"class_list":["post-93204","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-antiukrainischen","tag-blocks","tag-eines","tag-idee","tag-mit","tag-slowakei","tag-tschechien","tag-und","tag-ungarn","tag-unterstuetzen","tag-wird"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Slowakei wird Idee eines antiukrainischen Blocks mit Ungarn und Tschechien unterst\u00fctzen - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Slowakei wird Idee eines antiukrainischen Blocks mit Ungarn und Tschechien unterst\u00fctzen\" \/>\n<meta property=\"og:description\" content=\"Bratislava, Budapest und Prag k\u00f6nnten einen Ukraine-skeptischen Block bilden und gemeinsam gegen die EU-Milit\u00e4rhilfe auftreten, meint Lubo\u0161 Blaha, stellvertretender Vorsitzender der regierenden slowakischen Partei Smer. Die Idee eines solchen Blocks wird von Ungarn vorangetrieben, berichtete &#8220;Politico&#8221;. Die Slowakei werde die Idee eines Anti-Ukraine-Blocks mit Ungarn und Tschechien unterst\u00fctzen. Dies erkl\u00e4rte Lubo\u0161 Blaha, der Abgeordnete des [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-11-01T20:45:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/6905de69b480cc18334a02db.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Slowakei wird Idee eines antiukrainischen Blocks mit Ungarn und Tschechien unterst\u00fctzen\",\"datePublished\":\"2025-11-01T20:45:13+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\\\/\"},\"wordCount\":502,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/11\\\/Slowakei-wird-Idee-eines-antiukrainischen-Blocks-mit-Ungarn-und-Tschechien.jpg\",\"keywords\":[\"antiukrainischen\",\"Blocks\",\"eines\",\"Idee\",\"mit\",\"Slowakei\",\"Tschechien\",\"und\",\"Ungarn\",\"unterst\u00fctzen\",\"wird\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\\\/\",\"name\":\"Slowakei wird Idee eines antiukrainischen Blocks mit Ungarn und Tschechien unterst\u00fctzen - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/11\\\/Slowakei-wird-Idee-eines-antiukrainischen-Blocks-mit-Ungarn-und-Tschechien.jpg\",\"datePublished\":\"2025-11-01T20:45:13+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/11\\\/Slowakei-wird-Idee-eines-antiukrainischen-Blocks-mit-Ungarn-und-Tschechien.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/11\\\/Slowakei-wird-Idee-eines-antiukrainischen-Blocks-mit-Ungarn-und-Tschechien.jpg\",\"width\":460,\"height\":259,\"caption\":\"Slowakei wird Idee eines antiukrainischen Blocks mit Ungarn und Tschechien unterst\u00fctzen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Slowakei wird Idee eines antiukrainischen Blocks mit Ungarn und Tschechien unterst\u00fctzen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Slowakei wird Idee eines antiukrainischen Blocks mit Ungarn und Tschechien unterst\u00fctzen - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\/","og_locale":"de_DE","og_type":"article","og_title":"Slowakei wird Idee eines antiukrainischen Blocks mit Ungarn und Tschechien unterst\u00fctzen","og_description":"Bratislava, Budapest und Prag k\u00f6nnten einen Ukraine-skeptischen Block bilden und gemeinsam gegen die EU-Milit\u00e4rhilfe auftreten, meint Lubo\u0161 Blaha, stellvertretender Vorsitzender der regierenden slowakischen Partei Smer. Die Idee eines solchen Blocks wird von Ungarn vorangetrieben, berichtete &#8220;Politico&#8221;. Die Slowakei werde die Idee eines Anti-Ukraine-Blocks mit Ungarn und Tschechien unterst\u00fctzen. Dies erkl\u00e4rte Lubo\u0161 Blaha, der Abgeordnete des [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-11-01T20:45:13+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/6905de69b480cc18334a02db.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Slowakei wird Idee eines antiukrainischen Blocks mit Ungarn und Tschechien unterst\u00fctzen","datePublished":"2025-11-01T20:45:13+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\/"},"wordCount":502,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Slowakei-wird-Idee-eines-antiukrainischen-Blocks-mit-Ungarn-und-Tschechien.jpg","keywords":["antiukrainischen","Blocks","eines","Idee","mit","Slowakei","Tschechien","und","Ungarn","unterst\u00fctzen","wird"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\/","url":"https:\/\/now-news.de\/de\/deutschland\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\/","name":"Slowakei wird Idee eines antiukrainischen Blocks mit Ungarn und Tschechien unterst\u00fctzen - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Slowakei-wird-Idee-eines-antiukrainischen-Blocks-mit-Ungarn-und-Tschechien.jpg","datePublished":"2025-11-01T20:45:13+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Slowakei-wird-Idee-eines-antiukrainischen-Blocks-mit-Ungarn-und-Tschechien.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/11\/Slowakei-wird-Idee-eines-antiukrainischen-Blocks-mit-Ungarn-und-Tschechien.jpg","width":460,"height":259,"caption":"Slowakei wird Idee eines antiukrainischen Blocks mit Ungarn und Tschechien unterst\u00fctzen"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/slowakei-wird-idee-eines-antiukrainischen-blocks-mit-ungarn-und-tschechien-unterstuetzen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Slowakei wird Idee eines antiukrainischen Blocks mit Ungarn und Tschechien unterst\u00fctzen"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/93204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=93204"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/93204\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/93205"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=93204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=93204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=93204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}