{"id":92916,"date":"2025-10-27T17:52:35","date_gmt":"2025-10-27T15:52:35","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/"},"modified":"2025-10-27T17:52:35","modified_gmt":"2025-10-27T15:52:35","slug":"karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/","title":{"rendered":"Karin Kneissl: EU entwickelt sich zu einem Milit\u00e4rb\u00fcndnis\u00a0  \u00a0"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/68ff67e6b480cc3d2639b44c.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die fr\u00fchere Au\u00dfenministerin \u00d6sterreichs, Karin Kneissl, meint in einem Interview, dass sich die Europ\u00e4ische Union aktuell zunehmend zu einem Milit\u00e4rb\u00fcndnis entwickle. F\u00fcr ein neutrales Land sei dies ein gro\u00dfes Dilemma.<\/p>\n<p>\u00a0\n            <\/p><\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Fast alle politischen Parteien in \u00d6sterreich, mit Ausnahme vielleicht der Sozialdemokraten, sind auf die eine oder andere Weise an einem NATO-Beitritt des Landes interessiert. Diese Meinung \u00e4u\u00dferte die ehemalige \u00f6sterreichische Au\u00dfenministerin, Karin Kneissl, in einem Interview. Kneissl leitet derzeit das Zentrum G.O.R.K.l. (Geopolitisches Observatorium f\u00fcr Russische Schl\u00fcsselfragen) an der Staatlichen Universit\u00e4t Sankt Petersburg.<\/p>\n<p>Ihr zufolge erfreue sich heute die Idee des Transatlantismus in den politischen und milit\u00e4rischen Kreisen des Landes gro\u00dfer Beliebtheit.<\/p>\n<p>In dem Zusammenhang f\u00fchrt Kneissl im Gespr\u00e4ch mit der Nachrichtenagentur <em>RIA Nowoti<\/em> aus:<\/p>\n<blockquote>\n<p><em>&#8220;Das Dilemma f\u00fcr \u00d6sterreich besteht meiner Meinung nach nicht so sehr darin, der NATO beizutreten. Was wir erleben, ist die fortschreitende Umwandlung der Europ\u00e4ischen Union in ein Milit\u00e4rb\u00fcndnis.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>F\u00fcr das Land, das am 26. Oktober 1955 die immerw\u00e4hrende Neutralit\u00e4t erkl\u00e4rt habe, bedeute das eine Zwangslage.<\/p>\n<p>Die Wurzel des Dilemmas liege darin, f\u00fcgte die Ex-Au\u00dfenministerin hinzu, dass \u00d6sterreich der EU erst 1995 beigetreten sei, als diese sich bereits als politisches und defensives B\u00fcndnis etabliert habe. Der Beitrittsantrag selbst sei 1989 gestellt worden, als die Lage grunds\u00e4tzlich anders gewesen sei und es lediglich die Europ\u00e4ische Wirtschaftsgemeinschaft gegeben habe.<\/p>\n<p>Damals sei \u00fcber den EU-Beitritt \u00d6sterreichs diskutiert worden, wobei die Vorstellung im Vordergrund gestanden habe, dass eine Mitgliedschaft Wien dazu verpflichten w\u00fcrde, die politischen und milit\u00e4rischen Entscheidungen Br\u00fcssels einzuhalten. Allerdings konnte niemand im Jahr 1995 vorhersagen, welche Ziele die Gemeinschaft in Zukunft verfolgen w\u00fcrde.<\/p>\n<p>Mit Blick auf die Schweiz sagte Kneissl, dass zwischen Bern und Br\u00fcssel Kooperationsabkommen verschiedener Art best\u00fcnden, obwohl der Beitritt des Landes zu der Gemeinschaft offiziell nicht auf der Tagesordnung stehe.<\/p>\n<blockquote>\n<p><em>&#8220;Ich bin \u00fcberzeugt, dass die \u00fcberwiegende Mehrheit der Schweizer B\u00fcrger aus dem einen oder anderen Grund einen EU-Beitritt ablehnen w\u00fcrde. Einer davon ist, dass dies ihrem Status als neutrale Macht widerspricht.&#8221;<\/em><\/p>\n<\/blockquote>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/kurzclips\/video\/259777-russland-reagiert-auf-19-eu\/\">Russland reagiert auf 19. EU-Sanktionspaket \u2013 Europa schadet sich selbst<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6yntma\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/260054-karin-kneissl-eu-entwickelt-sich\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die fr\u00fchere Au\u00dfenministerin \u00d6sterreichs, Karin Kneissl, meint in einem Interview, dass sich die Europ\u00e4ische Union aktuell zunehmend zu einem Milit\u00e4rb\u00fcndnis entwickle. F\u00fcr ein neutrales Land sei dies ein gro\u00dfes Dilemma. \u00a0 Fast alle politischen Parteien in \u00d6sterreich, mit Ausnahme vielleicht der Sozialdemokraten, sind auf die eine oder andere Weise an einem NATO-Beitritt des Landes interessiert. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":92917,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1761581247"],"wp_automatic_camp":["217"],"861a5b4ca0cbba1bd78ad5beab65bd90":["Karin Kneissl: EU entwickelt sich zu einem Milit\u00e4rb\u00fcndnis\u00a0  \u00a0"],"original_link":["https:\/\/de.rt.com\/international\/260054-karin-kneissl-eu-entwickelt-sich\/"],"_thumbnail_id":["92917"],"jnews_social_counter_last_update":["1784097018"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-10-27 18:08:30\";}"]},"categories":[19,23],"tags":[352,4042,1604,1605,39472,434],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Karin Kneissl: EU entwickelt sich zu einem Milit\u00e4rb\u00fcndnis\u00a0 \u00a0 - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Karin Kneissl: EU entwickelt sich zu einem Milit\u00e4rb\u00fcndnis\u00a0 \u00a0\" \/>\n<meta property=\"og:description\" content=\"Die fr\u00fchere Au\u00dfenministerin \u00d6sterreichs, Karin Kneissl, meint in einem Interview, dass sich die Europ\u00e4ische Union aktuell zunehmend zu einem Milit\u00e4rb\u00fcndnis entwickle. F\u00fcr ein neutrales Land sei dies ein gro\u00dfes Dilemma. \u00a0 Fast alle politischen Parteien in \u00d6sterreich, mit Ausnahme vielleicht der Sozialdemokraten, sind auf die eine oder andere Weise an einem NATO-Beitritt des Landes interessiert. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-27T15:52:35+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/68ff67e6b480cc3d2639b44c.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Karin Kneissl: EU entwickelt sich zu einem Milit\u00e4rb\u00fcndnis\u00a0 \u00a0\",\"datePublished\":\"2025-10-27T15:52:35+00:00\",\"dateModified\":\"2025-10-27T15:52:35+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/\"},\"wordCount\":377,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Karin-Kneissl-EU-entwickelt-sich-zu-einem-Militaerbuendnis.jpg\",\"keywords\":[\"einem\",\"entwickelt\",\"Karin\",\"Kneissl\",\"Milit\u00e4rb\u00fcndnis\",\"sich\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/\",\"name\":\"Karin Kneissl: EU entwickelt sich zu einem Milit\u00e4rb\u00fcndnis\u00a0 \u00a0 - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Karin-Kneissl-EU-entwickelt-sich-zu-einem-Militaerbuendnis.jpg\",\"datePublished\":\"2025-10-27T15:52:35+00:00\",\"dateModified\":\"2025-10-27T15:52:35+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Karin-Kneissl-EU-entwickelt-sich-zu-einem-Militaerbuendnis.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Karin-Kneissl-EU-entwickelt-sich-zu-einem-Militaerbuendnis.jpg\",\"width\":460,\"height\":259,\"caption\":\"Karin Kneissl: EU entwickelt sich zu einem Milit\u00e4rb\u00fcndnis\u00a0 \u00a0\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Karin Kneissl: EU entwickelt sich zu einem Milit\u00e4rb\u00fcndnis\u00a0 \u00a0\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Karin Kneissl: EU entwickelt sich zu einem Milit\u00e4rb\u00fcndnis\u00a0 \u00a0 - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/","og_locale":"de_DE","og_type":"article","og_title":"Karin Kneissl: EU entwickelt sich zu einem Milit\u00e4rb\u00fcndnis\u00a0 \u00a0","og_description":"Die fr\u00fchere Au\u00dfenministerin \u00d6sterreichs, Karin Kneissl, meint in einem Interview, dass sich die Europ\u00e4ische Union aktuell zunehmend zu einem Milit\u00e4rb\u00fcndnis entwickle. F\u00fcr ein neutrales Land sei dies ein gro\u00dfes Dilemma. \u00a0 Fast alle politischen Parteien in \u00d6sterreich, mit Ausnahme vielleicht der Sozialdemokraten, sind auf die eine oder andere Weise an einem NATO-Beitritt des Landes interessiert. [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-10-27T15:52:35+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/68ff67e6b480cc3d2639b44c.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Karin Kneissl: EU entwickelt sich zu einem Milit\u00e4rb\u00fcndnis\u00a0 \u00a0","datePublished":"2025-10-27T15:52:35+00:00","dateModified":"2025-10-27T15:52:35+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/"},"wordCount":377,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Karin-Kneissl-EU-entwickelt-sich-zu-einem-Militaerbuendnis.jpg","keywords":["einem","entwickelt","Karin","Kneissl","Milit\u00e4rb\u00fcndnis","sich"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/","url":"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/","name":"Karin Kneissl: EU entwickelt sich zu einem Milit\u00e4rb\u00fcndnis\u00a0 \u00a0 - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Karin-Kneissl-EU-entwickelt-sich-zu-einem-Militaerbuendnis.jpg","datePublished":"2025-10-27T15:52:35+00:00","dateModified":"2025-10-27T15:52:35+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Karin-Kneissl-EU-entwickelt-sich-zu-einem-Militaerbuendnis.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Karin-Kneissl-EU-entwickelt-sich-zu-einem-Militaerbuendnis.jpg","width":460,"height":259,"caption":"Karin Kneissl: EU entwickelt sich zu einem Milit\u00e4rb\u00fcndnis\u00a0 \u00a0"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/karin-kneissl-eu-entwickelt-sich-zu-einem-militaerbuendnis\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Karin Kneissl: EU entwickelt sich zu einem Milit\u00e4rb\u00fcndnis\u00a0 \u00a0"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/92916"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=92916"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/92916\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/92917"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=92916"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=92916"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=92916"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}