{"id":92388,"date":"2025-10-17T21:02:21","date_gmt":"2025-10-17T19:02:21","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/"},"modified":"2025-10-17T21:02:21","modified_gmt":"2025-10-17T19:02:21","slug":"szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/","title":{"rendered":"Szijj\u00e1rt\u00f3: Budapest garantiert Sicherheit f\u00fcr Trump-Putin-Gipfel"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/68f22fa048fbef26326cdc55.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Ungarn garantiert Putin volle Sicherheit f\u00fcr das Treffen mit Trump in Budapest. Au\u00dfenminister Szijj\u00e1rt\u00f3 betont: Die Pr\u00e4sidenten von Russland und den USA sollen in Ruhe verhandeln k\u00f6nnen. Budapest sei bereit, den Gipfel effektiv auszurichten.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Ungarn bereitet sich auf das Treffen der Pr\u00e4sidenten Russlands und der USA, Wladimir Putin und Donald Trump, in Budapest vor. Auf Nachfrage von Journalisten versicherte Ungarns Au\u00dfenminister P\u00e9ter Szijj\u00e1rt\u00f3, dass Putin w\u00e4hrend seines Besuchs nicht durch einen Haftbefehl des Internationalen Strafgerichtshofs (IStGH) bedroht sei. <em>TASS<\/em> zitiert ihn mit den Worten:<\/p>\n<p><em>&#8220;Wir werden Wladimir Putin hier empfangen und daf\u00fcr sorgen, dass er erfolgreiche Gespr\u00e4che f\u00fchrt und anschlie\u00dfend nach Hause zur\u00fcckkehrt.&#8221;<\/em><\/p>\n<p>Szijj\u00e1rt\u00f3 betonte, dass Ungarn alle Bedingungen schaffen werde, damit die Pr\u00e4sidenten in einer sicheren und ruhigen Umgebung verhandeln k\u00f6nnen. Zudem sei keine Konsultation mit Verb\u00fcndeten \u00fcber Putins Besuch oder den IStGH-Haftbefehl n\u00f6tig: &#8220;Ungarn ist ein souver\u00e4nes Land&#8221;, unterstrich er. In seinem Facebook-Profil erkl\u00e4rte Szijj\u00e1rt\u00f3 au\u00dferdem:<\/p>\n<p><em>&#8220;Ungarn als Insel des Friedens ist bereit, den Gipfel auszurichten. Wir werden alle Bedingungen schaffen, damit die Pr\u00e4sidenten effektiv verhandeln k\u00f6nnen und der Frieden nach Europa zur\u00fcckkehrt.&#8221;<\/em><\/p>\n<p>Trump\u00a0hatte das Treffen am 16. Oktober angek\u00fcndigt. Einen genauen Termin gibt es noch nicht. Putins\u00a0Berater Juri Uschakow erkl\u00e4rte, Moskau und Washington w\u00fcrden &#8220;ohne Verz\u00f6gerung&#8221; mit den Vorbereitungen beginnen. Daraufhin ordnete Ministerpr\u00e4sident Viktor Orb\u00e1n die Einrichtung eines Organisationskomitees f\u00fcr den Gipfel an.\u00a0<\/p>\n<p>Au\u00dferdem hat Szijj\u00e1rt\u00f3 bereits mit dem russischen Au\u00dfenminister Sergei Lawrow und dem stellvertretenden US-Au\u00dfenminister Christopher Landau \u00fcber den Gipfel gesprochen. Der Minister hob zugleich die Rolle Ungarns als Friedensvermittler hervor. Er schrieb\u00a0auf Facebook:<\/p>\n<p><em>&#8220;Ungarn unterst\u00fctzt seit Beginn des Krieges in der Ukraine konsequent die Sache des Friedens. Auf dem Schlachtfeld gibt es keine L\u00f6sung. Frieden kann nur durch Verhandlungen erreicht werden. Deshalb ist es eine gute Nachricht, dass Trump und Putin in st\u00e4ndigem Kontakt stehen \u2013 und noch besser, dass sie sich bald pers\u00f6nlich treffen.&#8221;<\/em><\/p>\n<p>Bereits zu Beginn des Ukraine-Krieges hatte Ungarn seine Vermittlungsdienste angeboten,\u00a0so Szijj\u00e1rt\u00f3.<\/p>\n<p><em>&#8220;Bereits drei Tage nach Ausbruch des Krieges haben wir unsere Bereitschaft erkl\u00e4rt, im Bedarfsfall einen Ort, Unterst\u00fctzung oder Vermittlungsdienste zur Beendigung des Krieges zur Verf\u00fcgung zu stellen.&#8221;<\/em><\/p>\n<p>Ungarn hat das R\u00f6mische Statut 1999 unterzeichnet und 2001 ratifiziert. Bereits 2023 erkl\u00e4rte das Land, dass Putin bei einem Besuch nicht festgenommen werde. Auch andere Staatsg\u00e4ste mit IStGH-Haftbefehlen, wie etwa Israels Premierminister Benjamin Netanjahu, konnten in den vergangenen Jahren Ungarn besuchen.<\/p>\n<p>Putin selbst reiste im September 2024 in die Mongolei und im Oktober 2025 nach Tadschikistan. In beiden L\u00e4ndern wurde das R\u00f6mische Statut ratifiziert, ohne dass der russische Pr\u00e4sident festgenommen wurde.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/259050-putin-und-trump-telefonieren\/\">Putin und Trump telefonieren<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6y8f8s\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/259114-szijjarto-budapest-empfaengt-putin-sicher-fuer-trump-gipfel\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ungarn garantiert Putin volle Sicherheit f\u00fcr das Treffen mit Trump in Budapest. Au\u00dfenminister Szijj\u00e1rt\u00f3 betont: Die Pr\u00e4sidenten von Russland und den USA sollen in Ruhe verhandeln k\u00f6nnen. Budapest sei bereit, den Gipfel effektiv auszurichten. Ungarn bereitet sich auf das Treffen der Pr\u00e4sidenten Russlands und der USA, Wladimir Putin und Donald Trump, in Budapest vor. Auf [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":92389,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1760728472"],"wp_automatic_camp":["217"],"e634f3ae7252c46a0799fd44a10e9f40":["Szijj\u00e1rt\u00f3: Budapest garantiert Sicherheit f\u00fcr Trump-Putin-Gipfel"],"original_link":["https:\/\/de.rt.com\/international\/259114-szijjarto-budapest-empfaengt-putin-sicher-fuer-trump-gipfel\/"],"_thumbnail_id":["92389"],"jnews_social_counter_last_update":["1778650315"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-10-17 21:15:35\";}"]},"categories":[19,23],"tags":[10836,221,31914,840,31849,62414],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Szijj\u00e1rt\u00f3: Budapest garantiert Sicherheit f\u00fcr Trump-Putin-Gipfel - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Szijj\u00e1rt\u00f3: Budapest garantiert Sicherheit f\u00fcr Trump-Putin-Gipfel\" \/>\n<meta property=\"og:description\" content=\"Ungarn garantiert Putin volle Sicherheit f\u00fcr das Treffen mit Trump in Budapest. Au\u00dfenminister Szijj\u00e1rt\u00f3 betont: Die Pr\u00e4sidenten von Russland und den USA sollen in Ruhe verhandeln k\u00f6nnen. Budapest sei bereit, den Gipfel effektiv auszurichten. Ungarn bereitet sich auf das Treffen der Pr\u00e4sidenten Russlands und der USA, Wladimir Putin und Donald Trump, in Budapest vor. Auf [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-17T19:02:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/68f22fa048fbef26326cdc55.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Szijj\u00e1rt\u00f3: Budapest garantiert Sicherheit f\u00fcr Trump-Putin-Gipfel\",\"datePublished\":\"2025-10-17T19:02:21+00:00\",\"dateModified\":\"2025-10-17T19:02:21+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/\"},\"wordCount\":477,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Szijjarto-Budapest-garantiert-Sicherheit-fuer-Trump-Putin-Gipfel.jpg\",\"keywords\":[\"Budapest\",\"f\u00fcr\",\"garantiert\",\"Sicherheit\",\"Szijj\u00e1rt\u00f3\",\"TrumpPutinGipfel\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/\",\"name\":\"Szijj\u00e1rt\u00f3: Budapest garantiert Sicherheit f\u00fcr Trump-Putin-Gipfel - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Szijjarto-Budapest-garantiert-Sicherheit-fuer-Trump-Putin-Gipfel.jpg\",\"datePublished\":\"2025-10-17T19:02:21+00:00\",\"dateModified\":\"2025-10-17T19:02:21+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Szijjarto-Budapest-garantiert-Sicherheit-fuer-Trump-Putin-Gipfel.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Szijjarto-Budapest-garantiert-Sicherheit-fuer-Trump-Putin-Gipfel.jpg\",\"width\":460,\"height\":259,\"caption\":\"Szijj\u00e1rt\u00f3: Budapest garantiert Sicherheit f\u00fcr Trump-Putin-Gipfel\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Szijj\u00e1rt\u00f3: Budapest garantiert Sicherheit f\u00fcr Trump-Putin-Gipfel\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Szijj\u00e1rt\u00f3: Budapest garantiert Sicherheit f\u00fcr Trump-Putin-Gipfel - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/","og_locale":"de_DE","og_type":"article","og_title":"Szijj\u00e1rt\u00f3: Budapest garantiert Sicherheit f\u00fcr Trump-Putin-Gipfel","og_description":"Ungarn garantiert Putin volle Sicherheit f\u00fcr das Treffen mit Trump in Budapest. Au\u00dfenminister Szijj\u00e1rt\u00f3 betont: Die Pr\u00e4sidenten von Russland und den USA sollen in Ruhe verhandeln k\u00f6nnen. Budapest sei bereit, den Gipfel effektiv auszurichten. Ungarn bereitet sich auf das Treffen der Pr\u00e4sidenten Russlands und der USA, Wladimir Putin und Donald Trump, in Budapest vor. Auf [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-10-17T19:02:21+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/68f22fa048fbef26326cdc55.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Szijj\u00e1rt\u00f3: Budapest garantiert Sicherheit f\u00fcr Trump-Putin-Gipfel","datePublished":"2025-10-17T19:02:21+00:00","dateModified":"2025-10-17T19:02:21+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/"},"wordCount":477,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Szijjarto-Budapest-garantiert-Sicherheit-fuer-Trump-Putin-Gipfel.jpg","keywords":["Budapest","f\u00fcr","garantiert","Sicherheit","Szijj\u00e1rt\u00f3","TrumpPutinGipfel"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/","url":"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/","name":"Szijj\u00e1rt\u00f3: Budapest garantiert Sicherheit f\u00fcr Trump-Putin-Gipfel - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Szijjarto-Budapest-garantiert-Sicherheit-fuer-Trump-Putin-Gipfel.jpg","datePublished":"2025-10-17T19:02:21+00:00","dateModified":"2025-10-17T19:02:21+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Szijjarto-Budapest-garantiert-Sicherheit-fuer-Trump-Putin-Gipfel.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Szijjarto-Budapest-garantiert-Sicherheit-fuer-Trump-Putin-Gipfel.jpg","width":460,"height":259,"caption":"Szijj\u00e1rt\u00f3: Budapest garantiert Sicherheit f\u00fcr Trump-Putin-Gipfel"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/szijjarto-budapest-garantiert-sicherheit-fuer-trump-putin-gipfel\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Szijj\u00e1rt\u00f3: Budapest garantiert Sicherheit f\u00fcr Trump-Putin-Gipfel"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/92388"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=92388"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/92388\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/92389"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=92388"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=92388"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=92388"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}