{"id":91533,"date":"2025-10-02T12:23:31","date_gmt":"2025-10-02T10:23:31","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/"},"modified":"2025-10-02T12:23:31","modified_gmt":"2025-10-02T10:23:31","slug":"popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/","title":{"rendered":"Pops\u00e4nger Pupo: &quot;Das italienische Volk sollte den Russen dankbar sein&quot;"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/68dd5863b480cc6e130606c9.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Der italienische Pops\u00e4nger Pupo kommt nach Moskau und best\u00e4tigt damit erneut seine Liebe zum russischen Publikum. Er sei wegen seiner Haltung st\u00e4ndig unter Druck gesetzt worden, aber er schicke die europ\u00e4ischen Diplomaten &#8220;zum Teufel&#8221;, so der Italiener in einem Interview.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Eine m\u00f6gliche Anordnung der italienischen Regierung, Italienern die Einreise nach Russland zu verbieten, k\u00f6nnte Pupo dazu veranlassen, die russische Staatsb\u00fcrgerschaft zu beantragen, r\u00e4umt er vor seinem bevorstehenden Besuch in Moskau ein. Der Autor des Hits &#8220;Gelato Al Cioccolato&#8221; ist bereit, bei &#8220;Intervision&#8221; aufzutreten, und wird &#8220;Kalinka&#8221; bei seinem Solokonzert am 4. Oktober in der Live Arena in Moskau singen. Dar\u00fcber berichtete er in einem Interview mit der Zeitung <em>I<\/em><em>sw<\/em><em>esti<\/em><em>j<\/em><em>a<\/em>.<\/p>\n<p>Es ist nicht das erste Mal, dass Pupo &#8220;gegen den Strom schwimmt&#8221;. Als sich nach dem Jahr 2022 alle westlichen Medien und Musikinstitutionen gegen Russland stellten, sprang Pupo zu dessen Verteidigung: Er nahm auf Russisch ein Lied zur Musik von Alexander Sazepin mit dem Titel &#8220;Es gibt nur einen Augenblick&#8221; auf. Das Video verbreitete sich viral im Internet. Und l\u00f6ste eine Welle des Hasses der europ\u00e4ischen Eliten aus, die versuchten, die Konzerte des S\u00e4ngers als &#8220;Strafe&#8221; abzusagen. So handelten beispielsweise die Beh\u00f6rden in Belgien und Litauen. &#8220;Die Absage dieses Konzerts, ebenso wie die Absage des Konzerts in Litauen und anderen Orten, ist ein inakzeptabler Ausdruck von Arroganz&#8221;, bemerkt Pupo. Und f\u00fcgt hinzu:<\/p>\n<blockquote>\n<p><em>&#8220;<\/em><em>Vor den Absagen wurde von mir verlangt, Erkl\u00e4rungen in \u00dcbereinstimmung mit ihren diplomatischen Anweisungen abzugeben. Ich nehme jedoch von niemandem Befehle entgegen. Ich habe sie einfach abblitzen lassen und erkl\u00e4rt, dass ich von nun an und bis zur Wiederherstellung eines gerechten Gleichgewichts nicht mehr in ihren L\u00e4ndern singen m\u00f6chte.<\/em><em>&#8220;<\/em><strong><br \/><\/strong><\/p>\n<\/blockquote>\n<p>Au\u00dferdem erinnert er daran, dass die Russen w\u00e4hrend der Pandemie als Erste Hilfe nach Italien geschickt haben \u2013 \u00c4rzte und Rettungskr\u00e4fte \u2013 und so Tausende Italiener vor Covid gerettet haben. &#8220;Das italienische Volk sollte den Russen daf\u00fcr dankbar sein&#8221;, sagt Pupo \u00fcberzeugt. Und erkl\u00e4rt gleich darauf, dass das Problem eigentlich nicht beim italienischen Volk liegt, sondern bei den Politikern. Er betont:<\/p>\n<blockquote>\n<p><em>&#8220;<\/em><em>Die Italiener sch\u00e4tzen und lieben die Russen, genauso wie die Russen die Italiener. Das eigentliche Problem ist die Regierung. Sie ist das gr\u00f6\u00dfte Hindernis [&#8230;] Die italienische Regierung ist mit meiner Haltung nicht einverstanden, aber es gibt Millionen Italiener, die genauso denken wie ich. Sie sind der Meinung, dass keine Form von Kunst, Kultur und sogar Sport Sanktionen oder Verboten unterliegen sollte. Ich habe das russische Volk schon immer geliebt. Schon seit den Zeiten, als ich mir noch nicht vorstellen konnte, dass diese wunderbaren Menschen mir eines Tages gro\u00dfz\u00fcgig meine Zuneigung erwidern w\u00fcrden.<\/em><em>&#8220;<\/em><\/p>\n<\/blockquote>\n<p>Sein Konzert in Russland, bei dem Pupo auch das ber\u00fchmte russische Lied &#8220;Kalinka&#8221; singen will, m\u00f6chte er der &#8220;Liebe zwischen Russland und Italien&#8221; widmen. &#8220;Damit alle Russen wissen, dass wir Italiener sie gern haben&#8221;, erkl\u00e4rt er, &#8220;werde ich w\u00e4hrend des Konzerts immer wieder sagen, dass die Italiener die Russen lieben.&#8221;<\/p>\n<p><strong>Mehr zum Thema \u2012<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/russland\/199259-fuer-frieden-in-schuetzengraeben-italienischer\/\">&#8220;F\u00fcr den Frieden in die Sch\u00fctzengr\u00e4ben!&#8221;: Italienischer S\u00e4nger Pupo kommt zum Konzert nach Moskau<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/257678-popsaenger-pupo-italienische-volk-sollte\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der italienische Pops\u00e4nger Pupo kommt nach Moskau und best\u00e4tigt damit erneut seine Liebe zum russischen Publikum. Er sei wegen seiner Haltung st\u00e4ndig unter Druck gesetzt worden, aber er schicke die europ\u00e4ischen Diplomaten &#8220;zum Teufel&#8221;, so der Italiener in einem Interview. Eine m\u00f6gliche Anordnung der italienischen Regierung, Italienern die Einreise nach Russland zu verbieten, k\u00f6nnte Pupo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":91534,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1759400856"],"wp_automatic_camp":["217"],"4195a6047f32ab08f0bd8b248f83e02f":["Pops\u00e4nger Pupo: &quot;Das italienische Volk sollte den Russen dankbar sein&quot;"],"original_link":["https:\/\/de.rt.com\/europa\/257678-popsaenger-pupo-italienische-volk-sollte\/"],"_thumbnail_id":["91534"],"jnews_social_counter_last_update":["1778627314"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-10-02 12:28:36\";}"]},"categories":[19,23],"tags":[11950,48,7224,26705,54408,4209,4405,18579,3590,8952],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pops\u00e4nger Pupo: &quot;Das italienische Volk sollte den Russen dankbar sein&quot; - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pops\u00e4nger Pupo: &quot;Das italienische Volk sollte den Russen dankbar sein&quot;\" \/>\n<meta property=\"og:description\" content=\"Der italienische Pops\u00e4nger Pupo kommt nach Moskau und best\u00e4tigt damit erneut seine Liebe zum russischen Publikum. Er sei wegen seiner Haltung st\u00e4ndig unter Druck gesetzt worden, aber er schicke die europ\u00e4ischen Diplomaten &#8220;zum Teufel&#8221;, so der Italiener in einem Interview. Eine m\u00f6gliche Anordnung der italienischen Regierung, Italienern die Einreise nach Russland zu verbieten, k\u00f6nnte Pupo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-02T10:23:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/68dd5863b480cc6e130606c9.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Pops\u00e4nger Pupo: &quot;Das italienische Volk sollte den Russen dankbar sein&quot;\",\"datePublished\":\"2025-10-02T10:23:31+00:00\",\"dateModified\":\"2025-10-02T10:23:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/\"},\"wordCount\":542,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Popsaenger-Pupo-quotDas-italienische-Volk-sollte-den-Russen-dankbar-seinquot.jpg\",\"keywords\":[\"dankbar\",\"den\",\"italienische\",\"Pops\u00e4nger\",\"Pupo\",\"quotDas\",\"Russen\",\"seinquot\",\"sollte\",\"volk\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/\",\"name\":\"Pops\u00e4nger Pupo: &quot;Das italienische Volk sollte den Russen dankbar sein&quot; - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Popsaenger-Pupo-quotDas-italienische-Volk-sollte-den-Russen-dankbar-seinquot.jpg\",\"datePublished\":\"2025-10-02T10:23:31+00:00\",\"dateModified\":\"2025-10-02T10:23:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Popsaenger-Pupo-quotDas-italienische-Volk-sollte-den-Russen-dankbar-seinquot.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Popsaenger-Pupo-quotDas-italienische-Volk-sollte-den-Russen-dankbar-seinquot.jpg\",\"width\":460,\"height\":259,\"caption\":\"Pops\u00e4nger Pupo: &quot;Das italienische Volk sollte den Russen dankbar sein&quot;\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pops\u00e4nger Pupo: &quot;Das italienische Volk sollte den Russen dankbar sein&quot;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Pops\u00e4nger Pupo: &quot;Das italienische Volk sollte den Russen dankbar sein&quot; - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/","og_locale":"de_DE","og_type":"article","og_title":"Pops\u00e4nger Pupo: &quot;Das italienische Volk sollte den Russen dankbar sein&quot;","og_description":"Der italienische Pops\u00e4nger Pupo kommt nach Moskau und best\u00e4tigt damit erneut seine Liebe zum russischen Publikum. Er sei wegen seiner Haltung st\u00e4ndig unter Druck gesetzt worden, aber er schicke die europ\u00e4ischen Diplomaten &#8220;zum Teufel&#8221;, so der Italiener in einem Interview. Eine m\u00f6gliche Anordnung der italienischen Regierung, Italienern die Einreise nach Russland zu verbieten, k\u00f6nnte Pupo [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-10-02T10:23:31+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/68dd5863b480cc6e130606c9.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Pops\u00e4nger Pupo: &quot;Das italienische Volk sollte den Russen dankbar sein&quot;","datePublished":"2025-10-02T10:23:31+00:00","dateModified":"2025-10-02T10:23:31+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/"},"wordCount":542,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Popsaenger-Pupo-quotDas-italienische-Volk-sollte-den-Russen-dankbar-seinquot.jpg","keywords":["dankbar","den","italienische","Pops\u00e4nger","Pupo","quotDas","Russen","seinquot","sollte","volk"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/","url":"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/","name":"Pops\u00e4nger Pupo: &quot;Das italienische Volk sollte den Russen dankbar sein&quot; - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Popsaenger-Pupo-quotDas-italienische-Volk-sollte-den-Russen-dankbar-seinquot.jpg","datePublished":"2025-10-02T10:23:31+00:00","dateModified":"2025-10-02T10:23:31+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Popsaenger-Pupo-quotDas-italienische-Volk-sollte-den-Russen-dankbar-seinquot.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Popsaenger-Pupo-quotDas-italienische-Volk-sollte-den-Russen-dankbar-seinquot.jpg","width":460,"height":259,"caption":"Pops\u00e4nger Pupo: &quot;Das italienische Volk sollte den Russen dankbar sein&quot;"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/popsaenger-pupo-das-italienische-volk-sollte-den-russen-dankbar-sein\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Pops\u00e4nger Pupo: &quot;Das italienische Volk sollte den Russen dankbar sein&quot;"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/91533"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=91533"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/91533\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/91534"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=91533"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=91533"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=91533"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}