{"id":91485,"date":"2025-10-01T17:26:28","date_gmt":"2025-10-01T15:26:28","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/"},"modified":"2025-10-01T17:26:28","modified_gmt":"2025-10-01T15:26:28","slug":"enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/","title":{"rendered":"Enormer Druck auf Hamas: Trump-Friedensplan &quot;ignoriert Interessen des Pal\u00e4stinener&quot;"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/68dcedfbb480cc42823a8b8d.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die Hamas soll Einw\u00e4nde gegen die Stationierung einer internationalen Stabilisierungstruppe (ISF) in Gaza haben. Katar, \u00c4gypten und die T\u00fcrkei dr\u00e4ngen die Hamas zugleich, positiv auf den Vorschlag von Trump zur Beendigung des Krieges im Gazastreifen zu reagieren.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Ein hochrangiger Hamas-Vertreter erkl\u00e4rte gegen\u00fcber der <em>BBC<\/em>, dass die Gruppe Donald Trumps Friedensplan f\u00fcr den Gazastreifen wahrscheinlich ablehnen werde, da dieser &#8220;den Interessen Israels dient&#8221; und &#8220;die Interessen des pal\u00e4stinensischen Volkes ignoriert&#8221;. Der Vertreter sagte, dass die Hamas wahrscheinlich nicht bereit sei, ihre Waffen abzugeben und zu \u00fcbergeben \u2013 eine zentrale Bedingung von Trumps Plan.<\/p>\n<p>Die Hamas soll auch Einw\u00e4nde gegen die Stationierung einer internationalen Stabilisierungstruppe (ISF) in Gaza haben, die sie als eine neue Form der Besatzung betrachtet.<\/p>\n<p>Der israelische Ministerpr\u00e4sident Benjamin Netanjahu akzeptierte Trumps Plan w\u00e4hrend der Gespr\u00e4che im Wei\u00dfen Haus am Montag. Die Hamas hat noch keine offizielle Stellungnahme abgegeben.<\/p>\n<p>Katar, \u00c4gypten und die T\u00fcrkei dr\u00e4ngen die Hamas zugleich, positiv auf den Vorschlag von Pr\u00e4sident Trump zur Beendigung des Krieges im Gazastreifen zu reagieren, wie zwei mit den Gespr\u00e4chen vertraute Quellen gegen\u00fcber <em>AXIOS<\/em> berichten.<\/p>\n<p>Die drei L\u00e4nder sind die Vermittler mit den engsten Beziehungen zur Hamas und tragen die Hauptverantwortung f\u00fcr die \u00dcbermittlung von Botschaften zwischen der Gruppe und Israel sowie den USA. Hochrangige Vertreter dieser L\u00e4nder haben sich in den vergangenen 24 Stunden zweimal mit F\u00fchrern der Hamas getroffen.<\/p>\n<p>Pr\u00e4sident Trump erkl\u00e4rte am Dienstag, er gebe der Hamas drei bis vier Tage Zeit, um auf seinen Vorschlag zu reagieren. Die Hamas werde &#8220;ein sehr trauriges Ende nehmen&#8221; und &#8220;in der H\u00f6lle zahlen&#8221;, wenn sie den Vorschlag nicht annimmt, sagte Trump in einer Rede vor Hunderten Gener\u00e4len und Marineoffizieren in Quantico, Virginia. US-amerikanische und israelische Beamte erwarten, dass die Hamas Trumps Vorschlag mit einigen Vorbehalten grunds\u00e4tzlich positiv aufnehmen wird.<\/p>\n<p>Der Plan gibt der Hamas zwar vieles, was sie wollte, wie die Freilassung von 2.000 pal\u00e4stinensischen Gefangenen und eine Aufstockung der humanit\u00e4ren Hilfe, enth\u00e4lt aber auch erhebliche Zugest\u00e4ndnisse \u2013 von denen einige auf Wunsch des israelischen Premierministers Benjamin Netanjahu hinzugef\u00fcgt wurden.<\/p>\n<p>Der Plan sieht einen schrittweisen R\u00fcckzug Israels und die vollst\u00e4ndige Entwaffnung der Hamas vor, was diese bisher abgelehnt hat.<\/p>\n<p>Einige der \u00c4nderungen hinsichtlich der Bedingungen und des Zeitplans f\u00fcr den R\u00fcckzug Israels aus dem Gazastreifen haben arabische Politiker ver\u00e4rgert und k\u00f6nnten f\u00fcr die Hamas schwer zu akzeptieren sein.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2013\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/257554-palaestinensische-autonomiebehoerde-spricht-sich-fuer\/\">Pal\u00e4stinensische Autonomiebeh\u00f6rde spricht sich f\u00fcr Trumps Gaza-Plan aus<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6xdxl4\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/der-nahe-osten\/257609-enormer-druck-auf-hamas-trump\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Hamas soll Einw\u00e4nde gegen die Stationierung einer internationalen Stabilisierungstruppe (ISF) in Gaza haben. Katar, \u00c4gypten und die T\u00fcrkei dr\u00e4ngen die Hamas zugleich, positiv auf den Vorschlag von Trump zur Beendigung des Krieges im Gazastreifen zu reagieren. Ein hochrangiger Hamas-Vertreter erkl\u00e4rte gegen\u00fcber der BBC, dass die Gruppe Donald Trumps Friedensplan f\u00fcr den Gazastreifen wahrscheinlich ablehnen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":91486,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1759332451"],"wp_automatic_camp":["217"],"4a382a53d9bc7ae181d1f2502866b695":["Enormer Druck auf Hamas: Trump-Friedensplan &quot;ignoriert Interessen des Pal\u00e4stinener&quot;"],"original_link":["https:\/\/de.rt.com\/der-nahe-osten\/257609-enormer-druck-auf-hamas-trump\/"],"_thumbnail_id":["91486"],"jnews_social_counter_last_update":["1778604604"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-10-01 17:28:30\";}"]},"categories":[19,23],"tags":[133,583,1610,68137,5832,28396,68139,68138,60866],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Enormer Druck auf Hamas: Trump-Friedensplan &quot;ignoriert Interessen des Pal\u00e4stinener&quot; - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Enormer Druck auf Hamas: Trump-Friedensplan &quot;ignoriert Interessen des Pal\u00e4stinener&quot;\" \/>\n<meta property=\"og:description\" content=\"Die Hamas soll Einw\u00e4nde gegen die Stationierung einer internationalen Stabilisierungstruppe (ISF) in Gaza haben. Katar, \u00c4gypten und die T\u00fcrkei dr\u00e4ngen die Hamas zugleich, positiv auf den Vorschlag von Trump zur Beendigung des Krieges im Gazastreifen zu reagieren. Ein hochrangiger Hamas-Vertreter erkl\u00e4rte gegen\u00fcber der BBC, dass die Gruppe Donald Trumps Friedensplan f\u00fcr den Gazastreifen wahrscheinlich ablehnen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-10-01T15:26:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/68dcedfbb480cc42823a8b8d.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Enormer Druck auf Hamas: Trump-Friedensplan &quot;ignoriert Interessen des Pal\u00e4stinener&quot;\",\"datePublished\":\"2025-10-01T15:26:28+00:00\",\"dateModified\":\"2025-10-01T15:26:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/\"},\"wordCount\":441,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Enormer-Druck-auf-Hamas-Trump-Friedensplan-quotignoriert-Interessen-des-Palaestinenerquot.jpg\",\"keywords\":[\"AUF\",\"des\",\"Druck\",\"Enormer\",\"Hamas\",\"Interessen\",\"Pal\u00e4stinenerquot\",\"quotignoriert\",\"TrumpFriedensplan\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/\",\"name\":\"Enormer Druck auf Hamas: Trump-Friedensplan &quot;ignoriert Interessen des Pal\u00e4stinener&quot; - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Enormer-Druck-auf-Hamas-Trump-Friedensplan-quotignoriert-Interessen-des-Palaestinenerquot.jpg\",\"datePublished\":\"2025-10-01T15:26:28+00:00\",\"dateModified\":\"2025-10-01T15:26:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Enormer-Druck-auf-Hamas-Trump-Friedensplan-quotignoriert-Interessen-des-Palaestinenerquot.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Enormer-Druck-auf-Hamas-Trump-Friedensplan-quotignoriert-Interessen-des-Palaestinenerquot.jpg\",\"width\":460,\"height\":259,\"caption\":\"Enormer Druck auf Hamas: Trump-Friedensplan &quot;ignoriert Interessen des Pal\u00e4stinener&quot;\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Enormer Druck auf Hamas: Trump-Friedensplan &quot;ignoriert Interessen des Pal\u00e4stinener&quot;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Enormer Druck auf Hamas: Trump-Friedensplan &quot;ignoriert Interessen des Pal\u00e4stinener&quot; - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/","og_locale":"de_DE","og_type":"article","og_title":"Enormer Druck auf Hamas: Trump-Friedensplan &quot;ignoriert Interessen des Pal\u00e4stinener&quot;","og_description":"Die Hamas soll Einw\u00e4nde gegen die Stationierung einer internationalen Stabilisierungstruppe (ISF) in Gaza haben. Katar, \u00c4gypten und die T\u00fcrkei dr\u00e4ngen die Hamas zugleich, positiv auf den Vorschlag von Trump zur Beendigung des Krieges im Gazastreifen zu reagieren. Ein hochrangiger Hamas-Vertreter erkl\u00e4rte gegen\u00fcber der BBC, dass die Gruppe Donald Trumps Friedensplan f\u00fcr den Gazastreifen wahrscheinlich ablehnen [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-10-01T15:26:28+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/68dcedfbb480cc42823a8b8d.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Enormer Druck auf Hamas: Trump-Friedensplan &quot;ignoriert Interessen des Pal\u00e4stinener&quot;","datePublished":"2025-10-01T15:26:28+00:00","dateModified":"2025-10-01T15:26:28+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/"},"wordCount":441,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Enormer-Druck-auf-Hamas-Trump-Friedensplan-quotignoriert-Interessen-des-Palaestinenerquot.jpg","keywords":["AUF","des","Druck","Enormer","Hamas","Interessen","Pal\u00e4stinenerquot","quotignoriert","TrumpFriedensplan"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/","url":"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/","name":"Enormer Druck auf Hamas: Trump-Friedensplan &quot;ignoriert Interessen des Pal\u00e4stinener&quot; - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Enormer-Druck-auf-Hamas-Trump-Friedensplan-quotignoriert-Interessen-des-Palaestinenerquot.jpg","datePublished":"2025-10-01T15:26:28+00:00","dateModified":"2025-10-01T15:26:28+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Enormer-Druck-auf-Hamas-Trump-Friedensplan-quotignoriert-Interessen-des-Palaestinenerquot.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/10\/Enormer-Druck-auf-Hamas-Trump-Friedensplan-quotignoriert-Interessen-des-Palaestinenerquot.jpg","width":460,"height":259,"caption":"Enormer Druck auf Hamas: Trump-Friedensplan &quot;ignoriert Interessen des Pal\u00e4stinener&quot;"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/enormer-druck-auf-hamas-trump-friedensplan-ignoriert-interessen-des-palaestinener\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Enormer Druck auf Hamas: Trump-Friedensplan &quot;ignoriert Interessen des Pal\u00e4stinener&quot;"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/91485"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=91485"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/91485\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/91486"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=91485"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=91485"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=91485"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}