{"id":91377,"date":"2025-09-29T18:16:10","date_gmt":"2025-09-29T16:16:10","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/"},"modified":"2025-09-29T18:16:10","modified_gmt":"2025-09-29T16:16:10","slug":"us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/","title":{"rendered":"US-Sondergesandter Kellogg: Kiew hat Erlaubnis f\u00fcr Angriffe in die Tiefe Russlands"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/68da6d4648fbef7a8d4b5a69.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Keith Kellog glaubt an einen milit\u00e4rischen Sieg der Ukraine im Krieg gegen Russland. In einem TV-Interview behauptete der US-Sondergesagte f\u00fcr die Ukraine und Russland nun, dass die Ukraine gr\u00fcnes Licht f\u00fcr den Einsatz von Langstreckenwaffe gegen Ziele tief in Russland bekommen habe.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>In einem Interview wurde der US-Sondergesandte f\u00fcr die Ukraine und Russland, Keith Kellogg, auf die rhetorische Kehrtwende von Donald Trump vergangene Woche angesprochen.<\/p>\n<p>Der US-Pr\u00e4sident hatte erkl\u00e4rt, dass die Ukraine mit der Unterst\u00fctzung europ\u00e4ischer L\u00e4nder in der Lage w\u00e4re, ihr gesamtes Territorium, einschlie\u00dflich der Krim, zur\u00fcckzuerobern. Zuvor hatte Trump stets erkl\u00e4rt, dass Moskau &#8220;die Karten in der Hand&#8221; habe und Kiew den Konflikt nicht milit\u00e4risch f\u00fcr sich entscheiden k\u00f6nne.\u00a0\u00a0<\/p>\n<p>Trump hatte zudem angedeutet, dass die Ukraine &#8220;weiter&#8221; gehen k\u00f6nnte, als sich auf die R\u00fcckeroberung verlorener Gebiete zu beschr\u00e4nken. Ob das bedeute, dass Trump Kiew gr\u00fcnes Licht f\u00fcr Angriffe tief in russischem Territorium gegeben hat, wollte die <em>Fox-News<\/em>-Moderatorin Monica Paige von Kellogg wissen.<\/p>\n<p>&#8220;Russland gewinnt diesen Krieg nicht&#8221;, antwortete Kellogg unter Berufung auf Informationen der Geheimdienste und des Pentagons. &#8220;W\u00fcrden sie [die Russen] gewinnen, w\u00e4ren sie in Kiew, sie w\u00e4ren in Odessa,\u00a0sie w\u00e4ren \u00fcber den Dnjepr&#8221;, f\u00fchrte der Sondergesandte weiter aus.<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\" data-media-max-width=\"560\">\n<p lang=\"en\" dir=\"ltr\">US envoy Keith Kellogg tells Fox News Trump greenlights Ukraine to strike deep inside Russia <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/u9cbq2jYS2\">pic.twitter.com\/u9cbq2jYS2<\/a><\/p>\n<p>\u2014 Jungle Journey (@JnglJourney) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/JnglJourney\/status\/1972547355313574200?ref_src=twsrc%5Etfw\">September 29, 2025<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Deshalb habe Kiew &#8220;die Gelegenheit&#8221;, Russland &#8220;viel aggressiver&#8221; &#8220;herauszufordern&#8221;, wenn es die entsprechenden Waffensysteme bekomme.\u00a0Kellogg betonte, dass die Ukraine nie nach der Entsendung von US-Truppen verlangt habe.\u00a0<\/p>\n<p>&#8220;Aber was sie [die Ukrainer] wollen, sind die Waffen sowie die F\u00e4higkeit und Autorisierung, diese einzusetzen. Wenn sie das tun,\u00a0k\u00f6nnen sie das Blatt wenden&#8221;, glaubt Kellog. Ob die Ukrainer denn die Autorisierung haben, wollte\u00a0Paige daraufhin wissen. &#8220;Es ist gemischt, manchmal erhalten sie\u00a0die Autorisierung, manchmal nicht&#8221;, antwortete Kellogg.\u00a0<\/p>\n<p>Der Sondergesandte best\u00e4tigte <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/257290-medienberichte-was-verlangt-wladimir-selenskij-von-donald-trump\/\">Medienberichte<\/a>, dass der ukrainische Pr\u00e4sident Wladimir Selenskij am Rande\u00a0der UN-Generalversammlung in New York letzte Woche Donald Trump ausdr\u00fccklich um die Lieferung von\u00a0Tomahawk-Marschflugk\u00f6rpern gebeten habe.\u00a0Die Raketen haben eine Reichweite von bis zu 2.500 Kilometern und k\u00f6nnen mit Atomsprengk\u00f6pfen best\u00fcckt werden. Die Entscheidung sei diesbez\u00fcglich aber noch nicht gefallen, so Kellogg.\u00a0<\/p>\n<p>Als Paige nachhakte, ob Trump die Erlaubnis erteilt habe, &#8220;dass die Ukraine Langstreckenangriffe auf Russland durchf\u00fchren&#8221; kann, sagte Kellog:<\/p>\n<blockquote>\n<p><em>&#8220;Wenn man liest, was er gesagt hat und was ebenso Vizepr\u00e4sident Vance und Au\u00dfenminister Rubio gesagt haben, lautet die Antwort: &#8216;Ja, nutzt eure F\u00e4higkeiten und schlagt tief zu. Es gibt keine\u00a0Schongebiete&#8217;.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Der Einsatz weitreichender US-Waffensysteme wie ATACAMS oder wom\u00f6glich Tomahak-Raketen durch die Ukraine erfordert\u00a0Daten US-amerikanischer Satelliten sowie die Anleitung durch US-Spezialisten. De facto w\u00fcrde es sich also um US-Angriffe tief in Russland handeln, weshalb die Trump-Regierung aus Furcht vor einer Eskalation bislang davon abgesehen hatte, Kiew gr\u00fcnes Licht f\u00fcr den Einsatz gegen Ziele tief in Russland zu geben.\u00a0<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0<strong>&#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/257039-nach-trumps-neuer-kehrtwende-europaeer-fuerchten-in-ukraine-krise-im-stich-gelassen-zu-werden\/\">Nach Trumps neuer Kehrtwende: Europ\u00e4er f\u00fcrchten, in der Ukraine-Krise im Stich gelassen zu werden<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6xe33a\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/257417-us-sondergesandter-kellogg-kiew-hat\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Keith Kellog glaubt an einen milit\u00e4rischen Sieg der Ukraine im Krieg gegen Russland. In einem TV-Interview behauptete der US-Sondergesagte f\u00fcr die Ukraine und Russland nun, dass die Ukraine gr\u00fcnes Licht f\u00fcr den Einsatz von Langstreckenwaffe gegen Ziele tief in Russland bekommen habe. In einem Interview wurde der US-Sondergesandte f\u00fcr die Ukraine und Russland, Keith Kellogg, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":91378,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1759162873"],"wp_automatic_camp":["217"],"0c2c2c26ae7eddd4dba0ccbef8d0439c":["US-Sondergesandter Kellogg: Kiew hat Erlaubnis f\u00fcr Angriffe in die Tiefe Russlands"],"original_link":["https:\/\/de.rt.com\/international\/257417-us-sondergesandter-kellogg-kiew-hat\/"],"_thumbnail_id":["91378"],"jnews_social_counter_last_update":["1784082357"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-09-29 18:22:17\";}"]},"categories":[19,23],"tags":[4404,45,43232,221,423,41543,1025,142,21524,64209],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>US-Sondergesandter Kellogg: Kiew hat Erlaubnis f\u00fcr Angriffe in die Tiefe Russlands - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"US-Sondergesandter Kellogg: Kiew hat Erlaubnis f\u00fcr Angriffe in die Tiefe Russlands\" \/>\n<meta property=\"og:description\" content=\"Keith Kellog glaubt an einen milit\u00e4rischen Sieg der Ukraine im Krieg gegen Russland. In einem TV-Interview behauptete der US-Sondergesagte f\u00fcr die Ukraine und Russland nun, dass die Ukraine gr\u00fcnes Licht f\u00fcr den Einsatz von Langstreckenwaffe gegen Ziele tief in Russland bekommen habe. In einem Interview wurde der US-Sondergesandte f\u00fcr die Ukraine und Russland, Keith Kellogg, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-29T16:16:10+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/68da6d4648fbef7a8d4b5a69.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"US-Sondergesandter Kellogg: Kiew hat Erlaubnis f\u00fcr Angriffe in die Tiefe Russlands\",\"datePublished\":\"2025-09-29T16:16:10+00:00\",\"dateModified\":\"2025-09-29T16:16:10+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/\"},\"wordCount\":539,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/US-Sondergesandter-Kellogg-Kiew-hat-Erlaubnis-fuer-Angriffe-in-die-Tiefe.jpg\",\"keywords\":[\"Angriffe\",\"die\",\"Erlaubnis\",\"f\u00fcr\",\"hat\",\"Kellogg\",\"Kiew\",\"Russlands\",\"tiefe\",\"USSondergesandter\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/\",\"name\":\"US-Sondergesandter Kellogg: Kiew hat Erlaubnis f\u00fcr Angriffe in die Tiefe Russlands - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/US-Sondergesandter-Kellogg-Kiew-hat-Erlaubnis-fuer-Angriffe-in-die-Tiefe.jpg\",\"datePublished\":\"2025-09-29T16:16:10+00:00\",\"dateModified\":\"2025-09-29T16:16:10+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/US-Sondergesandter-Kellogg-Kiew-hat-Erlaubnis-fuer-Angriffe-in-die-Tiefe.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/US-Sondergesandter-Kellogg-Kiew-hat-Erlaubnis-fuer-Angriffe-in-die-Tiefe.jpg\",\"width\":460,\"height\":259,\"caption\":\"US-Sondergesandter Kellogg: Kiew hat Erlaubnis f\u00fcr Angriffe in die Tiefe Russlands\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"US-Sondergesandter Kellogg: Kiew hat Erlaubnis f\u00fcr Angriffe in die Tiefe Russlands\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"US-Sondergesandter Kellogg: Kiew hat Erlaubnis f\u00fcr Angriffe in die Tiefe Russlands - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/","og_locale":"de_DE","og_type":"article","og_title":"US-Sondergesandter Kellogg: Kiew hat Erlaubnis f\u00fcr Angriffe in die Tiefe Russlands","og_description":"Keith Kellog glaubt an einen milit\u00e4rischen Sieg der Ukraine im Krieg gegen Russland. In einem TV-Interview behauptete der US-Sondergesagte f\u00fcr die Ukraine und Russland nun, dass die Ukraine gr\u00fcnes Licht f\u00fcr den Einsatz von Langstreckenwaffe gegen Ziele tief in Russland bekommen habe. In einem Interview wurde der US-Sondergesandte f\u00fcr die Ukraine und Russland, Keith Kellogg, [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-09-29T16:16:10+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/68da6d4648fbef7a8d4b5a69.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"US-Sondergesandter Kellogg: Kiew hat Erlaubnis f\u00fcr Angriffe in die Tiefe Russlands","datePublished":"2025-09-29T16:16:10+00:00","dateModified":"2025-09-29T16:16:10+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/"},"wordCount":539,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/US-Sondergesandter-Kellogg-Kiew-hat-Erlaubnis-fuer-Angriffe-in-die-Tiefe.jpg","keywords":["Angriffe","die","Erlaubnis","f\u00fcr","hat","Kellogg","Kiew","Russlands","tiefe","USSondergesandter"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/","url":"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/","name":"US-Sondergesandter Kellogg: Kiew hat Erlaubnis f\u00fcr Angriffe in die Tiefe Russlands - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/US-Sondergesandter-Kellogg-Kiew-hat-Erlaubnis-fuer-Angriffe-in-die-Tiefe.jpg","datePublished":"2025-09-29T16:16:10+00:00","dateModified":"2025-09-29T16:16:10+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/US-Sondergesandter-Kellogg-Kiew-hat-Erlaubnis-fuer-Angriffe-in-die-Tiefe.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/US-Sondergesandter-Kellogg-Kiew-hat-Erlaubnis-fuer-Angriffe-in-die-Tiefe.jpg","width":460,"height":259,"caption":"US-Sondergesandter Kellogg: Kiew hat Erlaubnis f\u00fcr Angriffe in die Tiefe Russlands"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/us-sondergesandter-kellogg-kiew-hat-erlaubnis-fuer-angriffe-in-die-tiefe-russlands\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"US-Sondergesandter Kellogg: Kiew hat Erlaubnis f\u00fcr Angriffe in die Tiefe Russlands"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/91377"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=91377"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/91377\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/91378"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=91377"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=91377"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=91377"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}