{"id":9130,"date":"2022-05-29T02:59:00","date_gmt":"2022-05-29T00:59:00","guid":{"rendered":"http:\/\/just-now.news\/de\/usa\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\/"},"modified":"2022-05-29T02:59:00","modified_gmt":"2022-05-29T00:59:00","slug":"mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/usa\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\/","title":{"rendered":"Mann bei Attacke am hellichten Tag in New York City mehrfach erstochen (VIDEO)"},"content":{"rendered":"<div class=\"entry-content\">\n<p><\/p>\n<p>W\u00e4hrenddessen im demokratischen H\u00f6llenloch von New York City \u2026<\/p>\n<p>Ein Mann wurde am Donnerstag am helllichten Tag an der Ecke 3rd Avenue und East 63rd Street mehrfach erstochen.<\/p>\n<div id=\"IC1-ad\" class=\"sponsor IC1\">\n<p class=\"ad-notice flipboard-remove\" fl:fl-noexcerpt=\"true\">Werbung \u2013 die Geschichte geht unten weiter<\/p>\n<div id=\"IC1\">\n<script>\n\t\t\t\t\tif( FFADS.units.IC1 && FFADS.units.IC1.ad_type == 'custom' && FFADS.units.IC1.custom_ads && ! getCookie( 'ff_subbed' ) ) {\n\t\t\t\t\t\tdocument.getElementById( 'IC1' ).innerHTML = FFADS.units.IC1.custom_ads[0].code;\n\t\t\t\t\t\tif( ! FFADS.units.IC1.lazy_load ) eval( FFADS.units.IC1.custom_ads[0].rendering_script );\n\t\t\t\t\t}\n\t\t\t\t\telse if( FFADS.units.IC1 && ! getCookie( 'ff_subbed' ) ) {\n\t\t\t\t\t\tif( 'IC' != 'SB' && 'IC' != 'SA' && FFADS.use_fixed_containers ) {\n\t\t\t\t\t\t\tlet max_wh = firefly_size_list_to_max_wh( FFADS.units.IC1.sizes );\n\t\t\t\t\t\t\tlet el = document.querySelector( '#IC1' );\n\t\t\t\t\t\t\tif( 'IC' != 'SA' && FFADS.slide_pixels ) {\n\t\t\t\t\t\t\t\tmax_wh[1] += parseInt( FFADS.slide_pixels );\n\t\t\t\t\t\t\t\tel.classList.add( 'sliding' );\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\tel.style.width = max_wh[0] + 'px';\n\t\t\t\t\t\t\tel.style.height = max_wh[1] + 'px';\n\t\t\t\t\t\t\tel.classList.add( 'fixed-size' );\n\t\t\t\t\t\t}\n\t\t\t\t\t\tgoogletag.cmd.push( function() {\n\t\t\t\t\t\t\tFFADS.debug( 'googletag.displaying IC1' );\n\t\t\t\t\t\t\tgoogletag.display( 'IC1' );\n\t\t\t\t\t\t} );\n\t\t\t\t\t}\n\t\t\t\t\telse {\n\t\t\t\t\t\tdocument.querySelector( '#IC1-ad' ).style.display = 'none';}\n\t\t\t\t<\/script><\/div>\n<\/div>\n<p>Der Angreifer stach mehrmals auf einen 29-j\u00e4hrigen Mann ein, als Fu\u00dfg\u00e4nger die Stra\u00dfe \u00fcberquerten und Autos vorbeifuhren.<\/p>\n<p>VIDEO:<\/p>\n<p><script>\n\t\t\t\t\tif( ! getCookie( 'ff_subbed' ) ) if( typeof FFADS.replace_ict != 'undefined' ) if( FFADS.replace_ict ) eval( FFADS.replace_ict );\n\t\t\t\t<\/script><\/p>\n<blockquote class=\"twitter-tweet\">\n<p lang=\"en\" dir=\"ltr\">WEGEN EINES \u00dcBERFALLS GESUCHT: Am Donnerstag, 26. Mai 2022 um ca.  13:50 Uhr, auf der C\/O 3 Ave. und East 63 St., <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/NYPD19Pct\">@nypd19pct<\/a> Ein Unbekannter stach mehrmals auf einen 29-j\u00e4hrigen Mann ein und verursachte schwere k\u00f6rperliche Verletzungen.  l Rufen Sie uns unter 800-577-TIPS an <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/RTSfw91OfT\">pic.twitter.com\/RTSfw91OfT<\/a><\/p>\n<p>\u2013 NYPD Verbrechensstopper (@NYPDTips) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/NYPDTips\/status\/1530482423586336768\">28. Mai 2022<\/a><\/p>\n<\/blockquote>\n<p> <script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><\/p>\n<div id=\"IC2-ad\" class=\"sponsor IC2\">\n<p class=\"ad-notice flipboard-remove\" fl:fl-noexcerpt=\"true\">Werbung \u2013 die Geschichte geht unten weiter<\/p>\n<div id=\"IC2\">\n<script>\n\t\t\t\t\tif( FFADS.units.IC2 && FFADS.units.IC2.ad_type == 'custom' && FFADS.units.IC2.custom_ads && ! getCookie( 'ff_subbed' ) ) {\n\t\t\t\t\t\tdocument.getElementById( 'IC2' ).innerHTML = FFADS.units.IC2.custom_ads[0].code;\n\t\t\t\t\t\tif( ! FFADS.units.IC2.lazy_load ) eval( FFADS.units.IC2.custom_ads[0].rendering_script );\n\t\t\t\t\t}\n\t\t\t\t\telse if( FFADS.units.IC2 && ! getCookie( 'ff_subbed' ) ) {\n\t\t\t\t\t\tif( 'IC' != 'SB' && 'IC' != 'SA' && FFADS.use_fixed_containers ) {\n\t\t\t\t\t\t\tlet max_wh = firefly_size_list_to_max_wh( FFADS.units.IC2.sizes );\n\t\t\t\t\t\t\tlet el = document.querySelector( '#IC2' );\n\t\t\t\t\t\t\tif( 'IC' != 'SA' && FFADS.slide_pixels ) {\n\t\t\t\t\t\t\t\tmax_wh[1] += parseInt( FFADS.slide_pixels );\n\t\t\t\t\t\t\t\tel.classList.add( 'sliding' );\n\t\t\t\t\t\t\t}\n\t\t\t\t\t\t\tel.style.width = max_wh[0] + 'px';\n\t\t\t\t\t\t\tel.style.height = max_wh[1] + 'px';\n\t\t\t\t\t\t\tel.classList.add( 'fixed-size' );\n\t\t\t\t\t\t}\n\t\t\t\t\t\tgoogletag.cmd.push( function() {\n\t\t\t\t\t\t\tFFADS.debug( 'googletag.displaying IC2' );\n\t\t\t\t\t\t\tgoogletag.display( 'IC2' );\n\t\t\t\t\t\t} );\n\t\t\t\t\t}\n\t\t\t\t\telse {\n\t\t\t\t\t\tdocument.querySelector( '#IC2-ad' ).style.display = 'none';}\n\t\t\t\t<\/script><\/div>\n<\/div>\n<p>Die Zahl der schweren Verbrechen in New York City stieg im Jahr 2022 aufgrund der demokratischen Politik an. <\/p>\n<p>\u201eDie New Yorker Polizeibeh\u00f6rde verzeichnete Anstiege in allen wichtigen Kriminalit\u00e4tskategorien.  Die Stadt verzeichnete in den ersten Monaten des Jahres 2022 im Vergleich zum Vorjahreszeitraum einen Anstieg der Gesamtkriminalit\u00e4t um 41\u00a0%, darunter einen Anstieg der Raub\u00fcberf\u00e4lle um fast 54\u00a0%, einen Anstieg der Gro\u00dfdiebst\u00e4hle um 56\u00a0% und einen Anstieg der Vergewaltigungsmeldungen um 22\u00a0% , die Daten zeigen.\u201c  CNN berichtete.<\/p>\n<p class=\"article-ask\"><span class=\"ask\"><script>\n  if( getParameterByName( \"utm_source\" ) == \"testpage\" ) {\n    !function(e,t,a,n,g){e[n]=e[n]||[],e[n].push({\"gtm.start\":(new Date).getTime(),event:\"gtm.js\"});var m=t.getElementsByTagName(a)[0],r=t.createElement(a);r.async=!0,r.src=\"https:\/\/www.googletagmanager.com\/gtm.js?id=GTM-PL4PD49\",m.parentNode.insertBefore(r,m)}(window.parent,window.parent.document,\"script\",\"dataLayer\");\n    var iframe=window.parent.document.createElement(\"iframe\");iframe.src=\"https:\/\/www.googletagmanager.com\/ns.html?id=GTM-PL4PD49\";iframe.height=\"0\";iframe.width=\"0\";iframe.style=\"display:none;visibility:hidden\";window.parent.document.body.appendChild(iframe);\n    window.parent[\"$$mm-analytics\"] = window.parent[\"$$mm-analytics\"] || {};if (typeof window.parent[\"$$mm-analytics\"].firstEmbed === \"undefined\") {window.parent[\"$$mm-analytics\"].firstEmbed = Date.now();}\n    let as1 = document.createElement( \"script\" );\n    as1.src = \"https:\/\/bucket1.mm-syringe.com\/prod\/configs\/ee2300c8-43d2-7f0b-dac0-40aaf31c9d3d.js\";\n    document.body.appendChild( as1 );\n    let as2 = document.createElement( \"script\" );\n    as2.src = \"https:\/\/bucket1.mm-syringe.com\/prod\/injector\/injector.1.5.3.js\";\n    document.body.appendChild( as2 );\n  }\n<\/script><\/p>\n<div class=\"apester-media\" data-token=\"5f10a39f94902bc81d3d59a7\" data-context=\"true\" data-tags=\"\" data-fallback=\"true\" height=\"350\"><\/div>\n<p><script id=\"apester_script\" src=\"https:\/\/static.apester.com\/js\/sdk\/latest\/apester-sdk.js\" async><\/script><script async src=\"https:\/\/www.googletagmanager.com\/gtag\/js?id=G-EFE91RJVSQ\"><\/script><script>\n  window.dataLayer = window.dataLayer || [];\n  function gtag(){dataLayer.push(arguments);}\n  gtag(\\'js\\', new Date());\n  gtag(\\'config\\', \\'G-EFE91RJVSQ\\');\n<\/script><\/span><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/www.thegatewaypundit.com\/2022\/05\/man-stabbed-multiple-times-in-broad-daylight-attack-in-new-york-city-video\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>W\u00e4hrenddessen im demokratischen H\u00f6llenloch von New York City \u2026 Ein Mann wurde am Donnerstag am helllichten Tag an der Ecke 3rd Avenue und East 63rd Street mehrfach erstochen. Werbung \u2013 die Geschichte geht unten weiter Der Angreifer stach mehrmals auf einen 29-j\u00e4hrigen Mann ein, als Fu\u00dfg\u00e4nger die Stra\u00dfe \u00fcberquerten und Autos vorbeifuhren. VIDEO: WEGEN EINES [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":9131,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["1161"],"edfe264629471a951d7e119265562781":["Mann bei Attacke am hellichten Tag in New York City mehrfach erstochen (VIDEO)\n"],"original_link":["https:\/\/www.thegatewaypundit.com\/2022\/05\/man-stabbed-multiple-times-in-broad-daylight-attack-in-new-york-city-video\/"],"_thumbnail_id":["9131"],"wp_automatic_remove_first_image":["yes"],"jnews_social_counter_last_update":["1788324144"]},"categories":[25],"tags":[22235,363,7685,11824,22236,8042,22237,7552,173,6849],"class_list":["post-9130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-usa","tag-attacke","tag-bei","tag-city","tag-erstochen","tag-hellichten","tag-mann","tag-mehrfach","tag-tag","tag-video","tag-york"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Mann bei Attacke am hellichten Tag in New York City mehrfach erstochen (VIDEO) - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/usa\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mann bei Attacke am hellichten Tag in New York City mehrfach erstochen (VIDEO)\" \/>\n<meta property=\"og:description\" content=\"W\u00e4hrenddessen im demokratischen H\u00f6llenloch von New York City \u2026 Ein Mann wurde am Donnerstag am helllichten Tag an der Ecke 3rd Avenue und East 63rd Street mehrfach erstochen. Werbung \u2013 die Geschichte geht unten weiter Der Angreifer stach mehrmals auf einen 29-j\u00e4hrigen Mann ein, als Fu\u00dfg\u00e4nger die Stra\u00dfe \u00fcberquerten und Autos vorbeifuhren. VIDEO: WEGEN EINES [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/usa\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-29T00:59:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/1653786487_Mann-bei-Attacke-am-hellichten-Tag-in-New-York-City.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1169\" \/>\n\t<meta property=\"og:image:height\" content=\"607\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"greatreset\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"greatreset\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/usa\\\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/usa\\\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\\\/\"},\"author\":{\"name\":\"greatreset\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/8afb4cd92b68572db7902c13a349ffcb\"},\"headline\":\"Mann bei Attacke am hellichten Tag in New York City mehrfach erstochen (VIDEO)\",\"datePublished\":\"2022-05-29T00:59:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/usa\\\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\\\/\"},\"wordCount\":207,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/usa\\\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/05\\\/1653786487_Mann-bei-Attacke-am-hellichten-Tag-in-New-York-City.jpg\",\"keywords\":[\"Attacke\",\"bei\",\"City\",\"erstochen\",\"hellichten\",\"Mann\",\"mehrfach\",\"Tag\",\"Video\",\"York\"],\"articleSection\":[\"USA\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/usa\\\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/usa\\\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/usa\\\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\\\/\",\"name\":\"Mann bei Attacke am hellichten Tag in New York City mehrfach erstochen (VIDEO) - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/usa\\\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/usa\\\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/05\\\/1653786487_Mann-bei-Attacke-am-hellichten-Tag-in-New-York-City.jpg\",\"datePublished\":\"2022-05-29T00:59:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/usa\\\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/usa\\\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/usa\\\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/05\\\/1653786487_Mann-bei-Attacke-am-hellichten-Tag-in-New-York-City.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/05\\\/1653786487_Mann-bei-Attacke-am-hellichten-Tag-in-New-York-City.jpg\",\"width\":1169,\"height\":607},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/usa\\\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mann bei Attacke am hellichten Tag in New York City mehrfach erstochen (VIDEO)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/8afb4cd92b68572db7902c13a349ffcb\",\"name\":\"greatreset\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a3af7ea9778d56451f106b163ecab7b53df87f335765bacd9f6feae52217d2ff?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a3af7ea9778d56451f106b163ecab7b53df87f335765bacd9f6feae52217d2ff?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/a3af7ea9778d56451f106b163ecab7b53df87f335765bacd9f6feae52217d2ff?s=96&d=mm&r=g\",\"caption\":\"greatreset\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/greatreset\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Mann bei Attacke am hellichten Tag in New York City mehrfach erstochen (VIDEO) - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/usa\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\/","og_locale":"de_DE","og_type":"article","og_title":"Mann bei Attacke am hellichten Tag in New York City mehrfach erstochen (VIDEO)","og_description":"W\u00e4hrenddessen im demokratischen H\u00f6llenloch von New York City \u2026 Ein Mann wurde am Donnerstag am helllichten Tag an der Ecke 3rd Avenue und East 63rd Street mehrfach erstochen. Werbung \u2013 die Geschichte geht unten weiter Der Angreifer stach mehrmals auf einen 29-j\u00e4hrigen Mann ein, als Fu\u00dfg\u00e4nger die Stra\u00dfe \u00fcberquerten und Autos vorbeifuhren. VIDEO: WEGEN EINES [&hellip;]","og_url":"https:\/\/now-news.de\/de\/usa\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-05-29T00:59:00+00:00","og_image":[{"width":1169,"height":607,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/1653786487_Mann-bei-Attacke-am-hellichten-Tag-in-New-York-City.jpg","type":"image\/jpeg"}],"author":"greatreset","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"greatreset","Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/usa\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/usa\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\/"},"author":{"name":"greatreset","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/8afb4cd92b68572db7902c13a349ffcb"},"headline":"Mann bei Attacke am hellichten Tag in New York City mehrfach erstochen (VIDEO)","datePublished":"2022-05-29T00:59:00+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/usa\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\/"},"wordCount":207,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/usa\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/1653786487_Mann-bei-Attacke-am-hellichten-Tag-in-New-York-City.jpg","keywords":["Attacke","bei","City","erstochen","hellichten","Mann","mehrfach","Tag","Video","York"],"articleSection":["USA"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/usa\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/usa\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\/","url":"https:\/\/now-news.de\/de\/usa\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\/","name":"Mann bei Attacke am hellichten Tag in New York City mehrfach erstochen (VIDEO) - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/usa\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/usa\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/1653786487_Mann-bei-Attacke-am-hellichten-Tag-in-New-York-City.jpg","datePublished":"2022-05-29T00:59:00+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/usa\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/usa\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/usa\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/1653786487_Mann-bei-Attacke-am-hellichten-Tag-in-New-York-City.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/1653786487_Mann-bei-Attacke-am-hellichten-Tag-in-New-York-City.jpg","width":1169,"height":607},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/usa\/mann-bei-attacke-am-hellichten-tag-in-new-york-city-mehrfach-erstochen-video\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Mann bei Attacke am hellichten Tag in New York City mehrfach erstochen (VIDEO)"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/8afb4cd92b68572db7902c13a349ffcb","name":"greatreset","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/a3af7ea9778d56451f106b163ecab7b53df87f335765bacd9f6feae52217d2ff?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/a3af7ea9778d56451f106b163ecab7b53df87f335765bacd9f6feae52217d2ff?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a3af7ea9778d56451f106b163ecab7b53df87f335765bacd9f6feae52217d2ff?s=96&d=mm&r=g","caption":"greatreset"},"url":"https:\/\/now-news.de\/de\/author\/greatreset\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/9130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=9130"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/9130\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/9131"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=9130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=9130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=9130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}