{"id":90630,"date":"2025-09-16T15:30:01","date_gmt":"2025-09-16T13:30:01","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\/"},"modified":"2025-09-16T15:30:01","modified_gmt":"2025-09-16T13:30:01","slug":"musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\/","title":{"rendered":"Musikalischer Br\u00fcckenschlag: Am Times Square l\u00e4uft Werbung f\u00fcr den russischen Intervision-Wettbewerb"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/68c9340bb480cc7d6868aef7.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Der Broadway steht in den Farben der russischen Nationalfahne. New York wirbt f\u00fcr das Pendant zum Eurovision Song Contest. Trotz der russophoben Propaganda kritisieren die B\u00fcrger das nicht. Mehr noch: Der US-Vertreter steht bald in Moskau auf der B\u00fchne.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Am Times Square in New York l\u00e4uft auf den riesigen Bildschirmen Werbung f\u00fcr Intervision, das russische Pendant zum Eurovision Song Contest. Mit dabei sind Bilder vom Kreml und Aufnahmen der wehenden russischen Trikolore. So was hat der Big Apple in den vergangenen drei Jahren wohl nicht gesehen. Das Auftauchen der Intervision-Werbung vor der Kulisse Moskauer Sehensw\u00fcrdigkeiten kam f\u00fcr die US-B\u00fcrger \u00fcberraschend, wie russische Medien berichten. Die Intervision-Spots werden nun f\u00fcnf Tage lang zu sehen sein. Korrespondenten der Zeitung<em> I<\/em><em>sw<\/em><em>esti<\/em><em>j<\/em><em>a<\/em>, die vor Ort waren, schreiben:<\/p>\n<blockquote>\n<p><em>&#8220;Der Morgen in New York ist sonnig, kein W\u00f6lkchen am Himmel. <\/em><em>Menschen <\/em><em>eilen zur Arbeit oder zur Schule, andere schlendern gem\u00e4chlich durch die Innenstadt. Die Werbetafeln mit ihren schnell wechselnden Werbespots finden wenig Beachtung. Bis pl\u00f6tzlich der Moskauer Kreml auf der Fassade eines Hochhauses erscheint. Das kann man kaum ignorieren! Die interaktive Werbetafel mit den Ma\u00dfen 17 x 10 m befindet sich auf dem Broadway zwischen der 46. und 47. Stra\u00dfe.<\/em><\/p>\n<p><em>Ein zweiter Bildschirm steht in der N\u00e4he zwischen der 43. und 44. Stra\u00dfe. Er ist mit 16 x 8 m etwas kleiner. Daf\u00fcr ist sein Standort symboltr\u00e4chtig: das Theaterviertel. In der Nachbarschaft befinden sich die Redaktion der Zeitung The New York Times, das Lyceum Theater, in dem das ber\u00fchmte Musical Mamma Mia aufgef\u00fchrt wird, und die st\u00e4dtische Oase New Yorks, der Bryant Park.<\/em><em>&#8220;<\/em><\/p>\n<\/blockquote>\n<p>Die Zeitung <em>I<\/em><em>sw<\/em><em>esti<\/em><em>j<\/em><em>a<\/em> sprach mit Einwohnern New Yorks und fragte sie, wie sie eine solche Werbung wahrnehmen. Gerade im Hinblick auf die geopolitische Lage der letzten vier Jahre ist das sicherlich von Bedeutung. Doch wie die russischen Journalisten feststellen mussten, hat die russophobe Propaganda keinerlei Einfluss auf die Stimmung der New Yorker.<\/p>\n<p>&#8220;Das Musikvideo ist sehr cool&#8221;, sagten die Menschen. &#8220;Ein gro\u00dfartiger Wettbewerb, der mehr Menschen zusammenbringen wird.&#8221; Und: &#8220;Wir k\u00f6nnen also miteinander auskommen und gemeinsam etwas tun, ohne dass es zu einem Drama kommt. Das ist sehr toll!&#8221; Eine Person meinte sogar: &#8220;Ich mag diesen Wettbewerb, ich w\u00fcrde gerne daran teilnehmen.&#8221;<\/p>\n<p>In diesem Jahr nehmen K\u00fcnstler aus 23 L\u00e4ndern, darunter auch aus den USA, am ersten Intervision teil. Die Vereinigten Staaten werden in Moskau von dem S\u00e4nger Brandon Howard vertreten, der eine Zeit lang aufgrund seiner \u00c4hnlichkeit mit Michael Jackson f\u00fcr dessen Sohn gehalten wurde. Der aus Kalifornien stammende S\u00e4nger gestand russischen Journalisten, dass die Teilnahme am Intervision-Wettbewerb f\u00fcr ihn ein neues Kapitel in seiner Karriere darstellt. &#8220;Es ist eine mitrei\u00dfende Hymne, geschaffen f\u00fcr Stadien, Festivals und f\u00fcr die wahre internationale Verbundenheit&#8221;, sagte er \u00fcber seinen Wettbewerbsbeitrag mit dem Titel &#8220;We are champions&#8221;. Seiner Vorstellung nach soll das Lied die Menschen vereinen, ihnen Energie und Selbstvertrauen geben.<\/p>\n<p><strong>Mehr zum Thema <\/strong>\u2013\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/kurzclips\/video\/256158-song-contest-in-moskau-intervision-bringt-23-nationen-zusammen\/\">Song Contest in Moskau: &#8220;Intervision&#8221; bringt 23 Nationen zusammen<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/256168-schock-in-new-york-am\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Broadway steht in den Farben der russischen Nationalfahne. New York wirbt f\u00fcr das Pendant zum Eurovision Song Contest. Trotz der russophoben Propaganda kritisieren die B\u00fcrger das nicht. Mehr noch: Der US-Vertreter steht bald in Moskau auf der B\u00fchne. Am Times Square in New York l\u00e4uft auf den riesigen Bildschirmen Werbung f\u00fcr Intervision, das russische [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":90631,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1758030163"],"wp_automatic_camp":["217"],"cf221735171b8ce5b799f1a9128d5ce8":["Musikalischer Br\u00fcckenschlag: Am Times Square l\u00e4uft Werbung f\u00fcr den russischen Intervision-Wettbewerb"],"original_link":["https:\/\/de.rt.com\/international\/256168-schock-in-new-york-am\/"],"_thumbnail_id":["90631"],"jnews_social_counter_last_update":["1788387410"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-09-16 15:43:43\";}"]},"categories":[19,23],"tags":[67796,48,221,67797,15743,67795,973,23284,259,23240],"class_list":["post-90630","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-brueckenschlag","tag-den","tag-fuer","tag-intervisionwettbewerb","tag-laeuft","tag-musikalischer","tag-russischen","tag-square","tag-times","tag-werbung"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Musikalischer Br\u00fcckenschlag: Am Times Square l\u00e4uft Werbung f\u00fcr den russischen Intervision-Wettbewerb - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Musikalischer Br\u00fcckenschlag: Am Times Square l\u00e4uft Werbung f\u00fcr den russischen Intervision-Wettbewerb\" \/>\n<meta property=\"og:description\" content=\"Der Broadway steht in den Farben der russischen Nationalfahne. New York wirbt f\u00fcr das Pendant zum Eurovision Song Contest. Trotz der russophoben Propaganda kritisieren die B\u00fcrger das nicht. Mehr noch: Der US-Vertreter steht bald in Moskau auf der B\u00fchne. Am Times Square in New York l\u00e4uft auf den riesigen Bildschirmen Werbung f\u00fcr Intervision, das russische [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-16T13:30:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/68c9340bb480cc7d6868aef7.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Musikalischer Br\u00fcckenschlag: Am Times Square l\u00e4uft Werbung f\u00fcr den russischen Intervision-Wettbewerb\",\"datePublished\":\"2025-09-16T13:30:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\\\/\"},\"wordCount\":525,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/Musikalischer-Brueckenschlag-Am-Times-Square-laeuft-Werbung-fuer-den-russischen.jpg\",\"keywords\":[\"Br\u00fcckenschlag\",\"den\",\"f\u00fcr\",\"IntervisionWettbewerb\",\"l\u00e4uft\",\"Musikalischer\",\"russischen\",\"Square\",\"Times\",\"Werbung\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\\\/\",\"name\":\"Musikalischer Br\u00fcckenschlag: Am Times Square l\u00e4uft Werbung f\u00fcr den russischen Intervision-Wettbewerb - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/Musikalischer-Brueckenschlag-Am-Times-Square-laeuft-Werbung-fuer-den-russischen.jpg\",\"datePublished\":\"2025-09-16T13:30:01+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/Musikalischer-Brueckenschlag-Am-Times-Square-laeuft-Werbung-fuer-den-russischen.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/Musikalischer-Brueckenschlag-Am-Times-Square-laeuft-Werbung-fuer-den-russischen.jpg\",\"width\":460,\"height\":259,\"caption\":\"Musikalischer Br\u00fcckenschlag: Am Times Square l\u00e4uft Werbung f\u00fcr den russischen Intervision-Wettbewerb\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Musikalischer Br\u00fcckenschlag: Am Times Square l\u00e4uft Werbung f\u00fcr den russischen Intervision-Wettbewerb\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Musikalischer Br\u00fcckenschlag: Am Times Square l\u00e4uft Werbung f\u00fcr den russischen Intervision-Wettbewerb - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\/","og_locale":"de_DE","og_type":"article","og_title":"Musikalischer Br\u00fcckenschlag: Am Times Square l\u00e4uft Werbung f\u00fcr den russischen Intervision-Wettbewerb","og_description":"Der Broadway steht in den Farben der russischen Nationalfahne. New York wirbt f\u00fcr das Pendant zum Eurovision Song Contest. Trotz der russophoben Propaganda kritisieren die B\u00fcrger das nicht. Mehr noch: Der US-Vertreter steht bald in Moskau auf der B\u00fchne. Am Times Square in New York l\u00e4uft auf den riesigen Bildschirmen Werbung f\u00fcr Intervision, das russische [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-09-16T13:30:01+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/68c9340bb480cc7d6868aef7.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Musikalischer Br\u00fcckenschlag: Am Times Square l\u00e4uft Werbung f\u00fcr den russischen Intervision-Wettbewerb","datePublished":"2025-09-16T13:30:01+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\/"},"wordCount":525,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/Musikalischer-Brueckenschlag-Am-Times-Square-laeuft-Werbung-fuer-den-russischen.jpg","keywords":["Br\u00fcckenschlag","den","f\u00fcr","IntervisionWettbewerb","l\u00e4uft","Musikalischer","russischen","Square","Times","Werbung"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\/","url":"https:\/\/now-news.de\/de\/deutschland\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\/","name":"Musikalischer Br\u00fcckenschlag: Am Times Square l\u00e4uft Werbung f\u00fcr den russischen Intervision-Wettbewerb - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/Musikalischer-Brueckenschlag-Am-Times-Square-laeuft-Werbung-fuer-den-russischen.jpg","datePublished":"2025-09-16T13:30:01+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/Musikalischer-Brueckenschlag-Am-Times-Square-laeuft-Werbung-fuer-den-russischen.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/Musikalischer-Brueckenschlag-Am-Times-Square-laeuft-Werbung-fuer-den-russischen.jpg","width":460,"height":259,"caption":"Musikalischer Br\u00fcckenschlag: Am Times Square l\u00e4uft Werbung f\u00fcr den russischen Intervision-Wettbewerb"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/musikalischer-brueckenschlag-am-times-square-laeuft-werbung-fuer-den-russischen-intervision-wettbewerb\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Musikalischer Br\u00fcckenschlag: Am Times Square l\u00e4uft Werbung f\u00fcr den russischen Intervision-Wettbewerb"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/90630","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=90630"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/90630\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/90631"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=90630"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=90630"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=90630"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}