{"id":89976,"date":"2025-09-04T19:32:49","date_gmt":"2025-09-04T17:32:49","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\/"},"modified":"2025-09-04T19:32:49","modified_gmt":"2025-09-04T17:32:49","slug":"gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\/","title":{"rendered":"GPS-Attacke auf Flugzeug: Bulgarien widerlegt von der Leyens Behauptungen"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/68b9ba21b480cc3862681894.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die Pr\u00e4sidentin der EU-Kommission hatte behauptet, Russland habe das Navigationssystems ihres Flugzeugs gest\u00f6rt. Eine Behauptung, der von Flugbeobachtungsseiten bald widersprochen wurde. Nun widersprachen auch Vertreter der bulgarischen Regierung.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Es gibt keinen Beleg daf\u00fcr, dass Russland das Flugzeug der Pr\u00e4sidentin der EU-Kommission, Ursula von der Leyen, bei ihrem j\u00fcngsten Flug nach Bulgarien in irgendeiner Weise gest\u00f6rt habe, erkl\u00e4rten die Beh\u00f6rden des Landes. Zuvor hatte die Europ\u00e4ische Kommission erkl\u00e4rt, die bulgarischen Beh\u00f6rden h\u00e4tten den Zwischenfall best\u00e4tigt.<\/p>\n<p>Am Sonntag soll von der Leyens Pilot Probleme mit dem Navigationssystem bei der Landung in Plowdiw berichtet haben. Sp\u00e4ter erkl\u00e4rte Br\u00fcssel gegen\u00fcber der <em>Financial Times<\/em>, von der Leyens Flug sei gezwungen gewesen, &#8220;eine Stunde lang zu kreisen&#8221;, und behauptete, die St\u00f6rung des GPS-Signals sei auf eine &#8220;unverhohlene Einmischung&#8221; Russlands zur\u00fcckzuf\u00fchren.<\/p>\n<p>Der bulgarische Premierminister Rossen Scheljaskow hat den Br\u00fcsseler Behauptungen direkt widersprochen und dem Parlament am Donnerstag mitgeteilt, dass kein Beleg f\u00fcr einen russischen Angriff gefunden wurde und dass das Flugzeug von der Leyens keinerlei ernste Probleme hatte, nur eine kurzfristige Signalabschw\u00e4chung, die \u00fcber dicht bev\u00f6lkerten Gebieten \u00fcblich sei.<\/p>\n<p>&#8220;Nach dem Check der Flugaufzeichnungen sahen wir, dass es keine Anzeichen f\u00fcr Sorgen des Piloten gab. F\u00fcnf Minuten schwebte die Maschine im Wartebereich, die Signalqualit\u00e4t war dabei durchgehend gut&#8221;, sage Scheljaskow laut <em>Bild<\/em>.<\/p>\n<p>Der stellvertretende Premierminister und Transportminister Grosdan Karadschow <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.rt.com\/news\/624127-bulgaria-debunks-eu-jet-claim\/\">erkl\u00e4rte<\/a>, &#8220;weder die bulgarische Zivilluftfahrt noch die Luftwaffe in Sofia und Plowdiw, nicht einmal die Aufzeichnungen der Kommission zur Kommunikationsregulierung zeigen irgendeinen R\u00fcckgang des GPS-Signals&#8221;.<\/p>\n<p>Er betonte, niemand aus der bulgarischen Regierung habe jemanden aus der Europ\u00e4ischen Kommission in die Irre gef\u00fchrt, und bestritt jegliche Kommunikation zwischen Sofia und Br\u00fcssel zu diesem Thema.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211;\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/europa\/254878-flightradar-medienberichte-zu-russischer-gps\/\">Flightradar: Medienberichte zu russischer GPS-Manipulation bei von der Leyen-Flug sind falsch <\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6w5u0e\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/255154-bulgarien-widerlegt-von-leyens-behauptungen\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Pr\u00e4sidentin der EU-Kommission hatte behauptet, Russland habe das Navigationssystems ihres Flugzeugs gest\u00f6rt. Eine Behauptung, der von Flugbeobachtungsseiten bald widersprochen wurde. Nun widersprachen auch Vertreter der bulgarischen Regierung. Es gibt keinen Beleg daf\u00fcr, dass Russland das Flugzeug der Pr\u00e4sidentin der EU-Kommission, Ursula von der Leyen, bei ihrem j\u00fcngsten Flug nach Bulgarien in irgendeiner Weise gest\u00f6rt [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":89977,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1757007268"],"wp_automatic_camp":["217"],"d42119e7aef45d46ef0ccb91601df4ad":["GPS-Attacke auf Flugzeug: Bulgarien widerlegt von der Leyens Behauptungen"],"original_link":["https:\/\/de.rt.com\/europa\/255154-bulgarien-widerlegt-von-leyens-behauptungen\/"],"_thumbnail_id":["89977"],"jnews_social_counter_last_update":["1788227987"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-09-04 19:35:31\";}"]},"categories":[19,23],"tags":[133,10881,10878,82,11437,67492,26960,50,21098],"class_list":["post-89976","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-auf","tag-behauptungen","tag-bulgarien","tag-der","tag-flugzeug","tag-gpsattacke","tag-leyens","tag-von","tag-widerlegt"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>GPS-Attacke auf Flugzeug: Bulgarien widerlegt von der Leyens Behauptungen - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GPS-Attacke auf Flugzeug: Bulgarien widerlegt von der Leyens Behauptungen\" \/>\n<meta property=\"og:description\" content=\"Die Pr\u00e4sidentin der EU-Kommission hatte behauptet, Russland habe das Navigationssystems ihres Flugzeugs gest\u00f6rt. Eine Behauptung, der von Flugbeobachtungsseiten bald widersprochen wurde. Nun widersprachen auch Vertreter der bulgarischen Regierung. Es gibt keinen Beleg daf\u00fcr, dass Russland das Flugzeug der Pr\u00e4sidentin der EU-Kommission, Ursula von der Leyen, bei ihrem j\u00fcngsten Flug nach Bulgarien in irgendeiner Weise gest\u00f6rt [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-09-04T17:32:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/68b9ba21b480cc3862681894.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"GPS-Attacke auf Flugzeug: Bulgarien widerlegt von der Leyens Behauptungen\",\"datePublished\":\"2025-09-04T17:32:49+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\\\/\"},\"wordCount\":324,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/GPS-Attacke-auf-Flugzeug-Bulgarien-widerlegt-von-der-Leyens-Behauptungen.jpg\",\"keywords\":[\"AUF\",\"Behauptungen\",\"Bulgarien\",\"der\",\"flugzeug\",\"GPSAttacke\",\"Leyens\",\"von\",\"widerlegt\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\\\/\",\"name\":\"GPS-Attacke auf Flugzeug: Bulgarien widerlegt von der Leyens Behauptungen - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/GPS-Attacke-auf-Flugzeug-Bulgarien-widerlegt-von-der-Leyens-Behauptungen.jpg\",\"datePublished\":\"2025-09-04T17:32:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/GPS-Attacke-auf-Flugzeug-Bulgarien-widerlegt-von-der-Leyens-Behauptungen.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/09\\\/GPS-Attacke-auf-Flugzeug-Bulgarien-widerlegt-von-der-Leyens-Behauptungen.jpg\",\"width\":460,\"height\":259,\"caption\":\"GPS-Attacke auf Flugzeug: Bulgarien widerlegt von der Leyens Behauptungen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GPS-Attacke auf Flugzeug: Bulgarien widerlegt von der Leyens Behauptungen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"GPS-Attacke auf Flugzeug: Bulgarien widerlegt von der Leyens Behauptungen - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\/","og_locale":"de_DE","og_type":"article","og_title":"GPS-Attacke auf Flugzeug: Bulgarien widerlegt von der Leyens Behauptungen","og_description":"Die Pr\u00e4sidentin der EU-Kommission hatte behauptet, Russland habe das Navigationssystems ihres Flugzeugs gest\u00f6rt. Eine Behauptung, der von Flugbeobachtungsseiten bald widersprochen wurde. Nun widersprachen auch Vertreter der bulgarischen Regierung. Es gibt keinen Beleg daf\u00fcr, dass Russland das Flugzeug der Pr\u00e4sidentin der EU-Kommission, Ursula von der Leyen, bei ihrem j\u00fcngsten Flug nach Bulgarien in irgendeiner Weise gest\u00f6rt [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-09-04T17:32:49+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/68b9ba21b480cc3862681894.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"GPS-Attacke auf Flugzeug: Bulgarien widerlegt von der Leyens Behauptungen","datePublished":"2025-09-04T17:32:49+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\/"},"wordCount":324,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/GPS-Attacke-auf-Flugzeug-Bulgarien-widerlegt-von-der-Leyens-Behauptungen.jpg","keywords":["AUF","Behauptungen","Bulgarien","der","flugzeug","GPSAttacke","Leyens","von","widerlegt"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\/","url":"https:\/\/now-news.de\/de\/deutschland\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\/","name":"GPS-Attacke auf Flugzeug: Bulgarien widerlegt von der Leyens Behauptungen - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/GPS-Attacke-auf-Flugzeug-Bulgarien-widerlegt-von-der-Leyens-Behauptungen.jpg","datePublished":"2025-09-04T17:32:49+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/GPS-Attacke-auf-Flugzeug-Bulgarien-widerlegt-von-der-Leyens-Behauptungen.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/09\/GPS-Attacke-auf-Flugzeug-Bulgarien-widerlegt-von-der-Leyens-Behauptungen.jpg","width":460,"height":259,"caption":"GPS-Attacke auf Flugzeug: Bulgarien widerlegt von der Leyens Behauptungen"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/gps-attacke-auf-flugzeug-bulgarien-widerlegt-von-der-leyens-behauptungen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"GPS-Attacke auf Flugzeug: Bulgarien widerlegt von der Leyens Behauptungen"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/89976","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=89976"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/89976\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/89977"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=89976"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=89976"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=89976"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}