{"id":89594,"date":"2025-08-28T21:35:38","date_gmt":"2025-08-28T19:35:38","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/"},"modified":"2025-08-28T21:35:38","modified_gmt":"2025-08-28T19:35:38","slug":"trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/","title":{"rendered":"Trump-Berater: Ukraine-Konflikt ist &quot;im Wesentlichen Modis Krieg&quot;"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/68b085d648fbef02ce79b245.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Donald Trumps Berater Peter Navarro behauptete, der Ukraine-Konflikt sei &#8220;im Wesentlichen Narendra Modis Krieg&#8221;, da Neu-Delhis verg\u00fcnstigte \u00d6lk\u00e4ufe aus Moskau den russischen Streitkr\u00e4ften helfen. Seine \u00c4u\u00dferungen erfolgten im Zusammenhang mit der Einf\u00fchrung von Trumps 50-prozentigen Z\u00f6llen auf indische Waren.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Ein ranghoher Handelsberater von US-Pr\u00e4sident Donald Trump hat behauptet, der Ukraine-Konflikt sei in Wirklichkeit der &#8220;Krieg&#8221; des indischen Premierministers Narendra Modi. Er vertritt die Auffassung, dass Neu-Delhis verg\u00fcnstigte \u00d6lk\u00e4ufe aus Moskau den russischen Streitkr\u00e4ften helfen.<\/p>\n<p>In einem Gespr\u00e4ch mit <em>Bloomberg\u00a0TV <\/em>sagte Peter Navarro am Mittwoch, dass Indien die US-Z\u00f6lle sofort von 50\u00a0Prozent auf 25\u00a0Prozent reduziert bek\u00e4me, wenn es kein russisches \u00d6l mehr kaufen w\u00fcrde.<\/p>\n<p>&#8220;Ich meine, das ist im Wesentlichen Modis Krieg, denn der Weg zum Frieden f\u00fchrt zum Teil durch Neu-Delhi&#8221;, sagte er.<\/p>\n<p>Navarros \u00c4u\u00dferungen erfolgten im Zusammenhang mit der Einf\u00fchrung von Trumps 50-prozentigen Z\u00f6llen auf indische Waren, die zu den h\u00f6chsten im Welthandel geh\u00f6ren.<\/p>\n<p>In der vergangenen Woche hatte Navarro in \u00e4hnlicher Weise behauptet, dass Indien mit seinen verg\u00fcnstigten K\u00e4ufen von russischem \u00d6l indirekt Moskaus Truppen unterst\u00fctze, und das s\u00fcdasiatische Land sogar als &#8220;Waschsalon f\u00fcr den Kreml&#8221; bezeichnet.<\/p>\n<p>Der indische Au\u00dfenminister Subrahmanyam\u00a0Jaishankar entgegnete, dass niemand &#8220;gezwungen&#8221; sei, \u00d6lprodukte aus seinem Land zu kaufen. &#8220;Europa kauft [russische Energieprodukte], Amerika kauft, also wenn es Ihnen nicht gef\u00e4llt, kaufen Sie es nicht&#8221;, sagte er.<\/p>\n<p>Neu-Delhi hat die US-Z\u00f6lle als &#8220;unfair und unangemessen&#8221; verurteilt und argumentiert, dass die westlichen L\u00e4nder selbst noch mehr Gesch\u00e4fte mit Moskau betreiben. Indien besteht darauf, dass seine Importe aus Russland dem nationalen Interesse dienen und dazu beitragen, dass seine Verbraucher erschwingliche Energie erhalten.<\/p>\n<p><strong>Mehr zum Thema \u2013\u00a0<\/strong><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/253681-trumps-berater-fordert-indien-auf\/\">Trump-Berater kritisiert Indiens \u00d6lpolitik gegen\u00fcber Russland <\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/254546-trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Donald Trumps Berater Peter Navarro behauptete, der Ukraine-Konflikt sei &#8220;im Wesentlichen Narendra Modis Krieg&#8221;, da Neu-Delhis verg\u00fcnstigte \u00d6lk\u00e4ufe aus Moskau den russischen Streitkr\u00e4ften helfen. Seine \u00c4u\u00dferungen erfolgten im Zusammenhang mit der Einf\u00fchrung von Trumps 50-prozentigen Z\u00f6llen auf indische Waren. Ein ranghoher Handelsberater von US-Pr\u00e4sident Donald Trump hat behauptet, der Ukraine-Konflikt sei in Wirklichkeit der &#8220;Krieg&#8221; [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":89595,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1756410555"],"wp_automatic_camp":["217"],"b570d8019e0987bc2554389e6e15ada8":["Trump-Berater: Ukraine-Konflikt ist &quot;im Wesentlichen Modis Krieg&quot;"],"original_link":["https:\/\/de.rt.com\/international\/254546-trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/"],"_thumbnail_id":["89595"],"jnews_social_counter_last_update":["1788320168"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-08-28 21:50:16\";}"]},"categories":[19,23],"tags":[414,18890,55495,36708,27863,1173,66205],"class_list":["post-89594","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-ist","tag-kriegquot","tag-modis","tag-quotim","tag-trumpberater","tag-ukrainekonflikt","tag-wesentlichen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Trump-Berater: Ukraine-Konflikt ist &quot;im Wesentlichen Modis Krieg&quot; - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Trump-Berater: Ukraine-Konflikt ist &quot;im Wesentlichen Modis Krieg&quot;\" \/>\n<meta property=\"og:description\" content=\"Donald Trumps Berater Peter Navarro behauptete, der Ukraine-Konflikt sei &#8220;im Wesentlichen Narendra Modis Krieg&#8221;, da Neu-Delhis verg\u00fcnstigte \u00d6lk\u00e4ufe aus Moskau den russischen Streitkr\u00e4ften helfen. Seine \u00c4u\u00dferungen erfolgten im Zusammenhang mit der Einf\u00fchrung von Trumps 50-prozentigen Z\u00f6llen auf indische Waren. Ein ranghoher Handelsberater von US-Pr\u00e4sident Donald Trump hat behauptet, der Ukraine-Konflikt sei in Wirklichkeit der &#8220;Krieg&#8221; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-28T19:35:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/68b085d648fbef02ce79b245.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Trump-Berater: Ukraine-Konflikt ist &quot;im Wesentlichen Modis Krieg&quot;\",\"datePublished\":\"2025-08-28T19:35:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\\\/\"},\"wordCount\":309,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/08\\\/Trump-Berater-Ukraine-Konflikt-ist-quotim-Wesentlichen-Modis-Kriegquot.jpg\",\"keywords\":[\"ist\",\"Kriegquot\",\"Modis\",\"quotIm\",\"TrumpBerater\",\"UkraineKonflikt\",\"wesentlichen\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\\\/\",\"name\":\"Trump-Berater: Ukraine-Konflikt ist &quot;im Wesentlichen Modis Krieg&quot; - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/08\\\/Trump-Berater-Ukraine-Konflikt-ist-quotim-Wesentlichen-Modis-Kriegquot.jpg\",\"datePublished\":\"2025-08-28T19:35:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/08\\\/Trump-Berater-Ukraine-Konflikt-ist-quotim-Wesentlichen-Modis-Kriegquot.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/08\\\/Trump-Berater-Ukraine-Konflikt-ist-quotim-Wesentlichen-Modis-Kriegquot.jpg\",\"width\":460,\"height\":259,\"caption\":\"Trump-Berater: Ukraine-Konflikt ist &quot;im Wesentlichen Modis Krieg&quot;\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trump-Berater: Ukraine-Konflikt ist &quot;im Wesentlichen Modis Krieg&quot;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Trump-Berater: Ukraine-Konflikt ist &quot;im Wesentlichen Modis Krieg&quot; - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/","og_locale":"de_DE","og_type":"article","og_title":"Trump-Berater: Ukraine-Konflikt ist &quot;im Wesentlichen Modis Krieg&quot;","og_description":"Donald Trumps Berater Peter Navarro behauptete, der Ukraine-Konflikt sei &#8220;im Wesentlichen Narendra Modis Krieg&#8221;, da Neu-Delhis verg\u00fcnstigte \u00d6lk\u00e4ufe aus Moskau den russischen Streitkr\u00e4ften helfen. Seine \u00c4u\u00dferungen erfolgten im Zusammenhang mit der Einf\u00fchrung von Trumps 50-prozentigen Z\u00f6llen auf indische Waren. Ein ranghoher Handelsberater von US-Pr\u00e4sident Donald Trump hat behauptet, der Ukraine-Konflikt sei in Wirklichkeit der &#8220;Krieg&#8221; [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-08-28T19:35:38+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/68b085d648fbef02ce79b245.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Trump-Berater: Ukraine-Konflikt ist &quot;im Wesentlichen Modis Krieg&quot;","datePublished":"2025-08-28T19:35:38+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/"},"wordCount":309,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Trump-Berater-Ukraine-Konflikt-ist-quotim-Wesentlichen-Modis-Kriegquot.jpg","keywords":["ist","Kriegquot","Modis","quotIm","TrumpBerater","UkraineKonflikt","wesentlichen"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/","url":"https:\/\/now-news.de\/de\/deutschland\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/","name":"Trump-Berater: Ukraine-Konflikt ist &quot;im Wesentlichen Modis Krieg&quot; - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Trump-Berater-Ukraine-Konflikt-ist-quotim-Wesentlichen-Modis-Kriegquot.jpg","datePublished":"2025-08-28T19:35:38+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Trump-Berater-Ukraine-Konflikt-ist-quotim-Wesentlichen-Modis-Kriegquot.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Trump-Berater-Ukraine-Konflikt-ist-quotim-Wesentlichen-Modis-Kriegquot.jpg","width":460,"height":259,"caption":"Trump-Berater: Ukraine-Konflikt ist &quot;im Wesentlichen Modis Krieg&quot;"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/trump-berater-ukraine-konflikt-ist-im-wesentlichen-modis-krieg\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Trump-Berater: Ukraine-Konflikt ist &quot;im Wesentlichen Modis Krieg&quot;"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/89594","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=89594"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/89594\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/89595"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=89594"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=89594"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=89594"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}