{"id":89475,"date":"2025-08-26T20:35:38","date_gmt":"2025-08-26T18:35:38","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/"},"modified":"2025-08-26T20:35:38","modified_gmt":"2025-08-26T18:35:38","slug":"merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/","title":{"rendered":"Merz: &quot;Wenn Putin und Selenskij sich nicht treffen, liegt der Ball wieder bei uns&quot;"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/68adb794b480cc535304b5b4.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                &#8220;Treffen oder Sanktionen&#8221;: Merz erh\u00f6ht den Druck auf Moskau. Bleibt ein Gipfel zwischen Putin und Selenskij aus, drohen laut dem Kanzler neue Strafma\u00dfnahmen. Trump schlug f\u00fcr diesen Fall ein Dreiertreffen vor.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p data-start=\"223\" data-end=\"425\">Auf einer gemeinsamen Pressekonferenz mit dem kanadischen Premierminister Mark Carney hat Bundeskanzler Friedrich Merz bekr\u00e4ftigt, dass ein baldiges Treffen zwischen dem russischen Pr\u00e4sidenten Wladimir Putin und dem ukrainischen\u00a0Machthaber Wladimir Selenskij entscheidend sei. Sollte es nicht in den kommenden zwei Wochen zustande kommen, w\u00fcrden Europa und die USA erneut gefordert sein. Zudem drohte er mit versch\u00e4rften Sanktionen gegen Russland. Merz w\u00f6rtlich:<em><br \/><\/em><\/p>\n<p><em>&#8220;Wenn es zu so einem Treffen nicht kommt wie zwischen Trump und Putin vereinbart, dann liegt der Ball wieder bei uns. Ich meine damit: bei den Europ\u00e4ern und bei den Amerikanern.&#8221;<\/em><\/p>\n<p>Merz erkl\u00e4rte weiter, dass Trump f\u00fcr diesen Fall ein trilaterales Gespr\u00e4ch vorgeschlagen habe, also ein Treffen zwischen Putin, Selenskij und ihm. &#8220;Das w\u00e4re dann der logische n\u00e4chste Schritt&#8221;, wenn diese Begegnung nicht innerhalb von zwei Wochen zustande komme, so Merz.<\/p>\n<p>Er betonte, dass es im Falle einer Absage &#8220;noch mehr Druck braucht&#8221;. Die Europ\u00e4ische Union arbeite bereits an neuen Strafma\u00dfnahmen, w\u00e4hrend auch die USA zus\u00e4tzliche Z\u00f6lle gegen Russland ins Spiel gebracht h\u00e4tten. Dar\u00fcber hinaus w\u00fcrden Europa, die Vereinigten Staaten und die Ukraine an m\u00f6glichen Sicherheitsgarantien arbeiten.<\/p>\n<p><em>&#8220;Es sind Sicherheitsgarantien, die zuallererst das Ziel haben m\u00fcssen, die ukrainische Armee auf Dauer in die Lage zu versetzen, das Land zu verteidigen.&#8221;<br \/><\/em><br \/>Auf die Frage nach einer m\u00f6glichen Stationierung westlicher Bodentruppen in der Ukraine nach einem Friedensschluss erkl\u00e4rte Merz:<\/p>\n<p><em>\u00a0&#8220;Alle weiteren Fragen k\u00f6nnen erst dann gestellt und beantwortet werden.&#8221;<\/em><\/p>\n<p data-start=\"1990\" data-end=\"2291\">Zuvor hatte US-Pr\u00e4sident Trump mit Putin in Alaska \u00fcber die Ukraine gesprochen. Dabei sei es gelungen, &#8220;viele Punkte&#8221; der Konfliktproblematik zu kl\u00e4ren, in einigen Fragen gebe es jedoch weiterhin keine Einigung. In einem Interview mit <em>Fox News<\/em> betonte Trump anschlie\u00dfend, dass eine Einigung nun wesentlich von Selenskij abh\u00e4nge.<\/p>\n<p>Nach Angaben des Kremlberaters Juri Uschakow hatten Putin und Trump in einem Telefonat zuvor beide Seiten zur Fortsetzung direkter Verhandlungen zwischen den Delegationen Russlands und der Ukraine ermutigt. Diskutiert worden sei auch, das Verhandlungsniveau zu erh\u00f6hen, um Fortschritte zu erzielen.<\/p>\n<p data-start=\"2293\" data-end=\"2674\">Trump selbst bezeichnete die pers\u00f6nliche Abneigung zwischen Putin und Selenskij als gr\u00f6\u00dftes Hindernis f\u00fcr ein direktes Treffen. Er r\u00e4umte ein, dass es durchaus m\u00f6glich sei, dass ein Gipfel gar nicht zustande kommt. Ein Treffen auf h\u00f6chster Ebene zwischen Russland und der Ukraine bleibe daher zwar theoretisch m\u00f6glich, erscheine in der Praxis derzeit jedoch wenig wahrscheinlich.<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/europa\/253833-europa-plant-sanktionen-falls-putin\/\">Europa plant neue Sanktionen, falls Putin Treffen mit Selenskij ablehnt<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6vtfhi\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/254349-merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8220;Treffen oder Sanktionen&#8221;: Merz erh\u00f6ht den Druck auf Moskau. Bleibt ein Gipfel zwischen Putin und Selenskij aus, drohen laut dem Kanzler neue Strafma\u00dfnahmen. Trump schlug f\u00fcr diesen Fall ein Dreiertreffen vor. Auf einer gemeinsamen Pressekonferenz mit dem kanadischen Premierminister Mark Carney hat Bundeskanzler Friedrich Merz bekr\u00e4ftigt, dass ein baldiges Treffen zwischen dem russischen Pr\u00e4sidenten Wladimir [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":89476,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1756234157"],"wp_automatic_camp":["217"],"2017b374d59fe8a99d62b063c3c192a4":["Merz: &quot;Wenn Putin und Selenskij sich nicht treffen, liegt der Ball wieder bei uns&quot;"],"original_link":["https:\/\/de.rt.com\/international\/254349-merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/"],"_thumbnail_id":["89476"],"jnews_social_counter_last_update":["1788354784"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-08-26 20:50:18\";}"]},"categories":[19,23],"tags":[14826,363,82,3953,18728,800,125,26160,6158,434,354,140,32318,904],"class_list":["post-89475","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-ball","tag-bei","tag-der","tag-liegt","tag-merz","tag-nicht","tag-putin","tag-quotwenn","tag-selenskij","tag-sich","tag-treffen","tag-und","tag-unsquot","tag-wieder"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Merz: &quot;Wenn Putin und Selenskij sich nicht treffen, liegt der Ball wieder bei uns&quot; - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Merz: &quot;Wenn Putin und Selenskij sich nicht treffen, liegt der Ball wieder bei uns&quot;\" \/>\n<meta property=\"og:description\" content=\"&#8220;Treffen oder Sanktionen&#8221;: Merz erh\u00f6ht den Druck auf Moskau. Bleibt ein Gipfel zwischen Putin und Selenskij aus, drohen laut dem Kanzler neue Strafma\u00dfnahmen. Trump schlug f\u00fcr diesen Fall ein Dreiertreffen vor. Auf einer gemeinsamen Pressekonferenz mit dem kanadischen Premierminister Mark Carney hat Bundeskanzler Friedrich Merz bekr\u00e4ftigt, dass ein baldiges Treffen zwischen dem russischen Pr\u00e4sidenten Wladimir [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-26T18:35:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/68adb794b480cc535304b5b4.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Merz: &quot;Wenn Putin und Selenskij sich nicht treffen, liegt der Ball wieder bei uns&quot;\",\"datePublished\":\"2025-08-26T18:35:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\\\/\"},\"wordCount\":473,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/08\\\/Merz-quotWenn-Putin-und-Selenskij-sich-nicht-treffen-liegt-der.jpg\",\"keywords\":[\"Ball\",\"bei\",\"der\",\"liegt\",\"Merz\",\"nicht\",\"putin\",\"quotWenn\",\"Selenskij\",\"sich\",\"Treffen\",\"und\",\"unsquot\",\"wieder\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\\\/\",\"name\":\"Merz: &quot;Wenn Putin und Selenskij sich nicht treffen, liegt der Ball wieder bei uns&quot; - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/08\\\/Merz-quotWenn-Putin-und-Selenskij-sich-nicht-treffen-liegt-der.jpg\",\"datePublished\":\"2025-08-26T18:35:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/08\\\/Merz-quotWenn-Putin-und-Selenskij-sich-nicht-treffen-liegt-der.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/08\\\/Merz-quotWenn-Putin-und-Selenskij-sich-nicht-treffen-liegt-der.jpg\",\"width\":460,\"height\":259,\"caption\":\"Merz: &quot;Wenn Putin und Selenskij sich nicht treffen, liegt der Ball wieder bei uns&quot;\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Merz: &quot;Wenn Putin und Selenskij sich nicht treffen, liegt der Ball wieder bei uns&quot;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Merz: &quot;Wenn Putin und Selenskij sich nicht treffen, liegt der Ball wieder bei uns&quot; - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/","og_locale":"de_DE","og_type":"article","og_title":"Merz: &quot;Wenn Putin und Selenskij sich nicht treffen, liegt der Ball wieder bei uns&quot;","og_description":"&#8220;Treffen oder Sanktionen&#8221;: Merz erh\u00f6ht den Druck auf Moskau. Bleibt ein Gipfel zwischen Putin und Selenskij aus, drohen laut dem Kanzler neue Strafma\u00dfnahmen. Trump schlug f\u00fcr diesen Fall ein Dreiertreffen vor. Auf einer gemeinsamen Pressekonferenz mit dem kanadischen Premierminister Mark Carney hat Bundeskanzler Friedrich Merz bekr\u00e4ftigt, dass ein baldiges Treffen zwischen dem russischen Pr\u00e4sidenten Wladimir [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-08-26T18:35:38+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/68adb794b480cc535304b5b4.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Merz: &quot;Wenn Putin und Selenskij sich nicht treffen, liegt der Ball wieder bei uns&quot;","datePublished":"2025-08-26T18:35:38+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/"},"wordCount":473,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Merz-quotWenn-Putin-und-Selenskij-sich-nicht-treffen-liegt-der.jpg","keywords":["Ball","bei","der","liegt","Merz","nicht","putin","quotWenn","Selenskij","sich","Treffen","und","unsquot","wieder"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/","url":"https:\/\/now-news.de\/de\/deutschland\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/","name":"Merz: &quot;Wenn Putin und Selenskij sich nicht treffen, liegt der Ball wieder bei uns&quot; - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Merz-quotWenn-Putin-und-Selenskij-sich-nicht-treffen-liegt-der.jpg","datePublished":"2025-08-26T18:35:38+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Merz-quotWenn-Putin-und-Selenskij-sich-nicht-treffen-liegt-der.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Merz-quotWenn-Putin-und-Selenskij-sich-nicht-treffen-liegt-der.jpg","width":460,"height":259,"caption":"Merz: &quot;Wenn Putin und Selenskij sich nicht treffen, liegt der Ball wieder bei uns&quot;"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/merz-wenn-putin-und-selenskij-sich-nicht-treffen-liegt-der-ball-wieder-bei-uns\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Merz: &quot;Wenn Putin und Selenskij sich nicht treffen, liegt der Ball wieder bei uns&quot;"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/89475","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=89475"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/89475\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/89476"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=89475"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=89475"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=89475"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}