{"id":88580,"date":"2025-08-10T11:50:59","date_gmt":"2025-08-10T09:50:59","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/"},"modified":"2025-08-10T11:50:59","modified_gmt":"2025-08-10T09:50:59","slug":"digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/","title":{"rendered":"Digitaler Neokolonialismus: Der politische Hintergrund der k\u00fcnstlichen Intelligenz, Teil II"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/6896235548fbef2a00126894.jpg\" \/><\/p>\n<p><em>Von Maria Sacharowa<\/em><\/p>\n<p><strong>Teil II\u00a0<\/strong><\/p>\n<p><em>Zum ersten Teil geht es <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/meinung\/252698-digitaler-neokolonialismus-politische-hintergrund-kuenstlichen\">hier<\/a>\u00a0lang.<\/em><\/p>\n<p>Die zweite S\u00e4ule des neuen globalen Kontrollsystems ist die k\u00fcnstliche Intelligenz (KI) selbst und ihr wachsender Einfluss auf die Weltwirtschaft. In der Europ\u00e4ischen Union haben laut Sch\u00e4tzungen der Europ\u00e4ischen Kommission bereits zwei von f\u00fcnf Gro\u00dfunternehmen KI-basierte L\u00f6sungen integriert. Zwischen 2023 und 2024 hat sich die Einf\u00fchrung dieser Technologie im Vergleich zum Vorjahr verdoppelt und damit einen Trend zur raschen Expansion gefestigt.<\/p>\n<p>Der Markt f\u00fcr KI-bezogene Technologien hat derzeit ein Volumen von 75 Milliarden US-Dollar, mit einem j\u00e4hrlichen Wachstum von 30 Prozent. Und alles deutet darauf hin, dass er weiter expandieren wird.<\/p>\n<p>Die KI ist l\u00e4ngst nicht mehr auf spezialisierte Bereiche beschr\u00e4nkt, sie ist auch in den Haushalten angekommen: Fast alle modernen Smartphones verf\u00fcgen \u00fcber eine Form der KI-basierten Verarbeitung. Die Technologie ist buchst\u00e4blich in den H\u00e4nden jedes Menschen auf der Welt pr\u00e4sent.<\/p>\n<p>Die f\u00fcr die Entwicklung der KI bereitgestellten Haushaltsmittel spiegeln ihre strategische Bedeutung wider. Die USA haben 500 Milliarden Dollar f\u00fcr das Projekt Stargate bereitgestellt. Die EU hat trotz der Schwierigkeiten ihrer Wirtschaft 200 Milliarden Euro in ihre Initiative InvestAI investiert. Gro\u00dfbritannien hat 14 Milliarden Pfund ausschlie\u00dflich f\u00fcr seine Datenverarbeitungszentren bereitgestellt. Und China hat nach Sch\u00e4tzungen von Experten seine Investitionen in KI allein im Jahr 2024 um 48 Prozent auf 84\u00a0bis 98 Milliarden Dollar erh\u00f6ht.<\/p>\n<p>Dieses exponentielle Wachstum ist nicht autonom: Es h\u00e4ngt direkt vom Zugang zu kritischen Ressourcen und Energiequellen ab.<\/p>\n<p>Seltene Erden sind zu einer neuralgischen Ressource f\u00fcr das Wachstum der Produktion und die Einf\u00fchrung von KI-Standards geworden. Ihre Vorkommen sind jedoch begrenzt, was zu erbitterten Handelsstreitigkeiten zwischen den wichtigsten Anbietern von KI-Technologie gef\u00fchrt hat.<\/p>\n<p>Die politischen Eliten des Westens, die \u00fcber keine eigenen Vorkommen verf\u00fcgen, versuchen, sich den uneingeschr\u00e4nkten Zugang zu den Vorkommen in den L\u00e4ndern der Weltmehrheit zu sichern. Zu diesem Zweck verfolgen sie eine aggressive neokoloniale Politik, die oft an Pl\u00fcnderung und Ausbeutung grenzt.<\/p>\n<p>Laut Berichten der Konferenz der Vereinten Nationen f\u00fcr Handel und Entwicklung (UNCTAD) und des Instituts der Vereinten Nationen f\u00fcr Berufsbildung und Forschung (UNITAR) ist die F\u00f6rderung dieser nat\u00fcrlichen Ressourcen zu einem globalen Kampf um die Umverteilung von Reichtum geworden.<\/p>\n<p>Eine aufschlussreiche Zahl: F\u00fcr die Herstellung eines einzigen 100 Gramm schweren Smartphones werden etwa 70 Kilogramm Rohstoffe ben\u00f6tigt, die haupts\u00e4chlich in den sich entwickelnden L\u00e4ndern gewonnen werden. Angesichts der Tatsache, dass j\u00e4hrlich Milliarden von Smartphones produziert werden, warnen Experten vor einem Ph\u00e4nomen, das sie als &#8220;Mineralienkolonialismus&#8221; bezeichnen, bei dem westliche Unternehmen die Bodensch\u00e4tze und die Arbeitskr\u00e4fte dieser Nationen ausbeuten.<\/p>\n<p>Laut Prognosen wird die F\u00f6rderung von Mineralien, die f\u00fcr die digitale Transformation wichtig sind \u2013 wie Graphit, Lithium und Kobalt \u2013 bis 2050 um 500 Prozent steigen. Ein solch exponentielles Wachstum wird die ohnehin schon ungleiche Verteilung der \u00f6kologischen Belastung und der wirtschaftlichen Vorteile weltweit weiter versch\u00e4rfen.<\/p>\n<p>W\u00e4hrend die L\u00e4nder des sogenannten Kollektiven Westens weiterhin die nat\u00fcrlichen Ressourcen der sich entwickelnden L\u00e4nder ausbeuten, verarmen die L\u00e4nder des Globalen S\u00fcdens noch mehr und werden Opfer der wachsenden digitalen Ungleichheit.<\/p>\n<p>Aber die Auswirkungen beschr\u00e4nken sich nicht auf die Mineralien. Der Energie- und Wasserverbrauch f\u00fcr den Betrieb der Rechenzentren ist ein weiterer kritischer Faktor.<\/p>\n<p>Laut UNCTAD haben sich die Energiekosten der 13 gr\u00f6\u00dften Betreiber von Rechenzentren zwischen 2018 und 2022 verdoppelt. Im Jahr 2022 verbrauchten diese Zentren etwa 460 Terawatt pro Stunde, was dem gesamten Energieverbrauch Frankreichs entspricht, und es wird erwartet, dass sich diese Zahl in den n\u00e4chsten drei Jahren verdreifachen wird.<\/p>\n<p>Die Nutzung von Trinkwasser zur K\u00fchlung von Servern ist ebenso alarmierend. Allein im Jahr 2022 verbrauchte Google mehr als 21 Millionen Kubikmeter Wasser, w\u00e4hrend Microsoft 7 Millionen Kubikmeter ben\u00f6tigte, um sein Modell GPT-3 am Laufen zu halten. Im Kontrast dazu sch\u00e4tzt die UNO, dass 2 Milliarden Menschen auf der Welt keinen verl\u00e4sslichen Zugang zu sauberem Trinkwasser haben.<\/p>\n<p>Diese Realit\u00e4t offenbart eine widerspr\u00fcchliche Priorit\u00e4t: Nach Ansicht der westlichen L\u00e4nder ist Wasser n\u00f6tiger f\u00fcr die Aufrechterhaltung der k\u00fcnstlichen Intelligenz als f\u00fcr die Grundversorgung von Millionen von Menschen weltweit.<\/p>\n<p>Ein neues Element des sich herausbildenden neokolonialen Systems ist die \u00f6kologisch-ideologische Plattform, die von neoliberalen Kr\u00e4ften in den L\u00e4ndern des Kollektiven Westens gef\u00f6rdert wird. Diese M\u00e4chte haben ein universelles System des wirtschaftlichen Laissez-faire entworfen, das die r\u00e4uberischen Dynamiken des unregulierten Kapitalismus reproduziert.<\/p>\n<p>Gleichzeitig fordern sie, dass sich jede wirtschaftliche Entwicklung der &#8220;nicht ausgew\u00e4hlten&#8221; L\u00e4nder strikt an westliche &#8220;gr\u00fcne Standards&#8221; zu halten hat. Nach Jahrzehnten rasanten Wirtschaftswachstums schr\u00e4nken die OECD-Mitgliedsl\u00e4nder nun politisch den Fortschritt der L\u00e4nder der Weltmehrheit ein. Dabei greifen sie selbst oft zu &#8220;schmutzigen Praktiken&#8221;, um ihre Hegemonie aufrechtzuerhalten, solange die Gewinnung und Produktion nat\u00fcrlicher Ressourcen weit entfernt von ihren eigenen St\u00e4dten stattfindet.<\/p>\n<p>Die steigende Nachfrage nach neuartigen Technologien wie Blockchain, k\u00fcnstlicher Intelligenz, 5G-Mobilfunknetzen und dem &#8220;Internet der Dinge&#8221; f\u00fchrt nicht zu einer Verringerung der Schadstoffemissionen, sondern zu deren Anstieg. Der Sektor ist f\u00fcr mehr als 3 Prozent der weltweiten Treibhausgasemissionen verantwortlich und verursacht j\u00e4hrlich bis zu 1,6 Gigatonnen CO\u2082. Die Kohlendioxidemissionen steigen weiterhin rasant an, in geometrischer Progression.<\/p>\n<p>Das bewusste Management der Digitalisierung, die Einf\u00fchrung der KI und die sogenannte &#8220;gr\u00fcne Agenda&#8221; haben eine revolution\u00e4re Phase in der Entwicklung des KI-Sektors ausgel\u00f6st, die als der &#8220;Quantensprung&#8221; bekannt ist.<\/p>\n<p>Am Ende des vergangenen Jahrzehnts wurde eine radikal neue Architektur f\u00fcr die tiefen neuronalen Netze vorgestellt: die Transformer. Zu Beginn dieses Jahrzehnts f\u00fchrte diese Innovation zu Massenprodukten wie ChatGPT, das sich an fast jeden Bereich menschlicher Aktivit\u00e4ten anpassen kann.<\/p>\n<p>Heute ist klar, dass die Prozesse im Zusammenhang mit nachhaltiger Entwicklung, digitaler Transformation, Modernisierung des Verteidigungsbereichs, politischer Gestaltung, Massenkommunikation, Bildung, Gesundheitswesen und sogar kreativen Aktivit\u00e4ten untrennbar mit der universellen Einf\u00fchrung dieser Technologien verbunden sein werden.<\/p>\n<p>Dieses Szenario best\u00e4tigt, was\u00a0Russlands Pr\u00e4sident Wladimir Putin erkl\u00e4rte: Wer bei der Entwicklung dieser Technologie f\u00fchrend ist, wird die Welt beherrschen, und ihre Einf\u00fchrung er\u00f6ffnet ein neues Kapitel in der Geschichte der Menschheit.<\/p>\n<p>Die KI wird somit zu einem Feld geopolitischer Konkurrenz, millionenschwerer Investitionen und neuer Formen der technologischen Expansion, die durch die bereits genannten Motive vorangetrieben werden.<\/p>\n<p>Dar\u00fcber hinaus hat der Fortschritt der KI als autonomer und schnell wachsender Cluster Einzug in die internationalen Beziehungen gehalten. Die Themen im Zusammenhang mit neuronalen Netzen wurden rasch in die Agenda internationaler und regionaler Organisationen aufgenommen.<\/p>\n<p>Unter den wichtigsten Foren ist die Organisation der Vereinten Nationen (UNO), wo zwischenstaatliche Konsultationen stattfinden, um den Globalen Dialog \u00fcber die Governance der KI und die Internationale Wissenschaftliche Gruppe f\u00fcr diese Technologie auf den Weg zu bringen. Au\u00dferdem wird die Schaffung einer speziellen Stiftung im Rahmen der UNO diskutiert, die technische Hilfsprogramme in diesem Bereich unterst\u00fctzen soll.<\/p>\n<p>Seit Anfang des Jahres ist das Digital Office t\u00e4tig, das dem Sekretariat der Vereinten Nationen unterstellt ist. Parallel dazu arbeitet die UNESCO an der Ausarbeitung von ethischen Normen und Standards f\u00fcr KI auf der Grundlage der 2021 verabschiedeten Empfehlung zur Ethik der k\u00fcnstlichen Intelligenz.<\/p>\n<p>Unter der Schirmherrschaft der UNO arbeitet die Globale Allianz f\u00fcr KI in Industrie und Produktion und j\u00e4hrlich findet der Gipfel &#8220;KI f\u00fcr das Gemeinwohl&#8221; statt.<\/p>\n<p>Selbst die Organisation f\u00fcr Sicherheit und Zusammenarbeit in Europa (OSZE) hat Versuche unternommen, sich zu diesem Thema zu \u00e4u\u00dfern.<\/p>\n<p>Diese intensiven multilateralen Prozesse spiegeln die wachsende Rivalit\u00e4t um die F\u00fchrung im Bereich der k\u00fcnstlichen Intelligenz wider. Sie erfordern daher die st\u00e4ndige Aufmerksamkeit und ein aktives Engagement der Staaten, einschlie\u00dflich ihrer Au\u00dfenministerien.<\/p>\n<p>Letztlich wird der Aufbau einer gerechten und multipolaren Weltordnung von der F\u00e4higkeit abh\u00e4ngen, die Versuche zu stoppen, die neokolonialen Ungleichheiten und die Unterdr\u00fcckung der Vergangenheit im digitalen Bereich zu reproduzieren.<\/p>\n<p><em><strong>Maria Sacharowa<\/strong> ist die offizielle Sprecherin des russischen Au\u00dfenministeriums.<\/em><\/p>\n<p><em>Redaktionelle Anmerkung: Dieser Artikel wurde urspr\u00fcnglich am 17. Juli 2025 in der Rossijskaja Gaseta\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.rg.ru\/2025\/07\/17\/neokoloniializm.html\">ver\u00f6ffentlicht<\/a>, jedoch auch im &#8220;Globalen S\u00fcden&#8221; beachtet, so beispielsweise in Venezuela. Die vorstehende \u00dcbersetzung\u00a0 aus dem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/misionverdad.com\/opinion\/neocolonialismo-digital-el-trasfondo-politico-de-la-inteligencia-artificial\">Spanischen<\/a> besorgte Olga Esp\u00edn.<\/em><\/p>\n<p><em>Teil I finden Sie hier.<\/em><\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211;\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/meinung\/252141-ruhmlos-verlaesst-europa-weltbuehne\/\">Alle inneren Ressourcen verloren: Ruhmlos verl\u00e4sst Europa die Weltb\u00fchne<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><\/div><\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/252699-digitaler-neokolonialismus-politische-hintergrund-kuenstlichen\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Von Maria Sacharowa Teil II\u00a0 Zum ersten Teil geht es hier\u00a0lang. Die zweite S\u00e4ule des neuen globalen Kontrollsystems ist die k\u00fcnstliche Intelligenz (KI) selbst und ihr wachsender Einfluss auf die Weltwirtschaft. In der Europ\u00e4ischen Union haben laut Sch\u00e4tzungen der Europ\u00e4ischen Kommission bereits zwei von f\u00fcnf Gro\u00dfunternehmen KI-basierte L\u00f6sungen integriert. Zwischen 2023 und 2024 hat sich [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":88581,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1754820220"],"wp_automatic_camp":["217"],"66d12c71e733be301a2bfdbc20934a2d":["Digitaler Neokolonialismus: Der politische Hintergrund der k\u00fcnstlichen Intelligenz, Teil II"],"original_link":["https:\/\/de.rt.com\/meinung\/252699-digitaler-neokolonialismus-politische-hintergrund-kuenstlichen\/"],"_thumbnail_id":["88581"],"jnews_social_counter_last_update":["1778326515"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-08-10 12:04:38\";}"]},"categories":[19,23],"tags":[82,3497,27125,775,43774,46567,4434,3240],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Digitaler Neokolonialismus: Der politische Hintergrund der k\u00fcnstlichen Intelligenz, Teil II - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Digitaler Neokolonialismus: Der politische Hintergrund der k\u00fcnstlichen Intelligenz, Teil II\" \/>\n<meta property=\"og:description\" content=\"Von Maria Sacharowa Teil II\u00a0 Zum ersten Teil geht es hier\u00a0lang. Die zweite S\u00e4ule des neuen globalen Kontrollsystems ist die k\u00fcnstliche Intelligenz (KI) selbst und ihr wachsender Einfluss auf die Weltwirtschaft. In der Europ\u00e4ischen Union haben laut Sch\u00e4tzungen der Europ\u00e4ischen Kommission bereits zwei von f\u00fcnf Gro\u00dfunternehmen KI-basierte L\u00f6sungen integriert. Zwischen 2023 und 2024 hat sich [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-10T09:50:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/6896235548fbef2a00126894.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Digitaler Neokolonialismus: Der politische Hintergrund der k\u00fcnstlichen Intelligenz, Teil II\",\"datePublished\":\"2025-08-10T09:50:59+00:00\",\"dateModified\":\"2025-08-10T09:50:59+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/\"},\"wordCount\":1386,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Digitaler-Neokolonialismus-Der-politische-Hintergrund-der-kuenstlichen-Intelligenz-Teil-II.jpg\",\"keywords\":[\"der\",\"digitaler\",\"Hintergrund\",\"Intelligenz\",\"K\u00fcnstlichen\",\"Neokolonialismus\",\"politische\",\"Teil\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/\",\"name\":\"Digitaler Neokolonialismus: Der politische Hintergrund der k\u00fcnstlichen Intelligenz, Teil II - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Digitaler-Neokolonialismus-Der-politische-Hintergrund-der-kuenstlichen-Intelligenz-Teil-II.jpg\",\"datePublished\":\"2025-08-10T09:50:59+00:00\",\"dateModified\":\"2025-08-10T09:50:59+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Digitaler-Neokolonialismus-Der-politische-Hintergrund-der-kuenstlichen-Intelligenz-Teil-II.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Digitaler-Neokolonialismus-Der-politische-Hintergrund-der-kuenstlichen-Intelligenz-Teil-II.jpg\",\"width\":460,\"height\":259,\"caption\":\"Digitaler Neokolonialismus: Der politische Hintergrund der k\u00fcnstlichen Intelligenz, Teil II\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Digitaler Neokolonialismus: Der politische Hintergrund der k\u00fcnstlichen Intelligenz, Teil II\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Digitaler Neokolonialismus: Der politische Hintergrund der k\u00fcnstlichen Intelligenz, Teil II - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/","og_locale":"de_DE","og_type":"article","og_title":"Digitaler Neokolonialismus: Der politische Hintergrund der k\u00fcnstlichen Intelligenz, Teil II","og_description":"Von Maria Sacharowa Teil II\u00a0 Zum ersten Teil geht es hier\u00a0lang. Die zweite S\u00e4ule des neuen globalen Kontrollsystems ist die k\u00fcnstliche Intelligenz (KI) selbst und ihr wachsender Einfluss auf die Weltwirtschaft. In der Europ\u00e4ischen Union haben laut Sch\u00e4tzungen der Europ\u00e4ischen Kommission bereits zwei von f\u00fcnf Gro\u00dfunternehmen KI-basierte L\u00f6sungen integriert. Zwischen 2023 und 2024 hat sich [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-08-10T09:50:59+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/6896235548fbef2a00126894.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"7\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Digitaler Neokolonialismus: Der politische Hintergrund der k\u00fcnstlichen Intelligenz, Teil II","datePublished":"2025-08-10T09:50:59+00:00","dateModified":"2025-08-10T09:50:59+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/"},"wordCount":1386,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Digitaler-Neokolonialismus-Der-politische-Hintergrund-der-kuenstlichen-Intelligenz-Teil-II.jpg","keywords":["der","digitaler","Hintergrund","Intelligenz","K\u00fcnstlichen","Neokolonialismus","politische","Teil"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/","url":"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/","name":"Digitaler Neokolonialismus: Der politische Hintergrund der k\u00fcnstlichen Intelligenz, Teil II - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Digitaler-Neokolonialismus-Der-politische-Hintergrund-der-kuenstlichen-Intelligenz-Teil-II.jpg","datePublished":"2025-08-10T09:50:59+00:00","dateModified":"2025-08-10T09:50:59+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Digitaler-Neokolonialismus-Der-politische-Hintergrund-der-kuenstlichen-Intelligenz-Teil-II.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Digitaler-Neokolonialismus-Der-politische-Hintergrund-der-kuenstlichen-Intelligenz-Teil-II.jpg","width":460,"height":259,"caption":"Digitaler Neokolonialismus: Der politische Hintergrund der k\u00fcnstlichen Intelligenz, Teil II"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/digitaler-neokolonialismus-der-politische-hintergrund-der-kuenstlichen-intelligenz-teil-ii\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Digitaler Neokolonialismus: Der politische Hintergrund der k\u00fcnstlichen Intelligenz, Teil II"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/88580"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=88580"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/88580\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/88581"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=88580"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=88580"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=88580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}