{"id":88367,"date":"2025-08-06T11:45:27","date_gmt":"2025-08-06T09:45:27","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/"},"modified":"2025-08-06T11:45:27","modified_gmt":"2025-08-06T09:45:27","slug":"warum-schickt-trump-seinen-boten-zu-putin","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/","title":{"rendered":"Warum schickt Trump seinen Boten zu Putin?"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/6893017148fbef08967d726e.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Im Vorfeld des Besuchs des US-Sondergesandten Witkoff drohte Trump mit  neuen Sanktionen. Sollte bis zum 8. August keine Einigung zustande kommen, sollen auch L\u00e4nder bestraft werden, die mit Russland handelt. Trump ist entt\u00e4uscht. Vor allem von sich selbst. Seine Erwartungen waren zu hoch.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Pjotr Akopow<\/em><\/p>\n<p>Am Freitag l\u00e4uft das dem russischen Pr\u00e4sidenten Wladimir Putin von US-Pr\u00e4sident Donald Trump gestellte Ultimatum ab: entweder ein Waffenstillstand in der Ukraine oder neue Sanktionen gegen Russland. Doch bereits morgen oder \u00fcbermorgen wird Steve Witkoff in Moskau eintreffen\u00a0\u2013 der Besuch seines Sonderbeauftragten wurde vom US-Pr\u00e4sidenten selbst angek\u00fcndigt. Handelt es sich hierbei um einen letzten Versuch, eine Einigung zu erzielen, oder um eine reine Formalit\u00e4t?<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6v0jui\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<p><a><\/a> Witkoff war seit mehr als drei Monaten nicht mehr in Russland, obwohl er unser Land in den vorangegangenen drei Monaten viermal besucht hatte. Seither \u00e4nderte Trump seine Haltung: Er \u00e4u\u00dferte sich entt\u00e4uscht \u00fcber Putin und erkl\u00e4rte sich bereit, Sanktionen gegen Russland zu verh\u00e4ngen und die Waffenlieferungen an die Ukraine zu intensivieren (die Kosten daf\u00fcr soll die Europ\u00e4ische Union \u00fcbernehmen). Welche Sanktionen Trump genau plant, ist noch unklar, doch es d\u00fcrfte sich um Ma\u00dfnahmen handeln, die den Export russischer Energietr\u00e4ger beeintr\u00e4chtigen sollen. Trump droht mit erh\u00f6hten Einfuhrz\u00f6llen f\u00fcr Waren aus L\u00e4ndern, die aktiv russisches \u00d6l und Gas kaufen, darunter vor allem China, Indien und die T\u00fcrkei. Aber keines dieser L\u00e4nder beabsichtigt, auf die sehr vorteilhaften Importe aus Russland zu verzichten\u00a0\u2013 denn hier geht es nicht nur um wirtschaftliche, sondern auch um politische, ja sogar geopolitische Fragen. Dar\u00fcber hinaus f\u00fchren die USA mit Peking und Neu-Delhi noch immer Verhandlungen \u00fcber neue Handelsbedingungen und drohen ihnen mit hohen Z\u00f6llen. Zu diesen ohnehin schon schwierigen Verhandlungen kommt nun noch die Forderung hinzu, auf russische Energietr\u00e4ger zu verzichten, was die Chinesen und Inder nur in ihrer Meinung best\u00e4rken kann, dass normale, stabile Vereinbarungen mit den USA ausgeschlossen sind.<\/p>\n<p>Worauf st\u00fctzt sich Trump also, um Putin drohen zu k\u00f6nnen? Schlie\u00dflich gab er in den letzten Tagen mehrfach zu, dass die Russen gelernt h\u00e4tten, die Sanktionen zu umgehen, und er daher die Auswirkungen der neuen US-Ma\u00dfnahmen nicht vorhersagen k\u00f6nne. Dabei geht Trump davon aus, dass die neuen Sanktionen im Gro\u00dfen und Ganzen funktionieren\u00a0\u2013 beispielsweise halte Indien sie ein. Dies ist jedoch nicht der Fall: Aus Neu-Delhi wurde bereits mitgeteilt, man habe nicht die Absicht, auf russisches \u00d6l zu verzichten. Ganz zu schweigen von China\u00a0\u2013 die Gas- und \u00d6llieferungen aus Russland werden weiter zunehmen. Warum also greift Trump dieses Thema \u00fcberhaupt auf?<\/p>\n<p>Wie Putin sagte, seien \u00fcbertriebene Erwartungen der Grund f\u00fcr die Entt\u00e4uschung\u00a0\u2013 und genau darum geht es hier. Trump \u00fcbersch\u00e4tzte seine Einflussm\u00f6glichkeiten im Ukraine-Konflikt\u00a0\u2013 er glaubte, Russland w\u00fcrde sich bereit erkl\u00e4ren, &#8220;Gewinne zu sichern&#8221;, also die Lage an der Frontlinie einzufrieren. Worauf beruhen diese Erwartungen? Gab Putin in seinen Gespr\u00e4chen mit Witkoff und in Telefonaten mit Trump selbst Anlass zu solchen Erwartungen? Nat\u00fcrlich nicht \u2013 jedoch interpretierte Trump Putins Position als Verhandlungsspielraum, als M\u00f6glichkeit zum Feilschen.<\/p>\n<p>Dabei war unsere Position von Anfang an ganz konkret und eindeutig: die Beendigung der Milit\u00e4rhilfe f\u00fcr die Ukraine, die Garantie, dass die Ukraine nicht der NATO beitritt (und dass keine westlichen Milit\u00e4rs auf ihrem Territorium stationiert werden), die \u00dcbergabe der unter der Kontrolle der ukrainischen Streitkr\u00e4fte verbliebenen Territorien der neuen russischen Gebiete an Russland\u00a0\u2013 und dann w\u00fcrde ein stabiler Waffenstillstand eintreten, dem Friedensverhandlungen folgen w\u00fcrden. Dies ist eine kurze Zusammenfassung der Bedingungen Russlands\u00a0\u2013 ausf\u00fchrlicher waren sie bereits im vergangenen Jahr von Putin in seiner Rede im russischen Au\u00dfenministerium formuliert worden, worauf er k\u00fcrzlich erneut hinwies. H\u00e4tte Trump diese Bedingungen erf\u00fcllen k\u00f6nnen?<\/p>\n<p>Rein theoretisch ja\u00a0\u2013 wenn er maximalen Druck auf Kiew und Europa ausge\u00fcbt h\u00e4tte. Ja, das h\u00e4tte zu sehr ernsten Problemen zwischen den beiden Seiten des Atlantiks gef\u00fchrt und einen Schock oder sogar Unruhen in Kiew ausgel\u00f6st, aber wenn Trump hart geblieben w\u00e4re und weiter Druck ausge\u00fcbt h\u00e4tte, w\u00e4re eine Waffenruhe durchaus m\u00f6glich gewesen. Der US-Pr\u00e4sident beschr\u00e4nkte sich jedoch haupts\u00e4chlich auf demonstrative Ma\u00dfnahmen\u00a0\u2013 er stellte Wladimir Selenskij blo\u00df und erkl\u00e4rte, dass es unm\u00f6glich sei, die Ukraine in die NATO aufzunehmen. Doch die Lieferungen von US-Waffen wurden fortgesetzt, die milit\u00e4rische Zusammenarbeit zwischen Europa und der Ukraine wurde intensiviert, und Emmanuel Macron sowie Keir Starmer bestanden darauf, unmittelbar nach dem Waffenstillstand ein Milit\u00e4rkontingent in die Ukraine zu entsenden \u2013 mit anderen Worten, es wurde alles getan, um Moskau davon zu \u00fcberzeugen, dass der Westen nicht den geringsten Willen hat, den Konflikt zu beenden. Putin hatte ohnehin keine Illusionen \u00fcber die Bereitschaft des Westens, zumindest einen neutralen Status f\u00fcr die Nachkriegs-Ukraine zu akzeptieren\u00a0\u2013 und genau das wurde durch das Verhalten der Atlantiker in den letzten Monaten best\u00e4tigt.<\/p>\n<p>Man k\u00f6nnte zwar verhandeln, aber die russische Milit\u00e4roffensive wird fortgesetzt\u00a0\u2013 Russland wird seine Forderungen und Ziele nicht aufgeben. Sollte der Westen bereit sein, diese anzuerkennen, dann nehmen wir echte Verhandlungen auf: \u00fcber einen Waffenstillstand, \u00fcber ein Friedensabkommen, \u00fcber die Nachkriegsordnung der Ukraine, \u00fcber die europ\u00e4ische Sicherheit und \u00fcber eine neue Weltordnung. Bei Witkoffs f\u00fcnftem Besuch in Moskau geht es eindeutig nicht darum.<\/p>\n<p><em>\u00dcbersetzt aus dem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/ria.ru\/20250805\/tramp-2033346188.html\">Russischen<\/a>. Der Artikel ist am 5.\u00a0August 2025 zuerst bei RIA Nowosti erschienen.<\/em><\/p>\n<p><strong>Mehr zum Thema\u00a0<\/strong>\u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/252388-im-toten-winkel-nachrichten-mainstream\/\">Im toten Winkel der Nachrichten: Mainstream berichtet nicht mehr \u00fcber die Ukraine-Front<\/a><em><br \/><\/em><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6uz80k\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/252516-warum-schickt-trump-seinen-boten-zu-putin\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Im Vorfeld des Besuchs des US-Sondergesandten Witkoff drohte Trump mit neuen Sanktionen. Sollte bis zum 8. August keine Einigung zustande kommen, sollen auch L\u00e4nder bestraft werden, die mit Russland handelt. Trump ist entt\u00e4uscht. Vor allem von sich selbst. Seine Erwartungen waren zu hoch. Von Pjotr Akopow Am Freitag l\u00e4uft das dem russischen Pr\u00e4sidenten Wladimir Putin [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":88368,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1754473852"],"wp_automatic_camp":["217"],"ce8130637fd69ee3fc0b76e7b59540ce":["Warum schickt Trump seinen Boten zu Putin?"],"original_link":["https:\/\/de.rt.com\/international\/252516-warum-schickt-trump-seinen-boten-zu-putin\/"],"_thumbnail_id":["88368"],"jnews_social_counter_last_update":["1784022888"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-08-06 11:51:57\";}"]},"categories":[19,23],"tags":[14710,125,2679,6583,1639,1289],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Warum schickt Trump seinen Boten zu Putin? - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Warum schickt Trump seinen Boten zu Putin?\" \/>\n<meta property=\"og:description\" content=\"Im Vorfeld des Besuchs des US-Sondergesandten Witkoff drohte Trump mit neuen Sanktionen. Sollte bis zum 8. August keine Einigung zustande kommen, sollen auch L\u00e4nder bestraft werden, die mit Russland handelt. Trump ist entt\u00e4uscht. Vor allem von sich selbst. Seine Erwartungen waren zu hoch. Von Pjotr Akopow Am Freitag l\u00e4uft das dem russischen Pr\u00e4sidenten Wladimir Putin [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-08-06T09:45:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/6893017148fbef08967d726e.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Warum schickt Trump seinen Boten zu Putin?\",\"datePublished\":\"2025-08-06T09:45:27+00:00\",\"dateModified\":\"2025-08-06T09:45:27+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/\"},\"wordCount\":932,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Warum-schickt-Trump-seinen-Boten-zu-Putin.jpg\",\"keywords\":[\"boten\",\"putin\",\"schickt\",\"seinen\",\"trump\",\"Warum\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/\",\"name\":\"Warum schickt Trump seinen Boten zu Putin? - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Warum-schickt-Trump-seinen-Boten-zu-Putin.jpg\",\"datePublished\":\"2025-08-06T09:45:27+00:00\",\"dateModified\":\"2025-08-06T09:45:27+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Warum-schickt-Trump-seinen-Boten-zu-Putin.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Warum-schickt-Trump-seinen-Boten-zu-Putin.jpg\",\"width\":460,\"height\":259,\"caption\":\"Warum schickt Trump seinen Boten zu Putin?\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Warum schickt Trump seinen Boten zu Putin?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Warum schickt Trump seinen Boten zu Putin? - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/","og_locale":"de_DE","og_type":"article","og_title":"Warum schickt Trump seinen Boten zu Putin?","og_description":"Im Vorfeld des Besuchs des US-Sondergesandten Witkoff drohte Trump mit neuen Sanktionen. Sollte bis zum 8. August keine Einigung zustande kommen, sollen auch L\u00e4nder bestraft werden, die mit Russland handelt. Trump ist entt\u00e4uscht. Vor allem von sich selbst. Seine Erwartungen waren zu hoch. Von Pjotr Akopow Am Freitag l\u00e4uft das dem russischen Pr\u00e4sidenten Wladimir Putin [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-08-06T09:45:27+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/6893017148fbef08967d726e.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Warum schickt Trump seinen Boten zu Putin?","datePublished":"2025-08-06T09:45:27+00:00","dateModified":"2025-08-06T09:45:27+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/"},"wordCount":932,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Warum-schickt-Trump-seinen-Boten-zu-Putin.jpg","keywords":["boten","putin","schickt","seinen","trump","Warum"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/","url":"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/","name":"Warum schickt Trump seinen Boten zu Putin? - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Warum-schickt-Trump-seinen-Boten-zu-Putin.jpg","datePublished":"2025-08-06T09:45:27+00:00","dateModified":"2025-08-06T09:45:27+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Warum-schickt-Trump-seinen-Boten-zu-Putin.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/08\/Warum-schickt-Trump-seinen-Boten-zu-Putin.jpg","width":460,"height":259,"caption":"Warum schickt Trump seinen Boten zu Putin?"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/warum-schickt-trump-seinen-boten-zu-putin\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Warum schickt Trump seinen Boten zu Putin?"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/88367"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=88367"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/88367\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/88368"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=88367"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=88367"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=88367"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}