{"id":87987,"date":"2025-07-29T20:18:14","date_gmt":"2025-07-29T18:18:14","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/"},"modified":"2025-07-29T20:18:14","modified_gmt":"2025-07-29T18:18:14","slug":"rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/","title":{"rendered":"Rum\u00e4nien: Keine Pl\u00e4ne zum Kriegseintritt aufseiten Kiews"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/07\/6888f7b1b480cc022179a4a1.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Das rum\u00e4nische Innenministerium hat via Facebook Berichte zur\u00fcckgewiesen, wonach das Land im Herbst in den Krieg in der Ukraine eintreten werde. Zuvor war im Netz ein Video aufgetaucht, in dem Ministerpr\u00e4sident Ilie Bolojan angeblich die Teilnahme am Konflikt angek\u00fcndigt hatte.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>In einem auf Facebook ver\u00f6ffentlichten Beitrag hat das rum\u00e4nische Innenministerium Meldungen dementiert, wonach Rum\u00e4nien im September in den Krieg in der Ukraine eintreten werde. Zuvor war in den sozialen Netzwerken ein Video verbreitet worden, in dem der rum\u00e4nische Ministerpr\u00e4sident Ilie Bolojan angeblich die baldige Teilnahme Rum\u00e4niens am Konflikt in der Ukraine ank\u00fcndigt.<\/p>\n<p>In diesem Zusammenhang warnte das Innenministerium in Bukarest vor einer Kampagne zur Verbreitung von Videoclips, die mithilfe k\u00fcnstlicher Intelligenz (KI) erstellt worden seien.<\/p>\n<p>Die gef\u00e4lschten Videos seien Teil eines Versuchs, die \u00f6ffentliche Meinung im Land gezielt zu manipulieren, erkl\u00e4rte die Beh\u00f6rde. Der rum\u00e4nische Ministerpr\u00e4sident habe solche Aussagen nicht gemacht, und Rum\u00e4nien trete nicht in den Ukraine-Konflikt ein.<\/p>\n<p>Hierbei riefen die Strafverfolgungsbeh\u00f6rde rum\u00e4nische Bev\u00f6lkerung nachdr\u00fccklich dazu auf, die Informationsquellen sorgf\u00e4ltig zu pr\u00fcfen und von der Verbreitung nicht verifizierter Inhalte abzusehen.<\/p>\n<p>Die rum\u00e4nischen B\u00fcrger, vor allem M\u00e4nner im wehrf\u00e4higen Alter, beobachten die anhaltenden K\u00e4mpfe im Nachbarstaat mit gro\u00dfer Sorge, berichtet die Nachrichtenagentur <em>TASS<\/em>. Rum\u00e4nien grenzt an die Ukraine im Norden. Deshalb l\u00f6sten selbst allt\u00e4gliche Nachrichten wie die geplante Einberufung von Reservisten bei vielen Rum\u00e4nen mittlerweile Panik aus.<\/p>\n<p>Wie es hei\u00dft, sei Rum\u00e4nien derzeit dabei, im gro\u00dfen Stil moderne Waffensysteme zu beschaffen. Au\u00dferdem werde im Land \u00fcber die Notwendigkeit diskutiert, die Streitkr\u00e4fte aufzustocken.<\/p>\n<p>Es sei auch bekannt, dass Rum\u00e4nien auf seinem Staatsgebiet ukrainische Piloten ausbilde und Kiew milit\u00e4rische Hilfe leiste, wobei es sich weigere, den Umfang und die Art dieser Unterst\u00fctzung offenzulegen.<\/p>\n<p>Vor diesem Hintergrund w\u00fcrden beharrliche Beteuerungen der rum\u00e4nischen Beh\u00f6rden, das Land werde keine Truppen in die Ukraine entsenden, mit Misstrauen aufgenommen.<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2012\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/245549-unangebracht-rumaeniens-gewaehlter-praesident-lehnt-ukraine-einsatz-ab\/\">&#8220;Unangebracht&#8221; \u2013 Rum\u00e4niens gew\u00e4hlter Pr\u00e4sident lehnt Ukraine-Einsatz ab<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6unfx0\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/251941-rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-der-ukraine\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das rum\u00e4nische Innenministerium hat via Facebook Berichte zur\u00fcckgewiesen, wonach das Land im Herbst in den Krieg in der Ukraine eintreten werde. Zuvor war im Netz ein Video aufgetaucht, in dem Ministerpr\u00e4sident Ilie Bolojan angeblich die Teilnahme am Konflikt angek\u00fcndigt hatte. In einem auf Facebook ver\u00f6ffentlichten Beitrag hat das rum\u00e4nische Innenministerium Meldungen dementiert, wonach Rum\u00e4nien im [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":87988,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1753813116"],"wp_automatic_camp":["217"],"f3aa1c18c93fac9930f753f70f1f2b8a":["Rum\u00e4nien: Keine Pl\u00e4ne zum Kriegseintritt aufseiten Kiews"],"original_link":["https:\/\/de.rt.com\/international\/251941-rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-der-ukraine\/"],"_thumbnail_id":["87988"],"jnews_social_counter_last_update":["1778499851"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-07-29 20:19:39\";}"]},"categories":[19,23],"tags":[36873,375,6313,66716,5349,24443,565],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Rum\u00e4nien: Keine Pl\u00e4ne zum Kriegseintritt aufseiten Kiews - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Rum\u00e4nien: Keine Pl\u00e4ne zum Kriegseintritt aufseiten Kiews\" \/>\n<meta property=\"og:description\" content=\"Das rum\u00e4nische Innenministerium hat via Facebook Berichte zur\u00fcckgewiesen, wonach das Land im Herbst in den Krieg in der Ukraine eintreten werde. Zuvor war im Netz ein Video aufgetaucht, in dem Ministerpr\u00e4sident Ilie Bolojan angeblich die Teilnahme am Konflikt angek\u00fcndigt hatte. In einem auf Facebook ver\u00f6ffentlichten Beitrag hat das rum\u00e4nische Innenministerium Meldungen dementiert, wonach Rum\u00e4nien im [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-07-29T18:18:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/07\/6888f7b1b480cc022179a4a1.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Rum\u00e4nien: Keine Pl\u00e4ne zum Kriegseintritt aufseiten Kiews\",\"datePublished\":\"2025-07-29T18:18:14+00:00\",\"dateModified\":\"2025-07-29T18:18:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/\"},\"wordCount\":362,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/07\/Rumaenien-Keine-Plaene-zum-Kriegseintritt-aufseiten-Kiews.jpg\",\"keywords\":[\"aufseiten\",\"keine\",\"Kiews\",\"Kriegseintritt\",\"Pl\u00e4ne\",\"Rum\u00e4nien\",\"zum\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/\",\"name\":\"Rum\u00e4nien: Keine Pl\u00e4ne zum Kriegseintritt aufseiten Kiews - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/07\/Rumaenien-Keine-Plaene-zum-Kriegseintritt-aufseiten-Kiews.jpg\",\"datePublished\":\"2025-07-29T18:18:14+00:00\",\"dateModified\":\"2025-07-29T18:18:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/07\/Rumaenien-Keine-Plaene-zum-Kriegseintritt-aufseiten-Kiews.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/07\/Rumaenien-Keine-Plaene-zum-Kriegseintritt-aufseiten-Kiews.jpg\",\"width\":460,\"height\":259,\"caption\":\"Rum\u00e4nien: Keine Pl\u00e4ne zum Kriegseintritt aufseiten Kiews\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Rum\u00e4nien: Keine Pl\u00e4ne zum Kriegseintritt aufseiten Kiews\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Rum\u00e4nien: Keine Pl\u00e4ne zum Kriegseintritt aufseiten Kiews - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/","og_locale":"de_DE","og_type":"article","og_title":"Rum\u00e4nien: Keine Pl\u00e4ne zum Kriegseintritt aufseiten Kiews","og_description":"Das rum\u00e4nische Innenministerium hat via Facebook Berichte zur\u00fcckgewiesen, wonach das Land im Herbst in den Krieg in der Ukraine eintreten werde. Zuvor war im Netz ein Video aufgetaucht, in dem Ministerpr\u00e4sident Ilie Bolojan angeblich die Teilnahme am Konflikt angek\u00fcndigt hatte. In einem auf Facebook ver\u00f6ffentlichten Beitrag hat das rum\u00e4nische Innenministerium Meldungen dementiert, wonach Rum\u00e4nien im [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-07-29T18:18:14+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/07\/6888f7b1b480cc022179a4a1.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Rum\u00e4nien: Keine Pl\u00e4ne zum Kriegseintritt aufseiten Kiews","datePublished":"2025-07-29T18:18:14+00:00","dateModified":"2025-07-29T18:18:14+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/"},"wordCount":362,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/07\/Rumaenien-Keine-Plaene-zum-Kriegseintritt-aufseiten-Kiews.jpg","keywords":["aufseiten","keine","Kiews","Kriegseintritt","Pl\u00e4ne","Rum\u00e4nien","zum"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/","url":"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/","name":"Rum\u00e4nien: Keine Pl\u00e4ne zum Kriegseintritt aufseiten Kiews - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/07\/Rumaenien-Keine-Plaene-zum-Kriegseintritt-aufseiten-Kiews.jpg","datePublished":"2025-07-29T18:18:14+00:00","dateModified":"2025-07-29T18:18:14+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/07\/Rumaenien-Keine-Plaene-zum-Kriegseintritt-aufseiten-Kiews.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/07\/Rumaenien-Keine-Plaene-zum-Kriegseintritt-aufseiten-Kiews.jpg","width":460,"height":259,"caption":"Rum\u00e4nien: Keine Pl\u00e4ne zum Kriegseintritt aufseiten Kiews"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/rumaenien-keine-plaene-zum-kriegseintritt-aufseiten-kiews\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Rum\u00e4nien: Keine Pl\u00e4ne zum Kriegseintritt aufseiten Kiews"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/87987"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=87987"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/87987\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/87988"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=87987"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=87987"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=87987"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}