{"id":8774,"date":"2022-05-25T06:45:00","date_gmt":"2022-05-25T04:45:00","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\/"},"modified":"2022-05-25T06:45:00","modified_gmt":"2022-05-25T04:45:00","slug":"die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\/","title":{"rendered":"Die Ukraine durch Diebstahl russischen Verm\u00f6gens &quot;aus der Asche erheben&quot; \u2013 von der Leyen in Davos"},"content":{"rendered":"<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>EU-Kommissionspr\u00e4sidentin Ursula von der Leyen wurde auf dem Weltwirtschaftsforum in Davos pathetisch. &#8220;Wir mobilisieren unsere gesamte wirtschaftliche Macht&#8221;, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.tagesschau.de\/ausland\/europa\/weltwirtschaftsforum-davos-treffen-101.html\">erkl\u00e4rte<\/a> sie, &#8220;die Ukraine muss diesen Krieg gewinnen.&#8221;<\/p>\n<p>Weitere zehn Milliarden Euro Finanzhilfe sollen an das Land gehen, dem von der Leyen &#8220;Hand in Hand helfen&#8221; will, &#8220;sich aus der Asche zu erheben&#8221;. Dabei erwog sie auch den Diebstahl russischen Verm\u00f6gens: &#8220;Wir sollten daf\u00fcr jeden Stein umdrehen \u2013 wenn m\u00f6glich auch russische Verm\u00f6genswerte, die wir eingefroren haben.&#8221;<\/p>\n<div class=\"ReadMore-root Section-root Section-is1to3-xs_is1to1\" data-widgets=\"ReadMore\" data-has-alias>\n<div class=\"Section-container Section-isRow-isTop-isWrap\">\n<article class=\"Card-root Card-is1to1 \">\n<div class=\"Card-imageWrap\">\n<div class=\"Card-picture\">\n<picture class=\"Picture-root Picture-default\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/628c943b48fbef038c764e9e.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/1653415682_57_628c943b48fbef038c764e9e.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/628c943b48fbef038c764e9e.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/1653415682_57_628c943b48fbef038c764e9e.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-default lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/628c943b48fbef038c764e9e.jpg\" alt=\"Kreml weist Verantwortung f\u00fcr drohende Nahrungsmittelkrise von sich\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/1653415682_57_628c943b48fbef038c764e9e.jpg\" alt=\"Kreml weist Verantwortung f\u00fcr drohende Nahrungsmittelkrise von sich\"><\/noscript>    <\/div><\/div>\n<div class=\"Card-contentWrap\">\n<div class=\"Card-content\">\n<div class=\"Card-title\">\n<div class=\"HeaderNews-root HeaderNews-type_6 \">\n<p>            <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/international\/139224-kreml-weist-schuld-an-drohender-hungerkrise-zurueck\/\" class=\"Link-root Link-isFullCard \"><br \/>\n                Kreml weist Verantwortung f\u00fcr drohende Nahrungsmittelkrise von sich<br \/>\n            <\/a><\/p><\/div><\/div><\/div><\/div>\n<\/article>\n<\/div><\/div>\n<p>Russland nutze Getreide und Energie als Waffe, so ihr Vorwurf; als Beispiel f\u00fcr L\u00e4nder, die darunter zu leiden h\u00e4tten, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.spiegel.de\/wirtschaft\/soziales\/ursula-von-der-leyen-beim-wef-in-davos-russland-nutzt-hunger-und-getreide-um-macht-auszuueben-a-c42af96b-a608-4d6c-ba18-073e0b5f4035\">nannte<\/a> sie ausgerechnet den Libanon, in dem der Brotpreis um 70 Prozent gestiegen sei. Dass der Libanon ebenfalls das Ziel westlicher Sanktionen ist, erw\u00e4hnte sie in diesem Zusammenhang nicht.<\/p>\n<p>Die EU-Kommissionspr\u00e4sidentin sieht auch keinen Widerspruch gegen die Pl\u00e4ne, den Anteil &#8220;gr\u00fcner&#8221; Energiequellen bis 2030 auf 45 Prozent zu erh\u00f6hen und dadurch den Bedarf an russischen fossilen Brennstoffen weiter zu senken. Der Krieg in der Ukraine zwinge die EU dazu, die Transformation der europ\u00e4ischen Wirtschaft zu beschleunigen.<\/p>\n<p>Nachdem bereits sowohl die Chemie- als auch die Automobilindustrie erkl\u00e4rt hatten, unter den durch die Sanktionen geschaffenen Bedingungen k\u00f6nnten sie nicht produzieren, sind nach <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.handelsblatt.com\/politik\/international\/weltwirtschaftsforum-in-davos-von-der-leyen-skizziert-globale-krisenreaktion-aerger-kommt-aus-den-eigenen-reihen\/28371324.html\">Angaben<\/a> des <em>Handelsblatts<\/em> die angek\u00fcndigten Pl\u00e4ne der Kommission auch beim Mittelstand auf wenig Gegenliebe gesto\u00dfen. Dessen Verb\u00e4nde wandten sich in einem Brief an von der Leyen und forderten ein Ende der Mehrbelastungen und mehr Zeit f\u00fcr die erforderlichen Anpassungen. Das Lieferkettengesetz sowie die Einf\u00fchrung eines CO\u2082-Grenzausgleichsmechanismus und diverse Vorgaben f\u00fcr strengere Nachweispflichten sollten ihrer Ansicht nach verschoben werden.<\/p>\n<p>Auch der Pr\u00e4sident des Verbands der europ\u00e4ischen Industrie- und Handelskammern (Eurochambres), Luc Frieden, erkl\u00e4rte, von der Leyen m\u00fcsse sich &#8220;mit der Wirtschaft neu abstimmen&#8221;.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/europa\/139244-litauen-fordert-marinekoalition-zur-eskortierung-ukrainischen-getreides\/\">Litauen fordert Marinekoalition zur Eskortierung von Getreide aus der Ukraine<\/a><\/p>\n<\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/139293-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>EU-Kommissionspr\u00e4sidentin Ursula von der Leyen wurde auf dem Weltwirtschaftsforum in Davos pathetisch. &#8220;Wir mobilisieren unsere gesamte wirtschaftliche Macht&#8221;, erkl\u00e4rte sie, &#8220;die Ukraine muss diesen Krieg gewinnen.&#8221; Weitere zehn Milliarden Euro Finanzhilfe sollen an das Land gehen, dem von der Leyen &#8220;Hand in Hand helfen&#8221; will, &#8220;sich aus der Asche zu erheben&#8221;. Dabei erwog sie auch [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":8700,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["217"],"d7b3750a449c8d6d879920e8d476724b":["Die Ukraine durch Diebstahl russischen Verm\u00f6gens &quot;aus der Asche erheben&quot; \u2013 von der Leyen in Davos"],"original_link":["https:\/\/de.rt.com\/europa\/139293-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben\/"],"_thumbnail_id":["8700"],"_wptg_p2tg_sent2tg":["2022-05-25 07:05:59"],"jnews_social_counter_last_update":["1788271831"]},"categories":[19,23],"tags":[21730,92,82,45,11617,1024,21731,368,21729,973,127,21728,50],"class_list":["post-8774","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-asche","tag-davos","tag-der","tag-die","tag-diebstahl","tag-durch","tag-erhebenquot","tag-leyen","tag-quotaus","tag-russischen","tag-ukraine","tag-vermoegens","tag-von"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Die Ukraine durch Diebstahl russischen Verm\u00f6gens &quot;aus der Asche erheben&quot; \u2013 von der Leyen in Davos - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Ukraine durch Diebstahl russischen Verm\u00f6gens &quot;aus der Asche erheben&quot; \u2013 von der Leyen in Davos\" \/>\n<meta property=\"og:description\" content=\"EU-Kommissionspr\u00e4sidentin Ursula von der Leyen wurde auf dem Weltwirtschaftsforum in Davos pathetisch. &#8220;Wir mobilisieren unsere gesamte wirtschaftliche Macht&#8221;, erkl\u00e4rte sie, &#8220;die Ukraine muss diesen Krieg gewinnen.&#8221; Weitere zehn Milliarden Euro Finanzhilfe sollen an das Land gehen, dem von der Leyen &#8220;Hand in Hand helfen&#8221; will, &#8220;sich aus der Asche zu erheben&#8221;. Dabei erwog sie auch [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-25T04:45:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Kreml-weist-Verantwortung-fuer-drohende-Nahrungsmittelkrise-von-sich.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"460\" \/>\n\t<meta property=\"og:image:height\" content=\"259\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Die Ukraine durch Diebstahl russischen Verm\u00f6gens &quot;aus der Asche erheben&quot; \u2013 von der Leyen in Davos\",\"datePublished\":\"2022-05-25T04:45:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\\\/\"},\"wordCount\":345,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/05\\\/Kreml-weist-Verantwortung-fuer-drohende-Nahrungsmittelkrise-von-sich.jpg\",\"keywords\":[\"Asche\",\"Davos\",\"der\",\"die\",\"Diebstahl\",\"durch\",\"erhebenquot\",\"Leyen\",\"quotaus\",\"russischen\",\"ukraine\",\"Verm\u00f6gens\",\"von\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\\\/\",\"name\":\"Die Ukraine durch Diebstahl russischen Verm\u00f6gens &quot;aus der Asche erheben&quot; \u2013 von der Leyen in Davos - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/05\\\/Kreml-weist-Verantwortung-fuer-drohende-Nahrungsmittelkrise-von-sich.jpg\",\"datePublished\":\"2022-05-25T04:45:00+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/05\\\/Kreml-weist-Verantwortung-fuer-drohende-Nahrungsmittelkrise-von-sich.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/05\\\/Kreml-weist-Verantwortung-fuer-drohende-Nahrungsmittelkrise-von-sich.jpg\",\"width\":460,\"height\":259,\"caption\":\"Kreml weist Verantwortung f\u00fcr drohende Nahrungsmittelkrise von sich\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Ukraine durch Diebstahl russischen Verm\u00f6gens &quot;aus der Asche erheben&quot; \u2013 von der Leyen in Davos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Die Ukraine durch Diebstahl russischen Verm\u00f6gens &quot;aus der Asche erheben&quot; \u2013 von der Leyen in Davos - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\/","og_locale":"de_DE","og_type":"article","og_title":"Die Ukraine durch Diebstahl russischen Verm\u00f6gens &quot;aus der Asche erheben&quot; \u2013 von der Leyen in Davos","og_description":"EU-Kommissionspr\u00e4sidentin Ursula von der Leyen wurde auf dem Weltwirtschaftsforum in Davos pathetisch. &#8220;Wir mobilisieren unsere gesamte wirtschaftliche Macht&#8221;, erkl\u00e4rte sie, &#8220;die Ukraine muss diesen Krieg gewinnen.&#8221; Weitere zehn Milliarden Euro Finanzhilfe sollen an das Land gehen, dem von der Leyen &#8220;Hand in Hand helfen&#8221; will, &#8220;sich aus der Asche zu erheben&#8221;. Dabei erwog sie auch [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-05-25T04:45:00+00:00","og_image":[{"width":460,"height":259,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Kreml-weist-Verantwortung-fuer-drohende-Nahrungsmittelkrise-von-sich.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Die Ukraine durch Diebstahl russischen Verm\u00f6gens &quot;aus der Asche erheben&quot; \u2013 von der Leyen in Davos","datePublished":"2022-05-25T04:45:00+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\/"},"wordCount":345,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Kreml-weist-Verantwortung-fuer-drohende-Nahrungsmittelkrise-von-sich.jpg","keywords":["Asche","Davos","der","die","Diebstahl","durch","erhebenquot","Leyen","quotaus","russischen","ukraine","Verm\u00f6gens","von"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\/","url":"https:\/\/now-news.de\/de\/deutschland\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\/","name":"Die Ukraine durch Diebstahl russischen Verm\u00f6gens &quot;aus der Asche erheben&quot; \u2013 von der Leyen in Davos - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Kreml-weist-Verantwortung-fuer-drohende-Nahrungsmittelkrise-von-sich.jpg","datePublished":"2022-05-25T04:45:00+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Kreml-weist-Verantwortung-fuer-drohende-Nahrungsmittelkrise-von-sich.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Kreml-weist-Verantwortung-fuer-drohende-Nahrungsmittelkrise-von-sich.jpg","width":460,"height":259,"caption":"Kreml weist Verantwortung f\u00fcr drohende Nahrungsmittelkrise von sich"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/die-ukraine-durch-diebstahl-russischen-vermoegens-aus-der-asche-erheben-von-der-leyen-in-davos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Die Ukraine durch Diebstahl russischen Verm\u00f6gens &quot;aus der Asche erheben&quot; \u2013 von der Leyen in Davos"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/8774","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=8774"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/8774\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/8700"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=8774"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=8774"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=8774"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}