{"id":85438,"date":"2025-06-11T21:34:28","date_gmt":"2025-06-11T19:34:28","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/"},"modified":"2025-06-11T21:34:28","modified_gmt":"2025-06-11T19:34:28","slug":"sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/","title":{"rendered":"Sozialdemokraten besinnen sich: Ein Manifest f\u00fcr Frieden und Abr\u00fcstung"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/06\/6849d914b480cc40b56cfe93.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Prominente Sozialdemokraten fordern in einem neuen Manifest eine Kehrtwende in der Au\u00dfenpolitik: weniger Aufr\u00fcstung, mehr Diplomatie. Autor Wolfgang Bittner sieht darin ein wichtiges Signal gegen milit\u00e4rische Eskalation und f\u00fcr eine europ\u00e4ische Friedensordnung.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Wolfgang Bittner<\/em><\/p>\n<p>Wenn ich heute meinungsf\u00fchrende Politiker und Journalisten h\u00f6re und sehe oder ihre Verlautbarungen lese, str\u00e4uben sich mir die Haare. Ich kann das kaum noch ertragen, einige dieser Leute halte ich f\u00fcr Hochverr\u00e4ter, die vor Gericht geh\u00f6ren. Sie fordern, Deutschland m\u00fcsse aufr\u00fcsten und wieder &#8220;kriegst\u00fcchtig&#8221; werden. Sie hetzen bei jeder Gelegenheit gegen Russland, auch gegen andere Staaten und gegen Kritiker ihrer Kriegspolitik. Waren zwei Weltkriege, die zur v\u00f6lligen Zerst\u00f6rung Deutschlands gef\u00fchrt haben und bis in die Gegenwart nachwirken, noch nicht genug?<\/p>\n<p>Hoffnung gibt ein\u00a0gerade ver\u00f6ffentlichtes <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.erhard-eppler-kreis.de\/manifest\/\">Manifest<\/a> prominenter Sozialdemokraten, die gegen die Au\u00dfen- und Sicherheitspolitik der Bundesregierung protestieren, auch wenn man nicht mit allem, was sie schreiben, einverstanden sein muss. Immerhin: Der ehemalige Fraktionsvorsitzende Rolf M\u00fctzenich, Au\u00dfenpolitiker Ralf Stegner, Ex-Parteivorsitzender Norbert Walter-Borjans, der fr\u00fchere Finanzminister Hans Eichel und viele andere fordern eine sofortige Kehrtwende im Umgang mit Russland und in Fragen der Aufr\u00fcstung. Sie wenden sich unter anderem gegen die hohen Aufr\u00fcstungskosten und die Stationierung neuer US-Mittelstreckenraketen in Deutschland.<\/p>\n<p>In dem Manifest hei\u00dft es unter anderem: <em>&#8220;80 Jahre nach Ende der Jahrhundertkatastrophe des Zweiten Weltkriegs und der Befreiung vom Hitler-Faschismus ist der Frieden auch in Europa wieder bedroht\u2026 Von einer R\u00fcckkehr zu einer stabilen Friedens- und Sicherheitsordnung in Europa sind wir weit entfernt. Im Gegenteil: In Deutschland und in den meisten europ\u00e4ischen Staaten haben sich Kr\u00e4fte durchgesetzt, die die Zukunft vor allem in einer milit\u00e4rischen Konfrontationsstrategie und Hunderten von Milliarden Euro f\u00fcr Aufr\u00fcstung suchen.&#8221;<\/em><\/p>\n<p>Aber &#8220;milit\u00e4rische <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.welt.de\/politik\/deutschland\/article256235460\/manifest-spd-politiker-fordern-grundlegende-kehrtwende-in-aussenpolitik-und-zusammenarbeit-mit-russland.html\">Alarmrhetorik<\/a> und riesige Aufr\u00fcstungsprogramme&#8221; schafften nicht mehr Sicherheit f\u00fcr Deutschland und Europa, so die Verfasser des Manifests, sondern f\u00fchrten &#8220;zur Destabilisierung und zur Verst\u00e4rkung der wechselseitigen Bedrohungswahrnehmung zwischen NATO und Russland&#8221;. Daher brauche es eine &#8220;von allen getragene und von allen respektierte Friedens- und Sicherheitsordnung f\u00fcr Europa&#8221;.<\/p>\n<p>Die Widerst\u00e4nde, die sich sofort formierten, sind gro\u00df, aber das Manifest der Sozialdemokraten k\u00f6nnte das Signal zu einer friedenspolitischen Neubesinnung sein. Gut, dass immer mehr Menschen begreifen, dass sie betrogen und in einen Krieg mit Russland hineingelogen werden sollen.<\/p>\n<p><em>Der Schriftsteller und Publizist Dr. jur. <\/em><em><strong>Wolfgang Bittner<\/strong><\/em><em> hat unter anderem die B\u00fccher &#8220;Deutschland \u2013 verraten und verkauft&#8221;\u00a0und &#8220;Niemand soll hungern, ohne zu frieren&#8221; ver\u00f6ffentlicht.<\/em><\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211;\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/europa\/247446-disput-von-wolodin-und-kloeckner\/\">Wolodin reagiert erneut auf Kl\u00f6ckner: &#8220;Haben Sie daf\u00fcr das Mandat des deutschen Volkes?&#8221;<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6sdgwx\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/247475-sozialdemokraten-besinnen-sich-manifest-fuer\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Prominente Sozialdemokraten fordern in einem neuen Manifest eine Kehrtwende in der Au\u00dfenpolitik: weniger Aufr\u00fcstung, mehr Diplomatie. Autor Wolfgang Bittner sieht darin ein wichtiges Signal gegen milit\u00e4rische Eskalation und f\u00fcr eine europ\u00e4ische Friedensordnung. Von Wolfgang Bittner Wenn ich heute meinungsf\u00fchrende Politiker und Journalisten h\u00f6re und sehe oder ihre Verlautbarungen lese, str\u00e4uben sich mir die Haare. Ich [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":85439,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1749675104"],"wp_automatic_camp":["217"],"d4c4f92d0ff73d726076467a807d20bc":["Sozialdemokraten besinnen sich: Ein Manifest f\u00fcr Frieden und Abr\u00fcstung"],"original_link":["https:\/\/de.rt.com\/meinung\/247475-sozialdemokraten-besinnen-sich-manifest-fuer\/"],"_thumbnail_id":["85439"],"jnews_social_counter_last_update":["1778692121"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-06-11 22:52:50\";}"]},"categories":[19,23],"tags":[25681,50388,357,614,221,8769,434,51422,140],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sozialdemokraten besinnen sich: Ein Manifest f\u00fcr Frieden und Abr\u00fcstung - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sozialdemokraten besinnen sich: Ein Manifest f\u00fcr Frieden und Abr\u00fcstung\" \/>\n<meta property=\"og:description\" content=\"Prominente Sozialdemokraten fordern in einem neuen Manifest eine Kehrtwende in der Au\u00dfenpolitik: weniger Aufr\u00fcstung, mehr Diplomatie. Autor Wolfgang Bittner sieht darin ein wichtiges Signal gegen milit\u00e4rische Eskalation und f\u00fcr eine europ\u00e4ische Friedensordnung. Von Wolfgang Bittner Wenn ich heute meinungsf\u00fchrende Politiker und Journalisten h\u00f6re und sehe oder ihre Verlautbarungen lese, str\u00e4uben sich mir die Haare. Ich [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-06-11T19:34:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/06\/6849d914b480cc40b56cfe93.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Sozialdemokraten besinnen sich: Ein Manifest f\u00fcr Frieden und Abr\u00fcstung\",\"datePublished\":\"2025-06-11T19:34:28+00:00\",\"dateModified\":\"2025-06-11T19:34:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/\"},\"wordCount\":454,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/06\/Sozialdemokraten-besinnen-sich-Ein-Manifest-fuer-Frieden-und-Abruestung.jpg\",\"keywords\":[\"Abr\u00fcstung\",\"besinnen\",\"ein\",\"Frieden\",\"f\u00fcr\",\"manifest\",\"sich\",\"Sozialdemokraten\",\"und\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/\",\"name\":\"Sozialdemokraten besinnen sich: Ein Manifest f\u00fcr Frieden und Abr\u00fcstung - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/06\/Sozialdemokraten-besinnen-sich-Ein-Manifest-fuer-Frieden-und-Abruestung.jpg\",\"datePublished\":\"2025-06-11T19:34:28+00:00\",\"dateModified\":\"2025-06-11T19:34:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/06\/Sozialdemokraten-besinnen-sich-Ein-Manifest-fuer-Frieden-und-Abruestung.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/06\/Sozialdemokraten-besinnen-sich-Ein-Manifest-fuer-Frieden-und-Abruestung.jpg\",\"width\":460,\"height\":259,\"caption\":\"Sozialdemokraten besinnen sich: Ein Manifest f\u00fcr Frieden und Abr\u00fcstung\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sozialdemokraten besinnen sich: Ein Manifest f\u00fcr Frieden und Abr\u00fcstung\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sozialdemokraten besinnen sich: Ein Manifest f\u00fcr Frieden und Abr\u00fcstung - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/","og_locale":"de_DE","og_type":"article","og_title":"Sozialdemokraten besinnen sich: Ein Manifest f\u00fcr Frieden und Abr\u00fcstung","og_description":"Prominente Sozialdemokraten fordern in einem neuen Manifest eine Kehrtwende in der Au\u00dfenpolitik: weniger Aufr\u00fcstung, mehr Diplomatie. Autor Wolfgang Bittner sieht darin ein wichtiges Signal gegen milit\u00e4rische Eskalation und f\u00fcr eine europ\u00e4ische Friedensordnung. Von Wolfgang Bittner Wenn ich heute meinungsf\u00fchrende Politiker und Journalisten h\u00f6re und sehe oder ihre Verlautbarungen lese, str\u00e4uben sich mir die Haare. Ich [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-06-11T19:34:28+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/06\/6849d914b480cc40b56cfe93.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Sozialdemokraten besinnen sich: Ein Manifest f\u00fcr Frieden und Abr\u00fcstung","datePublished":"2025-06-11T19:34:28+00:00","dateModified":"2025-06-11T19:34:28+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/"},"wordCount":454,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/06\/Sozialdemokraten-besinnen-sich-Ein-Manifest-fuer-Frieden-und-Abruestung.jpg","keywords":["Abr\u00fcstung","besinnen","ein","Frieden","f\u00fcr","manifest","sich","Sozialdemokraten","und"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/","url":"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/","name":"Sozialdemokraten besinnen sich: Ein Manifest f\u00fcr Frieden und Abr\u00fcstung - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/06\/Sozialdemokraten-besinnen-sich-Ein-Manifest-fuer-Frieden-und-Abruestung.jpg","datePublished":"2025-06-11T19:34:28+00:00","dateModified":"2025-06-11T19:34:28+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/06\/Sozialdemokraten-besinnen-sich-Ein-Manifest-fuer-Frieden-und-Abruestung.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/06\/Sozialdemokraten-besinnen-sich-Ein-Manifest-fuer-Frieden-und-Abruestung.jpg","width":460,"height":259,"caption":"Sozialdemokraten besinnen sich: Ein Manifest f\u00fcr Frieden und Abr\u00fcstung"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/sozialdemokraten-besinnen-sich-ein-manifest-fuer-frieden-und-abruestung\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Sozialdemokraten besinnen sich: Ein Manifest f\u00fcr Frieden und Abr\u00fcstung"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/85438"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=85438"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/85438\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/85439"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=85438"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=85438"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=85438"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}