{"id":83314,"date":"2025-05-06T12:50:48","date_gmt":"2025-05-06T10:50:48","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/"},"modified":"2025-05-06T12:50:48","modified_gmt":"2025-05-06T10:50:48","slug":"ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/","title":{"rendered":"Ehemalige AfD-Vorsitzende Petry will neue Partei gr\u00fcnden"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/6819e37cb480cc087c7c733e.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Frauke Petry, die einstige Mitbegr\u00fcnderin und Vorsitzende der AfD, will eine neue Partei gr\u00fcnden. Diese soll die &#8220;Leerstelle eines anti-etatistischen, freiheitlichen Angebots&#8221; f\u00fcllen. Nach dem Austritt aus der AfD war Petry bis 2021 parteilose Abgeordnete im Bundestag.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die Mitgr\u00fcnderin und Ex-Vorsitzende der Alternative f\u00fcr Deutschland Frauke Petry will eine neue Partei gr\u00fcnden. Im Interview mit der <em>Welt<\/em> wollte die Politikerin den Namen der Partei noch nicht verraten, hat jedoch deren Programm kurz skizziert.<\/p>\n<p>Petry zufolge wird sich die Partei auf &#8220;eine Erneuerung der kulturellen Westbindung und ein anti-etatistisches Angebot als positiver Gegenentwurf zur bisherigen Parteienlandschaft&#8221; konzentrieren:<\/p>\n<p><em>&#8220;Die L\u00fccke im Parteiensystem klafft eben nicht zwischen CDU und AfD, sondern in der Leerstelle eines anti-etatistischen, freiheitlichen Angebots.&#8221;<\/em><\/p>\n<p>Au\u00dferdem m\u00fcsse die Staatsquote, das Verh\u00e4ltnis der Staatsausgaben zum Bruttoinlandsprodukt, binnen f\u00fcnf Jahren von knapp 50 auf 25 Prozent gesenkt werden. Eine Partei, die dieses Ziel habe und Meinungsfreiheit durchsetzen wolle, gebe es im aktuellen politischen System Deutschlands nicht, so Petry.<\/p>\n<p>In Vorbereitung f\u00fcr die Gr\u00fcndung der Partei sollen Petry und ihre Mitstreiter vor einigen Monaten den Verein Team Freiheit gegr\u00fcndet haben. Bereits 2026 will die Partei bei Landtagswahlen antreten, zun\u00e4chst in Baden-W\u00fcrttemberg:<\/p>\n<p>&#8220;Mit der Besonderheit, dass wir parteilose B\u00fcrger und Unternehmer mit Lebens- und Berufserfahrung als Kandidaten gewinnen wollen. Sie sollen daf\u00fcr nicht Mitglieder der Partei werden&#8221;, so Petry.<\/p>\n<p>Im Jahr 2013 war Petry neben Bernd Lucke unter den Mitgr\u00fcndern der AfD. Kurz nach der Bundestagswahl 2017 musste sie wegen innerparteilicher Streitigkeiten austreten. Bis 2021 geh\u00f6rte Petry dem Bundestag als fraktionslose Abgeordnete an. Inzwischen gr\u00fcndete sie die Blaue Partei, die Ende 2019 nach Wahlniederlagen in Sachsen und Th\u00fcringen aufgel\u00f6st wurde.<\/p>\n<p><strong>Mehr zum Thema \u2013<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/94306-frauke-petry-lost-ihre-partei\/\">&#8220;Abschied aus der aktiven Politik&#8221; \u2013 Frauke Petry k\u00fcndigt Aufl\u00f6sung ihrer &#8220;Blauen Partei&#8221; an<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6qo341\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/244251-ehemalige-afd-vorsitzende-petry-will-partei\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Frauke Petry, die einstige Mitbegr\u00fcnderin und Vorsitzende der AfD, will eine neue Partei gr\u00fcnden. Diese soll die &#8220;Leerstelle eines anti-etatistischen, freiheitlichen Angebots&#8221; f\u00fcllen. Nach dem Austritt aus der AfD war Petry bis 2021 parteilose Abgeordnete im Bundestag. Die Mitgr\u00fcnderin und Ex-Vorsitzende der Alternative f\u00fcr Deutschland Frauke Petry will eine neue Partei gr\u00fcnden. Im Interview mit [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":83315,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1746529297"],"wp_automatic_camp":["217"],"8a6878cdd545e815bcc48556bbae54ef":["Ehemalige AfD-Vorsitzende Petry will neue Partei gr\u00fcnden"],"original_link":["https:\/\/de.rt.com\/inland\/244251-ehemalige-afd-vorsitzende-petry-will-partei\/"],"_thumbnail_id":["83315"],"jnews_social_counter_last_update":["1784109387"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-05-06 13:02:38\";}"]},"categories":[19,23],"tags":[52851,8611,25545,1227,2504,64768],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ehemalige AfD-Vorsitzende Petry will neue Partei gr\u00fcnden - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ehemalige AfD-Vorsitzende Petry will neue Partei gr\u00fcnden\" \/>\n<meta property=\"og:description\" content=\"Frauke Petry, die einstige Mitbegr\u00fcnderin und Vorsitzende der AfD, will eine neue Partei gr\u00fcnden. Diese soll die &#8220;Leerstelle eines anti-etatistischen, freiheitlichen Angebots&#8221; f\u00fcllen. Nach dem Austritt aus der AfD war Petry bis 2021 parteilose Abgeordnete im Bundestag. Die Mitgr\u00fcnderin und Ex-Vorsitzende der Alternative f\u00fcr Deutschland Frauke Petry will eine neue Partei gr\u00fcnden. Im Interview mit [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-05-06T10:50:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/6819e37cb480cc087c7c733e.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Ehemalige AfD-Vorsitzende Petry will neue Partei gr\u00fcnden\",\"datePublished\":\"2025-05-06T10:50:48+00:00\",\"dateModified\":\"2025-05-06T10:50:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/\"},\"wordCount\":310,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/Ehemalige-AfD-Vorsitzende-Petry-will-neue-Partei-gruenden.jpg\",\"keywords\":[\"AfDVorsitzende\",\"ehemalige\",\"gr\u00fcnden\",\"NEUE\",\"Partei\",\"Petry\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/\",\"name\":\"Ehemalige AfD-Vorsitzende Petry will neue Partei gr\u00fcnden - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/Ehemalige-AfD-Vorsitzende-Petry-will-neue-Partei-gruenden.jpg\",\"datePublished\":\"2025-05-06T10:50:48+00:00\",\"dateModified\":\"2025-05-06T10:50:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/Ehemalige-AfD-Vorsitzende-Petry-will-neue-Partei-gruenden.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/Ehemalige-AfD-Vorsitzende-Petry-will-neue-Partei-gruenden.jpg\",\"width\":460,\"height\":259,\"caption\":\"Ehemalige AfD-Vorsitzende Petry will neue Partei gr\u00fcnden\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ehemalige AfD-Vorsitzende Petry will neue Partei gr\u00fcnden\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ehemalige AfD-Vorsitzende Petry will neue Partei gr\u00fcnden - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/","og_locale":"de_DE","og_type":"article","og_title":"Ehemalige AfD-Vorsitzende Petry will neue Partei gr\u00fcnden","og_description":"Frauke Petry, die einstige Mitbegr\u00fcnderin und Vorsitzende der AfD, will eine neue Partei gr\u00fcnden. Diese soll die &#8220;Leerstelle eines anti-etatistischen, freiheitlichen Angebots&#8221; f\u00fcllen. Nach dem Austritt aus der AfD war Petry bis 2021 parteilose Abgeordnete im Bundestag. Die Mitgr\u00fcnderin und Ex-Vorsitzende der Alternative f\u00fcr Deutschland Frauke Petry will eine neue Partei gr\u00fcnden. Im Interview mit [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-05-06T10:50:48+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/6819e37cb480cc087c7c733e.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Ehemalige AfD-Vorsitzende Petry will neue Partei gr\u00fcnden","datePublished":"2025-05-06T10:50:48+00:00","dateModified":"2025-05-06T10:50:48+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/"},"wordCount":310,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/Ehemalige-AfD-Vorsitzende-Petry-will-neue-Partei-gruenden.jpg","keywords":["AfDVorsitzende","ehemalige","gr\u00fcnden","NEUE","Partei","Petry"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/","url":"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/","name":"Ehemalige AfD-Vorsitzende Petry will neue Partei gr\u00fcnden - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/Ehemalige-AfD-Vorsitzende-Petry-will-neue-Partei-gruenden.jpg","datePublished":"2025-05-06T10:50:48+00:00","dateModified":"2025-05-06T10:50:48+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/Ehemalige-AfD-Vorsitzende-Petry-will-neue-Partei-gruenden.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/05\/Ehemalige-AfD-Vorsitzende-Petry-will-neue-Partei-gruenden.jpg","width":460,"height":259,"caption":"Ehemalige AfD-Vorsitzende Petry will neue Partei gr\u00fcnden"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/ehemalige-afd-vorsitzende-petry-will-neue-partei-gruenden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Ehemalige AfD-Vorsitzende Petry will neue Partei gr\u00fcnden"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/83314"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=83314"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/83314\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/83315"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=83314"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=83314"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=83314"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}