{"id":82666,"date":"2025-04-24T14:23:48","date_gmt":"2025-04-24T12:23:48","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/"},"modified":"2025-04-24T14:23:48","modified_gmt":"2025-04-24T12:23:48","slug":"wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/","title":{"rendered":"&quot;Wer Ja sagt, vers\u00fcndigt sich&quot; \u2013 Springer-Chef D\u00f6pfner warnt vor Ukraine-&quot;Diktat-Frieden&quot;"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/6809ee08b480cc6d83426b38.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Mathias D\u00f6pfner, Vorstandsvorsitzender des Springer-Verlags, schreibt sich zum Thema eines m\u00f6glichen, ausgehandelten Friedensplans im Ukraine-Krieg in Rage. Im Rahmen eines Bild-Kommentars fordert er: &#8220;Europa darf diesen &#8216;Plan&#8217; nicht einmal diskutieren&#8221;.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Mathias D\u00f6pfner, Springer-Vorstandsvorsitzender seit dem Jahr 2002, schaltet sich h\u00f6chstpers\u00f6nlich im Rahmen eines Kommentars im Verlagsflaggschiff\u00a0<em>Bild<\/em>-Zeitung in die Diskussion eines m\u00f6glichen, nahenden Ukraine-Friedensplans ein. D\u00f6pfner kann den m\u00f6glichen\u00a0Absprachen in Moskau und Washington anscheinend Nullkommanichts abgewinnen. Der\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.bild.de\/politik\/meinung-kommentare-kolumnen\/kommentar-mathias-doepfner-entweder-wir-stehen-zusammen-oder-wir-fallen-6808fceda0edaf6915c50b2f\">Artikel<\/a>\u00a0tr\u00e4gt die \u00dcberschrift samt Aufforderung: &#8220;Entweder wir stehen zusammen. Oder wir fallen&#8221;.<\/p>\n<p>Der Publizist ist sich demnach sicher:\u00a0<\/p>\n<p><em>&#8220;Der ultimativ vorgetragene &#8216;Friedensplan&#8217; f\u00fcr die Ukraine ist \u2013 wenn stimmt, was dar\u00fcber bisher berichtet wird \u2013 schlimmer als die schlimmsten Bef\u00fcrchtungen.&#8221;<\/em><\/p>\n<p>F\u00fcr D\u00f6pfner zeichne sich laut medialen Mutma\u00dfungen zu den ausgehandelten Details ab, dass &#8220;auf dem Tisch ein reiner Diktat-Frieden liegt&#8221;, um sich weiter zu echauffieren:<\/p>\n<p><em>&#8220;Er [der Friedensplan] l\u00e4utet das Ende einer einigerma\u00dfen stabilen Weltordnung ein. Denn er etabliert das Recht des St\u00e4rkeren, sich zu nehmen, was er will.&#8221;<\/em><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"de\" dir=\"ltr\">Europa darf diesen \u201ePlan\u201c nicht einmal diskutieren. Es geht \u2013 wie einige von Anfang an gesagt haben \u2013 l\u00e4ngst nicht mehr um die Verteidigung der Ukraine. Es geht um die Zukunft unserer Werte, einer auf dem Recht basierenden Weltordnung.<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/21WnFG9JBr\">https:\/\/t.co\/21WnFG9JBr<\/a><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/gT1VJ7vTpO\">pic.twitter.com\/gT1VJ7vTpO<\/a><\/p>\n<p>\u2014 Julian R\u00f6pcke\ud83c\uddfa\ud83c\udde6 (@JulianRoepcke) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/JulianRoepcke\/status\/1915076676733575455?ref_src=twsrc%5Etfw\">April 23, 2025<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Der Springer-Chef\u00a0steht demnach jetzt schon \u00fcber den weiterhin nur angedeuteten Inhalten eines Friedensplans. So erkl\u00e4rt der Medienprofi den\u00a0<em>Bild<\/em>-Lesern:<\/p>\n<p><em>&#8220;Man muss sich nicht mit den Details des Vorschlags besch\u00e4ftigen. Ein Satz reicht: die offizielle Anerkennung der Krim als russisches Territorium.\u00a0Wenn Putin damit durchkommt und zus\u00e4tzlich noch ein paar andere Gebiete der Ukraine kontrolliert, und die Ukraine nicht in die NATO\u00a0kommt, hat er alles und mehr erreicht, als er je ertr\u00e4umte.&#8221;<\/em><\/p>\n<p>D\u00f6pfner schreibt sich regelrecht in Rage:<\/p>\n<p><em>&#8220;Wer zu diesem Plan Ja sagt, vers\u00fcndigt sich f\u00fcr immer an jeder Art von V\u00f6lkerrecht und territorialer Integrit\u00e4t.\u00a0Die Lektion f\u00fcr andere Autokratien von China bis Iran ist: Wer nur aggressiv und gewaltsam genug auftritt, erreicht seine Ziele \u2013 die Annexion Taiwans, die Zerst\u00f6rung Israels.&#8221;<\/em><\/p>\n<p>Final erkl\u00e4rt der 62-J\u00e4hrige, dass &#8220;Europa diesen &#8216;Plan&#8217; nicht einmal diskutieren darf&#8221;, da es alleinig &#8220;um die Zukunft unserer Werte, einer auf dem Recht basierenden Weltordnung geht&#8221;. Die Abschlussmutma\u00dfung lautet:<\/p>\n<p><em>&#8220;Vielleicht ist das nun wirklich der historische Moment Europas. Entweder wir stehen zusammen. Oder wir fallen.&#8221;<\/em><\/p>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/russland\/243205-peskow-kiew-muss-seine-truppen-abziehen\/\">Peskow: Kiew muss seine Truppen aus vier Regionen abziehen, dann ist sofort Frieden<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6qaash\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/243224-wer-ja-sagt-versuendigt-sich\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mathias D\u00f6pfner, Vorstandsvorsitzender des Springer-Verlags, schreibt sich zum Thema eines m\u00f6glichen, ausgehandelten Friedensplans im Ukraine-Krieg in Rage. Im Rahmen eines Bild-Kommentars fordert er: &#8220;Europa darf diesen &#8216;Plan&#8217; nicht einmal diskutieren&#8221;. Mathias D\u00f6pfner, Springer-Vorstandsvorsitzender seit dem Jahr 2002, schaltet sich h\u00f6chstpers\u00f6nlich im Rahmen eines Kommentars im Verlagsflaggschiff\u00a0Bild-Zeitung in die Diskussion eines m\u00f6glichen, nahenden Ukraine-Friedensplans ein. D\u00f6pfner [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":82667,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1745498397"],"wp_automatic_camp":["217"],"5b2eb592c6185f6a5718d6e7265b7445":["&quot;Wer Ja sagt, vers\u00fcndigt sich&quot; \u2013 Springer-Chef D\u00f6pfner warnt vor Ukraine-&quot;Diktat-Frieden&quot;"],"original_link":["https:\/\/de.rt.com\/inland\/243224-wer-ja-sagt-versuendigt-sich\/"],"_thumbnail_id":["82667"],"jnews_social_counter_last_update":["1778555563"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-04-24 14:40:58\";}"]},"categories":[19,23],"tags":[19026,22676,3564,20737,19025,64501,64500,320,912],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Wer Ja sagt, vers\u00fcndigt sich&quot; \u2013 Springer-Chef D\u00f6pfner warnt vor Ukraine-&quot;Diktat-Frieden&quot; - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Wer Ja sagt, vers\u00fcndigt sich&quot; \u2013 Springer-Chef D\u00f6pfner warnt vor Ukraine-&quot;Diktat-Frieden&quot;\" \/>\n<meta property=\"og:description\" content=\"Mathias D\u00f6pfner, Vorstandsvorsitzender des Springer-Verlags, schreibt sich zum Thema eines m\u00f6glichen, ausgehandelten Friedensplans im Ukraine-Krieg in Rage. Im Rahmen eines Bild-Kommentars fordert er: &#8220;Europa darf diesen &#8216;Plan&#8217; nicht einmal diskutieren&#8221;. Mathias D\u00f6pfner, Springer-Vorstandsvorsitzender seit dem Jahr 2002, schaltet sich h\u00f6chstpers\u00f6nlich im Rahmen eines Kommentars im Verlagsflaggschiff\u00a0Bild-Zeitung in die Diskussion eines m\u00f6glichen, nahenden Ukraine-Friedensplans ein. D\u00f6pfner [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-24T12:23:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/6809ee08b480cc6d83426b38.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"&quot;Wer Ja sagt, vers\u00fcndigt sich&quot; \u2013 Springer-Chef D\u00f6pfner warnt vor Ukraine-&quot;Diktat-Frieden&quot;\",\"datePublished\":\"2025-04-24T12:23:48+00:00\",\"dateModified\":\"2025-04-24T12:23:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/\"},\"wordCount\":447,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/quotWer-Ja-sagt-versuendigt-sichquot-\u2013-Springer-Chef-Doepfner-warnt-vor.jpg\",\"keywords\":[\"D\u00f6pfner\",\"quotWer\",\"sagt\",\"sichquot\",\"SpringerChef\",\"UkrainequotDiktatFriedenquot\",\"vers\u00fcndigt\",\"vor\",\"warnt\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/\",\"name\":\"&quot;Wer Ja sagt, vers\u00fcndigt sich&quot; \u2013 Springer-Chef D\u00f6pfner warnt vor Ukraine-&quot;Diktat-Frieden&quot; - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/quotWer-Ja-sagt-versuendigt-sichquot-\u2013-Springer-Chef-Doepfner-warnt-vor.jpg\",\"datePublished\":\"2025-04-24T12:23:48+00:00\",\"dateModified\":\"2025-04-24T12:23:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/quotWer-Ja-sagt-versuendigt-sichquot-\u2013-Springer-Chef-Doepfner-warnt-vor.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/quotWer-Ja-sagt-versuendigt-sichquot-\u2013-Springer-Chef-Doepfner-warnt-vor.jpg\",\"width\":460,\"height\":259,\"caption\":\"&quot;Wer Ja sagt, vers\u00fcndigt sich&quot; \u2013 Springer-Chef D\u00f6pfner warnt vor Ukraine-&quot;Diktat-Frieden&quot;\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&quot;Wer Ja sagt, vers\u00fcndigt sich&quot; \u2013 Springer-Chef D\u00f6pfner warnt vor Ukraine-&quot;Diktat-Frieden&quot;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"&quot;Wer Ja sagt, vers\u00fcndigt sich&quot; \u2013 Springer-Chef D\u00f6pfner warnt vor Ukraine-&quot;Diktat-Frieden&quot; - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/","og_locale":"de_DE","og_type":"article","og_title":"&quot;Wer Ja sagt, vers\u00fcndigt sich&quot; \u2013 Springer-Chef D\u00f6pfner warnt vor Ukraine-&quot;Diktat-Frieden&quot;","og_description":"Mathias D\u00f6pfner, Vorstandsvorsitzender des Springer-Verlags, schreibt sich zum Thema eines m\u00f6glichen, ausgehandelten Friedensplans im Ukraine-Krieg in Rage. Im Rahmen eines Bild-Kommentars fordert er: &#8220;Europa darf diesen &#8216;Plan&#8217; nicht einmal diskutieren&#8221;. Mathias D\u00f6pfner, Springer-Vorstandsvorsitzender seit dem Jahr 2002, schaltet sich h\u00f6chstpers\u00f6nlich im Rahmen eines Kommentars im Verlagsflaggschiff\u00a0Bild-Zeitung in die Diskussion eines m\u00f6glichen, nahenden Ukraine-Friedensplans ein. D\u00f6pfner [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-04-24T12:23:48+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/6809ee08b480cc6d83426b38.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"&quot;Wer Ja sagt, vers\u00fcndigt sich&quot; \u2013 Springer-Chef D\u00f6pfner warnt vor Ukraine-&quot;Diktat-Frieden&quot;","datePublished":"2025-04-24T12:23:48+00:00","dateModified":"2025-04-24T12:23:48+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/"},"wordCount":447,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/quotWer-Ja-sagt-versuendigt-sichquot-\u2013-Springer-Chef-Doepfner-warnt-vor.jpg","keywords":["D\u00f6pfner","quotWer","sagt","sichquot","SpringerChef","UkrainequotDiktatFriedenquot","vers\u00fcndigt","vor","warnt"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/","url":"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/","name":"&quot;Wer Ja sagt, vers\u00fcndigt sich&quot; \u2013 Springer-Chef D\u00f6pfner warnt vor Ukraine-&quot;Diktat-Frieden&quot; - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/quotWer-Ja-sagt-versuendigt-sichquot-\u2013-Springer-Chef-Doepfner-warnt-vor.jpg","datePublished":"2025-04-24T12:23:48+00:00","dateModified":"2025-04-24T12:23:48+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/quotWer-Ja-sagt-versuendigt-sichquot-\u2013-Springer-Chef-Doepfner-warnt-vor.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/quotWer-Ja-sagt-versuendigt-sichquot-\u2013-Springer-Chef-Doepfner-warnt-vor.jpg","width":460,"height":259,"caption":"&quot;Wer Ja sagt, vers\u00fcndigt sich&quot; \u2013 Springer-Chef D\u00f6pfner warnt vor Ukraine-&quot;Diktat-Frieden&quot;"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/wer-ja-sagt-versuendigt-sich-springer-chef-doepfner-warnt-vor-ukraine-diktat-frieden\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"&quot;Wer Ja sagt, vers\u00fcndigt sich&quot; \u2013 Springer-Chef D\u00f6pfner warnt vor Ukraine-&quot;Diktat-Frieden&quot;"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/82666"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=82666"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/82666\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/82667"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=82666"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=82666"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=82666"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}