{"id":82641,"date":"2025-04-23T21:09:51","date_gmt":"2025-04-23T19:09:51","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\/"},"modified":"2025-04-23T21:09:51","modified_gmt":"2025-04-23T19:09:51","slug":"bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\/","title":{"rendered":"Bericht: Bezirk Treptow-K\u00f6penick plant nicht, russische Diplomaten am 9. Mai auszusperren"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/68090f2d48fbef05761323b5.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Der Berliner Bezirk Treptow-K\u00f6penick erweist sich offenbar als weiser denn alle Bundes- und Landesbeh\u00f6rden. Wenn es stimmt, was die &#8220;Berliner Zeitung&#8221; am Mittwoch berichtet, erspart er Deutschland eine Peinlichkeit: die Botschafter Russlands und Wei\u00dfrusslands am 80. Jahrestag des Sieges \u00fcber Hitler von der Polizei abf\u00fchren zu lassen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Russische Diplomaten k\u00f6nnen im Berliner Bezirk Treptow-K\u00f6penick, wo sich der Treptower Park mit dem ber\u00fchmten sowjetischen Ehrenmal befindet, ungehindert an Veranstaltungen zum Gedenken an die Niederlage Nazideutschlands teilnehmen. Dies teilte eine Sprecherin des Bezirksamtes mit, die am Mittwoch von der <em>Berliner Zeitung<\/em> mit dieser Aussage <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.berliner-zeitung.de\/mensch-metropole\/gegen-baerbock-bezirksamt-treptow-wird-russischen-botschafter-nicht-rauswerfen-li.2318538?id=9a1d551bd40143858be7c782dbb70d34\">zitiert wird<\/a>:<\/p>\n<blockquote>\n<p><em>&#8220;Angesichts der historischen Rolle der Sowjetunion bei der Befreiung Deutschlands und Europas vom Nationalsozialismus und angesichts der Opfer der Sowjetunion im Zweiten Weltkrieg, w\u00fcrde das Bezirksamt Treptow-K\u00f6penick es f\u00fcr nicht angemessen halten, Vertreter der Botschaften Russlands oder Belarus&#8217; \u2013 selbst wenn sie nicht eingeladen wurden und unangek\u00fcndigt erscheinen sollten \u2013 unter Anwendung des Hausrechts des Platzes zu verweisen.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Das Bezirksamt wendet sich damit de facto gegen eine Handreichung des Ausw\u00e4rtigen Amtes, in dem die Beh\u00f6rde von Annalena Baerbock den Landkreisen und Kommunen &#8220;empfiehlt&#8221;, Vertreter Russlands und Wei\u00dfrusslands zu Veranstaltungen in Berlin und Brandenburg anl\u00e4sslich des 80. Jahrestages der Niederlage Nazi-Deutschlands nicht einzuladen. Falls sie dennoch erscheinen, empfiehlt Baerbocks Ministerium &#8220;die Anwendung des Hausrechts&#8221;. Die Sprecherin des Bezirksamtes sagte der <em>Berliner Zeitung<\/em> aber auch, eine offizielle Handreichung des Ausw\u00e4rtigen Amtes zu dieser Angelegenheit sei ihr nicht bekannt.\u00a0<\/p>\n<p>Auch die Landesbeh\u00f6rden des Bundeslandes Brandenburg <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/243130-brandenburgs-gedenkstaettenleiter-droht-russischem-botschafter\/\">haben erkl\u00e4rt<\/a>, dass sie den russischen Botschafter Sergei Netschajew polizeilich des Platzes verweisen werden, falls er zu der Gedenkveranstaltung kommt. Der Botschafter selbst bezeichnete dies als &#8220;bittere Entt\u00e4uschung&#8221;, die &#8220;Empfehlungen&#8221; des AA gef\u00e4hrdeten die jahrzehntelangen Bem\u00fchungen um eine Auss\u00f6hnung zwischen den beiden L\u00e4ndern.<\/p>\n<p>Dar\u00fcber hinaus wurden die Botschafter Russlands und Wei\u00dfrusslands zu einer Veranstaltung des Deutschen Bundestages zum Gedenken an das Ende des Zweiten Weltkriegs am 8. Mai ausdr\u00fccklich nicht in den Bundestag <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/kurzclips\/video\/242740-80-jahrestag-kriegsendes-russland-und\/\">eingeladen<\/a>.<\/p>\n<p>Die Pressesprecherin des russischen Au\u00dfenministeriums, Maria Sacharowa, kritisierte dies. Deutschlands Ausw\u00e4rtiges Amt habe sich &#8220;selbst entlarvt und die H\u00e4sslichkeit der Russophobie und Anzeichen von Neonazismus offengelegt&#8221;.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/meinung\/242675-bundestag-schande-politik-instrumentalisiert-gedenken\/\">Bundestag der Schande: Politik instrumentalisiert das Gedenken ans Kriegsende<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/243188-berliner-zeitung-bezirk-treptow-koepenick\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Berliner Bezirk Treptow-K\u00f6penick erweist sich offenbar als weiser denn alle Bundes- und Landesbeh\u00f6rden. Wenn es stimmt, was die &#8220;Berliner Zeitung&#8221; am Mittwoch berichtet, erspart er Deutschland eine Peinlichkeit: die Botschafter Russlands und Wei\u00dfrusslands am 80. Jahrestag des Sieges \u00fcber Hitler von der Polizei abf\u00fchren zu lassen. Russische Diplomaten k\u00f6nnen im Berliner Bezirk Treptow-K\u00f6penick, wo [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":82642,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1745435871"],"wp_automatic_camp":["217"],"d3b53cc2dca0161648f157c0544a5566":["Bericht: Bezirk Treptow-K\u00f6penick plant nicht, russische Diplomaten am 9. Mai auszusperren"],"original_link":["https:\/\/de.rt.com\/inland\/243188-berliner-zeitung-bezirk-treptow-koepenick\/"],"_thumbnail_id":["82642"],"jnews_social_counter_last_update":["1788332341"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-04-23 21:18:52\";}"]},"categories":[19,23],"tags":[64495,667,29713,9831,9933,800,2559,570,64494],"class_list":["post-82641","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-auszusperren","tag-bericht","tag-bezirk","tag-diplomaten","tag-mai","tag-nicht","tag-plant","tag-russische","tag-treptowkoepenick"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Bericht: Bezirk Treptow-K\u00f6penick plant nicht, russische Diplomaten am 9. Mai auszusperren - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Bericht: Bezirk Treptow-K\u00f6penick plant nicht, russische Diplomaten am 9. Mai auszusperren\" \/>\n<meta property=\"og:description\" content=\"Der Berliner Bezirk Treptow-K\u00f6penick erweist sich offenbar als weiser denn alle Bundes- und Landesbeh\u00f6rden. Wenn es stimmt, was die &#8220;Berliner Zeitung&#8221; am Mittwoch berichtet, erspart er Deutschland eine Peinlichkeit: die Botschafter Russlands und Wei\u00dfrusslands am 80. Jahrestag des Sieges \u00fcber Hitler von der Polizei abf\u00fchren zu lassen. Russische Diplomaten k\u00f6nnen im Berliner Bezirk Treptow-K\u00f6penick, wo [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-23T19:09:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/68090f2d48fbef05761323b5.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Bericht: Bezirk Treptow-K\u00f6penick plant nicht, russische Diplomaten am 9. Mai auszusperren\",\"datePublished\":\"2025-04-23T19:09:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\\\/\"},\"wordCount\":387,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/04\\\/Bericht-Bezirk-Treptow-Koepenick-plant-nicht-russische-Diplomaten-am-9-Mai.jpg\",\"keywords\":[\"auszusperren\",\"Bericht\",\"Bezirk\",\"Diplomaten\",\"Mai\",\"nicht\",\"plant\",\"Russische\",\"TreptowK\u00f6penick\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\\\/\",\"name\":\"Bericht: Bezirk Treptow-K\u00f6penick plant nicht, russische Diplomaten am 9. Mai auszusperren - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/04\\\/Bericht-Bezirk-Treptow-Koepenick-plant-nicht-russische-Diplomaten-am-9-Mai.jpg\",\"datePublished\":\"2025-04-23T19:09:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/04\\\/Bericht-Bezirk-Treptow-Koepenick-plant-nicht-russische-Diplomaten-am-9-Mai.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/04\\\/Bericht-Bezirk-Treptow-Koepenick-plant-nicht-russische-Diplomaten-am-9-Mai.jpg\",\"width\":460,\"height\":259,\"caption\":\"Bericht: Bezirk Treptow-K\u00f6penick plant nicht, russische Diplomaten am 9. Mai auszusperren\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Bericht: Bezirk Treptow-K\u00f6penick plant nicht, russische Diplomaten am 9. Mai auszusperren\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Bericht: Bezirk Treptow-K\u00f6penick plant nicht, russische Diplomaten am 9. Mai auszusperren - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\/","og_locale":"de_DE","og_type":"article","og_title":"Bericht: Bezirk Treptow-K\u00f6penick plant nicht, russische Diplomaten am 9. Mai auszusperren","og_description":"Der Berliner Bezirk Treptow-K\u00f6penick erweist sich offenbar als weiser denn alle Bundes- und Landesbeh\u00f6rden. Wenn es stimmt, was die &#8220;Berliner Zeitung&#8221; am Mittwoch berichtet, erspart er Deutschland eine Peinlichkeit: die Botschafter Russlands und Wei\u00dfrusslands am 80. Jahrestag des Sieges \u00fcber Hitler von der Polizei abf\u00fchren zu lassen. Russische Diplomaten k\u00f6nnen im Berliner Bezirk Treptow-K\u00f6penick, wo [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-04-23T19:09:51+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/68090f2d48fbef05761323b5.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Bericht: Bezirk Treptow-K\u00f6penick plant nicht, russische Diplomaten am 9. Mai auszusperren","datePublished":"2025-04-23T19:09:51+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\/"},"wordCount":387,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/Bericht-Bezirk-Treptow-Koepenick-plant-nicht-russische-Diplomaten-am-9-Mai.jpg","keywords":["auszusperren","Bericht","Bezirk","Diplomaten","Mai","nicht","plant","Russische","TreptowK\u00f6penick"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\/","url":"https:\/\/now-news.de\/de\/deutschland\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\/","name":"Bericht: Bezirk Treptow-K\u00f6penick plant nicht, russische Diplomaten am 9. Mai auszusperren - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/Bericht-Bezirk-Treptow-Koepenick-plant-nicht-russische-Diplomaten-am-9-Mai.jpg","datePublished":"2025-04-23T19:09:51+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/Bericht-Bezirk-Treptow-Koepenick-plant-nicht-russische-Diplomaten-am-9-Mai.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/Bericht-Bezirk-Treptow-Koepenick-plant-nicht-russische-Diplomaten-am-9-Mai.jpg","width":460,"height":259,"caption":"Bericht: Bezirk Treptow-K\u00f6penick plant nicht, russische Diplomaten am 9. Mai auszusperren"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/bericht-bezirk-treptow-koepenick-plant-nicht-russische-diplomaten-am-9-mai-auszusperren\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Bericht: Bezirk Treptow-K\u00f6penick plant nicht, russische Diplomaten am 9. Mai auszusperren"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/82641","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=82641"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/82641\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/82642"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=82641"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=82641"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=82641"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}