{"id":82637,"date":"2025-04-23T20:23:58","date_gmt":"2025-04-23T18:23:58","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/"},"modified":"2025-04-23T20:23:58","modified_gmt":"2025-04-23T18:23:58","slug":"bsw-uebergibt-einspruch-gegen-bundestagswahl","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/","title":{"rendered":"BSW \u00fcbergibt Einspruch gegen Bundestagswahl"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/6809071bb480cc55ea239e46.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Das BSW nahm heute einen weiteren Anlauf, um eine erneute Ausz\u00e4hlung der Bundestagswahl zu erreichen. Ob diese Bem\u00fchungen Erfolg haben, bleibt fraglich. Immerhin w\u00fcrde ein Ergebnis, das zugunsten des BSW ausf\u00e4llt, die MiniKo zum Platzen bringen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die Co-Vorsitzende Amira Mohamed Ali r\u00fcckte heute mit drei Kartons voller Unterlagen an. Der 23.\u00a0April war der letzte Tag, an dem Einspruch gegen die Bundestagswahl eingelegt werden konnte; die drei Kartons enthalten die Belege, mit denen das BSW seinen Einspruch untermauern will.<\/p>\n<p>Mehrere juristische Versuche, eine Neuausz\u00e4hlung im Eilverfahren zu erreichen, sind bisher gescheitert. Allerdings gab es in einigen Wahlbezirken Neuausz\u00e4hlungen, die die Bef\u00fcrchtungen des BSW zu best\u00e4tigen scheinen, dass Stimmen, die f\u00fcr die Partei abgegeben wurden, einer anderen zugerechnet worden sind.<\/p>\n<p>Die Partei hatte denkbar knapp den Einzug in den Bundestag verfehlt.\u00a0Das Ergebnis lag bei 4,981 Prozent. Genau 9.529 Kreuze fehlten, um die erforderlichen f\u00fcnf Prozent zu erreichen.<\/p>\n<p>Die drei Kartons von Mohamed Ali sind nur einer von insgesamt 900 Einspr\u00fcchen gegen die Bundestagswahl, die der noch nicht konstituierte Wahlpr\u00fcfungsausschuss des neuen Bundestags behandeln muss. Da der Ausschuss keiner Frist bei der Bearbeitung unterliegt, kann diese l\u00e4ngere Zeit in Anspruch nehmen. Eine ordentliche Klage vor dem Bundesverfassungsgericht ist aber erst m\u00f6glich, nachdem der Wahlpr\u00fcfungsausschuss und danach der Bundestag \u00fcber einen Einspruch entschieden haben. Einen Eilantrag des BSW hatte das Verfassungsgericht zur\u00fcckgewiesen.<\/p>\n<p>Sollte das BSW am Ende doch noch in den Bundestag einziehen \u2013 die Partei ist \u00fcberzeugt, dass ihr durch Z\u00e4hlfehler 30.000 Stimmen entgangen seien \u2013, hie\u00dfe das, dass die gerade erst formierte Koalition aus CDU\/CSU und SPD keine Mehrheit mehr h\u00e4tte. Allein diese Tatsache macht es unwahrscheinlich, dass sich im Wahlpr\u00fcfungsausschuss eine Mehrheit hinter diesen Einspruch stellt, obwohl das BSW keine Wahlwiederholung, sondern nur eine Neuausz\u00e4hlung verlangt.<\/p>\n<p>Gleich wie das Verfahren um diesen und alle anderen Einspr\u00fcche jedoch ausgeht \u2013 vor dem Beitritt zu Landesregierungen im vergangenen Sommer lagen die Umfragewerte des BSW hoch genug, um die F\u00fcnf-Prozent-H\u00fcrde problemlos zu nehmen. Vielfach als zu weitgehend wahrgenommene Kompromisse im Interesse der Regierungsbeteiligung und die Kooperation bei peinlichen Man\u00f6vern wie bei der Konstituierung des Th\u00fcringer Landtags lie\u00dfen aber die zu erwartenden Prozente in Folge deutlich fallen; bei der INSA-Umfrage im Juni letzten Jahres, also vor den Landtagswahlen, konnte das BSW noch\u00a0neun Prozent erwarten.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/239291-fuer-neuauszaehlung-bsw-geht-nach\/\">F\u00fcr Neuausz\u00e4hlung: BSW geht nach Karlsruhe \u2013 Wagenknecht-Partei steht vor Zerrei\u00dfprobe in Th\u00fcringen<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6omoii\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/243187-bsw-uebergibt-einspruch-gegen-bundestagswahl\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das BSW nahm heute einen weiteren Anlauf, um eine erneute Ausz\u00e4hlung der Bundestagswahl zu erreichen. Ob diese Bem\u00fchungen Erfolg haben, bleibt fraglich. Immerhin w\u00fcrde ein Ergebnis, das zugunsten des BSW ausf\u00e4llt, die MiniKo zum Platzen bringen. Die Co-Vorsitzende Amira Mohamed Ali r\u00fcckte heute mit drei Kartons voller Unterlagen an. Der 23.\u00a0April war der letzte Tag, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":82638,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1745432990"],"wp_automatic_camp":["217"],"91faf1b6b7094642f5ac91676be1473f":["BSW \u00fcbergibt Einspruch gegen Bundestagswahl"],"original_link":["https:\/\/de.rt.com\/inland\/243187-bsw-uebergibt-einspruch-gegen-bundestagswahl\/"],"_thumbnail_id":["82638"],"jnews_social_counter_last_update":["1778634516"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-04-23 20:30:48\";}"]},"categories":[19,23],"tags":[51583,6333,21838,278,18844],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>BSW \u00fcbergibt Einspruch gegen Bundestagswahl - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"BSW \u00fcbergibt Einspruch gegen Bundestagswahl\" \/>\n<meta property=\"og:description\" content=\"Das BSW nahm heute einen weiteren Anlauf, um eine erneute Ausz\u00e4hlung der Bundestagswahl zu erreichen. Ob diese Bem\u00fchungen Erfolg haben, bleibt fraglich. Immerhin w\u00fcrde ein Ergebnis, das zugunsten des BSW ausf\u00e4llt, die MiniKo zum Platzen bringen. Die Co-Vorsitzende Amira Mohamed Ali r\u00fcckte heute mit drei Kartons voller Unterlagen an. Der 23.\u00a0April war der letzte Tag, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-23T18:23:58+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/6809071bb480cc55ea239e46.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"BSW \u00fcbergibt Einspruch gegen Bundestagswahl\",\"datePublished\":\"2025-04-23T18:23:58+00:00\",\"dateModified\":\"2025-04-23T18:23:58+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/\"},\"wordCount\":420,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/BSW-uebergibt-Einspruch-gegen-Bundestagswahl.jpg\",\"keywords\":[\"BSW\",\"Bundestagswahl\",\"Einspruch\",\"gegen\",\"\u00fcbergibt\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/\",\"name\":\"BSW \u00fcbergibt Einspruch gegen Bundestagswahl - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/BSW-uebergibt-Einspruch-gegen-Bundestagswahl.jpg\",\"datePublished\":\"2025-04-23T18:23:58+00:00\",\"dateModified\":\"2025-04-23T18:23:58+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/BSW-uebergibt-Einspruch-gegen-Bundestagswahl.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/BSW-uebergibt-Einspruch-gegen-Bundestagswahl.jpg\",\"width\":460,\"height\":259,\"caption\":\"BSW \u00fcbergibt Einspruch gegen Bundestagswahl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"BSW \u00fcbergibt Einspruch gegen Bundestagswahl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"BSW \u00fcbergibt Einspruch gegen Bundestagswahl - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/","og_locale":"de_DE","og_type":"article","og_title":"BSW \u00fcbergibt Einspruch gegen Bundestagswahl","og_description":"Das BSW nahm heute einen weiteren Anlauf, um eine erneute Ausz\u00e4hlung der Bundestagswahl zu erreichen. Ob diese Bem\u00fchungen Erfolg haben, bleibt fraglich. Immerhin w\u00fcrde ein Ergebnis, das zugunsten des BSW ausf\u00e4llt, die MiniKo zum Platzen bringen. Die Co-Vorsitzende Amira Mohamed Ali r\u00fcckte heute mit drei Kartons voller Unterlagen an. Der 23.\u00a0April war der letzte Tag, [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-04-23T18:23:58+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/6809071bb480cc55ea239e46.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"BSW \u00fcbergibt Einspruch gegen Bundestagswahl","datePublished":"2025-04-23T18:23:58+00:00","dateModified":"2025-04-23T18:23:58+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/"},"wordCount":420,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/BSW-uebergibt-Einspruch-gegen-Bundestagswahl.jpg","keywords":["BSW","Bundestagswahl","Einspruch","gegen","\u00fcbergibt"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/","url":"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/","name":"BSW \u00fcbergibt Einspruch gegen Bundestagswahl - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/BSW-uebergibt-Einspruch-gegen-Bundestagswahl.jpg","datePublished":"2025-04-23T18:23:58+00:00","dateModified":"2025-04-23T18:23:58+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/BSW-uebergibt-Einspruch-gegen-Bundestagswahl.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/BSW-uebergibt-Einspruch-gegen-Bundestagswahl.jpg","width":460,"height":259,"caption":"BSW \u00fcbergibt Einspruch gegen Bundestagswahl"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/bsw-uebergibt-einspruch-gegen-bundestagswahl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"BSW \u00fcbergibt Einspruch gegen Bundestagswahl"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/82637"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=82637"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/82637\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/82638"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=82637"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=82637"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=82637"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}