{"id":81734,"date":"2025-04-07T15:12:17","date_gmt":"2025-04-07T13:12:17","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/"},"modified":"2025-04-07T15:12:17","modified_gmt":"2025-04-07T13:12:17","slug":"ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/","title":{"rendered":"&quot;Ermangelung von Mut&quot; \u2013 Dieter Hallervorden reagiert auf Medienschelte nach &quot;Negerkuss&quot;-Gag"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/67f3aebfb480cc012e3ddf8e.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die ARD pr\u00e4sentierte die Aufzeichnung einer lobhudelnden Jubil\u00e4umsshow. Der Humorist Dieter Hallervorden sorgte mit einer neuen Version eines alten Sketches f\u00fcr mediale, scharfe Kritik, bis hin zu Rassismusvorw\u00fcrfen. Hallervorden erkl\u00e4rt nun in einer Reaktion seinen Blick auf die f\u00fcr ihn bedenkliche &#8220;Wokeness&#8221;-Schelte.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die\u00a0<em>ARD<\/em>\u00a0g\u00f6nnte sich im 75.\u00a0Jahr des Bestehens\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.ardmediathek.de\/video\/75-jahre-ard\/75-jahre-ard-die-grosse-jubilaeumsshow\/ard\/Y3JpZDovL25kci5kZS9mYWFjMzRiMy03NjVhLTQzNmEtYTlhYy0xMjUzZGM3N2VkY2ZfZ2FuemVTZW5kdW5n\">eine Jubil\u00e4umsshow<\/a>,\u00a0dazu geladen, laut Eigenlob, die vermeintlich &#8220;prominenten G\u00e4ste Barbara Sch\u00f6neberger, G\u00fcnther Jauch, Iris Berben und Ingo Zamperoni&#8221;. Dabei nat\u00fcrlich bekannt und gesch\u00e4tzt seitens des GEZ-zahlenden Zielpublikums. \u00c4ltere Zuschauer sollten sich auch an unbeschwerte Fernsehjahre erinnern. Deshalb lud die junge Redaktion einen Humoristen alter Schule ein,\u00a0Dieter Hallervorden. Wie sich herausstellte, ein Fehler, oder wie es das\u00a0<em>Stern<\/em>-Magazin nach Ausstrahlung unmissverst\u00e4ndlich formulierte: &#8220;Doch die gef\u00fchlige Gala hinterlie\u00df in Teilen einen unverhofft bitteren Nachgeschmack.&#8221;\u00a0<\/p>\n<p>Was war nun vorgefallen? F\u00fcr Unkundige,\u00a0Dieter Hallervorden war in der alten Bundesrepublik bis 1980 Quoten-Garant, dies in Bezug auf seine Sendung &#8220;Nonstop Nonsens&#8221;. Kurze und knackige Alltagsszenen nachgespielt, humoristisch verpackt, inhaltlich schlicht, aber f\u00fcr Kinder und Eltern ein gro\u00dfes Vergn\u00fcgen an den Ger\u00e4ten. Jeder B\u00fcrger jener Zeit reagiert auf den Ruf &#8220;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=iZNOk7upy7A\">Palim Palim<\/a>&#8221; mit der Reaktion: &#8220;Eine Flasche Pommes Frites bitte&#8221;. Ein zeitloser Gag und Schenkelklopfer aus dem Jahr 1977. Hallervorden nahm sich nun rund 50 Jahre sp\u00e4ter vor, nach\u00a0<em>ARD<\/em>-Einladung zur Jubil\u00e4umssendung, diesen Sketch inhaltlich etwas aufzupeppen. Bezogen auf seine bekannte Kritik an der grassierenden Einschr\u00e4nkung der freien Rede, ohne R\u00fccksicht auf die &#8220;woken&#8221; Vorgaben junger Produzenten und Medienschaffenden. Es gelang ihm der inhaltliche Volltreffer.<\/p>\n<p>Eine\u00a0<em>Stern<\/em>-Autorin reagierte noch am Abend mit Schnappatmung und der Ver\u00f6ffentlichung eines Artikels, so hie\u00df es:<\/p>\n<p><em>&#8220;Das N-Wort in der ARD:\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.stern.de\/kultur\/tv\/dieter-hallervorden-und-das-n-wort-in-der-ard--geht-s-noch--35616110.html\">Geht\u2019s noch, Herr Hallervorden?<\/a>\u00a0Die Geburtstagsshow der ARD versprach, denkw\u00fcrdig zu werden. Dass es tats\u00e4chlich so kam, lag dann aber vor allem an der Darbietung eines bestimmten Gastes.&#8221;<\/em><\/p>\n<p>Hallervorden &#8220;versah den Gag in der Neuauflage mit einigen zus\u00e4tzlichen Zeilen&#8221;, oh welch Anma\u00dfung. Die\u00a0<em>Stern<\/em>-Autorin (<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/wiebketomescheit.blogspot.com\/\">Jahrgang 1984<\/a>) erkl\u00e4rt inbr\u00fcnstig korrekt:<\/p>\n<p><em>&#8220;Zu Anfang fragte [Gag-Partner] Effenberg ihn n\u00e4mlich, warum er [im Gef\u00e4ngnis] einsitze. Hallervorden antwortete, er habe die falschen Worte f\u00fcr Schokokuss und Sauce ungarischer Art benutzt \u2013 allerdings formulierte er es nicht so, sondern nutzte sowohl das N- als auch Z-Wort unbefangen vor einem Millionenpublikum.&#8221;\u00a0<\/em><\/p>\n<p>Die Autorin wollte dabei den\u00a0<em>Stern<\/em>-Lesern die Worte &#8220;Negerkuss&#8221; und &#8220;Zigeunerschnitzel&#8221; nicht zumuten. Weitere mediale Reaktionen lauteten:<\/p>\n<ul>\n<li><em><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.zeit.de\/kultur\/2025-04\/dieter-hallervorden-75-jahre-ard-meinungsfreiheit\">Die Zeit<\/a><\/em>:\u00a0Zum Jubil\u00e4um das N-Wort (\u2026)\u00a0Und dann erlaubt sich Didi Hallervorden einen rassistischen Ausfall<\/li>\n<li><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.spiegel.de\/kultur\/tv\/dieter-hallervorden-bei-75-jahre-ard-die-grosse-jubilaeumsshow-rassismusvorwuerfe-wegen-sketch-a-e6814c80-f9b5-453e-b2f7-5f15a9847bf8\"><em>Der Spiegel<\/em><\/a>: Rassismusvorw\u00fcrfe \u2013 Hallervorden weist Kritik an Sketch in ARD-Show von sich<\/li>\n<li><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.faz.net\/aktuell\/feuilleton\/dieter-hallervorden-provoziert-mit-palim-palim-rassismus-in-der-ard-110403511.html\"><em>FAZ<\/em><\/a>: Rassismus in der ARD? Dieter Hallervorden provoziert mit &#8216;Palim, Palim&#8217;<\/li>\n<\/ul>\n<p>Die\u00a0<em>Zeit<\/em>-Autorin (<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.anne-rabe.de\/ueber-mich\/\">Jahrgang 1986<\/a>) schildert dabei in ihrer Emp\u00f6rung ein exemplarisches Beispiel von woker Inflexibilit\u00e4t samt verinnerlichter Forderungshaltung (Bezahlschranke):<\/p>\n<p><em>&#8220;Die Show geht danach kommentarlos weiter. Nun kann man nicht beurteilen, ob beispielsweise der Moderator Pflaume geh\u00f6rt hat, was Hallervorden gesagt hat. Wom\u00f6glich waren er und die anderen G\u00e4ste auf dem anderen Teil der B\u00fchne gerade abgelenkt. Im Bild waren sie jedenfalls nicht. Aber die Show wurde aufgezeichnet, vor mehreren Tagen. Die Verantwortlichen h\u00e4tten diese Sequenz problemlos herausschneiden k\u00f6nnen. Sie h\u00e4tten den erst nach dieser Einleitung richtig beginnenden Sketch auch dann noch ausstrahlen k\u00f6nnen.&#8221;<\/em><\/p>\n<p>\u00dcberraschend dabei, bis zum Zeitpunkt der Ver\u00f6ffentlichung ist die\u00a0<em>Bild<\/em>-Zeitung noch nicht auf den medialen Emp\u00f6rungszug aufgesprungen. Das X-Portal &#8220;_Horizont_&#8221; pr\u00e4sentiert eine Zusammenfassung des vermeintlichen Eklats:<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"de\" dir=\"ltr\">Dieter Hallervorden und die Sprachpolizei <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/puf4kRz0Cg\">pic.twitter.com\/puf4kRz0Cg<\/a><\/p>\n<p>\u2014 _horizont_ (@hori_____zont) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/hori_____zont\/status\/1908942286244683860?ref_src=twsrc%5Etfw\">April 6, 2025<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Hallervorden sah sich nun dazu gezwungen, auf die breite, auch in den sozialen Medien, teils harsche Kritik an seiner neuen Version eines alten Gags reagieren zu m\u00fcssen. Im Rahmen eines Instagram-<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.instagram.com\/p\/DIHj3HKIyrp\/?igsh=MWdzM244MWQxYW5jcg%3D%3D\">Beitrags<\/a>\u00a0gibt der Satiriker unter anderem einleitend zu Protokoll:<\/p>\n<p><em>&#8220;Satire wird nicht mehr verstanden, diesmal betrifft es die gestrige Ausstrahlung der Jubil\u00e4umssendung &#8217;75 Jahre ARD&#8217;. Es werden Fragen wie diese gestellt: &#8216;Warum hat der Sender die Entgleisungen Hallervordens gesendet?&#8217; Es herrscht Verwunderung dar\u00fcber, wieso die ARD diesen Moment unzensiert zulie\u00df. Gut so. Ich will auf kein Gleis gestellt werden. Ich m\u00f6chte nicht zensiert werden. DANKE, ARD.&#8221;<\/em><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-instagram\">\n<div class=\"InstagramEmbed\">\n<blockquote class=\"instagram-media lazyload\" data-instagram=\"intagrm\" data-instgrm-captioned data-instgrm-permalink=\"https:\/\/www.instagram.com\/p\/DIHj3HKIyrp\/?utm_source=ig_embed&amp;utm_campaign=loading\" data-instgrm-version=\"14\" style=\" background:#FFF; border:0; border-radius:3px; box-shadow:0 0 1px 0 rgba(0,0,0,0.5),0 1px 10px 0 rgba(0,0,0,0.15); margin: 1px; max-width:540px; min-width:326px; padding:0; width:99.375%; width:-webkit-calc(100% - 2px); width:calc(100% - 2px);\">\n<div style=\"padding:16px;\"><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.instagram.com\/p\/DIHj3HKIyrp\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" background:#FFFFFF; line-height:0; padding:0 0; text-align:center; text-decoration:none; width:100%;\"><\/p>\n<div style=\" display: flex; flex-direction: row; align-items: center;\">\n<div style=\"background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 40px; margin-right: 14px; width: 40px;\"><\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 100px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 60px;\"><\/div>\n<\/div>\n<\/div>\n<div style=\"padding: 19% 0;\"><\/div>\n<div style=\"display:block; height:50px; margin:0 auto 12px; width:50px;\"><svg width=\"50px\" height=\"50px\" viewbox=\"0 0 60 60\" version=\"1.1\" xmlns=\"https:\/\/www.w3.org\/2000\/svg\" xmlns:xlink=\"https:\/\/www.w3.org\/1999\/xlink\"><g stroke=\"none\" stroke-width=\"1\" fill=\"none\" fill-rule=\"evenodd\"><g transform=\"translate(-511.000000, -20.000000)\" fill=\"#000000\"><g><path d=\"M556.869,30.41 C554.814,30.41 553.148,32.076 553.148,34.131 C553.148,36.186 554.814,37.852 556.869,37.852 C558.924,37.852 560.59,36.186 560.59,34.131 C560.59,32.076 558.924,30.41 556.869,30.41 M541,60.657 C535.114,60.657 530.342,55.887 530.342,50 C530.342,44.114 535.114,39.342 541,39.342 C546.887,39.342 551.658,44.114 551.658,50 C551.658,55.887 546.887,60.657 541,60.657 M541,33.886 C532.1,33.886 524.886,41.1 524.886,50 C524.886,58.899 532.1,66.113 541,66.113 C549.9,66.113 557.115,58.899 557.115,50 C557.115,41.1 549.9,33.886 541,33.886 M565.378,62.101 C565.244,65.022 564.756,66.606 564.346,67.663 C563.803,69.06 563.154,70.057 562.106,71.106 C561.058,72.155 560.06,72.803 558.662,73.347 C557.607,73.757 556.021,74.244 553.102,74.378 C549.944,74.521 548.997,74.552 541,74.552 C533.003,74.552 532.056,74.521 528.898,74.378 C525.979,74.244 524.393,73.757 523.338,73.347 C521.94,72.803 520.942,72.155 519.894,71.106 C518.846,70.057 518.197,69.06 517.654,67.663 C517.244,66.606 516.755,65.022 516.623,62.101 C516.479,58.943 516.448,57.996 516.448,50 C516.448,42.003 516.479,41.056 516.623,37.899 C516.755,34.978 517.244,33.391 517.654,32.338 C518.197,30.938 518.846,29.942 519.894,28.894 C520.942,27.846 521.94,27.196 523.338,26.654 C524.393,26.244 525.979,25.756 528.898,25.623 C532.057,25.479 533.004,25.448 541,25.448 C548.997,25.448 549.943,25.479 553.102,25.623 C556.021,25.756 557.607,26.244 558.662,26.654 C560.06,27.196 561.058,27.846 562.106,28.894 C563.154,29.942 563.803,30.938 564.346,32.338 C564.756,33.391 565.244,34.978 565.378,37.899 C565.522,41.056 565.552,42.003 565.552,50 C565.552,57.996 565.522,58.943 565.378,62.101 M570.82,37.631 C570.674,34.438 570.167,32.258 569.425,30.349 C568.659,28.377 567.633,26.702 565.965,25.035 C564.297,23.368 562.623,22.342 560.652,21.575 C558.743,20.834 556.562,20.326 553.369,20.18 C550.169,20.033 549.148,20 541,20 C532.853,20 531.831,20.033 528.631,20.18 C525.438,20.326 523.257,20.834 521.349,21.575 C519.376,22.342 517.703,23.368 516.035,25.035 C514.368,26.702 513.342,28.377 512.574,30.349 C511.834,32.258 511.326,34.438 511.181,37.631 C511.035,40.831 511,41.851 511,50 C511,58.147 511.035,59.17 511.181,62.369 C511.326,65.562 511.834,67.743 512.574,69.651 C513.342,71.625 514.368,73.296 516.035,74.965 C517.703,76.634 519.376,77.658 521.349,78.425 C523.257,79.167 525.438,79.673 528.631,79.82 C531.831,79.965 532.853,80.001 541,80.001 C549.148,80.001 550.169,79.965 553.369,79.82 C556.562,79.673 558.743,79.167 560.652,78.425 C562.623,77.658 564.297,76.634 565.965,74.965 C567.633,73.296 568.659,71.625 569.425,69.651 C570.167,67.743 570.674,65.562 570.82,62.369 C570.966,59.17 571,58.147 571,50 C571,41.851 570.966,40.831 570.82,37.631\"><\/path><\/g><\/g><\/g><\/svg><\/div>\n<div style=\"padding-top: 8px;\">\n<div style=\" color:#3897f0; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:550; line-height:18px;\">View this post on Instagram<\/div>\n<\/div>\n<div style=\"padding: 12.5% 0;\"><\/div>\n<div style=\"display: flex; flex-direction: row; margin-bottom: 14px; align-items: center;\">\n<div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(0px) translateY(7px);\"><\/div>\n<div style=\"background-color: #F4F4F4; height: 12.5px; transform: rotate(-45deg) translateX(3px) translateY(1px); width: 12.5px; flex-grow: 0; margin-right: 14px; margin-left: 2px;\"><\/div>\n<div style=\"background-color: #F4F4F4; border-radius: 50%; height: 12.5px; width: 12.5px; transform: translateX(9px) translateY(-18px);\"><\/div>\n<\/div>\n<div style=\"margin-left: 8px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 50%; flex-grow: 0; height: 20px; width: 20px;\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 2px solid transparent; border-left: 6px solid #f4f4f4; border-bottom: 2px solid transparent; transform: translateX(16px) translateY(-4px) rotate(30deg)\"><\/div>\n<\/div>\n<div style=\"margin-left: auto;\">\n<div style=\" width: 0px; border-top: 8px solid #F4F4F4; border-right: 8px solid transparent; transform: translateY(16px);\"><\/div>\n<div style=\" background-color: #F4F4F4; flex-grow: 0; height: 12px; width: 16px; transform: translateY(-4px);\"><\/div>\n<div style=\" width: 0; height: 0; border-top: 8px solid #F4F4F4; border-left: 8px solid transparent; transform: translateY(-4px) translateX(8px);\"><\/div>\n<\/div>\n<\/div>\n<div style=\"display: flex; flex-direction: column; flex-grow: 1; justify-content: center; margin-bottom: 24px;\">\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; margin-bottom: 6px; width: 224px;\"><\/div>\n<div style=\" background-color: #F4F4F4; border-radius: 4px; flex-grow: 0; height: 14px; width: 144px;\"><\/div>\n<\/div>\n<p><\/a><\/p>\n<p style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; line-height:17px; margin-bottom:0; margin-top:8px; overflow:hidden; padding:8px 0 7px; text-align:center; text-overflow:ellipsis; white-space:nowrap;\"><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.instagram.com\/p\/DIHj3HKIyrp\/?utm_source=ig_embed&amp;utm_campaign=loading\" style=\" color:#c9c8cd; font-family:Arial,sans-serif; font-size:14px; font-style:normal; font-weight:normal; line-height:17px; text-decoration:none;\">A post shared by Dieter Hallervorden (@dieterhallervorden)<\/a><\/p>\n<\/div>\n<\/blockquote>\n<\/div>\n<\/div>\n<p>Pressevertretern, die nach Ausstrahlung der Sendung anscheinend umgehend eine Stellungnahme einforderten, habe Hallervorden Folgendes schriftlich mitgeteilt:<\/p>\n<p><em>&#8220;Woke-Menschen von heute versuchen \u00e4ngstlich, nicht aus der Reihe zu tanzen, befolgen akribisch alle Social Media Gebote, um keine Likes aufs Spiel zu setzen und verstehen keine Satire mehr, weil Satire aus Angst vor Missverst\u00e4ndnissen nicht mehr vorkommt. In Ermangelung von Mut, sich \u00fcber die wirklichen Missst\u00e4nde zu erregen, weil diese anzuprangern, gerade nicht in Mode ist, ereifert man sich \u00fcber einen Komiker, der auf einem Knastbett sitzt und einen ber\u00fchmten Sketch mit neuem Text beginnt: &#8216;Uiuiuiui, ich habe dies gesagt und das gesagt und das darf man heute alles nicht mehr tun, das hab ich irgendwie verpeilt und nun sitze ich im Bau.&#8217; Wer wei\u00df, vielleicht k\u00f6nnte das durchaus bald passieren, weil solche Bestrafung von den wirklichen Verfehlungen unserer Zeitenwende ablenkt.&#8221;<\/em><\/p>\n<p>Der Satiriker erkennt folgende Gefahr f\u00fcr die Gegenwart, den dynamischen, zu beobachtenden Umbauma\u00dfnahmen der Gesellschaft samt eingeschr\u00e4nktem Meinungskorridor:<\/p>\n<p><em>&#8220;Wenn Wokeness bedeutet: &#8216;Wachsamkeit f\u00fcr Missst\u00e4nde&#8217; so w\u00e4re es w\u00fcnschenswert, dass sie ihre Aufmerksamkeit auf die eine oder andere Realsatire unserer Zeit lenkt, die leider gar nicht satirisch gemeint ist, sondern mit feierlichem Ernst verk\u00fcndet wird: Die Bundesregierung nimmt gerade den Tod von tausenden von jungen Menschen billigend in Kauf, denkt dar\u00fcber nach, dass die Streitkraft um 70.000 Soldat:innen erweitert werden m\u00fcsste, denn die NATO hat letzte Woche ausgerechnet, dass an der &#8220;Ostfront&#8221; t\u00e4glich 5000 Soldat:innen sterben werden. Ich gehe jede Wette ein, dass eine Satire mit Regierungsbeamten im Knast auf dem Index st\u00fcnde und dass man &#8216;Kanonenfutter an der Ostfront&#8217; im Zuge unseres neuen Demokratie-Verst\u00e4ndnisses nicht sagen darf.&#8221;<\/em><\/p>\n<p>Ob dabei die Nutzung von &#8220;Gender-Sprache&#8221; seitens Hallervordens als erster Kotau gewertet wird oder einen weiteren schlichten Nadelstich darstellt, obliegt der Betrachtung des jeweiligen Lesers. Die\u00a0<em>Stern<\/em>-Redaktion zeigt sich zumindest noch nicht befriedet. Es folgt der Anschlussartikel, die Brandmarkung Hallervordens als Wiederholungst\u00e4ter. Der\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.stern.de\/lifestyle\/leute\/dieter-hallervorden-sagt-das-n-wort---nicht-sein-erster-aussetzer-35618412.html\">Titel\u00a0<\/a>lautet dabei mehr als entlarvend:<\/p>\n<p><em>&#8220;Blackfacing, Antisemitismus, Provokationen: Die Akte Dieter Hallervorden.&#8221;<\/em><\/p>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/gesellschaft\/241606-vorwurf-russlandfreundlichkeit-zeitung-unterzieht-saenger-tino-eisbrenner-einem-verhoer\/\">Vorwurf der &#8220;Russlandfreundlichkeit&#8221;: Zeitung unterzieht den S\u00e4nger Tino Eisbrenner einem Verh\u00f6r<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6pjdph\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><script async defer src=\"https:\/\/platform.instagram.com\/en_US\/embeds.js\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/241770-ermangelung-von-mut-dieter-hallervorden\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die ARD pr\u00e4sentierte die Aufzeichnung einer lobhudelnden Jubil\u00e4umsshow. Der Humorist Dieter Hallervorden sorgte mit einer neuen Version eines alten Sketches f\u00fcr mediale, scharfe Kritik, bis hin zu Rassismusvorw\u00fcrfen. Hallervorden erkl\u00e4rt nun in einer Reaktion seinen Blick auf die f\u00fcr ihn bedenkliche &#8220;Wokeness&#8221;-Schelte. Die\u00a0ARD\u00a0g\u00f6nnte sich im 75.\u00a0Jahr des Bestehens\u00a0eine Jubil\u00e4umsshow,\u00a0dazu geladen, laut Eigenlob, die vermeintlich &#8220;prominenten [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":81735,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1744031649"],"wp_automatic_camp":["217"],"ba4379596e0dd83d5c4f16029afe48dd":["&quot;Ermangelung von Mut&quot; \u2013 Dieter Hallervorden reagiert auf Medienschelte nach &quot;Negerkuss&quot;-Gag"],"original_link":["https:\/\/de.rt.com\/inland\/241770-ermangelung-von-mut-dieter-hallervorden\/"],"_thumbnail_id":["81735"],"jnews_social_counter_last_update":["1778680308"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-04-07 15:15:20\";}"]},"categories":[19,23],"tags":[133,15701,64103,64104,34354,979,64102,64105,281,50],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Ermangelung von Mut&quot; \u2013 Dieter Hallervorden reagiert auf Medienschelte nach &quot;Negerkuss&quot;-Gag - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Ermangelung von Mut&quot; \u2013 Dieter Hallervorden reagiert auf Medienschelte nach &quot;Negerkuss&quot;-Gag\" \/>\n<meta property=\"og:description\" content=\"Die ARD pr\u00e4sentierte die Aufzeichnung einer lobhudelnden Jubil\u00e4umsshow. Der Humorist Dieter Hallervorden sorgte mit einer neuen Version eines alten Sketches f\u00fcr mediale, scharfe Kritik, bis hin zu Rassismusvorw\u00fcrfen. Hallervorden erkl\u00e4rt nun in einer Reaktion seinen Blick auf die f\u00fcr ihn bedenkliche &#8220;Wokeness&#8221;-Schelte. Die\u00a0ARD\u00a0g\u00f6nnte sich im 75.\u00a0Jahr des Bestehens\u00a0eine Jubil\u00e4umsshow,\u00a0dazu geladen, laut Eigenlob, die vermeintlich &#8220;prominenten [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-07T13:12:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/67f3aebfb480cc012e3ddf8e.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"5\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"&quot;Ermangelung von Mut&quot; \u2013 Dieter Hallervorden reagiert auf Medienschelte nach &quot;Negerkuss&quot;-Gag\",\"datePublished\":\"2025-04-07T13:12:17+00:00\",\"dateModified\":\"2025-04-07T13:12:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/\"},\"wordCount\":1076,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/quotErmangelung-von-Mutquot-\u2013-Dieter-Hallervorden-reagiert-auf-Medienschelte-nach.jpg\",\"keywords\":[\"AUF\",\"Dieter\",\"Hallervorden\",\"Medienschelte\",\"Mutquot\",\"nach\",\"quotErmangelung\",\"quotNegerkussquotGag\",\"reagiert\",\"von\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/\",\"name\":\"&quot;Ermangelung von Mut&quot; \u2013 Dieter Hallervorden reagiert auf Medienschelte nach &quot;Negerkuss&quot;-Gag - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/quotErmangelung-von-Mutquot-\u2013-Dieter-Hallervorden-reagiert-auf-Medienschelte-nach.jpg\",\"datePublished\":\"2025-04-07T13:12:17+00:00\",\"dateModified\":\"2025-04-07T13:12:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/quotErmangelung-von-Mutquot-\u2013-Dieter-Hallervorden-reagiert-auf-Medienschelte-nach.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/quotErmangelung-von-Mutquot-\u2013-Dieter-Hallervorden-reagiert-auf-Medienschelte-nach.jpg\",\"width\":460,\"height\":259,\"caption\":\"&quot;Ermangelung von Mut&quot; \u2013 Dieter Hallervorden reagiert auf Medienschelte nach &quot;Negerkuss&quot;-Gag\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&quot;Ermangelung von Mut&quot; \u2013 Dieter Hallervorden reagiert auf Medienschelte nach &quot;Negerkuss&quot;-Gag\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"&quot;Ermangelung von Mut&quot; \u2013 Dieter Hallervorden reagiert auf Medienschelte nach &quot;Negerkuss&quot;-Gag - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/","og_locale":"de_DE","og_type":"article","og_title":"&quot;Ermangelung von Mut&quot; \u2013 Dieter Hallervorden reagiert auf Medienschelte nach &quot;Negerkuss&quot;-Gag","og_description":"Die ARD pr\u00e4sentierte die Aufzeichnung einer lobhudelnden Jubil\u00e4umsshow. Der Humorist Dieter Hallervorden sorgte mit einer neuen Version eines alten Sketches f\u00fcr mediale, scharfe Kritik, bis hin zu Rassismusvorw\u00fcrfen. Hallervorden erkl\u00e4rt nun in einer Reaktion seinen Blick auf die f\u00fcr ihn bedenkliche &#8220;Wokeness&#8221;-Schelte. Die\u00a0ARD\u00a0g\u00f6nnte sich im 75.\u00a0Jahr des Bestehens\u00a0eine Jubil\u00e4umsshow,\u00a0dazu geladen, laut Eigenlob, die vermeintlich &#8220;prominenten [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-04-07T13:12:17+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/67f3aebfb480cc012e3ddf8e.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"5\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"&quot;Ermangelung von Mut&quot; \u2013 Dieter Hallervorden reagiert auf Medienschelte nach &quot;Negerkuss&quot;-Gag","datePublished":"2025-04-07T13:12:17+00:00","dateModified":"2025-04-07T13:12:17+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/"},"wordCount":1076,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/quotErmangelung-von-Mutquot-\u2013-Dieter-Hallervorden-reagiert-auf-Medienschelte-nach.jpg","keywords":["AUF","Dieter","Hallervorden","Medienschelte","Mutquot","nach","quotErmangelung","quotNegerkussquotGag","reagiert","von"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/","url":"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/","name":"&quot;Ermangelung von Mut&quot; \u2013 Dieter Hallervorden reagiert auf Medienschelte nach &quot;Negerkuss&quot;-Gag - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/quotErmangelung-von-Mutquot-\u2013-Dieter-Hallervorden-reagiert-auf-Medienschelte-nach.jpg","datePublished":"2025-04-07T13:12:17+00:00","dateModified":"2025-04-07T13:12:17+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/quotErmangelung-von-Mutquot-\u2013-Dieter-Hallervorden-reagiert-auf-Medienschelte-nach.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/quotErmangelung-von-Mutquot-\u2013-Dieter-Hallervorden-reagiert-auf-Medienschelte-nach.jpg","width":460,"height":259,"caption":"&quot;Ermangelung von Mut&quot; \u2013 Dieter Hallervorden reagiert auf Medienschelte nach &quot;Negerkuss&quot;-Gag"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/ermangelung-von-mut-dieter-hallervorden-reagiert-auf-medienschelte-nach-negerkuss-gag\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"&quot;Ermangelung von Mut&quot; \u2013 Dieter Hallervorden reagiert auf Medienschelte nach &quot;Negerkuss&quot;-Gag"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/81734"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=81734"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/81734\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/81735"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=81734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=81734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=81734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}