{"id":81653,"date":"2025-04-05T21:41:29","date_gmt":"2025-04-05T19:41:29","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/"},"modified":"2025-04-05T21:41:29","modified_gmt":"2025-04-05T19:41:29","slug":"schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/","title":{"rendered":"Schweiz gegen Trump: Komplimente und Charme als geheime Waffe der Diplomaten"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/67f0f85fb480cc4a1e0c8eb2.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die Schweiz steht vor hohen US-Z\u00f6llen von 31 Prozent. Der Bundesrat hofft, durch Zugest\u00e4ndnisse wie Investitionsgarantien in die USA eine L\u00f6sung zu finden, \u00e4hnlich wie beim Abkommen mit Indien. Alternativ k\u00f6nnten Agrar- und Medizintechnikregulierungen gelockert werden.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p data-start=\"0\" data-end=\"250\"><em>von Hans-Ueli L\u00e4ppli<\/em><\/p>\n<p data-start=\"0\" data-end=\"250\">Donald Trump tut wieder, was er am besten kann: Drohen, Druck aus\u00fcben und dann Deals abschlie\u00dfen, die er als &#8220;historisch&#8221; darstellt. Was jedoch tats\u00e4chlich als historisch in die Geschichte eingeht, ist der weltweite B\u00f6rsenabsturz \u2013 inklusive der Schweiz.<\/p>\n<p data-start=\"252\" data-end=\"496\">Diesmal trifft es die Schweiz besonders hart: 31 Prozent Z\u00f6lle auf Exporte in die USA \u2013 eine wirtschaftliche Kampfansage. Doch anstatt laut zu protestieren, versucht der Bundesrat einmal mehr, den &#8220;Dealmaker&#8221; mit Schweizer Charme zu \u00fcberlisten.<\/p>\n<p data-start=\"491\" data-end=\"890\">Nat\u00fcrlich ist die Schweiz ein fairer Handelspartner. Nat\u00fcrlich hat sie kaum Z\u00f6lle. Nat\u00fcrlich spielt sie nach den Regeln. Aber interessiert das Trump? Nein. Seine Z\u00f6lle sind keine rationalen Ma\u00dfnahmen, sondern ein politisches Muskelspiel. Die Schweiz kann also noch so oft betonen, dass sie keinen Handelskrieg provoziert hat \u2013 die Realit\u00e4t ist: Trump will ein Zugest\u00e4ndnis, koste es, was es wolle.<\/p>\n<p data-start=\"892\" data-end=\"944\"><strong data-start=\"896\" data-end=\"942\">Die Indien-Strategie \u2013 ein bew\u00e4hrter Trick<\/strong><\/p>\n<p data-start=\"946\" data-end=\"1220\">Nun bastelt die Schweiz an einer Gegenstrategie: Investitionen versprechen, so wie es mit Indien gemacht wurde. 100 Milliarden Franken f\u00fcr 20 Jahre, eine Million Arbeitspl\u00e4tze \u2013 das klingt gro\u00df, war aber ein clever kalkulierter Deal. Ob das mit den USA funktioniert? Maybe.<\/p>\n<p data-start=\"1222\" data-end=\"1591\">Denn die US-Wirtschaft ist keine aufstrebende Boomregion mit Investitionsbedarf. Sie ist ges\u00e4ttigt, kapitalstark und wird nicht beeindruckt sein, wenn ein paar Schweizer Firmen versprechen, noch mehr zu investieren. Zudem ist die Schweiz l\u00e4ngst unter den Top-6-Investoren in den USA. Was soll da noch kommen? 500 Milliarden? Ein neues Silicon Valley &#8220;Made in Zug&#8221;?<\/p>\n<p data-start=\"1629\" data-end=\"1880\">Vielleicht hofft man in Bern auch einfach, dass Trump blufft. Dass die Schweiz doch noch eine Ausnahme bekommt. Doch so funktioniert Trumps Welt nicht. Wer ihm nichts gibt, zahlt drauf. Die Schweiz muss sich also entscheiden: Mitspielen oder zahlen.<\/p>\n<p data-start=\"1882\" data-end=\"2172\">Es gibt durchaus Alternativen \u2013 etwa Agrarprodukte oder Medizintechnik-Regulierungen zu lockern. Doch das sind keine &#8220;Big Deals&#8221;, sondern kleine Gef\u00e4lligkeiten. Wenn es also bei den 31 Prozent bleibt, k\u00f6nnte der clevere Schweizer Plan als das enden, was Trump am meisten verachtet: ein Zeichen der Schw\u00e4che.<\/p>\n<p data-start=\"1882\" data-end=\"2172\"><strong>Mehr zum Thema<\/strong>\u00a0&#8211;\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/dert.tech\/oesterreich\/241491-oesterreich-fordert-rasche-einigung-im\/\">\u00d6sterreich fordert rasche Einigung im Zollstreit<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6p7xpm\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/241635-schweiz-gegen-trump-komplimente-und\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die Schweiz steht vor hohen US-Z\u00f6llen von 31 Prozent. Der Bundesrat hofft, durch Zugest\u00e4ndnisse wie Investitionsgarantien in die USA eine L\u00f6sung zu finden, \u00e4hnlich wie beim Abkommen mit Indien. Alternativ k\u00f6nnten Agrar- und Medizintechnikregulierungen gelockert werden. von Hans-Ueli L\u00e4ppli Donald Trump tut wieder, was er am besten kann: Drohen, Druck aus\u00fcben und dann Deals abschlie\u00dfen, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":81654,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1743882234"],"wp_automatic_camp":["217"],"8c3c4ebd82b5da2cd96962da6ec9bc82":["Schweiz gegen Trump: Komplimente und Charme als geheime Waffe der Diplomaten"],"original_link":["https:\/\/de.rt.com\/meinung\/241635-schweiz-gegen-trump-komplimente-und\/"],"_thumbnail_id":["81654"],"jnews_social_counter_last_update":["1784099515"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-04-05 21:44:57\";}"]},"categories":[19,23],"tags":[273,40769,82,9831,278,5312,64062,4207,1639,140,6663],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Schweiz gegen Trump: Komplimente und Charme als geheime Waffe der Diplomaten - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Schweiz gegen Trump: Komplimente und Charme als geheime Waffe der Diplomaten\" \/>\n<meta property=\"og:description\" content=\"Die Schweiz steht vor hohen US-Z\u00f6llen von 31 Prozent. Der Bundesrat hofft, durch Zugest\u00e4ndnisse wie Investitionsgarantien in die USA eine L\u00f6sung zu finden, \u00e4hnlich wie beim Abkommen mit Indien. Alternativ k\u00f6nnten Agrar- und Medizintechnikregulierungen gelockert werden. von Hans-Ueli L\u00e4ppli Donald Trump tut wieder, was er am besten kann: Drohen, Druck aus\u00fcben und dann Deals abschlie\u00dfen, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-04-05T19:41:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/67f0f85fb480cc4a1e0c8eb2.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Schweiz gegen Trump: Komplimente und Charme als geheime Waffe der Diplomaten\",\"datePublished\":\"2025-04-05T19:41:29+00:00\",\"dateModified\":\"2025-04-05T19:41:29+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/\"},\"wordCount\":397,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/Schweiz-gegen-Trump-Komplimente-und-Charme-als-geheime-Waffe-der.jpg\",\"keywords\":[\"als\",\"Charme\",\"der\",\"Diplomaten\",\"gegen\",\"geheime\",\"Komplimente\",\"schweiz\",\"trump\",\"und\",\"Waffe\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/\",\"name\":\"Schweiz gegen Trump: Komplimente und Charme als geheime Waffe der Diplomaten - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/Schweiz-gegen-Trump-Komplimente-und-Charme-als-geheime-Waffe-der.jpg\",\"datePublished\":\"2025-04-05T19:41:29+00:00\",\"dateModified\":\"2025-04-05T19:41:29+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/Schweiz-gegen-Trump-Komplimente-und-Charme-als-geheime-Waffe-der.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/Schweiz-gegen-Trump-Komplimente-und-Charme-als-geheime-Waffe-der.jpg\",\"width\":460,\"height\":259,\"caption\":\"Schweiz gegen Trump: Komplimente und Charme als geheime Waffe der Diplomaten\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Schweiz gegen Trump: Komplimente und Charme als geheime Waffe der Diplomaten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Schweiz gegen Trump: Komplimente und Charme als geheime Waffe der Diplomaten - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/","og_locale":"de_DE","og_type":"article","og_title":"Schweiz gegen Trump: Komplimente und Charme als geheime Waffe der Diplomaten","og_description":"Die Schweiz steht vor hohen US-Z\u00f6llen von 31 Prozent. Der Bundesrat hofft, durch Zugest\u00e4ndnisse wie Investitionsgarantien in die USA eine L\u00f6sung zu finden, \u00e4hnlich wie beim Abkommen mit Indien. Alternativ k\u00f6nnten Agrar- und Medizintechnikregulierungen gelockert werden. von Hans-Ueli L\u00e4ppli Donald Trump tut wieder, was er am besten kann: Drohen, Druck aus\u00fcben und dann Deals abschlie\u00dfen, [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-04-05T19:41:29+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/67f0f85fb480cc4a1e0c8eb2.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Schweiz gegen Trump: Komplimente und Charme als geheime Waffe der Diplomaten","datePublished":"2025-04-05T19:41:29+00:00","dateModified":"2025-04-05T19:41:29+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/"},"wordCount":397,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/Schweiz-gegen-Trump-Komplimente-und-Charme-als-geheime-Waffe-der.jpg","keywords":["als","Charme","der","Diplomaten","gegen","geheime","Komplimente","schweiz","trump","und","Waffe"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/","url":"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/","name":"Schweiz gegen Trump: Komplimente und Charme als geheime Waffe der Diplomaten - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/Schweiz-gegen-Trump-Komplimente-und-Charme-als-geheime-Waffe-der.jpg","datePublished":"2025-04-05T19:41:29+00:00","dateModified":"2025-04-05T19:41:29+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/Schweiz-gegen-Trump-Komplimente-und-Charme-als-geheime-Waffe-der.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/04\/Schweiz-gegen-Trump-Komplimente-und-Charme-als-geheime-Waffe-der.jpg","width":460,"height":259,"caption":"Schweiz gegen Trump: Komplimente und Charme als geheime Waffe der Diplomaten"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/schweiz-gegen-trump-komplimente-und-charme-als-geheime-waffe-der-diplomaten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Schweiz gegen Trump: Komplimente und Charme als geheime Waffe der Diplomaten"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/81653"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=81653"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/81653\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/81654"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=81653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=81653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=81653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}