{"id":80839,"date":"2025-03-24T18:23:24","date_gmt":"2025-03-24T16:23:24","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/"},"modified":"2025-03-24T18:23:24","modified_gmt":"2025-03-24T16:23:24","slug":"im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/","title":{"rendered":"Im Herbst ist Krieg \u2013 Deutscher Professor irritiert mit Panikmache"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/67e1748848fbef242e65985d.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Deutschland will aufr\u00fcsten. Als Grund m\u00fcssen angebliche \u00dcberfallpl\u00e4ne Russlands herhalten. Deutschland versinkt in einem Sumpf aus Propaganda, macht ein Interview mit Kriegsprofessor S\u00f6nke Neitzel deutlich. Die deutsche Gegenwart gleicht l\u00e4ngst den Drei\u00dfigerjahren des letzten Jahrhunderts.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Kaum eine Personalie f\u00fchrt so deutlich vor, dass Deutschland an den v\u00f6lkerrechtlichen Grundlagen der deutschen Einheit scheitert, wie der deutsche Kriegsprofessor S\u00f6nke Neitzel. Er trommelt seit Jahren f\u00fcr Aufr\u00fcstung und die Militarisierung Deutschlands. Bereits im Jahr 2017 forderte er, der Aufbau einer kriegsf\u00e4higen Bundeswehr m\u00fcsse als gesellschaftliche Querschnittsaufgabe gesehen werden.<\/p>\n<p>Angesichts des Ukraine-Konflikts und der damit ganz hochoffiziell verbreiteten Desinformation der Bundesregierung sieht der Kriegsprofessor nun seine Stunde gekommen und wiederholt seine Forderungen. Um ihr Nachdruck zu verleihen, nutzt Neitzel ein ganz unlauteres Mittel, denn er setzt auf die Verbreitung von Angst und sch\u00fcrt Ressentiments.\u00a0<\/p>\n<p>In einem\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.bild.de\/politik\/inland\/putin-angriff-historiker-warnt-koennte-letzter-friedenssommer-sein-67d84e9a7de6aa748383cded\">Interview<\/a>\u00a0mit der\u00a0<em>Bild<\/em>-Zeitung behauptet er, dieser Sommer k\u00f6nnte zum letzten Sommer werden, den die Deutschen in Frieden verbringen k\u00f6nnen, denn Russland k\u00f6nnte bereits im Herbst das Baltikum \u00fcberfallen. Die vielen Konjunktive sollen \u00fcber das Fehlen von Belegen hinwegt\u00e4uschen.\u00a0<\/p>\n<p>Mit der Prognose, Russland wolle die EU \u00fcberfallen, ist Neitzel aber nicht allein. Die alte wie die k\u00fcnftige Bundesregierung setzen ebenfalls auf Panikmache. Und wenn schon alle so sch\u00f6n gleichf\u00f6rmig desinformieren, dann macht die Industrie eben auch mit. Airbus-Chef Obermann warnte gestern vor einem russischen \u00dcberfall bis sp\u00e4testens 2029. Neben Passagierflugzeugen produziert Airbus R\u00fcstungsg\u00fcter. Die Warnung wurzelt also mehr in finanziellem Eigeninteresse als in Fakten. Mit seiner Herbstprognose gibt Neitzel allerdings ein neues Tempo vor. In wenigen Monaten ist Krieg.\u00a0\u00a0<\/p>\n<p><strong>Behauptungen ohne Quelle<\/strong><\/p>\n<p>Nat\u00fcrlich ist das, was Neitzel und Co. von sich geben, propagandistischer Unsinn. Steve Witkoff hat erst vor wenigen Tagen versichert, dass Russland nicht die Absicht habe, die EU oder L\u00e4nder der NATO zu \u00fcberfallen. Grundlage f\u00fcr die Aussage Witkoffs sind seine Gespr\u00e4che mit Putin. Damit hat Witkoff dem deutschen Expertentum viel voraus. Direkte Kontakte nach Russland als Grundlage f\u00fcr ihre Behauptungen fehlen sowohl deutschen Politikern als auch deutschen Professoren, die sich vorgenommen haben, die deutsche Gesellschaft auf Krieg zu trimmen. Dies gilt auch f\u00fcr die Vertreter der deutschen R\u00fcstungsindustrie. Ihr dumpfes Geraune kommt ohne echte Quellen aus.<\/p>\n<p>Witkoff ist Diplomat und Vertrauter von US-Pr\u00e4sident Donald Trump. Er und sein Team versuchen etwas, was man in Deutschland strikt unterl\u00e4sst: den Ukraine-Konflikt diplomatisch zu l\u00f6sen. Deutschland ist hier nicht ganz zuf\u00e4llig ein Totalausfall. Deutschland hat an Frieden kein Interesse.\u00a0<\/p>\n<p>Statt den Weg der Vernunft zu gehen, setzt man in Deutschland auf Gewalt. Man setzt auf Aufr\u00fcstung und Militarisierung. Statt auf Diplomatie setzt man auf Propaganda, um die eigene Bev\u00f6lkerung mit Angst und Hass kriegswillig zu machen. Dabei wissen die Verantwortlichen wie Pistorius, Baerbock und Merz, dass die von ihnen gef\u00f6rderte Angst vor Russland unbegr\u00fcndet ist. Es gibt in Russland keine Pl\u00e4ne f\u00fcr einen \u00dcberfall.<\/p>\n<p><strong>Systematischer Aufbau von Hass und Ressentiment<\/strong>\u00a0<\/p>\n<p>Das ist neben Witkoffs Aussagen mit direktem Quellenbezug schon daran erkennbar, dass es f\u00fcr den systematischen Aufbau von Hass und die systematische Hetze gegen\u00fcber Russland und Russen, wie es in Deutschland gerade gang und g\u00e4be ist, in Russland kein \u00c4quivalent gibt. Auch \u00c4u\u00dferungen wie die westeurop\u00e4ischer Politiker, die sich offen zum Ziel eines Sieges \u00fcber Russland bekennen, sucht man in Russland vergebens. Den diplomatischen Kanal hat Russland immer offen gehalten. Ziel ist eine diplomatische L\u00f6sung des Ukraine-Konflikts. Deutschland hat mit diplomatischem Abbruch geantwortet und setzt stattdessen auf einen milit\u00e4rischen Sieg.\u00a0<\/p>\n<p>Weil aber jeder Beleg daf\u00fcr fehlt, dass Russland einen Krieg mit den L\u00e4ndern der EU plant, Deutschland und seine sogenannten Experten wie Kriegsprofessor Neitzel aber dennoch behaupten, es brauche nicht nur umfassende Aufr\u00fcstung, sondern es m\u00fcsse obendrein noch der Geist des Militarismus in die deutsche Gesellschaft gepflanzt werden, ist mit etwas anderem zu rechnen: Deutschland trifft Vorbereitungen f\u00fcr einen \u00dcberfall auf Russland. Zu diesem Zweck r\u00fcstet Deutschland auf.\u00a0<\/p>\n<p>Deutschland hat in den vergangenen Jahren schon eine Vielzahl an Bedingungen geschaffen, durch die eine totale Manipulation der Bev\u00f6lkerung m\u00f6glich geworden ist. In Deutschland wurde ein gesellschaftliches Umfeld etabliert, das an die Drei\u00dfigerjahre des vergangenen Jahrhunderts erinnert. Es herrscht ein umfassendes System an Zensur und Repression. Die enge Verflechtung des Staates mit seinen Vorfeldorganisationen, den sogenannten NGOs, dient der Verbreitung von Kriegspropaganda, der Unterdr\u00fcckung der Opposition und von Regierungskritikern. Der deutsche Informationsraum ist nahezu hermetisch von der Au\u00dfenwelt abgeschlossen.\u00a0<\/p>\n<p><strong>Deutschlands Geisterfahrt<\/strong><\/p>\n<p>Warnungen, die Meinungsfreiheit zu respektieren sowie die Grundlagen der Demokratie nicht zu untergraben, wie sie von US-Vizepr\u00e4sident J.D. Vance mehrfach an Deutschland und die EU gerichtet wurden, werden br\u00fcsk und reflexartig zur\u00fcckgewiesen. Dabei sind sie berechtigt. Deutschland h\u00e4lt inzwischen jede Kritik an den deutschen Verh\u00e4ltnissen f\u00fcr einen Hinweis darauf, dass es sich beim Kritiker um einen &#8220;Autokraten&#8221; handelt. Das hat inzwischen die Qualit\u00e4t eines alten Witzes um einen Autofahrer, der im Radio h\u00f6rt, auf seiner Strecke sei ein Geisterfahrer unterwegs, worauf er emp\u00f6rt ausruft: &#8220;Einer?! Hunderte!&#8221; Deutschland befindet sich auf einer Geisterfahrt. An Neitzels paranoiden Ausf\u00fchrungen zeigt sich das in aller Deutlichkeit.\u00a0<\/p>\n<p>An Personalien wie S\u00f6nke Neitzel l\u00e4sst sich zudem exemplarisch zeigen, wie Deutschland alle v\u00f6lkerrechtlich gegebenen Versprechen bricht. Neitzel hasst den Frieden, er will den Krieg. Wie das politische Deutschland als Ganzes ist auch Neitzel zu Frieden und Freiheit nicht bef\u00e4higt. Er sch\u00fcrt Angst, Ressentiment und Hass. Er betreibt das Gegenteil von Aufkl\u00e4rung, die es zur Freiheit ben\u00f6tigt. Dabei ist der Weg zum Frieden in Europa ganz einfach. F\u00fchlt sich Russland sicher vor Westeuropa, dann ist auch Westeuropa sicher vor Russland. Die Aufr\u00fcstungspl\u00e4ne Deutschlands f\u00fchren jedoch in genau die entgegengesetzte Richtung.\u00a0<\/p>\n<\/p>\n<p>Die deutschen Aufr\u00fcstungspl\u00e4ne verfolgt man daher in Russland mit gro\u00dfem Misstrauen. Dabei ist das Spiel, das Deutschland spielt, nicht ungef\u00e4hrlich. W\u00e4hrend man in Russland dar\u00fcber diskutiert, ob Deutschland noch den 2+4-Vertrag\u00a0einh\u00e4lt, der die Grundlage f\u00fcr die deutsche Einheit bildet, tauchte inzwischen in Deutschland im Umfeld der AfD das Wort &#8220;Feindstaatenklausel&#8221; auf. Nach ihr haben die alliierten M\u00e4chte jederzeit und unter Umgehung des UN-Sicherheitsrats das Recht, gegen Deutschland Zwangsma\u00dfnahmen zu verh\u00e4ngen, wenn es auf den Weg der Aggression zur\u00fcckkehrt. Lange Jahre galt die Klausel als obsolet. Jetzt ist die Diskussion dar\u00fcber wieder da, ob Deutschland mit seinem Kriegskurs noch Teil der internationalen Staatengemeinschaft ist oder nicht erneut aus der Zivilisation f\u00e4llt.<\/p>\n<p>Das Interview von Neitzel und die Aufr\u00fcstungspl\u00e4ne der Bundesregierung verbunden mit der Ablehnung von Diplomatie lassen am deutschen Bekenntnis zum Frieden ganz grundlegende und berechtigte Zweifel aufkommen. Diese berechtigten Zweifel haben das Potenzial, Deutschland zum gro\u00dfen Verlierer der historischen Entwicklung zu machen.\u00a0<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2013\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/meinung\/239921-kriegstuechtig-bis-2029-deutsche-vierjahresplan\/\">Kriegst\u00fcchtig bis 2029 \u2013 Der deutsche Vierjahresplan 2.0<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6otmyi\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/240523-im-herbst-ist-krieg-deutscher\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Deutschland will aufr\u00fcsten. Als Grund m\u00fcssen angebliche \u00dcberfallpl\u00e4ne Russlands herhalten. Deutschland versinkt in einem Sumpf aus Propaganda, macht ein Interview mit Kriegsprofessor S\u00f6nke Neitzel deutlich. Die deutsche Gegenwart gleicht l\u00e4ngst den Drei\u00dfigerjahren des letzten Jahrhunderts. Kaum eine Personalie f\u00fchrt so deutlich vor, dass Deutschland an den v\u00f6lkerrechtlichen Grundlagen der deutschen Einheit scheitert, wie der deutsche [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":80840,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1742834197"],"wp_automatic_camp":["217"],"6d9fb066f9b8ea028f185f3656858919":["Im Herbst ist Krieg \u2013 Deutscher Professor irritiert mit Panikmache"],"original_link":["https:\/\/de.rt.com\/meinung\/240523-im-herbst-ist-krieg-deutscher\/"],"_thumbnail_id":["80840"],"jnews_social_counter_last_update":["1784109401"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-03-24 18:37:39\";}"]},"categories":[19,23],"tags":[8305,529,32865,414,130,419,28055,3516],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Im Herbst ist Krieg \u2013 Deutscher Professor irritiert mit Panikmache - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Im Herbst ist Krieg \u2013 Deutscher Professor irritiert mit Panikmache\" \/>\n<meta property=\"og:description\" content=\"Deutschland will aufr\u00fcsten. Als Grund m\u00fcssen angebliche \u00dcberfallpl\u00e4ne Russlands herhalten. Deutschland versinkt in einem Sumpf aus Propaganda, macht ein Interview mit Kriegsprofessor S\u00f6nke Neitzel deutlich. Die deutsche Gegenwart gleicht l\u00e4ngst den Drei\u00dfigerjahren des letzten Jahrhunderts. Kaum eine Personalie f\u00fchrt so deutlich vor, dass Deutschland an den v\u00f6lkerrechtlichen Grundlagen der deutschen Einheit scheitert, wie der deutsche [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-24T16:23:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/67e1748848fbef242e65985d.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"6\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Im Herbst ist Krieg \u2013 Deutscher Professor irritiert mit Panikmache\",\"datePublished\":\"2025-03-24T16:23:24+00:00\",\"dateModified\":\"2025-03-24T16:23:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/\"},\"wordCount\":1163,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/Im-Herbst-ist-Krieg-\u2013-Deutscher-Professor-irritiert-mit-Panikmache.jpg\",\"keywords\":[\"deutscher\",\"Herbst\",\"irritiert\",\"ist\",\"krieg\",\"mit\",\"Panikmache\",\"Professor\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/\",\"name\":\"Im Herbst ist Krieg \u2013 Deutscher Professor irritiert mit Panikmache - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/Im-Herbst-ist-Krieg-\u2013-Deutscher-Professor-irritiert-mit-Panikmache.jpg\",\"datePublished\":\"2025-03-24T16:23:24+00:00\",\"dateModified\":\"2025-03-24T16:23:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/Im-Herbst-ist-Krieg-\u2013-Deutscher-Professor-irritiert-mit-Panikmache.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/Im-Herbst-ist-Krieg-\u2013-Deutscher-Professor-irritiert-mit-Panikmache.jpg\",\"width\":460,\"height\":259,\"caption\":\"Im Herbst ist Krieg \u2013 Deutscher Professor irritiert mit Panikmache\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Im Herbst ist Krieg \u2013 Deutscher Professor irritiert mit Panikmache\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Im Herbst ist Krieg \u2013 Deutscher Professor irritiert mit Panikmache - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/","og_locale":"de_DE","og_type":"article","og_title":"Im Herbst ist Krieg \u2013 Deutscher Professor irritiert mit Panikmache","og_description":"Deutschland will aufr\u00fcsten. Als Grund m\u00fcssen angebliche \u00dcberfallpl\u00e4ne Russlands herhalten. Deutschland versinkt in einem Sumpf aus Propaganda, macht ein Interview mit Kriegsprofessor S\u00f6nke Neitzel deutlich. Die deutsche Gegenwart gleicht l\u00e4ngst den Drei\u00dfigerjahren des letzten Jahrhunderts. Kaum eine Personalie f\u00fchrt so deutlich vor, dass Deutschland an den v\u00f6lkerrechtlichen Grundlagen der deutschen Einheit scheitert, wie der deutsche [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-03-24T16:23:24+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/67e1748848fbef242e65985d.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"6\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Im Herbst ist Krieg \u2013 Deutscher Professor irritiert mit Panikmache","datePublished":"2025-03-24T16:23:24+00:00","dateModified":"2025-03-24T16:23:24+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/"},"wordCount":1163,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/Im-Herbst-ist-Krieg-\u2013-Deutscher-Professor-irritiert-mit-Panikmache.jpg","keywords":["deutscher","Herbst","irritiert","ist","krieg","mit","Panikmache","Professor"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/","url":"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/","name":"Im Herbst ist Krieg \u2013 Deutscher Professor irritiert mit Panikmache - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/Im-Herbst-ist-Krieg-\u2013-Deutscher-Professor-irritiert-mit-Panikmache.jpg","datePublished":"2025-03-24T16:23:24+00:00","dateModified":"2025-03-24T16:23:24+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/Im-Herbst-ist-Krieg-\u2013-Deutscher-Professor-irritiert-mit-Panikmache.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/Im-Herbst-ist-Krieg-\u2013-Deutscher-Professor-irritiert-mit-Panikmache.jpg","width":460,"height":259,"caption":"Im Herbst ist Krieg \u2013 Deutscher Professor irritiert mit Panikmache"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/im-herbst-ist-krieg-deutscher-professor-irritiert-mit-panikmache\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Im Herbst ist Krieg \u2013 Deutscher Professor irritiert mit Panikmache"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/80839"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=80839"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/80839\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/80840"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=80839"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=80839"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=80839"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}