{"id":80319,"date":"2025-03-15T21:54:24","date_gmt":"2025-03-15T19:54:24","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/"},"modified":"2025-03-15T21:54:24","modified_gmt":"2025-03-15T19:54:24","slug":"die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/","title":{"rendered":"Die M\u00e4r von der &quot;friedlichen und wohlwollenden Europ\u00e4ischen Union&quot;"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/67d30c93b480cc42dd333146.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Man kann Donald Trump durchaus dankbar sein, dass er ungewollt interessante Gest\u00e4ndnisse provoziert: Als er behauptete, dass die EU gegr\u00fcndet worden sei, um die USA zu &#8220;betr\u00fcgen&#8221;, schrien proeurop\u00e4ische Politiker emp\u00f6rt auf und wiesen darauf hin, dass der Block unter der Schirmherrschaft Washingtons entstanden war.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Pierre L\u00e9vy<\/em><\/p>\n<p>Wieder einmal beschleunigen sich die diplomatisch-milit\u00e4rischen Ereignisse im Ukraine-Konflikt.\u00a0Wieder einmal ist also Vorsicht geboten, bevor eine mehr denn je unbest\u00e4ndige Situation analysiert wird. Eines ist jedoch sicher: Die Europ\u00e4ische Union wird aus dem Spiel gelassen\u00a0\u2013 und das ist gut f\u00fcr den Frieden.<\/p>\n<p>Ihre F\u00fchrer m\u00f6gen sich auch noch so verzweifelt abm\u00fchen, sie wurden nicht zu den wichtigen Sitzungen eingeladen. Und sie scheinen zu der Haltung verdammt zu sein, die sie mehr als alles andere f\u00fcrchteten: die der Zuschauer.<\/p>\n<p>Um diese Entt\u00e4uschung abzuwenden, schmieden sie einen Plan mit dem Namen &#8220;Europa wieder aufr\u00fcsten&#8221;. Der Europ\u00e4ische Rat best\u00e4tigte am 6.\u00a0M\u00e4rz das Prinzip eines Plans mit diesem Titel, den die Europ\u00e4ische Kommission zwei Tage zuvor vorgeschlagen hatte, in H\u00f6he von 800\u00a0Milliarden Euro. Einige Hauptst\u00e4dte sind sogar der Meinung, dass diese astronomische Zahl nicht ausreiche. Im Gegensatz dazu sprach sich das niederl\u00e4ndische Parlament am 12.\u00a0M\u00e4rz gegen den besagten Plan aus, da drei der vier in der Regierung vertretenen Parteien das Prinzip der gemeinsamen Verschuldung ablehnen.<\/p>\n<p>&#8220;Europa wieder aufr\u00fcsten&#8221; und nicht &#8220;Europa aufr\u00fcsten&#8221;. Der Ausdruck hat den Vorteil, dass er\u00a0\u2013 zweifellos ohne Absicht seiner Autoren\u00a0\u2013 an die Urspr\u00fcnge des &#8220;europ\u00e4ischen Aufbaus&#8221; erinnert: Die Vereinigung Europas (damals Westeuropas) entstand aus und im Kalten Krieg.<\/p>\n<p>Im Jahr 1949 wurde unter der Schirmherrschaft der Vereinigten Staaten die atlantische Allianz gegr\u00fcndet, ein Jahr sp\u00e4ter folgte die Gr\u00fcndung ihres milit\u00e4risch integrierten Instruments, der NATO. 1950 wurde die &#8220;Schuman-Erkl\u00e4rung&#8221; verk\u00fcndet: Diese markiert symbolisch den Beginn des europ\u00e4ischen Integrationsprozesses, aus dem 1957 der Vertrag von Rom hervorging, der die Grundlage zun\u00e4chst f\u00fcr die Europ\u00e4ische Wirtschaftsgemeinschaft (EWG) bildete. Bereits 1954 gab es den ersten Versuch eines milit\u00e4rischen Europa: die Europ\u00e4ische Verteidigungsgemeinschaft (EVG). Diese wurde in letzter Minute vom franz\u00f6sischen Parlament vereitelt, wo kommunistische und gaullistische Abgeordnete ihre Stimmen gegen dieses von den USA inspirierte Projekt vereinten.<\/p>\n<p>Aber ihre Bef\u00fcrworter gaben sich nie geschlagen. Die EWG (sp\u00e4ter die EU) und die NATO entwickelten sich wie Zwillingsschwestern, wobei die Zweite nat\u00fcrlich die F\u00fchrungsrolle Washington vorbehielt. Die DNA beider Institutionen war gleich, die sukzessiven &#8220;Erweiterungen&#8221; verliefen parallel, und man tauschte des \u00d6fteren die F\u00fchrungspersonen aus. Eines der bekanntesten Beispiele war Javier Solana, der nacheinander Generalsekret\u00e4r der NATO (1995\u20131999, w\u00e4hrend der Jugoslawienkriege und der Bombardierungen durch die NATO-Streitkr\u00e4fte) und dann Hoher Vertreter der EU (1999\u20132009) f\u00fcr Au\u00dfen- und Verteidigungspolitik war.<\/p>\n<p>Man kann auch daran erinnern, dass die aufeinanderfolgenden europ\u00e4ischen Vertr\u00e4ge die NATO ausdr\u00fccklich als privilegierten Partner nennen. Und dass eine Klausel des Vertrags von Lissabon, der die derzeitige EU regelt, ein automatisches milit\u00e4risches Engagement der Mitgliedstaaten vorsieht, falls einer von ihnen angegriffen wird\u00a0\u2013 eine Klausel, die sogar verbindlicher ist als ihr Gegenst\u00fcck f\u00fcr die atlantische Allianz.<\/p>\n<p>Kurz gesagt, die EU war nie eine &#8220;friedliche und wohlwollende Union&#8221;, wie ihre Propagandisten sie oft gepriesen haben und deren Verlust einige gutgl\u00e4ubige B\u00fcrger bedauern. Das derzeitige kriegerische Getue Br\u00fcssels ist keineswegs ein Abgleiten von einem gro\u00dfz\u00fcgigen Projekt, sondern die treue Fortsetzung des politischen Europa seit seiner Gr\u00fcndung.<\/p>\n<p>Und man kann Donald Trump dankbar sein, dass er in dieser Hinsicht ungewollt interessante Gest\u00e4ndnisse provoziert hat. In einer seiner provokanten \u00c4u\u00dferungen, die er so gut beherrscht, hatte der US-Pr\u00e4sident, um seine Politik der Z\u00f6lle auf europ\u00e4ische Waren zu rechtfertigen, die Ansicht vertreten, dass die EU gegr\u00fcndet worden sei, um die Vereinigten Staaten zu &#8220;betr\u00fcgen&#8221;.<\/p>\n<p>Emp\u00f6rt schrien proeurop\u00e4ische Politiker und gro\u00dfe Medien aufgrund des Skandal auf und erinnerten\u00a0\u2013 zu Recht!\u00a0\u2013 daran, dass die europ\u00e4ische Integration auf Initiative und unter der Schirmherrschaft Washingtons entstanden war. So schrieb der Leitartikler von <em>Le Monde<\/em> (11.03.2025), dass &#8220;die USA von Anfang an den Aufbau (Europas) gef\u00f6rdert&#8221; h\u00e4tten, &#8220;um sich Absatzm\u00e4rkte zu sichern und den Kommunismus einzud\u00e4mmen&#8221;.<\/p>\n<p>Diese Erinnerung ist willkommen, da sie im Gegensatz zu einer Propaganda steht, die die EU oft als das Mittel dargestellt hat, ein Gegengewicht zu den Vereinigten Staaten zu bilden und sich von ihrer Vormundschaft zu befreien. Insbesondere in Frankreich war dies eines der Themen, das die Bef\u00fcrworter bei den Referenden \u00fcber den Vertrag von Maastricht (der 1992 knapp angenommen wurde) und dann \u00fcber den Verfassungsvertrag (der 2005 weitgehend abgelehnt wurde) verwendeten.<\/p>\n<p>Es bedurfte also eines Krieges, damit einige emp\u00f6rte europ\u00e4ische F\u00fchrer ihre atlantische Nostalgie zur Schau stellten, indem sie die urspr\u00fcnglichen Verbindungen zwischen der Treue zu Uncle Sam und der Europ\u00e4ischen Union erw\u00e4hnen; und indem diese, die nun verzweifelt nach milit\u00e4rischer Macht strebt, offen ihre wahre Natur best\u00e4tigt\u00a0&#8230;<\/p>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/kurzclips\/video\/238849-mehr-spielraum-bei-ruestungsausgaben-scholz\/\">Mehr Spielraum bei R\u00fcstungsausgaben: Scholz f\u00fcr &#8220;\u00c4nderung des Regelwerks in Europa&#8221;\u00a0<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6o0k3y\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/239474-maer-von-friedlichen-und-wohlwollenden\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Man kann Donald Trump durchaus dankbar sein, dass er ungewollt interessante Gest\u00e4ndnisse provoziert: Als er behauptete, dass die EU gegr\u00fcndet worden sei, um die USA zu &#8220;betr\u00fcgen&#8221;, schrien proeurop\u00e4ische Politiker emp\u00f6rt auf und wiesen darauf hin, dass der Block unter der Schirmherrschaft Washingtons entstanden war. Von Pierre L\u00e9vy Wieder einmal beschleunigen sich die diplomatisch-milit\u00e4rischen Ereignisse [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":80320,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1742069371"],"wp_automatic_camp":["217"],"e52683675b74e14e99ae46d1eb9d5328":["Die M\u00e4r von der &quot;friedlichen und wohlwollenden Europ\u00e4ischen Union&quot;"],"original_link":["https:\/\/de.rt.com\/europa\/239474-maer-von-friedlichen-und-wohlwollenden\/"],"_thumbnail_id":["80320"],"jnews_social_counter_last_update":["1784098477"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-03-15 22:10:24\";}"]},"categories":[19,23],"tags":[82,45,20513,33973,63472,140,21895,50,63473],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Die M\u00e4r von der &quot;friedlichen und wohlwollenden Europ\u00e4ischen Union&quot; - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die M\u00e4r von der &quot;friedlichen und wohlwollenden Europ\u00e4ischen Union&quot;\" \/>\n<meta property=\"og:description\" content=\"Man kann Donald Trump durchaus dankbar sein, dass er ungewollt interessante Gest\u00e4ndnisse provoziert: Als er behauptete, dass die EU gegr\u00fcndet worden sei, um die USA zu &#8220;betr\u00fcgen&#8221;, schrien proeurop\u00e4ische Politiker emp\u00f6rt auf und wiesen darauf hin, dass der Block unter der Schirmherrschaft Washingtons entstanden war. Von Pierre L\u00e9vy Wieder einmal beschleunigen sich die diplomatisch-milit\u00e4rischen Ereignisse [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-15T19:54:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/67d30c93b480cc42dd333146.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"4\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Die M\u00e4r von der &quot;friedlichen und wohlwollenden Europ\u00e4ischen Union&quot;\",\"datePublished\":\"2025-03-15T19:54:24+00:00\",\"dateModified\":\"2025-03-15T19:54:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/\"},\"wordCount\":867,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/Die-Maer-von-der-quotfriedlichen-und-wohlwollenden-Europaeischen-Unionquot.jpg\",\"keywords\":[\"der\",\"die\",\"Europ\u00e4ischen\",\"M\u00e4r\",\"quotfriedlichen\",\"und\",\"Unionquot\",\"von\",\"wohlwollenden\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/\",\"name\":\"Die M\u00e4r von der &quot;friedlichen und wohlwollenden Europ\u00e4ischen Union&quot; - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/Die-Maer-von-der-quotfriedlichen-und-wohlwollenden-Europaeischen-Unionquot.jpg\",\"datePublished\":\"2025-03-15T19:54:24+00:00\",\"dateModified\":\"2025-03-15T19:54:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/Die-Maer-von-der-quotfriedlichen-und-wohlwollenden-Europaeischen-Unionquot.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/Die-Maer-von-der-quotfriedlichen-und-wohlwollenden-Europaeischen-Unionquot.jpg\",\"width\":460,\"height\":259,\"caption\":\"Die M\u00e4r von der &quot;friedlichen und wohlwollenden Europ\u00e4ischen Union&quot;\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die M\u00e4r von der &quot;friedlichen und wohlwollenden Europ\u00e4ischen Union&quot;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Die M\u00e4r von der &quot;friedlichen und wohlwollenden Europ\u00e4ischen Union&quot; - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/","og_locale":"de_DE","og_type":"article","og_title":"Die M\u00e4r von der &quot;friedlichen und wohlwollenden Europ\u00e4ischen Union&quot;","og_description":"Man kann Donald Trump durchaus dankbar sein, dass er ungewollt interessante Gest\u00e4ndnisse provoziert: Als er behauptete, dass die EU gegr\u00fcndet worden sei, um die USA zu &#8220;betr\u00fcgen&#8221;, schrien proeurop\u00e4ische Politiker emp\u00f6rt auf und wiesen darauf hin, dass der Block unter der Schirmherrschaft Washingtons entstanden war. Von Pierre L\u00e9vy Wieder einmal beschleunigen sich die diplomatisch-milit\u00e4rischen Ereignisse [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-03-15T19:54:24+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/67d30c93b480cc42dd333146.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"4\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Die M\u00e4r von der &quot;friedlichen und wohlwollenden Europ\u00e4ischen Union&quot;","datePublished":"2025-03-15T19:54:24+00:00","dateModified":"2025-03-15T19:54:24+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/"},"wordCount":867,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/Die-Maer-von-der-quotfriedlichen-und-wohlwollenden-Europaeischen-Unionquot.jpg","keywords":["der","die","Europ\u00e4ischen","M\u00e4r","quotfriedlichen","und","Unionquot","von","wohlwollenden"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/","url":"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/","name":"Die M\u00e4r von der &quot;friedlichen und wohlwollenden Europ\u00e4ischen Union&quot; - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/Die-Maer-von-der-quotfriedlichen-und-wohlwollenden-Europaeischen-Unionquot.jpg","datePublished":"2025-03-15T19:54:24+00:00","dateModified":"2025-03-15T19:54:24+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/Die-Maer-von-der-quotfriedlichen-und-wohlwollenden-Europaeischen-Unionquot.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/03\/Die-Maer-von-der-quotfriedlichen-und-wohlwollenden-Europaeischen-Unionquot.jpg","width":460,"height":259,"caption":"Die M\u00e4r von der &quot;friedlichen und wohlwollenden Europ\u00e4ischen Union&quot;"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/die-maer-von-der-friedlichen-und-wohlwollenden-europaeischen-union\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Die M\u00e4r von der &quot;friedlichen und wohlwollenden Europ\u00e4ischen Union&quot;"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/80319"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=80319"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/80319\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/80320"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=80319"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=80319"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=80319"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}