{"id":78618,"date":"2025-02-16T19:28:19","date_gmt":"2025-02-16T17:28:19","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/"},"modified":"2025-02-16T19:28:19","modified_gmt":"2025-02-16T17:28:19","slug":"us-armee-verbietet-rekrutierung-von-transgender","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/","title":{"rendered":"US-Armee verbietet Rekrutierung von Transgender"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/67b1e33148fbef31603661f5.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Alle derzeit dienenden Personen mit Genderst\u00f6rung w\u00fcrden mit &#8220;W\u00fcrde und Respekt&#8221; behandelt, versprach das Milit\u00e4r. Allerdings werden keine weiteren Neueinstellungen von Personen mit St\u00f6rungen der Geschlechtsidentit\u00e4t mehr stattfinden.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die US-Armee hat ein sofortiges Verbot f\u00fcr Transgender-Personen verk\u00fcndet, in die Streitkr\u00e4fte einzutreten, und hat, laut\u00a0einem Post auf ihrem offiziellen X-Account am Freitag, alle mit Geschlechtsumwandlungen verkn\u00fcpften medizinischen Behandlungen f\u00fcr aktive Armeeangeh\u00f6rige gestoppt.<\/p>\n<p>Diese Ver\u00e4nderung der Politik ist die Folge eines Dekrets von Pr\u00e4sident Donald Trump vom 27. Januar, das dem Milit\u00e4r vorschreibt, sich strikt an das biologische Geschlecht einer Person zu halten, und das damit faktisch \u00dcberlegungen zur Geschlechtsidentit\u00e4t in den Streitkr\u00e4ften beendet.<\/p>\n<p><em>&#8220;Mit sofortiger Wirksamkeit werden alle neuen Rekrutierungen f\u00fcr Personen mit einer Geschichte einer Geschlechtsst\u00f6rung angehalten und alle noch nicht terminierten, terminierten oder geplanten medizinischen Behandlungen, die mit einer Best\u00e4tigung oder einer Erleichterung eines Geschlechts\u00fcbergangs f\u00fcr Armeeangeh\u00f6rige verbunden sind, werden angehalten&#8221;<\/em>, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/x.com\/USArmy\/status\/1890524927549149584\">schrieb<\/a> die US-Armee.<\/p>\n<p>Mit Ankl\u00e4ngen an ein vor kurzem erschienenes <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.rt.com\/news\/612489-pentagon-transgender-troops-hegseth\/\">Memo<\/a> von Verteidigungsminister Pete Hegseth versprach die US-Armee, alle derzeit dienenden <em>&#8220;Individuen mit Geschlechtsst\u00f6rungen [&#8230;] mit W\u00fcrde und Respekt&#8221;<\/em> zu behandeln.<\/p>\n<p>W\u00e4hrend Interessengruppen behaupten, dass bis zu 15.000 Transgenderpersonen derzeit, \u00fcber alle Waffengattungen des US-Milit\u00e4rs verteilt, in dessen R\u00e4ngen dienten, legen die offiziellen Angaben weit niedrigere Zahlen nahe,\u00a0laut\u00a0<em>Reuters<\/em>\u00a0<em>&#8220;in den unteren Tausend&#8221;<\/em>.<\/p>\n<p>Anfang des Monats hatte sich Hegseth, ein ehemaliger Nachrichtenmoderator auf <em>Fox<\/em> und Veteran der US-Nationalgarde, gegen <em>&#8220;spaltende&#8221;<\/em> Initiativen in den Streitkr\u00e4ften ausgesprochen, als er daran ging, das Programm des Pentagon f\u00fcr Diversit\u00e4t, Gleichheit und Inklusion (DEI) zu beenden, mit dem Argument, diese Initiativen untergr\u00fcben den Zusammenhalt.<\/p>\n<p><em>&#8220;Ich denke, die d\u00fcmmste einzelne Aussage in der Milit\u00e4rgeschichte ist &#8216;Unsere Diversit\u00e4t ist unsere St\u00e4rke&#8217;. Ich denke, unsere St\u00e4rke ist unsere Einheit&#8221;<\/em>, sagte Hegseth vor Mitarbeitern des Verteidigungsministeriums. <em>&#8220;In diesem Ministerium werden wir jeden gleich behandeln [&#8230;] Wir behandeln jeden mit Respekt, und wir werden Euch als Individuen nach Euren Verdiensten und nach Eurer Hingabe an das Team und den Einsatz bewerten.&#8221;<\/em><\/p>\n<p>Trump hatte 2017 das erste Mal Transgender-Personen den Dienst im US-Milit\u00e4r untersagt. Der ehemalige Pr\u00e4sident Joe Biden hob dieses Verbot kurz nach Amtsantritt 2021 auf, woraufhin Trump es in seiner zweiten Amtszeit wieder verh\u00e4ngte.<\/p>\n<p>Seit er ins Amt zur\u00fcckgekehrt ist, hat Trump dutzende Dekrete, die sein Vorg\u00e4nger unterzeichnet hatte, aufgehoben, darunter mindestens ein Dutzend Ma\u00dfnahmen, die die Interessen rassischer Minderheiten und der LGBTQ-Gemeinschaft f\u00f6rderten.<\/p>\n<p>Er verordnete offiziell, dass die US-Regierung nur zwei Geschlechter, m\u00e4nnlich und weiblich, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.rt.com\/news\/611722-us-x-gender-passport\/\">anerkenne<\/a>, und f\u00fcgte hinzu, diese Bestimmung k\u00f6nne nicht ge\u00e4ndert werden. Trump <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.rt.com\/news\/611848-trump-defunds-sex-change-procedures\/\">beendete<\/a> auch die F\u00f6rderungen der Bundesregierung f\u00fcr <em>&#8220;chemische und chirurgische Verst\u00fcmmelung&#8221;<\/em> von Kindern durch Pubert\u00e4tsblocker, Hormone und andere medizinische Prozeduren, die mit Geschlechts\u00e4nderungen von Individuen unter 19 Jahren zu tun haben.<\/p>\n<p><strong>Mehr zum Thema:<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/europa\/210293-britische-armee-wirbt-um-weisse\/\">&#8220;Ziehen definitiv in den Krieg&#8221; \u2013 Britische Armee wirbt um wei\u00dfe Hetero-M\u00e4nner <\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6c20pg\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/nordamerika\/236959-us-armee-verbietet-transgender-zu\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alle derzeit dienenden Personen mit Genderst\u00f6rung w\u00fcrden mit &#8220;W\u00fcrde und Respekt&#8221; behandelt, versprach das Milit\u00e4r. Allerdings werden keine weiteren Neueinstellungen von Personen mit St\u00f6rungen der Geschlechtsidentit\u00e4t mehr stattfinden. Die US-Armee hat ein sofortiges Verbot f\u00fcr Transgender-Personen verk\u00fcndet, in die Streitkr\u00e4fte einzutreten, und hat, laut\u00a0einem Post auf ihrem offiziellen X-Account am Freitag, alle mit Geschlechtsumwandlungen verkn\u00fcpften [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":78619,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1739727129"],"wp_automatic_camp":["217"],"c3f4cdefa2b8d7f7590f89aa7d310dc2":["US-Armee verbietet Rekrutierung von Transgender"],"original_link":["https:\/\/de.rt.com\/nordamerika\/236959-us-armee-verbietet-transgender-zu\/"],"_thumbnail_id":["78619"],"jnews_social_counter_last_update":["1778614044"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-02-16 19:33:13\";}"]},"categories":[19,23],"tags":[28994,3161,14895,19452,50],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>US-Armee verbietet Rekrutierung von Transgender - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"US-Armee verbietet Rekrutierung von Transgender\" \/>\n<meta property=\"og:description\" content=\"Alle derzeit dienenden Personen mit Genderst\u00f6rung w\u00fcrden mit &#8220;W\u00fcrde und Respekt&#8221; behandelt, versprach das Milit\u00e4r. Allerdings werden keine weiteren Neueinstellungen von Personen mit St\u00f6rungen der Geschlechtsidentit\u00e4t mehr stattfinden. Die US-Armee hat ein sofortiges Verbot f\u00fcr Transgender-Personen verk\u00fcndet, in die Streitkr\u00e4fte einzutreten, und hat, laut\u00a0einem Post auf ihrem offiziellen X-Account am Freitag, alle mit Geschlechtsumwandlungen verkn\u00fcpften [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-16T17:28:19+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/67b1e33148fbef31603661f5.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"US-Armee verbietet Rekrutierung von Transgender\",\"datePublished\":\"2025-02-16T17:28:19+00:00\",\"dateModified\":\"2025-02-16T17:28:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/\"},\"wordCount\":504,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/US-Armee-verbietet-Rekrutierung-von-Transgender.jpg\",\"keywords\":[\"Rekrutierung\",\"Transgender\",\"USArmee\",\"verbietet\",\"von\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/\",\"name\":\"US-Armee verbietet Rekrutierung von Transgender - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/US-Armee-verbietet-Rekrutierung-von-Transgender.jpg\",\"datePublished\":\"2025-02-16T17:28:19+00:00\",\"dateModified\":\"2025-02-16T17:28:19+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/US-Armee-verbietet-Rekrutierung-von-Transgender.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/US-Armee-verbietet-Rekrutierung-von-Transgender.jpg\",\"width\":460,\"height\":259,\"caption\":\"US-Armee verbietet Rekrutierung von Transgender\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"US-Armee verbietet Rekrutierung von Transgender\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"US-Armee verbietet Rekrutierung von Transgender - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/","og_locale":"de_DE","og_type":"article","og_title":"US-Armee verbietet Rekrutierung von Transgender","og_description":"Alle derzeit dienenden Personen mit Genderst\u00f6rung w\u00fcrden mit &#8220;W\u00fcrde und Respekt&#8221; behandelt, versprach das Milit\u00e4r. Allerdings werden keine weiteren Neueinstellungen von Personen mit St\u00f6rungen der Geschlechtsidentit\u00e4t mehr stattfinden. Die US-Armee hat ein sofortiges Verbot f\u00fcr Transgender-Personen verk\u00fcndet, in die Streitkr\u00e4fte einzutreten, und hat, laut\u00a0einem Post auf ihrem offiziellen X-Account am Freitag, alle mit Geschlechtsumwandlungen verkn\u00fcpften [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-02-16T17:28:19+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/67b1e33148fbef31603661f5.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"US-Armee verbietet Rekrutierung von Transgender","datePublished":"2025-02-16T17:28:19+00:00","dateModified":"2025-02-16T17:28:19+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/"},"wordCount":504,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/US-Armee-verbietet-Rekrutierung-von-Transgender.jpg","keywords":["Rekrutierung","Transgender","USArmee","verbietet","von"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/","url":"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/","name":"US-Armee verbietet Rekrutierung von Transgender - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/US-Armee-verbietet-Rekrutierung-von-Transgender.jpg","datePublished":"2025-02-16T17:28:19+00:00","dateModified":"2025-02-16T17:28:19+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/US-Armee-verbietet-Rekrutierung-von-Transgender.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/US-Armee-verbietet-Rekrutierung-von-Transgender.jpg","width":460,"height":259,"caption":"US-Armee verbietet Rekrutierung von Transgender"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/us-armee-verbietet-rekrutierung-von-transgender\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"US-Armee verbietet Rekrutierung von Transgender"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/78618"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=78618"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/78618\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/78619"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=78618"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=78618"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=78618"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}