{"id":77751,"date":"2025-02-03T17:21:37","date_gmt":"2025-02-03T15:21:37","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\/"},"modified":"2025-02-03T17:21:37","modified_gmt":"2025-02-03T15:21:37","slug":"hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\/","title":{"rendered":"Hamas entl\u00e4sst russischen Staatb\u00fcrger Trufanow bald aus der Gefangenschaft"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/67a0c964b480cc702849da5a.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Als Teil des Abkommens mit Israel beabsichtigt die pal\u00e4stinensische Hamas, in naher Zukunft eine Geisel mit russischer Staatsb\u00fcrgerschaft freizulassen. Alexander Trufanow werde nur aus Respekt vor dem russischen Pr\u00e4sidenten Wladimir Putin entlassen, betonte ein Hamas-Funktion\u00e4r.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>In einem Interview mit der Nachrichtenagentur <em>RIA Nowosti<\/em> best\u00e4tigte der stellvertretende Leiter des Hamas-Politb\u00fcros, Musa Abu Marzouk, dass der russische Staatsb\u00fcrger Alexander Trufanow definitiv zeitnah aus der Gefangenschaft entlassen werde.<\/p>\n<blockquote>\n<p><em>&#8220;Er wird trotz der Tatsache freigelassen, dass er ein Armeangeh\u00f6riger ist.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Man habe beschlossen, Trufanow bereits in der ersten Phase der entsprechenden Vereinbarung mit Israel freizulassen, gibt Marzouk an, der am Montag an der Spitze einer Hamas-Delegation zu Besuch in Moskau eingetroffen ist. &#8220;Dies ist unsere Antwort auf die Position Russlands in der Pal\u00e4stinafrage&#8221;, f\u00fcgt er hinzu. Und weiter:<\/p>\n<p>Nach Ansicht Moskaus ist eine L\u00f6sung im Nahostkonflikt zwischen Israel und der Hamas nur auf der Grundlage der vom UN-Sicherheitsrat gebilligten Formel m\u00f6glich, die die Schaffung eines pal\u00e4stinensischen Staates in den Grenzen von 1967 mit der Hauptstadt Ostjerusalem vorsieht.<\/p>\n<blockquote><\/blockquote>\n<p>Laut dem Hamas-Funktion\u00e4r werde das Schicksal von Maxim Charkin, einer weiteren Geisel, die aus Donbass stammt, im Zuge der zus\u00e4tzlichen Vereinbarungen mit Israel besprochen. Charkin sei ein Kriegsgefangener und Gespr\u00e4che \u00fcber seine Freilassung w\u00fcrden nicht in der ersten, sondern in der zweiten Phase des Geisel-Deals gef\u00fchrt. Marzouk sagt w\u00f6rtlich in dem Interview:<\/p>\n<blockquote>\n<p><em>&#8220;Es gibt viele Einzelheiten, doch als Gegenleistung gegen\u00fcber Russland sind wir bereit, ihn vorrangig freizulassen, sodass sein Name ganz oben auf der Liste steht.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Eine Delegation der pal\u00e4stinensischen Bewegung unter der F\u00fchrung von Marzouk traf am Montag zu einem Besuch in Russland ein. Nach Angaben von <em>RIA Nowosti<\/em> sollen Gespr\u00e4che der Hamas-Vertreter im Au\u00dfenministerium in Moskau geplant sein.<\/p>\n<p>Bei einem Treffen mit Mitgliedern des russischen Sicherheitsrates Ende Januar hat Russlands Pr\u00e4sident Wladimir Putin das Au\u00dfenministerium in Moskau aufgefordert, alles zu unternehmen, um die Freilassung des russischen Staatsb\u00fcrgers Alexander Trufanow zu erzielen, der als Geisel von Hamas gefangen gehalten werde. &#8220;Wir haben auf die Bitte Russlands nur aus Respekt vor dem russischen Pr\u00e4sidenten Wladimir Putin reagiert&#8221;, erkl\u00e4rt\u00a0Marzouk gegen\u00fcber der <em>RIA Nowosti<\/em> am Montag.<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/der-nahe-osten\/235379-zweite-phase-waffenruhe-israels-premier\/\">Zweite Phase der Waffenruhe: Israels Premier Netanjahu zu Gespr\u00e4chen in Washington<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6cg0od\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/235531-hamas-entlaesst-russischen-staatbuerger-trufanow\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Als Teil des Abkommens mit Israel beabsichtigt die pal\u00e4stinensische Hamas, in naher Zukunft eine Geisel mit russischer Staatsb\u00fcrgerschaft freizulassen. Alexander Trufanow werde nur aus Respekt vor dem russischen Pr\u00e4sidenten Wladimir Putin entlassen, betonte ein Hamas-Funktion\u00e4r. In einem Interview mit der Nachrichtenagentur RIA Nowosti best\u00e4tigte der stellvertretende Leiter des Hamas-Politb\u00fcros, Musa Abu Marzouk, dass der russische [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":77752,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1738596996"],"wp_automatic_camp":["217"],"108af8a7d737f5d0daaff7fbd09aded5":["Hamas entl\u00e4sst russischen Staatb\u00fcrger Trufanow bald aus der Gefangenschaft"],"original_link":["https:\/\/de.rt.com\/international\/235531-hamas-entlaesst-russischen-staatbuerger-trufanow\/"],"_thumbnail_id":["77752"],"jnews_social_counter_last_update":["1788390352"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-02-03 17:37:38\";}"]},"categories":[19,23],"tags":[679,1624,82,22666,680,5832,973,62429,62430],"class_list":["post-77751","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-aus","tag-bald","tag-der","tag-entlaesst","tag-gefangenschaft","tag-hamas","tag-russischen","tag-staatbuerger","tag-trufanow"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hamas entl\u00e4sst russischen Staatb\u00fcrger Trufanow bald aus der Gefangenschaft - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hamas entl\u00e4sst russischen Staatb\u00fcrger Trufanow bald aus der Gefangenschaft\" \/>\n<meta property=\"og:description\" content=\"Als Teil des Abkommens mit Israel beabsichtigt die pal\u00e4stinensische Hamas, in naher Zukunft eine Geisel mit russischer Staatsb\u00fcrgerschaft freizulassen. Alexander Trufanow werde nur aus Respekt vor dem russischen Pr\u00e4sidenten Wladimir Putin entlassen, betonte ein Hamas-Funktion\u00e4r. In einem Interview mit der Nachrichtenagentur RIA Nowosti best\u00e4tigte der stellvertretende Leiter des Hamas-Politb\u00fcros, Musa Abu Marzouk, dass der russische [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-02-03T15:21:37+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/67a0c964b480cc702849da5a.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Hamas entl\u00e4sst russischen Staatb\u00fcrger Trufanow bald aus der Gefangenschaft\",\"datePublished\":\"2025-02-03T15:21:37+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\\\/\"},\"wordCount\":396,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/02\\\/Hamas-entlaesst-russischen-Staatbuerger-Trufanow-bald-aus-der-Gefangenschaft.jpg\",\"keywords\":[\"aus\",\"bald\",\"der\",\"entl\u00e4sst\",\"Gefangenschaft\",\"Hamas\",\"russischen\",\"Staatb\u00fcrger\",\"Trufanow\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\\\/\",\"name\":\"Hamas entl\u00e4sst russischen Staatb\u00fcrger Trufanow bald aus der Gefangenschaft - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/02\\\/Hamas-entlaesst-russischen-Staatbuerger-Trufanow-bald-aus-der-Gefangenschaft.jpg\",\"datePublished\":\"2025-02-03T15:21:37+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/02\\\/Hamas-entlaesst-russischen-Staatbuerger-Trufanow-bald-aus-der-Gefangenschaft.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/02\\\/Hamas-entlaesst-russischen-Staatbuerger-Trufanow-bald-aus-der-Gefangenschaft.jpg\",\"width\":460,\"height\":259,\"caption\":\"Hamas entl\u00e4sst russischen Staatb\u00fcrger Trufanow bald aus der Gefangenschaft\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hamas entl\u00e4sst russischen Staatb\u00fcrger Trufanow bald aus der Gefangenschaft\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hamas entl\u00e4sst russischen Staatb\u00fcrger Trufanow bald aus der Gefangenschaft - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\/","og_locale":"de_DE","og_type":"article","og_title":"Hamas entl\u00e4sst russischen Staatb\u00fcrger Trufanow bald aus der Gefangenschaft","og_description":"Als Teil des Abkommens mit Israel beabsichtigt die pal\u00e4stinensische Hamas, in naher Zukunft eine Geisel mit russischer Staatsb\u00fcrgerschaft freizulassen. Alexander Trufanow werde nur aus Respekt vor dem russischen Pr\u00e4sidenten Wladimir Putin entlassen, betonte ein Hamas-Funktion\u00e4r. In einem Interview mit der Nachrichtenagentur RIA Nowosti best\u00e4tigte der stellvertretende Leiter des Hamas-Politb\u00fcros, Musa Abu Marzouk, dass der russische [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-02-03T15:21:37+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/67a0c964b480cc702849da5a.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Hamas entl\u00e4sst russischen Staatb\u00fcrger Trufanow bald aus der Gefangenschaft","datePublished":"2025-02-03T15:21:37+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\/"},"wordCount":396,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/Hamas-entlaesst-russischen-Staatbuerger-Trufanow-bald-aus-der-Gefangenschaft.jpg","keywords":["aus","bald","der","entl\u00e4sst","Gefangenschaft","Hamas","russischen","Staatb\u00fcrger","Trufanow"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\/","url":"https:\/\/now-news.de\/de\/deutschland\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\/","name":"Hamas entl\u00e4sst russischen Staatb\u00fcrger Trufanow bald aus der Gefangenschaft - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/Hamas-entlaesst-russischen-Staatbuerger-Trufanow-bald-aus-der-Gefangenschaft.jpg","datePublished":"2025-02-03T15:21:37+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/Hamas-entlaesst-russischen-Staatbuerger-Trufanow-bald-aus-der-Gefangenschaft.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/02\/Hamas-entlaesst-russischen-Staatbuerger-Trufanow-bald-aus-der-Gefangenschaft.jpg","width":460,"height":259,"caption":"Hamas entl\u00e4sst russischen Staatb\u00fcrger Trufanow bald aus der Gefangenschaft"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/hamas-entlaesst-russischen-staatbuerger-trufanow-bald-aus-der-gefangenschaft\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Hamas entl\u00e4sst russischen Staatb\u00fcrger Trufanow bald aus der Gefangenschaft"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/77751","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=77751"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/77751\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/77752"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=77751"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=77751"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=77751"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}