{"id":77299,"date":"2025-01-27T15:54:31","date_gmt":"2025-01-27T13:54:31","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/"},"modified":"2025-01-27T15:54:31","modified_gmt":"2025-01-27T13:54:31","slug":"putin-gratuliert-lukaschenko-zur-wiederwahl","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/","title":{"rendered":"Putin gratuliert Lukaschenko zur Wiederwahl"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/67977e7f48fbef633d0e3805.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Alexander Lukaschenko ist am Sonntag f\u00fcr eine siebte Amtszeit als Pr\u00e4sident Wei\u00dfrusslands wiedergew\u00e4hlt worden. Wladimir Putin gratulierte ihm zur Wiederwahl und betonte die hohe Zustimmungsrate in der Bev\u00f6lkerung. Die EU erkennt das Wahlergebnis nicht an.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Der russische Pr\u00e4sident Wladimir Putin hat am Montag mit dem am Vortag wiedergew\u00e4hlten wei\u00dfrussischen Pr\u00e4sidenten Alexander Lukaschenko telefoniert. Putin gratulierte dem 70-J\u00e4hrigen zur Wiederwahl und bezeichnete den Sieg als klare Best\u00e4tigung seiner &#8220;hohen politischen Autorit\u00e4t&#8221; und der &#8220;unbestreitbaren Unterst\u00fctzung&#8221; der Bev\u00f6lkerung f\u00fcr den Kurs der Regierung.<\/p>\n<p>W\u00e4hrend des Gespr\u00e4chs betonte Putin, dass Moskau und Minsk in den letzten Jahren bedeutende Fortschritte bei der St\u00e4rkung ihrer bilateralen Beziehungen erzielt h\u00e4tten. Der russische Pr\u00e4sident unterstrich die Bedeutung der weiteren Vertiefung der Zusammenarbeit und der Entwicklung des Unionsstaates sowie der F\u00f6rderung der Integrationsprozesse im eurasischen Raum. Er sicherte Lukaschenko die weitere Unterst\u00fctzung Russlands bei der Umsetzung dieser Ziele zu und w\u00fcnschte ihm viel Erfolg bei seiner Arbeit f\u00fcr die br\u00fcderlichen V\u00f6lker des Nachbarlandes. Putin k\u00fcndigte zudem an, Lukaschenko in K\u00fcrze in Moskau zu erwarten.<\/p>\n<p>Der seit 1994 regierende Lukaschenko gewann die Wahl erwartungsgem\u00e4\u00df mit 86,82 Prozent der Stimmen bei einer Wahlbeteiligung von 85,7 Prozent und tritt damit seine siebte Amtszeit an. Das offizielle Wahlergebnis wird voraussichtlich Anfang Februar von der Zentralen Wahlkommission best\u00e4tigt. Die Exil-Opposition, vertreten durch Swetlana Tichanowskaja, hatte die Wahl bereits im Vorfeld als illegitim bezeichnet.<\/p>\n<p>Die EU-Au\u00dfenbeauftragte Kaja Kallas hatte die Wahl am Sonntag als Scheinwahl kritisiert und angek\u00fcndigt, die EU werde ihre &#8220;restriktiven und gezielten Ma\u00dfnahmen&#8221; fortsetzen. Die deutsche Au\u00dfenministerin Annalena Baerbock sprach von einem &#8220;bitteren Tag&#8221; f\u00fcr die Bev\u00f6lkerung des Landes.<\/p>\n<p>Gratuliert haben Lukaschenko internationale Spitzenpolitiker wie Chinas Pr\u00e4sident Xi Jinping, Aserbaidschans Pr\u00e4sident Ilham Alijew und Venezuelas Pr\u00e4sident Nicol\u00e1s Maduro.<\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2012 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freeassange.rtde.live\/kurzclips\/video\/234499-weissrussland-lukaschenko-fuer-siebte-amtszeit\/\">Wei\u00dfrussland: Lukaschenko f\u00fcr siebte Amtszeit wiedergew\u00e4hlt<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6abhnj\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/europa\/234582-putin-gratuliert-lukaschenko-zur-wiederwahl\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Alexander Lukaschenko ist am Sonntag f\u00fcr eine siebte Amtszeit als Pr\u00e4sident Wei\u00dfrusslands wiedergew\u00e4hlt worden. Wladimir Putin gratulierte ihm zur Wiederwahl und betonte die hohe Zustimmungsrate in der Bev\u00f6lkerung. Die EU erkennt das Wahlergebnis nicht an. Der russische Pr\u00e4sident Wladimir Putin hat am Montag mit dem am Vortag wiedergew\u00e4hlten wei\u00dfrussischen Pr\u00e4sidenten Alexander Lukaschenko telefoniert. Putin gratulierte [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":77300,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1737986169"],"wp_automatic_camp":["217"],"129d118c16bb1c878504e5e5c792649a":["Putin gratuliert Lukaschenko zur Wiederwahl"],"original_link":["https:\/\/de.rt.com\/europa\/234582-putin-gratuliert-lukaschenko-zur-wiederwahl\/"],"jnews_social_counter_last_update":["1784109406"],"_thumbnail_id":["77300"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-01-27 15:57:07\";}"]},"categories":[19,23],"tags":[18650,21453,125,5445,581],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Putin gratuliert Lukaschenko zur Wiederwahl - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Putin gratuliert Lukaschenko zur Wiederwahl\" \/>\n<meta property=\"og:description\" content=\"Alexander Lukaschenko ist am Sonntag f\u00fcr eine siebte Amtszeit als Pr\u00e4sident Wei\u00dfrusslands wiedergew\u00e4hlt worden. Wladimir Putin gratulierte ihm zur Wiederwahl und betonte die hohe Zustimmungsrate in der Bev\u00f6lkerung. Die EU erkennt das Wahlergebnis nicht an. Der russische Pr\u00e4sident Wladimir Putin hat am Montag mit dem am Vortag wiedergew\u00e4hlten wei\u00dfrussischen Pr\u00e4sidenten Alexander Lukaschenko telefoniert. Putin gratulierte [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-27T13:54:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/67977e7f48fbef633d0e3805.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Putin gratuliert Lukaschenko zur Wiederwahl\",\"datePublished\":\"2025-01-27T13:54:31+00:00\",\"dateModified\":\"2025-01-27T13:54:31+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/\"},\"wordCount\":333,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Putin-gratuliert-Lukaschenko-zur-Wiederwahl.jpg\",\"keywords\":[\"gratuliert\",\"Lukaschenko\",\"putin\",\"Wiederwahl\",\"zur\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/\",\"name\":\"Putin gratuliert Lukaschenko zur Wiederwahl - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Putin-gratuliert-Lukaschenko-zur-Wiederwahl.jpg\",\"datePublished\":\"2025-01-27T13:54:31+00:00\",\"dateModified\":\"2025-01-27T13:54:31+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Putin-gratuliert-Lukaschenko-zur-Wiederwahl.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Putin-gratuliert-Lukaschenko-zur-Wiederwahl.jpg\",\"width\":460,\"height\":259,\"caption\":\"Putin gratuliert Lukaschenko zur Wiederwahl\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Putin gratuliert Lukaschenko zur Wiederwahl\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Putin gratuliert Lukaschenko zur Wiederwahl - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/","og_locale":"de_DE","og_type":"article","og_title":"Putin gratuliert Lukaschenko zur Wiederwahl","og_description":"Alexander Lukaschenko ist am Sonntag f\u00fcr eine siebte Amtszeit als Pr\u00e4sident Wei\u00dfrusslands wiedergew\u00e4hlt worden. Wladimir Putin gratulierte ihm zur Wiederwahl und betonte die hohe Zustimmungsrate in der Bev\u00f6lkerung. Die EU erkennt das Wahlergebnis nicht an. Der russische Pr\u00e4sident Wladimir Putin hat am Montag mit dem am Vortag wiedergew\u00e4hlten wei\u00dfrussischen Pr\u00e4sidenten Alexander Lukaschenko telefoniert. Putin gratulierte [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-01-27T13:54:31+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/67977e7f48fbef633d0e3805.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Putin gratuliert Lukaschenko zur Wiederwahl","datePublished":"2025-01-27T13:54:31+00:00","dateModified":"2025-01-27T13:54:31+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/"},"wordCount":333,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Putin-gratuliert-Lukaschenko-zur-Wiederwahl.jpg","keywords":["gratuliert","Lukaschenko","putin","Wiederwahl","zur"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/","url":"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/","name":"Putin gratuliert Lukaschenko zur Wiederwahl - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Putin-gratuliert-Lukaschenko-zur-Wiederwahl.jpg","datePublished":"2025-01-27T13:54:31+00:00","dateModified":"2025-01-27T13:54:31+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Putin-gratuliert-Lukaschenko-zur-Wiederwahl.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Putin-gratuliert-Lukaschenko-zur-Wiederwahl.jpg","width":460,"height":259,"caption":"Putin gratuliert Lukaschenko zur Wiederwahl"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/putin-gratuliert-lukaschenko-zur-wiederwahl\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Putin gratuliert Lukaschenko zur Wiederwahl"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/77299"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=77299"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/77299\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/77300"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=77299"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=77299"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=77299"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}