{"id":77105,"date":"2025-01-24T16:08:43","date_gmt":"2025-01-24T14:08:43","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/"},"modified":"2025-01-24T16:08:43","modified_gmt":"2025-01-24T14:08:43","slug":"messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/","title":{"rendered":"Messerangriff in Schwerte: Drei Syrer jagten einen Rum\u00e4nen"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/679392bfb480cc6c1b20c62f.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Wie sehr banale Konflikte inzwischen eskalieren, zeigt dieser Vorfall  in Schwerte. Dass zwei unterschiedliche Gruppen von Migranten daran beteiligt waren, verleiht ihm zus\u00e4tzliches Eskalationspotenzial. In Schwerte wurde am gestrigen Donnerstag ein junger Mann von einem syrischen Jugendlichen niedergestochen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Inzwischen ist das Opfer au\u00dfer Lebensgefahr.<\/p>\n<p>Die Konfrontation entwickelte sich im Verlauf des Donnerstags: Ein 18-j\u00e4hriger Rum\u00e4ne war nachmittags mit einem 15-j\u00e4hrigen Syrer in Streit geraten und hatte ihn geschlagen. Dabei wurde Letzterer leicht verletzt und erstattete daraufhin sogar Anzeige.<\/p>\n<p>Sp\u00e4ter am Tag, gegen 18:45 Uhr, hat er dann, vermutlich zuf\u00e4llig, den Rum\u00e4nen in der Innenstadt von Schwerte wieder entdeckt. Zusammen mit seinem 24-j\u00e4hrigen Bruder und einem weiteren Bekannten attackierte er daraufhin den 18-J\u00e4hrigen.<\/p>\n<p><em>&#8220;Der 18-J\u00e4hrige wurde geschlagen und fl\u00fcchtete in Richtung eines Streifenwagens der Polizei&#8221;<\/em>,<\/p>\n<p>hei\u00dft es in der Presseerkl\u00e4rung des Polizeipr\u00e4sidiums Dortmund. Der Polizeiwagen war wegen eines gemeldeten Ladendiebstahls, der nichts mit der Messerstecherei zu tun hatte, vor Ort.<\/p>\n<p><em>&#8220;Der 15-J\u00e4hrige folgte ihm und stach mehrfach auf ihn ein. Das Opfer brach vor dem Streifenwagen zusammen.&#8221;<\/em><\/p>\n<p>Mit mehreren Stichwunden im R\u00fccken wurde der junge Mann mit einem Rettungshubschrauber in eine Spezialklinik in Bochum geflogen. Der junge Messerstecher und seine beiden Begleiter wurden festgenommen. Allerdings muss es noch weitere Beteiligte geben \u2013 es ist die Rede von einer &#8220;Auseinandersetzung unter sechs Personen&#8221;. Die Staatsanwaltschaft Hagen ermittelt wegen versuchten Mordes.<\/p>\n<p>Was den ersten Streit ausgel\u00f6st hat, ist noch unbekannt. Die Abfolge der Ereignisse legt nahe, dass die anderen beiden Personen, die an der erw\u00e4hnten Auseinandersetzung beteiligt waren, zum Kreis des Opfers geh\u00f6rten. Wom\u00f6glich ist daher dieser Abend nur der Anfang eines l\u00e4ngeren Konflikts.<\/p>\n<p>Im Jahr 2023 hatte es in Nordrhein-Westfalen insgesamt mehr als 3.500 Messerangriffe gegeben: 15 Menschen wurden dabei get\u00f6tet, 288 schwer verletzt. Syrische Staatsangeh\u00f6rige stellten nach Angaben der Polizei 23 Prozent der nichtdeutschen Tatverd\u00e4chtigen dar. Eine gesonderte Erfassung derartiger Delikte gibt es erst seit dem Jahr 2020.<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/kurzclips\/video\/224851-freiluftklapse-im-endstadium-plakataktion-gegen-messer\/\">&#8220;Freiluftklapse im Endstadium&#8221; \u2013 Plakataktion gegen Messergewalt sorgt f\u00fcr Spott und Hohn<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v6afqgd\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/234211-messerangriff-in-schwerte-drei-syrer\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wie sehr banale Konflikte inzwischen eskalieren, zeigt dieser Vorfall in Schwerte. Dass zwei unterschiedliche Gruppen von Migranten daran beteiligt waren, verleiht ihm zus\u00e4tzliches Eskalationspotenzial. In Schwerte wurde am gestrigen Donnerstag ein junger Mann von einem syrischen Jugendlichen niedergestochen. Inzwischen ist das Opfer au\u00dfer Lebensgefahr. Die Konfrontation entwickelte sich im Verlauf des Donnerstags: Ein 18-j\u00e4hriger Rum\u00e4ne [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":77106,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1737728234"],"wp_automatic_camp":["217"],"416cd2cc5f6ad2ba2d000f932aa2e429":["Messerangriff in Schwerte: Drei Syrer jagten einen Rum\u00e4nen"],"original_link":["https:\/\/de.rt.com\/inland\/234211-messerangriff-in-schwerte-drei-syrer\/"],"_thumbnail_id":["77106"],"jnews_social_counter_last_update":["1784026925"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-01-24 16:18:23\";}"]},"categories":[19,23],"tags":[3836,768,62182,23954,60563,62181,18074],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Messerangriff in Schwerte: Drei Syrer jagten einen Rum\u00e4nen - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Messerangriff in Schwerte: Drei Syrer jagten einen Rum\u00e4nen\" \/>\n<meta property=\"og:description\" content=\"Wie sehr banale Konflikte inzwischen eskalieren, zeigt dieser Vorfall in Schwerte. Dass zwei unterschiedliche Gruppen von Migranten daran beteiligt waren, verleiht ihm zus\u00e4tzliches Eskalationspotenzial. In Schwerte wurde am gestrigen Donnerstag ein junger Mann von einem syrischen Jugendlichen niedergestochen. Inzwischen ist das Opfer au\u00dfer Lebensgefahr. Die Konfrontation entwickelte sich im Verlauf des Donnerstags: Ein 18-j\u00e4hriger Rum\u00e4ne [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-24T14:08:43+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/679392bfb480cc6c1b20c62f.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Messerangriff in Schwerte: Drei Syrer jagten einen Rum\u00e4nen\",\"datePublished\":\"2025-01-24T14:08:43+00:00\",\"dateModified\":\"2025-01-24T14:08:43+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/\"},\"wordCount\":351,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Messerangriff-in-Schwerte-Drei-Syrer-jagten-einen-Rumaenen.jpg\",\"keywords\":[\"drei\",\"einen\",\"jagten\",\"Messerangriff\",\"Rum\u00e4nen\",\"Schwerte\",\"Syrer\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/\",\"name\":\"Messerangriff in Schwerte: Drei Syrer jagten einen Rum\u00e4nen - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Messerangriff-in-Schwerte-Drei-Syrer-jagten-einen-Rumaenen.jpg\",\"datePublished\":\"2025-01-24T14:08:43+00:00\",\"dateModified\":\"2025-01-24T14:08:43+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Messerangriff-in-Schwerte-Drei-Syrer-jagten-einen-Rumaenen.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Messerangriff-in-Schwerte-Drei-Syrer-jagten-einen-Rumaenen.jpg\",\"width\":460,\"height\":259,\"caption\":\"Messerangriff in Schwerte: Drei Syrer jagten einen Rum\u00e4nen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Messerangriff in Schwerte: Drei Syrer jagten einen Rum\u00e4nen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Messerangriff in Schwerte: Drei Syrer jagten einen Rum\u00e4nen - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/","og_locale":"de_DE","og_type":"article","og_title":"Messerangriff in Schwerte: Drei Syrer jagten einen Rum\u00e4nen","og_description":"Wie sehr banale Konflikte inzwischen eskalieren, zeigt dieser Vorfall in Schwerte. Dass zwei unterschiedliche Gruppen von Migranten daran beteiligt waren, verleiht ihm zus\u00e4tzliches Eskalationspotenzial. In Schwerte wurde am gestrigen Donnerstag ein junger Mann von einem syrischen Jugendlichen niedergestochen. Inzwischen ist das Opfer au\u00dfer Lebensgefahr. Die Konfrontation entwickelte sich im Verlauf des Donnerstags: Ein 18-j\u00e4hriger Rum\u00e4ne [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-01-24T14:08:43+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/679392bfb480cc6c1b20c62f.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Messerangriff in Schwerte: Drei Syrer jagten einen Rum\u00e4nen","datePublished":"2025-01-24T14:08:43+00:00","dateModified":"2025-01-24T14:08:43+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/"},"wordCount":351,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Messerangriff-in-Schwerte-Drei-Syrer-jagten-einen-Rumaenen.jpg","keywords":["drei","einen","jagten","Messerangriff","Rum\u00e4nen","Schwerte","Syrer"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/","url":"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/","name":"Messerangriff in Schwerte: Drei Syrer jagten einen Rum\u00e4nen - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Messerangriff-in-Schwerte-Drei-Syrer-jagten-einen-Rumaenen.jpg","datePublished":"2025-01-24T14:08:43+00:00","dateModified":"2025-01-24T14:08:43+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Messerangriff-in-Schwerte-Drei-Syrer-jagten-einen-Rumaenen.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Messerangriff-in-Schwerte-Drei-Syrer-jagten-einen-Rumaenen.jpg","width":460,"height":259,"caption":"Messerangriff in Schwerte: Drei Syrer jagten einen Rum\u00e4nen"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/messerangriff-in-schwerte-drei-syrer-jagten-einen-rumaenen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Messerangriff in Schwerte: Drei Syrer jagten einen Rum\u00e4nen"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/77105"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=77105"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/77105\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/77106"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=77105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=77105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=77105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}