{"id":75918,"date":"2025-01-07T13:44:38","date_gmt":"2025-01-07T11:44:38","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\/"},"modified":"2025-01-07T13:44:38","modified_gmt":"2025-01-07T11:44:38","slug":"hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\/","title":{"rendered":"Hessen: Bank\u00fcberfall und Geiselnahme \u2013 T\u00e4ter \u00fcberw\u00e4ltigt und festgenommen"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/677d06ffb480cc39051e001d.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Eine Bankangestellte im s\u00fcdhessischen Rimbach erlebte Todes\u00e4ngste, als ein bewaffneter Mann sie am fr\u00fchen Morgen als Geisel nahm. Die Polizei verhinderte eine Eskalation und konnte den T\u00e4ter \u00fcberw\u00e4ltigen. Die Frau blieb unverletzt.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Der T\u00e4ter war laut der zust\u00e4ndigen Polizei S\u00fcdhessen am fr\u00fchen Morgen in das Bankgeb\u00e4ude eingedrungen und hatte die Frau unmittelbar mit einem &#8220;Werkzeug&#8221; bedroht. Angeforderte Polizei und Einsatzkr\u00e4fte, darunter auch ein Spezialeinsatzkommando, konnten final den Mann \u00fcberw\u00e4ltigen. Gegen 11 Uhr erfolgte die Information der Polizei, dass der Einsatz beendet sei und die Geisel unverletzt aus den H\u00e4nden des T\u00e4ters befreit wurde.<\/p>\n<p>Laut Medienangaben handelt es sich bei dem T\u00e4ter um einen 36-j\u00e4hrigen Mann, der laut\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.presseportal.de\/blaulicht\/pm\/4969\/5944156\">Polizeimitteilung<\/a>\u00a0die 21-j\u00e4hrige Bankmitarbeiterin mit einem &#8220;Werkzeug&#8221; bedrohte, mehrere Medienartikel\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.bild.de\/news\/rimbach-hessen-geiselnahme-in-volksbank-mann-hat-frau-als-geisel-677cf0b80195b908c189c2fd\">berichten<\/a>\u00a0auch von einem Messer. Danach habe er die Frau &#8220;gegen ihren Willen festgehalten&#8221;.\u00a0Nach\u00a0<em>Bild<\/em>-Informationen ist der Mann bereits &#8220;vorbestraft und auf Bew\u00e4hrung&#8221;.<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"de\" dir=\"ltr\">In einer Bankfiliale in der Rathausstra\u00dfe in <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/hashtag\/Rimbach?src=hash&amp;ref_src=twsrc%5Etfw\">#Rimbach<\/a> kommt es zu einem Polizeieinsatz.Ein Mann drang heute Morgen gegen 8:00 Uhr in die Filiale ein. Derzeit h\u00e4lt er sich dort mit mindestens einer Person auf, die er gegen ihren Willen dort festh\u00e4lt.Wir sind mit einer Vielzahl\u2026<\/p>\n<p>\u2014 Polizei S\u00fcdhessen (@Polizei_SuedHE) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/Polizei_SuedHE\/status\/1876559279185940969?ref_src=twsrc%5Etfw\">January 7, 2025<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Nach Eintreffen der Polizei samt Spezialkr\u00e4ften, wurde der Bereich um die Bankfiliale weitr\u00e4umig abgesperrt, die Ortsdurchfahrt war komplett gesperrt. Laut Polizeimeldung konnte der Tatverd\u00e4chtige schlie\u00dflich von Spezialkr\u00e4ften &#8220;widerstandslos festgenommen&#8221; werden.<\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\">\n<p lang=\"de\" dir=\"ltr\">\ud83d\udfe2 Der Polizeieinsatz ist beendet.Wir haben den T\u00e4ter festgenommen. Die von ihm festgehaltene Person befindet sich in unserer Obhut.<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/hashtag\/rimbach0701?src=hash&amp;ref_src=twsrc%5Etfw\">#rimbach0701<\/a><\/p>\n<p>\u2014 Polizei S\u00fcdhessen (@Polizei_SuedHE) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/Polizei_SuedHE\/status\/1876572082324287564?ref_src=twsrc%5Etfw\">January 7, 2025<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>Die Ermittlungen zu den genauen Hintergr\u00fcnden dauern noch an. Die Geisel, wie auch der Geiselnehmer, blieben unverletzt, ebenso wie die betroffenen Arbeitskollegen und erste Bankkunden, die sich w\u00e4hrend der Tat weiterhin in der Filiale befanden.<\/p>\n<p>Rimbach, der Ort des Geschehens, liegt im Kreis Bergstra\u00dfe unweit der Landesgrenze von Hessen und Baden-W\u00fcrttemberg und hat rund 9.000 Einwohner.<\/p>\n<p><strong>Mehr zum Thema &#8211;<\/strong>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/215160-kriminalitaet-nirgendwo-in-europa-mehr\/\">Kriminalit\u00e4t: Nirgendwo in Europa mehr Anschl\u00e4ge auf Geldautomaten als in Deutschland <\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v61db6k\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/231983-hessen-bankueberfall-und-geiselnahme-mit\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Eine Bankangestellte im s\u00fcdhessischen Rimbach erlebte Todes\u00e4ngste, als ein bewaffneter Mann sie am fr\u00fchen Morgen als Geisel nahm. Die Polizei verhinderte eine Eskalation und konnte den T\u00e4ter \u00fcberw\u00e4ltigen. Die Frau blieb unverletzt. Der T\u00e4ter war laut der zust\u00e4ndigen Polizei S\u00fcdhessen am fr\u00fchen Morgen in das Bankgeb\u00e4ude eingedrungen und hatte die Frau unmittelbar mit einem &#8220;Werkzeug&#8221; [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":75919,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1736250923"],"wp_automatic_camp":["217"],"433976d2d7ea5928ef21bbd387fbe600":["Hessen: Bank\u00fcberfall und Geiselnahme \u2013 T\u00e4ter \u00fcberw\u00e4ltigt und festgenommen"],"original_link":["https:\/\/de.rt.com\/inland\/231983-hessen-bankueberfall-und-geiselnahme-mit\/"],"_thumbnail_id":["75919"],"jnews_social_counter_last_update":["1788351846"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2025-01-07 13:56:57\";}"]},"categories":[19,23],"tags":[61648,1356,41776,22554,7079,11749,140],"class_list":["post-75918","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-bankueberfall","tag-festgenommen","tag-geiselnahme","tag-hessen","tag-taeter","tag-ueberwaeltigt","tag-und"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Hessen: Bank\u00fcberfall und Geiselnahme \u2013 T\u00e4ter \u00fcberw\u00e4ltigt und festgenommen - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Hessen: Bank\u00fcberfall und Geiselnahme \u2013 T\u00e4ter \u00fcberw\u00e4ltigt und festgenommen\" \/>\n<meta property=\"og:description\" content=\"Eine Bankangestellte im s\u00fcdhessischen Rimbach erlebte Todes\u00e4ngste, als ein bewaffneter Mann sie am fr\u00fchen Morgen als Geisel nahm. Die Polizei verhinderte eine Eskalation und konnte den T\u00e4ter \u00fcberw\u00e4ltigen. Die Frau blieb unverletzt. Der T\u00e4ter war laut der zust\u00e4ndigen Polizei S\u00fcdhessen am fr\u00fchen Morgen in das Bankgeb\u00e4ude eingedrungen und hatte die Frau unmittelbar mit einem &#8220;Werkzeug&#8221; [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2025-01-07T11:44:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/677d06ffb480cc39051e001d.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Hessen: Bank\u00fcberfall und Geiselnahme \u2013 T\u00e4ter \u00fcberw\u00e4ltigt und festgenommen\",\"datePublished\":\"2025-01-07T11:44:38+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\\\/\"},\"wordCount\":365,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/01\\\/Hessen-Bankueberfall-und-Geiselnahme-\u2013-Taeter-ueberwaeltigt-und-festgenommen.jpg\",\"keywords\":[\"Bank\u00fcberfall\",\"festgenommen\",\"Geiselnahme\",\"Hessen\",\"T\u00e4ter\",\"\u00fcberw\u00e4ltigt\",\"und\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\\\/\",\"name\":\"Hessen: Bank\u00fcberfall und Geiselnahme \u2013 T\u00e4ter \u00fcberw\u00e4ltigt und festgenommen - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/01\\\/Hessen-Bankueberfall-und-Geiselnahme-\u2013-Taeter-ueberwaeltigt-und-festgenommen.jpg\",\"datePublished\":\"2025-01-07T11:44:38+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/01\\\/Hessen-Bankueberfall-und-Geiselnahme-\u2013-Taeter-ueberwaeltigt-und-festgenommen.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2025\\\/01\\\/Hessen-Bankueberfall-und-Geiselnahme-\u2013-Taeter-ueberwaeltigt-und-festgenommen.jpg\",\"width\":460,\"height\":259,\"caption\":\"Hessen: Bank\u00fcberfall und Geiselnahme \u2013 T\u00e4ter \u00fcberw\u00e4ltigt und festgenommen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Hessen: Bank\u00fcberfall und Geiselnahme \u2013 T\u00e4ter \u00fcberw\u00e4ltigt und festgenommen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Hessen: Bank\u00fcberfall und Geiselnahme \u2013 T\u00e4ter \u00fcberw\u00e4ltigt und festgenommen - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\/","og_locale":"de_DE","og_type":"article","og_title":"Hessen: Bank\u00fcberfall und Geiselnahme \u2013 T\u00e4ter \u00fcberw\u00e4ltigt und festgenommen","og_description":"Eine Bankangestellte im s\u00fcdhessischen Rimbach erlebte Todes\u00e4ngste, als ein bewaffneter Mann sie am fr\u00fchen Morgen als Geisel nahm. Die Polizei verhinderte eine Eskalation und konnte den T\u00e4ter \u00fcberw\u00e4ltigen. Die Frau blieb unverletzt. Der T\u00e4ter war laut der zust\u00e4ndigen Polizei S\u00fcdhessen am fr\u00fchen Morgen in das Bankgeb\u00e4ude eingedrungen und hatte die Frau unmittelbar mit einem &#8220;Werkzeug&#8221; [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2025-01-07T11:44:38+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/677d06ffb480cc39051e001d.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Hessen: Bank\u00fcberfall und Geiselnahme \u2013 T\u00e4ter \u00fcberw\u00e4ltigt und festgenommen","datePublished":"2025-01-07T11:44:38+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\/"},"wordCount":365,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Hessen-Bankueberfall-und-Geiselnahme-\u2013-Taeter-ueberwaeltigt-und-festgenommen.jpg","keywords":["Bank\u00fcberfall","festgenommen","Geiselnahme","Hessen","T\u00e4ter","\u00fcberw\u00e4ltigt","und"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\/","url":"https:\/\/now-news.de\/de\/deutschland\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\/","name":"Hessen: Bank\u00fcberfall und Geiselnahme \u2013 T\u00e4ter \u00fcberw\u00e4ltigt und festgenommen - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Hessen-Bankueberfall-und-Geiselnahme-\u2013-Taeter-ueberwaeltigt-und-festgenommen.jpg","datePublished":"2025-01-07T11:44:38+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Hessen-Bankueberfall-und-Geiselnahme-\u2013-Taeter-ueberwaeltigt-und-festgenommen.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2025\/01\/Hessen-Bankueberfall-und-Geiselnahme-\u2013-Taeter-ueberwaeltigt-und-festgenommen.jpg","width":460,"height":259,"caption":"Hessen: Bank\u00fcberfall und Geiselnahme \u2013 T\u00e4ter \u00fcberw\u00e4ltigt und festgenommen"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/hessen-bankueberfall-und-geiselnahme-taeter-ueberwaeltigt-und-festgenommen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Hessen: Bank\u00fcberfall und Geiselnahme \u2013 T\u00e4ter \u00fcberw\u00e4ltigt und festgenommen"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/75918","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=75918"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/75918\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/75919"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=75918"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=75918"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=75918"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}