{"id":7534,"date":"2022-05-12T17:46:03","date_gmt":"2022-05-12T15:46:03","guid":{"rendered":"http:\/\/just-now.news\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/"},"modified":"2022-05-12T17:46:03","modified_gmt":"2022-05-12T15:46:03","slug":"haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/","title":{"rendered":"Haubitzenlehrlinge oder Deutschlands Weg zur Kriegspartei"},"content":{"rendered":"<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>von Dagmar Henn<\/em><\/p>\n<p>Sie tun schon eigenartige Dinge in Berlin. Wie jetzt diese Nummer mit der Panzerhaubitze. Nun sitzen also etwas mehr als hundert ukrainische Soldaten in Idar-Oberstein, um im Verlauf von mindestens 40 Tagen zu lernen, wie man die zw\u00f6lf Haubitzen bedient, mit denen Deutschland und die Niederlande der Ukraine zum Sieg verhelfen wollen.<\/p>\n<div class=\"ReadMore-root Section-root Section-is1to3-xs_is1to1\" data-widgets=\"ReadMore\" data-has-alias>\n<div class=\"Section-container Section-isRow-isTop-isWrap\">\n<article class=\"Card-root Card-is1to1 \">\n<div class=\"Card-imageWrap\">\n<div class=\"Card-picture\">\n<picture class=\"Picture-root Picture-default\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/627a9413b480cc521a1e4084.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Bas-fordert-schnellen-EU-Beitritt-der-Ukraine.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/627a9413b480cc521a1e4084.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Bas-fordert-schnellen-EU-Beitritt-der-Ukraine.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Bas-fordert-schnellen-EU-Beitritt-der-Ukraine.jpg\" alt=\"Bas fordert schnellen EU-Beitritt der Ukraine\"><\/noscript>    <\/div><\/div>\n<div class=\"Card-contentWrap\">\n<div class=\"Card-content\">\n<div class=\"Card-title\">\n<div class=\"HeaderNews-root HeaderNews-type_6 \">\n<p>            <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/europa\/138125-bas-fordert-schnellen-eu-beitritt-der-ukraine\/\" class=\"Link-root Link-isFullCard \"><br \/>\n                Bas fordert schnellen EU-Beitritt der Ukraine<br \/>\n            <\/a><\/p><\/div><\/div><\/div><\/div>\n<\/article>\n<\/div><\/div>\n<p>Dabei gibt es eine heitere und eine weniger heitere Seite. Im Grunde ist jedem klar, dass auch diese zw\u00f6lf Haubitzen am Ergebnis der Kampfhandlungen nichts \u00e4ndern werden. Das sind mit die modernsten Gesch\u00fctze, die die Bundeswehr besitzt, aber die meisten gelieferten Waffen verwandeln sich durch den Einsatz russischer Raketen ohnehin in Schrotthaufen, ehe sie das Zielgebiet \u00fcberhaupt erreichen. Das d\u00fcrfte bei diesen Haubitzen nicht anders sein.<\/p>\n<p>Und die Ger\u00e4te sind zwanzig Jahre alt. Das ist zwar f\u00fcr die Bundeswehr ziemlich neu, aber in diesen zwanzig Jahren ist einiges geschehen. Die Struktur der russischen Armee hat sich daran angepasst, beispielsweise, indem die Luftabwehr immer ein Teil der Einheiten ist; weder der Aufbau der Struktur noch das Vorgehen ist in der NATO \u00fcberhaupt auf diesem Stand. Das war auch bei dem bisher einzigen Einsatz dieser Haubitze, in Afghanistan, nicht erforderlich. 2010 wurde diese Waffe bei Kundus erstmalig von der Bundeswehr <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.spiegel.de\/politik\/ausland\/krieg-in-afghanistan-bundeswehr-setzt-schwere-artillerie-gegen-aufstaendische-ein-a-705848.html\">eingesetzt<\/a> und feuerte ganze f\u00fcnf Schuss. Die Niederl\u00e4nder hatten bei einem anderen Gefecht ebenfalls in Afghanistan einige Jahre zuvor immerhin 4.000 Schuss verballert. Das bedeutet, wirkliche Erfahrungen liegen mit diesem Ger\u00e4t gar nicht vor.<\/p>\n<p>Erheiternd ist dabei die Tatsache, dass zumindest ein Typ der Munition (ausgerechnet die mit der h\u00f6chsten Reichweite) f\u00fcr diese Haubitze laut Wikipedia von einem s\u00fcdafrikanischen Munitionshersteller stammt. Ob S\u00fcdafrika einem Export dieser Munition in die Ukraine, zum Einsatz gegen Russland, zustimmt, ist ausgesprochen fraglich. Schlie\u00dflich hat der in S\u00fcdafrika regierende ANC traditionell gute Beziehungen zu Russland, nicht nur \u00fcber BRICS, sondern auch noch aus der Zeit des Kampfes gegen die Apartheid, und aus eben dieser Zeit nicht allzu gute Beziehungen zu Deutschland. Man kann entspannt abwarten, wie sich dieser Teil des Dramas entwickelt.<\/p>\n<div class=\"ReadMore-root Section-root Section-is1to3-xs_is1to1\" data-widgets=\"ReadMore\" data-has-alias>\n<div class=\"Section-container Section-isRow-isTop-isWrap\">\n<article class=\"Card-root Card-is1to1 \">\n<div class=\"Card-imageWrap\">\n<div class=\"Card-picture\">\n<picture class=\"Picture-root Picture-default\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/627965fc48fbef0eb10ced56.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/627965fc48fbef0eb10ced55.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/627965fc48fbef0eb10ced56.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/627965fc48fbef0eb10ced55.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-default lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/627965fc48fbef0eb10ced56.jpg\" alt='Waffenlieferungen \"schwerer Fehler\": AfD-Chef Chrupalla fordert Dialog mit Russland'><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/627965fc48fbef0eb10ced55.jpg\" alt='Waffenlieferungen \"schwerer Fehler\": AfD-Chef Chrupalla fordert Dialog mit Russland'><\/noscript>    <\/div><\/div>\n<div class=\"Card-contentWrap\">\n<div class=\"Card-content\">\n<div class=\"Card-title\">\n<div class=\"HeaderNews-root HeaderNews-type_6 \">\n<p>            <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/inland\/138048-waffenlieferungen-schwerer-fehler-afd-chef\/\" class=\"Link-root Link-isFullCard \"><br \/>\n                Waffenlieferungen &#8220;schwerer Fehler&#8221;: AfD-Chef Chrupalla fordert Dialog mit Russland<br \/>\n            <\/a><\/p><\/div><\/div><\/div><\/div>\n<\/article>\n<\/div><\/div>\n<p>Sollten diese Haubitzen tats\u00e4chlich jemals irgendwo ankommen, wo sie eingesetzt werden, haben sie noch ein ganz klassisches Problem \u2013 voll beladen, also aufgetankt, mit Munition und Mannschaft, wiegt das Ding 57 Tonnen. Es ist zu schwer. Man erinnere sich nur an die Bem\u00fchungen der EU, polnische Br\u00fccken auf NATO-Standard zu bringen, sprich, f\u00fcr eine Last von 60 Tonnen \u00fcberhaupt befahrbar zu machen. Die Br\u00fccken in der Ukraine sind auf das Gewicht der sowjetischen Panzer ausgelegt, die immerhin weniger als 50 Tonnen wiegen. Damit d\u00fcrfte die Beweglichkeit deutlich eingeschr\u00e4nkt sein. Nicht zu vergessen, dieses Fahrzeug braucht Treibstoff, um von der Stelle zu kommen, und auch damit soll es in der Ukraine mittlerweile nicht zum Besten stehen.<\/p>\n<p>Die aktuelle Form der Kriegsf\u00fchrung hat ohnehin alle Berechnungen, wie die Lebensdauer eines Artilleriegesch\u00fctzes bewahrt werden kann, \u00fcber den Haufen geworfen. Zwei Minuten br\u00e4uchte es nur, hei\u00dft es \u00fcber die Haubitze, bis sie einen Schuss abgefeuert hat und sich wieder zur\u00fcck ins Versteck begibt. So machen das Panzer \u00fcblicherweise auch; es werden ein paar Schuss abgefeuert, und schon zieht sich der Panzer zur\u00fcck. Auch die Raketenwerfer bleiben nicht stehen. Aber wenn in dem Moment, in dem das Gesch\u00fctz feuert, eine Aufkl\u00e4rungsdrohne in der N\u00e4he ist, kann sie ganz bequem bis ins Versteck folgen und die Koordinaten weiterleiten.<\/p>\n<p>Da gab es diesen Vorfall, als in der Ukraine angeblich ein Einkaufszentrum von der russischen Armee bombardiert wurde. Im Netz gab es dann ein Drohnenvideo zu sehen, auf dem die Drohne einem Raketenwerfer von der Feuerposition bis zu seinem Parkplatz unter dem geschlossenen Einkaufszentrum folgte. Das ist ein kleines Beispiel daf\u00fcr, wie sich die Abl\u00e4ufe ge\u00e4ndert haben. Um die Drohnen abzuwehren, braucht es eine Luftabwehr; das Maschinengewehr der Haubitze d\u00fcrfte da nur begrenzt von Nutzen sein.<\/p>\n<div class=\"ReadMore-root Section-root Section-is1to3-xs_is1to1\" data-widgets=\"ReadMore\" data-has-alias>\n<div class=\"Section-container Section-isRow-isTop-isWrap\">\n<article class=\"Card-root Card-is1to1 \">\n<div class=\"Card-imageWrap\">\n<div class=\"Card-picture\">\n<picture class=\"Picture-root Picture-default\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/627a4177b480cc7e01532d57.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/627a4177b480cc7e01532d56.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/627a4177b480cc7e01532d57.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/627a4177b480cc7e01532d56.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-default lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/627a4177b480cc7e01532d57.jpg\" alt=\"Der ukrainische Au\u00dfenminister formuliert das Kriegsziel neu: Kiew will nun gewinnen\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/627a4177b480cc7e01532d56.jpg\" alt=\"Der ukrainische Au\u00dfenminister formuliert das Kriegsziel neu: Kiew will nun gewinnen\"><\/noscript>    <\/div><\/div>\n<div class=\"Card-contentWrap\">\n<div class=\"Card-content\">\n<div class=\"Card-title\">\n<div class=\"HeaderNews-root HeaderNews-type_6 \">\n<p>            <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/international\/138093-ukrainische-aussenminister-formuliert-neue-kriegsziel\/\" class=\"Link-root Link-isFullCard \"><br \/>\n                Der ukrainische Au\u00dfenminister formuliert das Kriegsziel neu: Kiew will nun gewinnen<br \/>\n            <\/a><\/p><\/div><\/div><\/div><\/div>\n<\/article>\n<\/div><\/div>\n<p>Mehr als eine Geste ist es nicht, selbst wenn die Ausbildung problemlos klappen sollte obwohl es sicher keine ukrainische Sprachversion des Feuerleitcomputers gibt. Dort, wo im Grunde das Schicksal der ukrainischen Armee gerade besiegelt wird, im Donbass, d\u00fcrfte dieses Gesch\u00fctz ohnehin nicht mehr ankommen. Nicht einmal mit irgendwelchen Erkenntnissen kann die NATO rechnen, wie verletzlich die GPS-Verbindung gegen\u00fcber den elektronischen Kampfmitteln der russischen Armee ist, beispielsweise. Allerh\u00f6chstens kann dadurch, wie durch all das andere Zeug, das in die Ukraine geschafft wird, der Krieg etwas verl\u00e4ngert werden. Was, das kann man nicht oft genug wiederholen, einzig und allein den USA n\u00fctzt; weder dem durch die Sanktionen verw\u00fcsteten Europa noch der Ukraine, die dadurch nur weitere unn\u00f6tige Verluste hat. Nicht einmal eine merkliche Umsatzsteigerung f\u00fcr die Hersteller Rheinmetall und Krauss-Maffei Wegmann ist zu erwarten, die mit dieser Haubitze nicht gerade einen Verkaufsschlager konstruierten.<\/p>\n<p>Daf\u00fcr aber schafft die Anwesenheit der ukrainischen Azubis in der Bundesrepublik ein Risiko, das selbst f\u00fcr entschiedene Unterst\u00fctzer ihres Herkunftslandes den absehbar geringen Nutzen bei weitem \u00fcbersteigt. Schlie\u00dflich werden damit ukrainische Soldaten in Deutschland an deutschen Waffen ausgebildet; ein Schritt, mit dem nach dem Gutachten des wissenschaftlichen Dienstes des Bundestags die Grenze zur Kriegsbeteiligung \u00fcberschritten wird, was bei der reinen Lieferung noch nicht der Fall sein soll.<\/p>\n<p>So steht das im Gutachten: &#8220;Bei Unterst\u00fctzungsleistungen auf der Grundlage von <em>non-belligerency <\/em>bleibt der <strong>Umfang von Waffenlieferungen<\/strong>, aber auch die Frage, ob es sich dabei um &#8220;offensive&#8221; oder &#8220;defensive&#8221; Waffen handelt, <strong>rechtlich unerheblich<\/strong>. Erst wenn neben der Belieferung mit Waffen auch die <strong>Einweisung der Konfliktpartei <\/strong>bzw. <strong>Ausbildung an solchen Waffen <\/strong>in Rede st\u00fcnde, w\u00fcrde man den gesicherten Bereich der Nichtkriegsf\u00fchrung verlassen (Hervorhebungen im Original).&#8221;<\/p>\n<p>Dabei ist selbst diese Definition des Gutachtens nicht unproblematisch. Der Begriff der &#8220;Nichtkriegsf\u00fchrung&#8221; bezieht sich n\u00e4mlich auf Unterst\u00fctzungsleistungen innerhalb eines B\u00fcndnisses auf jene Staaten, die B\u00fcndnispartnern durch Lieferungen beistehen. Es gibt aber kein B\u00fcndnis mit der Ukraine, keine rechtliche Verpflichtung; insofern steht die Argumentation selbst bez\u00fcglich der Waffenlieferungen auf schwachen Beinen.<\/p>\n<div class=\"ReadMore-root Section-root Section-is1to3-xs_is1to1\" data-widgets=\"ReadMore\" data-has-alias>\n<div class=\"Section-container Section-isRow-isTop-isWrap\">\n<article class=\"Card-root Card-is1to1 \">\n<div class=\"Card-imageWrap\">\n<div class=\"Card-picture\">\n<picture class=\"Picture-root Picture-default\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/627a87b448fbef107573ee58.jpg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Der-westliche-Scheinriese-und-die-Sanktionen.jpg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/627a87b448fbef107573ee58.jpg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Der-westliche-Scheinriese-und-die-Sanktionen.jpg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-default lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/627a87b448fbef107573ee58.jpg\" alt=\"Der westliche Scheinriese und die Sanktionen\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Der-westliche-Scheinriese-und-die-Sanktionen.jpg\" alt=\"Der westliche Scheinriese und die Sanktionen\"><\/noscript>    <\/div><\/div>\n<div class=\"Card-contentWrap\">\n<div class=\"Card-label\">\n            <span class=\"Label-root\"><br \/>\n                Meinung<br \/>\n            <\/span>\n        <\/div>\n<div class=\"Card-content\">\n<div class=\"Card-title\">\n<div class=\"HeaderNews-root HeaderNews-type_6 \">\n<p>            <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/meinung\/138127-der-westliche-scheinriese-und-die-sanktionen\/\" class=\"Link-root Link-isFullCard \"><br \/>\n                Der westliche Scheinriese und die Sanktionen<br \/>\n            <\/a><\/p><\/div><\/div><\/div><\/div>\n<\/article>\n<\/div><\/div>\n<p>In Idar-Oberstein werden also Soldaten eines Staates, mit dem kein B\u00fcndnis besteht, an Waffen ausgebildet, die dann an diesen Staat geliefert werden sollen. Nach dem Gutachten wird die Bundesrepublik damit zum Kriegsbeteiligten und, das bedeutet es, zum legitimen Ziel milit\u00e4rischer Handlungen.<\/p>\n<p>An diesem Punkt ist die Lage Deutschlands ohnehin heikel, denn die ukrainische Armee d\u00fcrfte reichlich aus den Strukturen der US-Armee in Deutschland mit Daten versorgt werden. Auch das kann als Kriegsbeteiligung gesehen werden. Einzig die Tatsache, dass Russland keine direkte Auseinandersetzung mit der NATO anstrebt, verhindert, dass diese Art der Unterst\u00fctzungsleistung Konsequenzen hat.<\/p>\n<p>Bundesverteidigungsministerin Christine Lambrecht sieht das ganz <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.tagesspiegel.de\/politik\/nach-gutachten-des-bundestags-lambrecht-sieht-in-ausbildung-ukrainischer-soldaten-keine-kriegsbeteiligung\/28295660.html\">entspannt<\/a> und erkl\u00e4rt, sie s\u00e4he in der Ausbildung keine Beteiligung. Erst &#8220;wenn wir Soldatinnen und Soldaten entsenden w\u00fcrden in die Ukraine, das w\u00e4re ein ganz klares Zeichen. Das werden wir aber auch nicht tun.&#8221; So sehr ihr diese Meinung geg\u00f6nnt sei, ist sie nur leider v\u00f6llig irrelevant. Denn die Entscheidung dar\u00fcber, ob die m\u00f6gliche Bewertung als Kriegseintritt zu entsprechenden Konsequenzen f\u00fchrt oder nicht, f\u00e4llt nicht in Berlin, sondern in Moskau.<\/p>\n<p>Damit bewegt sich die Bundesrepublik von einer Position, in der die eigene &#8220;Nichtkriegsf\u00fchrung&#8221; einigerma\u00dfen rechtlich gesichert ist, in eine, in der es eine Frage der Gnade ist. F\u00fcr einen Staat, der in den letzten zwei Monaten wirklich keine Gelegenheit ausgelassen hat, um seine Missachtung des Rechts zu belegen, k\u00fchn. Denn man sollte nicht vergessen \u2013 s\u00e4mtliche gegen Russland verh\u00e4ngte Sanktionen sind nicht nur grenzenlos dumm, sie sind au\u00dferdem absolut illegal, weil einzig und allein der UN-Sicherheitsrat Sanktionen verh\u00e4ngen d\u00fcrfte.<\/p>\n<div class=\"ReadMore-root Section-root Section-is1to3-xs_is1to1\" data-widgets=\"ReadMore\" data-has-alias>\n<div class=\"Section-container Section-isRow-isTop-isWrap\">\n<article class=\"Card-root Card-is1to1 \">\n<div class=\"Card-imageWrap\">\n<div class=\"Card-picture\">\n<picture class=\"Picture-root Picture-default\"><!--[if IE 9]><video style=\"display: none;\"><![endif]--><source media=\"(-webkit-min-device-pixel-ratio: 2) and (min-resolution: 120dpi)\" data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/6277c95fb480cc76f96b1198.jpeg 850w,\n                http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/1652370660_486_6277c95fb480cc76f96b1198.jpeg 1960w,\n            \" ><source data-srcset=\" \nhttp:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/6277c95fb480cc76f96b1198.jpeg 460w,\n              http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/1652370660_486_6277c95fb480cc76f96b1198.jpeg 980w,\n            \" ><!--[if IE 9]><\/video><![endif]--><img decoding=\"async\" data- src=\"data:image\/png;base64,iVBORw0KGgoAAAANSUhEUgAAABAAAAAJCAQAAACRI2S5AAAAEElEQVR42mNkIAAYRxWAAQAG9gAKqv6+AwAAAABJRU5ErkJggg==\" class=\"Picture-root Picture-default lazyload\" data-src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/6277c95fb480cc76f96b1198.jpeg\" alt=\"Biden k\u00fcndigt neue Waffenlieferungen an Ukraine im Umfang von 150 Millionen Euro an\"><\/source><\/source><\/picture><!-- noscript pattern --><noscript><img decoding=\"async\" src=\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/1652370660_486_6277c95fb480cc76f96b1198.jpeg\" alt=\"Biden k\u00fcndigt neue Waffenlieferungen an Ukraine im Umfang von 150 Millionen Euro an\"><\/noscript>    <\/div><\/div>\n<div class=\"Card-contentWrap\">\n<div class=\"Card-content\">\n<div class=\"Card-title\">\n<div class=\"HeaderNews-root HeaderNews-type_6 \">\n<p>            <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/international\/137957-biden-kundigt-neue-waffenlieferungen-an\/\" class=\"Link-root Link-isFullCard \"><br \/>\n                Biden k\u00fcndigt neue Waffenlieferungen an Ukraine im Umfang von 150 Millionen Euro an<br \/>\n            <\/a><\/p><\/div><\/div><\/div><\/div>\n<\/article>\n<\/div><\/div>\n<p>Es wird zwar gerne so getan, als bewegte man sich auf dem Boden des Rechts, aber bei genauer Betrachtung ist das nicht der Fall; nicht einmal mit der st\u00e4ndig beschworenen Formel vom &#8220;russischen Angriffskrieg&#8221;. Schlie\u00dflich hat Russland einen Beistandspakt mit den beiden Donbassrepubliken, die bereits seit acht Jahren angegriffen werden, w\u00e4hrend die Bundesrepublik zwar st\u00e4ndig ihre innige Solidarit\u00e4t mit dem blaugelben Elend beteuert, aber eben keinerlei rechtliche Grundlage f\u00fcr ihre Unterst\u00fctzung hat.<\/p>\n<p>Und nur, weil es bisher so ist, dass Russland die ganze Einmischung der NATO, ja, die ganze Strippenzieherei derselben, der wir diesen Konflikt letztlich verdanken, milit\u00e4risch h\u00f6flich ignoriert hat, hei\u00dft das noch lange nicht, dass das so bleibt oder gar, dass es so bleiben muss. Selbst wenn Berlin der \u00dcberzeugung ist, man habe sich schon so weit aus dem Fenster gelehnt, dass diese paar Zentimeter die Lage auch nicht verschlimmern, oder insgeheim darauf setzt, dass Russland die Aktion als das alberne Theater verbucht, das sie milit\u00e4risch ist, es wird eine weitere Dummheit auf den schon beeindruckenden Berg vergangener Dummheiten geh\u00e4uft. W\u00e4hrend der russische Milit\u00e4reinsatz in der Ukraine eigentlich gezeigt haben sollte, dass auch die Geduld des B\u00e4ren nicht endlos ist.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/de.rt.com\/international\/137897-russland-greift-zu-gegenmassnahmen\/\">&#8220;\u00c0 la guerre comme \u00e0 la guerre&#8221;: Russland greift zu Gegenma\u00dfnahmen<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/138217-haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>von Dagmar Henn Sie tun schon eigenartige Dinge in Berlin. Wie jetzt diese Nummer mit der Panzerhaubitze. Nun sitzen also etwas mehr als hundert ukrainische Soldaten in Idar-Oberstein, um im Verlauf von mindestens 40 Tagen zu lernen, wie man die zw\u00f6lf Haubitzen bedient, mit denen Deutschland und die Niederlande der Ukraine zum Sieg verhelfen wollen. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":7535,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"wp_automatic_camp":["217"],"7f6d3c96a0e6eba973781d657326fe12":["Haubitzenlehrlinge oder Deutschlands Weg zur Kriegspartei"],"original_link":["https:\/\/de.rt.com\/meinung\/138217-haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/"],"_thumbnail_id":["7535"],"wp_automatic_remove_first_image":["yes"],"_wptg_p2tg_sent2tg":["2022-05-12 17:52:08"],"jnews_social_counter_last_update":["1778363594"]},"categories":[19,23],"tags":[4480,19847,1855,268,2404,581],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Haubitzenlehrlinge oder Deutschlands Weg zur Kriegspartei - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Haubitzenlehrlinge oder Deutschlands Weg zur Kriegspartei\" \/>\n<meta property=\"og:description\" content=\"von Dagmar Henn Sie tun schon eigenartige Dinge in Berlin. Wie jetzt diese Nummer mit der Panzerhaubitze. Nun sitzen also etwas mehr als hundert ukrainische Soldaten in Idar-Oberstein, um im Verlauf von mindestens 40 Tagen zu lernen, wie man die zw\u00f6lf Haubitzen bedient, mit denen Deutschland und die Niederlande der Ukraine zum Sieg verhelfen wollen. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2022-05-12T15:46:03+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Haubitzenlehrlinge-oder-Deutschlands-Weg-zur-Kriegspartei.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1104\" \/>\n\t<meta property=\"og:image:height\" content=\"622\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"8\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Haubitzenlehrlinge oder Deutschlands Weg zur Kriegspartei\",\"datePublished\":\"2022-05-12T15:46:03+00:00\",\"dateModified\":\"2022-05-12T15:46:03+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/\"},\"wordCount\":1541,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Haubitzenlehrlinge-oder-Deutschlands-Weg-zur-Kriegspartei.jpg\",\"keywords\":[\"Deutschlands\",\"Haubitzenlehrlinge\",\"Kriegspartei\",\"oder\",\"Weg\",\"zur\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/\",\"name\":\"Haubitzenlehrlinge oder Deutschlands Weg zur Kriegspartei - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Haubitzenlehrlinge-oder-Deutschlands-Weg-zur-Kriegspartei.jpg\",\"datePublished\":\"2022-05-12T15:46:03+00:00\",\"dateModified\":\"2022-05-12T15:46:03+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Haubitzenlehrlinge-oder-Deutschlands-Weg-zur-Kriegspartei.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Haubitzenlehrlinge-oder-Deutschlands-Weg-zur-Kriegspartei.jpg\",\"width\":1104,\"height\":622},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Haubitzenlehrlinge oder Deutschlands Weg zur Kriegspartei\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Haubitzenlehrlinge oder Deutschlands Weg zur Kriegspartei - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/","og_locale":"de_DE","og_type":"article","og_title":"Haubitzenlehrlinge oder Deutschlands Weg zur Kriegspartei","og_description":"von Dagmar Henn Sie tun schon eigenartige Dinge in Berlin. Wie jetzt diese Nummer mit der Panzerhaubitze. Nun sitzen also etwas mehr als hundert ukrainische Soldaten in Idar-Oberstein, um im Verlauf von mindestens 40 Tagen zu lernen, wie man die zw\u00f6lf Haubitzen bedient, mit denen Deutschland und die Niederlande der Ukraine zum Sieg verhelfen wollen. [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2022-05-12T15:46:03+00:00","og_image":[{"width":1104,"height":622,"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Haubitzenlehrlinge-oder-Deutschlands-Weg-zur-Kriegspartei.jpg","type":"image\/jpeg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"8\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Haubitzenlehrlinge oder Deutschlands Weg zur Kriegspartei","datePublished":"2022-05-12T15:46:03+00:00","dateModified":"2022-05-12T15:46:03+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/"},"wordCount":1541,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Haubitzenlehrlinge-oder-Deutschlands-Weg-zur-Kriegspartei.jpg","keywords":["Deutschlands","Haubitzenlehrlinge","Kriegspartei","oder","Weg","zur"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/","url":"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/","name":"Haubitzenlehrlinge oder Deutschlands Weg zur Kriegspartei - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Haubitzenlehrlinge-oder-Deutschlands-Weg-zur-Kriegspartei.jpg","datePublished":"2022-05-12T15:46:03+00:00","dateModified":"2022-05-12T15:46:03+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Haubitzenlehrlinge-oder-Deutschlands-Weg-zur-Kriegspartei.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2022\/05\/Haubitzenlehrlinge-oder-Deutschlands-Weg-zur-Kriegspartei.jpg","width":1104,"height":622},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/haubitzenlehrlinge-oder-deutschlands-weg-zur-kriegspartei\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Haubitzenlehrlinge oder Deutschlands Weg zur Kriegspartei"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/7534"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=7534"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/7534\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/7535"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=7534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=7534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=7534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}