{"id":74933,"date":"2024-12-21T17:32:51","date_gmt":"2024-12-21T15:32:51","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/"},"modified":"2024-12-21T17:32:51","modified_gmt":"2024-12-21T15:32:51","slug":"magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/","title":{"rendered":"Magdeburger Terroranschlag ist kaum neu \u2012 Jahrzehnte des &quot;Fahrzeug-Terrors&quot; in westlichen L\u00e4ndern"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/12\/6766d06348fbef1594361823.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Berlin, Nizza, London, Stockholm, Barcelona und andere \u2013 die Todesfahrt auf dem Weihnachtsmarkt in Magdeburg ist kein Einzelfall. Nachrichtenanalysen zufolge kam es in den letzten Jahren in westlichen L\u00e4ndern wiederholt zu Terroranschl\u00e4gen mit Fahrzeugen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>In den letzten zehn Jahren kam es in verschiedenen europ\u00e4ischen und US-amerikanischen St\u00e4dten zu terroristischen Anschl\u00e4gen, bei denen ein Autofahrer Fu\u00dfg\u00e4nger anfuhr, auch an Feiertagen oder w\u00e4hrend Jahrm\u00e4rkten.<\/p>\n<p><strong>Berlin<\/strong><strong><\/strong><\/p>\n<p>Am Abend des 19. Dezember 2016 fuhr ein Sattelzug in eine Menschenmenge auf dem Weihnachtsmarkt auf dem Breitscheidplatz im Berliner Stadtbezirk Charlottenburg-Wilmersdorf. Nachdem er durch den Marktbereich zwischen den St\u00e4nden und durch eine Einkaufsreihe hindurchgefahren war, fuhr der Lkw zur\u00fcck in eine angrenzende Stra\u00dfe und hielt kurz darauf an, woraufhin der Fahrer die Flucht ergriff. Infolgedessen starben 13 Menschen unter den R\u00e4dern des Lastwagens und mehr als 60 weitere Besucher wurden mehr oder weniger schwer verletzt.<strong><\/strong><\/p>\n<p>Der selbsternannte &#8220;Islamische Staat&#8221; (ISIS) bekannte sich zu dem Anschlag. Nach einer Untersuchung des verlassenen Lastwagens identifizierte die Polizei den Verd\u00e4chtigen \u2012 den 24-j\u00e4hrigen Tunesier Anis Amri, der f\u00fcnf Tage sp\u00e4ter in der N\u00e4he von Mailand, Italien, bei einem Schusswechsel mit der \u00f6rtlichen Polizei get\u00f6tet wurde.<\/p>\n<p><strong>Nizza<\/strong><strong><\/strong><\/p>\n<p>Im Jahr 2016 \u00fcberfuhr ein Mann w\u00e4hrend der Feierlichkeiten zum 14. Juli, dem Tag der Bastille, auf der Promenade des Anglais in Nizza Fu\u00dfg\u00e4nger mit einem Lastwagen und t\u00f6tete 86 Menschen. Die Organisation &#8220;Islamischer Staat&#8221; (ISIS) \u00fcbernahm die Verantwortung f\u00fcr den Anschlag. Unter den Toten waren 15 Minderj\u00e4hrige, mehr als 300 Menschen wurden verletzt.<strong><\/strong><\/p>\n<p>Bei dem T\u00e4ter handelte es sich um den 31-j\u00e4hrigen Tunesier Mohamed Salmene Lahouaiej Bouhlel, der von franz\u00f6sischen Polizeibeamten erschossen wurde, als diese versuchten, sein Auto zu stoppen.<strong><\/strong><\/p>\n<p>Im November 2020 wurde gegen acht Personen, gegen die im Zusammenhang mit dem Anschlag von Nizza ermittelt wurde, Anklage erhoben. Zwei von ihnen wurden der Beihilfe zum Terrorismus f\u00fcr schuldig befunden, die anderen sechs der kriminellen Verschw\u00f6rung und des Waffenschmuggels. Sie erhielten Haftstrafen zwischen zwei und 18 Jahren.<\/p>\n<p><strong>London<\/strong><strong><\/strong><\/p>\n<p>In der Nacht des 3. Juni 2017 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/kurzclips\/video\/52078-videos-messer-is-terroristen\/\">\u00fcberfuhr<\/a> ein Kleinbus in der N\u00e4he der London Bridge etwa zwanzig Fu\u00dfg\u00e4nger. Nach der Todesfahrt fuhren drei T\u00e4ter weiter zum nahegelegenen Borough Market, stiegen aus dem Fahrzeug und stachen auf mehrere Menschen ein. Die Polizei erschoss sie.<strong><\/strong><\/p>\n<p>Bei dem Anschlag wurden acht Menschen get\u00f6tet und mehr als 40 verletzt. Der &#8220;Islamische Staat&#8221; (ISIS) bekannte sich zu dem Anschlag.<\/p>\n<p><strong>Stockholm<\/strong><strong><\/strong><\/p>\n<p>Am 7. April 2017 wurden f\u00fcnf Menschen get\u00f6tet und 14 verletzt, als ein Lastwagen auf der Drottninggatan, einer Fu\u00dfg\u00e4ngerzone und einer der Hauptverkehrsadern der schwedischen Hauptstadt, in eine Menschenmenge raste.<strong><\/strong><\/p>\n<p>In einer schnellen Aktion nahm die Polizei den 39-j\u00e4hrigen usbekischen Staatsangeh\u00f6rigen Rachmat Akilow fest, der mit radikalen islamischen Extremistenorganisationen, insbesondere dem &#8220;Islamischen Staat&#8221; (ISIS), sympathisierte.<strong><\/strong><\/p>\n<p>Am 7. Juni 2018 wurde er von einem schwedischen Gericht wegen seiner Straftaten zu lebenslanger Haft verurteilt.<\/p>\n<p><strong>Barcelona<\/strong><strong><\/strong><\/p>\n<p>Am 17. August 2017 kam es zu einem Terroranschlag auf dem Boulevard\u00a0La Rambla in Barcelona \u2012 ein Lieferwagen fuhr auf den B\u00fcrgersteig und rammte Fu\u00dfg\u00e4nger. Infolgedessen wurden 14 Menschen get\u00f6tet und mehr als 110 verletzt.<strong><\/strong><\/p>\n<p>Am selben Tag gab es in der Gemeinde Alcanar in Katalonien zwei Explosionen, bei denen eine Person get\u00f6tet und etwa zehn verletzt wurden, und in der Stadt Cambrils, s\u00fcdlich von Barcelona, \u00fcberfuhr eine Gruppe von Terroristen ebenfalls Menschen mit einem Lieferwagen\u00a0\u2012 eine Person wurde get\u00f6tet, sechs wurden verletzt.<strong><\/strong><\/p>\n<p>Alle f\u00fcnf Angreifer wurden get\u00f6tet. Der &#8220;Islamische Staat&#8221; (ISIS) bekannte sich zu der Serie von Terroranschl\u00e4gen.<\/p>\n<p><strong>New York<\/strong><strong><\/strong><\/p>\n<p>Am 31. Oktober 2017 fuhr der aus Usbekistan stammende Saifulla Saipow mit einem Pickup-Truck mit hoher Geschwindigkeit auf einen Fahrradweg in New York City und steuerte das Fahrzeug absichtlich auf Menschen zu. Nachdem er etwa eineinhalb Kilometer gefahren war, krachte er in einen Schulbus.<strong><\/strong><\/p>\n<p>Bei dem Anschlag wurden acht Menschen get\u00f6tet und mindestens zw\u00f6lf verletzt. Der &#8220;Islamische Staat&#8221; (ISIS) \u00fcbernahm die Verantwortung f\u00fcr den Anschlag. <strong><\/strong><\/p>\n<p>Saipow wurde von der Polizei festgenommen und 2023 in allen Mordf\u00e4llen f\u00fcr schuldig befunden. Er wurde zu einer lebenslangen Freiheitsstrafe verurteilt.<\/p>\n<p><strong>Mehr zum Thema<\/strong> \u2012\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/230242-todesfahrt-in-magdeburg-zahl-terroropfer-steigt-4ueber-200-verletzte\/\">Todesfahrt in Magdeburg: Zahl der Terroropfer steigt auf f\u00fcnf, \u00fcber 200 Verletzte<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/230264-magdeburger-terroranschlag-ist-kaum-neu\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Berlin, Nizza, London, Stockholm, Barcelona und andere \u2013 die Todesfahrt auf dem Weihnachtsmarkt in Magdeburg ist kein Einzelfall. Nachrichtenanalysen zufolge kam es in den letzten Jahren in westlichen L\u00e4ndern wiederholt zu Terroranschl\u00e4gen mit Fahrzeugen. In den letzten zehn Jahren kam es in verschiedenen europ\u00e4ischen und US-amerikanischen St\u00e4dten zu terroristischen Anschl\u00e4gen, bei denen ein Autofahrer Fu\u00dfg\u00e4nger [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":74934,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1734796833"],"wp_automatic_camp":["217"],"9f70a1dcdee47b9109612c834a108884":["Magdeburger Terroranschlag ist kaum neu \u2012 Jahrzehnte des &quot;Fahrzeug-Terrors&quot; in westlichen L\u00e4ndern"],"original_link":["https:\/\/de.rt.com\/international\/230264-magdeburger-terroranschlag-ist-kaum-neu\/"],"_thumbnail_id":["74934"],"jnews_social_counter_last_update":["1778600827"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-12-21 18:01:32\";}"]},"categories":[19,23],"tags":[583,414,22383,22503,18784,61199,2392,61200,9473,712],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Magdeburger Terroranschlag ist kaum neu \u2012 Jahrzehnte des &quot;Fahrzeug-Terrors&quot; in westlichen L\u00e4ndern - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-\u2012-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Magdeburger Terroranschlag ist kaum neu \u2012 Jahrzehnte des &quot;Fahrzeug-Terrors&quot; in westlichen L\u00e4ndern\" \/>\n<meta property=\"og:description\" content=\"Berlin, Nizza, London, Stockholm, Barcelona und andere \u2013 die Todesfahrt auf dem Weihnachtsmarkt in Magdeburg ist kein Einzelfall. Nachrichtenanalysen zufolge kam es in den letzten Jahren in westlichen L\u00e4ndern wiederholt zu Terroranschl\u00e4gen mit Fahrzeugen. In den letzten zehn Jahren kam es in verschiedenen europ\u00e4ischen und US-amerikanischen St\u00e4dten zu terroristischen Anschl\u00e4gen, bei denen ein Autofahrer Fu\u00dfg\u00e4nger [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-\u2012-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-21T15:32:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/12\/6766d06348fbef1594361823.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Magdeburger Terroranschlag ist kaum neu \u2012 Jahrzehnte des &quot;Fahrzeug-Terrors&quot; in westlichen L\u00e4ndern\",\"datePublished\":\"2024-12-21T15:32:51+00:00\",\"dateModified\":\"2024-12-21T15:32:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/\"},\"wordCount\":702,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/12\/Magdeburger-Terroranschlag-ist-kaum-neu-\u2012-Jahrzehnte-des-quotFahrzeug-Terrorsquot-in.jpg\",\"keywords\":[\"des\",\"ist\",\"Jahrzehnte\",\"Kaum\",\"L\u00e4ndern\",\"Magdeburger\",\"neu\",\"quotFahrzeugTerrorsquot\",\"Terroranschlag\",\"westlichen\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/\",\"name\":\"Magdeburger Terroranschlag ist kaum neu \u2012 Jahrzehnte des &quot;Fahrzeug-Terrors&quot; in westlichen L\u00e4ndern - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/12\/Magdeburger-Terroranschlag-ist-kaum-neu-\u2012-Jahrzehnte-des-quotFahrzeug-Terrorsquot-in.jpg\",\"datePublished\":\"2024-12-21T15:32:51+00:00\",\"dateModified\":\"2024-12-21T15:32:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/12\/Magdeburger-Terroranschlag-ist-kaum-neu-\u2012-Jahrzehnte-des-quotFahrzeug-Terrorsquot-in.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/12\/Magdeburger-Terroranschlag-ist-kaum-neu-\u2012-Jahrzehnte-des-quotFahrzeug-Terrorsquot-in.jpg\",\"width\":460,\"height\":259,\"caption\":\"Magdeburger Terroranschlag ist kaum neu \u2012 Jahrzehnte des &quot;Fahrzeug-Terrors&quot; in westlichen L\u00e4ndern\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Magdeburger Terroranschlag ist kaum neu \u2012 Jahrzehnte des &quot;Fahrzeug-Terrors&quot; in westlichen L\u00e4ndern\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Magdeburger Terroranschlag ist kaum neu \u2012 Jahrzehnte des &quot;Fahrzeug-Terrors&quot; in westlichen L\u00e4ndern - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-\u2012-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/","og_locale":"de_DE","og_type":"article","og_title":"Magdeburger Terroranschlag ist kaum neu \u2012 Jahrzehnte des &quot;Fahrzeug-Terrors&quot; in westlichen L\u00e4ndern","og_description":"Berlin, Nizza, London, Stockholm, Barcelona und andere \u2013 die Todesfahrt auf dem Weihnachtsmarkt in Magdeburg ist kein Einzelfall. Nachrichtenanalysen zufolge kam es in den letzten Jahren in westlichen L\u00e4ndern wiederholt zu Terroranschl\u00e4gen mit Fahrzeugen. In den letzten zehn Jahren kam es in verschiedenen europ\u00e4ischen und US-amerikanischen St\u00e4dten zu terroristischen Anschl\u00e4gen, bei denen ein Autofahrer Fu\u00dfg\u00e4nger [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-\u2012-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-12-21T15:32:51+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/12\/6766d06348fbef1594361823.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Magdeburger Terroranschlag ist kaum neu \u2012 Jahrzehnte des &quot;Fahrzeug-Terrors&quot; in westlichen L\u00e4ndern","datePublished":"2024-12-21T15:32:51+00:00","dateModified":"2024-12-21T15:32:51+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/"},"wordCount":702,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/12\/Magdeburger-Terroranschlag-ist-kaum-neu-\u2012-Jahrzehnte-des-quotFahrzeug-Terrorsquot-in.jpg","keywords":["des","ist","Jahrzehnte","Kaum","L\u00e4ndern","Magdeburger","neu","quotFahrzeugTerrorsquot","Terroranschlag","westlichen"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/","url":"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/","name":"Magdeburger Terroranschlag ist kaum neu \u2012 Jahrzehnte des &quot;Fahrzeug-Terrors&quot; in westlichen L\u00e4ndern - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/12\/Magdeburger-Terroranschlag-ist-kaum-neu-\u2012-Jahrzehnte-des-quotFahrzeug-Terrorsquot-in.jpg","datePublished":"2024-12-21T15:32:51+00:00","dateModified":"2024-12-21T15:32:51+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/12\/Magdeburger-Terroranschlag-ist-kaum-neu-\u2012-Jahrzehnte-des-quotFahrzeug-Terrorsquot-in.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/12\/Magdeburger-Terroranschlag-ist-kaum-neu-\u2012-Jahrzehnte-des-quotFahrzeug-Terrorsquot-in.jpg","width":460,"height":259,"caption":"Magdeburger Terroranschlag ist kaum neu \u2012 Jahrzehnte des &quot;Fahrzeug-Terrors&quot; in westlichen L\u00e4ndern"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/magdeburger-terroranschlag-ist-kaum-neu-%e2%80%92-jahrzehnte-des-fahrzeug-terrors-in-westlichen-laendern\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Magdeburger Terroranschlag ist kaum neu \u2012 Jahrzehnte des &quot;Fahrzeug-Terrors&quot; in westlichen L\u00e4ndern"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/74933"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=74933"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/74933\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/74934"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=74933"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=74933"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=74933"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}