{"id":73680,"date":"2024-12-02T17:11:24","date_gmt":"2024-12-02T15:11:24","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\/"},"modified":"2024-12-02T17:11:24","modified_gmt":"2024-12-02T15:11:24","slug":"stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\/","title":{"rendered":"Stoltenberg \u00fcber Konfliktl\u00f6sung: Kiew k\u00f6nnte vor\u00fcbergehend Gebiete abtreten"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/12\/674d9cfb48fbef4da95e28ad.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Der Ex-NATO-Generalsekret\u00e4r h\u00e4lt es f\u00fcr unwahrscheinlich, dass Kiew Gebiete in naher Zukunft zur\u00fcckgewinnen kann. Selenskij r\u00e4umt ein, dass Kiew dazu nicht in der Lage sei. Putin erkl\u00e4rt, Moskau sei zu vern\u00fcnftigen Kompromissen, aber nicht zu Zugest\u00e4ndnissen bereit.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Jens Stoltenberg, der ehemalige NATO-Generalsekret\u00e4r, schl\u00e4gt eine &#8220;vor\u00fcbergehende Abtretung&#8221; einiger von der Ukraine kontrollierten Gebiete als M\u00f6glichkeit f\u00fcr ein schnelles Ende des Konflikts vor, berichtet die<em> Tagesschau:<\/em><\/p>\n<p><em>&#8220;Wenn die Waffenstillstandslinie bedeutet, dass Russland weiterhin alle besetzten Gebiete kontrolliert, bedeutet das nicht, dass die Ukraine f\u00fcr immer auf diese Gebiete verzichten muss.&#8221;<\/em><\/p>\n<p>Demnach k\u00f6nnte Kiew Sicherheitsgarantien im Austausch f\u00fcr ein &#8220;vor\u00fcbergehendes Abtreten von Gebieten&#8221; erhalten. Eine Garantie k\u00f6nnte die NATO-Mitgliedschaft sein, aber es g\u00e4be auch &#8220;andere M\u00f6glichkeiten, die Ukraine zu bewaffnen und zu unterst\u00fctzen&#8221;, f\u00fcgte der ehemalige Generalsekret\u00e4r hinzu:<\/p>\n<p><em>&#8220;Wir brauchen eine Waffenstillstandslinie, und nat\u00fcrlich sollte diese Linie idealerweise alle Gebiete umfassen, die derzeit von Russland kontrolliert werden. Aber wir sehen, dass dies in naher Zukunft unrealistisch ist.&#8221;<\/em><\/p>\n<p>Im November deutete der ukrainische Pr\u00e4sident Wladimir Selenskij an, dass die &#8220;hei\u00dfe Phase&#8221; des Konflikts beendet werden k\u00f6nnte, wenn die Ukraine mit den von ihr kontrollierten Gebieten in die NATO aufgenommen w\u00fcrde, da die verlorenen Gebiete sp\u00e4ter diplomatisch zur\u00fcckgewonnen werden k\u00f6nnten.<\/p>\n<p>Noch im Sommer hatte Selenskij erkl\u00e4rt, Kiew sei nicht bereit, seine Gebiete &#8220;als Friedensangebot&#8221; zur Verf\u00fcgung zu stellen. Andrei Jermak, der Leiter des ukrainischen Pr\u00e4sidentenb\u00fcros, nannte die R\u00fcckkehr zu den Grenzen vom 23. Februar 2022 als Ausgangspunkt f\u00fcr Gespr\u00e4che mit Russland.<\/p>\n<p>Am 1. Dezember r\u00e4umte Selenskij in einem Interview mit <em>Kyodo News<\/em>\u00a0allerdings ein, dass die ukrainischen Streitkr\u00e4fte nicht \u00fcber gen\u00fcgend Kr\u00e4fte verf\u00fcgten, um die Gebiete zur\u00fcckzugewinnen: &#8220;Unsere Armee hat keine Kr\u00e4fte daf\u00fcr. Das ist die Wahrheit.&#8221;<\/p>\n<p>Russlands\u00a0Pr\u00e4sident Wladimir Putin hatte im Oktober erkl\u00e4rt, Moskau sei zu vern\u00fcnftigen Kompromissen bereit, Zugest\u00e4ndnisse und &#8220;Tauschgesch\u00e4fte&#8221; k\u00e4men aber nicht in Frage:<\/p>\n<p><em>&#8220;Das Ergebnis muss zugunsten Russlands ausfallen, das sage ich ganz offen, und es muss sich an den Realit\u00e4ten orientieren, die sich auf dem Schlachtfeld abzeichnen. Wir sind zweifellos nicht bereit, hier Zugest\u00e4ndnisse zu machen, es wird keine Tauschgesch\u00e4fte geben.&#8221;<\/em><\/p>\n<p>Mehr zum Thema \u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/europa\/224704-ist-westen-endlich-bereit-seine\/\">Ist der Westen endlich bereit, seine Niederlage in der Ukraine einzugestehen?<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/228001-stoltenberg-zur-konfliktloesung-koennte-kiew-voruebergehend-gebiete-abtreten\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Ex-NATO-Generalsekret\u00e4r h\u00e4lt es f\u00fcr unwahrscheinlich, dass Kiew Gebiete in naher Zukunft zur\u00fcckgewinnen kann. Selenskij r\u00e4umt ein, dass Kiew dazu nicht in der Lage sei. Putin erkl\u00e4rt, Moskau sei zu vern\u00fcnftigen Kompromissen, aber nicht zu Zugest\u00e4ndnissen bereit. Jens Stoltenberg, der ehemalige NATO-Generalsekret\u00e4r, schl\u00e4gt eine &#8220;vor\u00fcbergehende Abtretung&#8221; einiger von der Ukraine kontrollierten Gebiete als M\u00f6glichkeit f\u00fcr [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":73681,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1733152873"],"wp_automatic_camp":["217"],"0320e3dcb329d2cb27a3611f56b02e34":["Stoltenberg \u00fcber Konfliktl\u00f6sung: Kiew k\u00f6nnte vor\u00fcbergehend Gebiete abtreten"],"original_link":["https:\/\/de.rt.com\/international\/228001-stoltenberg-zur-konfliktloesung-koennte-kiew-voruebergehend-gebiete-abtreten\/"],"_thumbnail_id":["73681"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-12-02 17:22:37\";}"],"jnews_social_counter_last_update":["1788378678"]},"categories":[19,23],"tags":[19933,11472,1025,31291,970,22084,139,22616],"class_list":["post-73680","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-abtreten","tag-gebiete","tag-kiew","tag-konfliktloesung","tag-koennte","tag-stoltenberg","tag-ueber","tag-voruebergehend"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Stoltenberg \u00fcber Konfliktl\u00f6sung: Kiew k\u00f6nnte vor\u00fcbergehend Gebiete abtreten - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Stoltenberg \u00fcber Konfliktl\u00f6sung: Kiew k\u00f6nnte vor\u00fcbergehend Gebiete abtreten\" \/>\n<meta property=\"og:description\" content=\"Der Ex-NATO-Generalsekret\u00e4r h\u00e4lt es f\u00fcr unwahrscheinlich, dass Kiew Gebiete in naher Zukunft zur\u00fcckgewinnen kann. Selenskij r\u00e4umt ein, dass Kiew dazu nicht in der Lage sei. Putin erkl\u00e4rt, Moskau sei zu vern\u00fcnftigen Kompromissen, aber nicht zu Zugest\u00e4ndnissen bereit. Jens Stoltenberg, der ehemalige NATO-Generalsekret\u00e4r, schl\u00e4gt eine &#8220;vor\u00fcbergehende Abtretung&#8221; einiger von der Ukraine kontrollierten Gebiete als M\u00f6glichkeit f\u00fcr [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-12-02T15:11:24+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/12\/674d9cfb48fbef4da95e28ad.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Stoltenberg \u00fcber Konfliktl\u00f6sung: Kiew k\u00f6nnte vor\u00fcbergehend Gebiete abtreten\",\"datePublished\":\"2024-12-02T15:11:24+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\\\/\"},\"wordCount\":413,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/12\\\/Stoltenberg-ueber-Konfliktloesung-Kiew-koennte-voruebergehend-Gebiete-abtreten.jpg\",\"keywords\":[\"abtreten\",\"Gebiete\",\"Kiew\",\"Konfliktl\u00f6sung\",\"K\u00f6nnte\",\"Stoltenberg\",\"\u00fcber\",\"vor\u00fcbergehend\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\\\/\",\"name\":\"Stoltenberg \u00fcber Konfliktl\u00f6sung: Kiew k\u00f6nnte vor\u00fcbergehend Gebiete abtreten - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/12\\\/Stoltenberg-ueber-Konfliktloesung-Kiew-koennte-voruebergehend-Gebiete-abtreten.jpg\",\"datePublished\":\"2024-12-02T15:11:24+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/12\\\/Stoltenberg-ueber-Konfliktloesung-Kiew-koennte-voruebergehend-Gebiete-abtreten.jpg\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/12\\\/Stoltenberg-ueber-Konfliktloesung-Kiew-koennte-voruebergehend-Gebiete-abtreten.jpg\",\"width\":460,\"height\":259,\"caption\":\"Stoltenberg \u00fcber Konfliktl\u00f6sung: Kiew k\u00f6nnte vor\u00fcbergehend Gebiete abtreten\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Stoltenberg \u00fcber Konfliktl\u00f6sung: Kiew k\u00f6nnte vor\u00fcbergehend Gebiete abtreten\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Stoltenberg \u00fcber Konfliktl\u00f6sung: Kiew k\u00f6nnte vor\u00fcbergehend Gebiete abtreten - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\/","og_locale":"de_DE","og_type":"article","og_title":"Stoltenberg \u00fcber Konfliktl\u00f6sung: Kiew k\u00f6nnte vor\u00fcbergehend Gebiete abtreten","og_description":"Der Ex-NATO-Generalsekret\u00e4r h\u00e4lt es f\u00fcr unwahrscheinlich, dass Kiew Gebiete in naher Zukunft zur\u00fcckgewinnen kann. Selenskij r\u00e4umt ein, dass Kiew dazu nicht in der Lage sei. Putin erkl\u00e4rt, Moskau sei zu vern\u00fcnftigen Kompromissen, aber nicht zu Zugest\u00e4ndnissen bereit. Jens Stoltenberg, der ehemalige NATO-Generalsekret\u00e4r, schl\u00e4gt eine &#8220;vor\u00fcbergehende Abtretung&#8221; einiger von der Ukraine kontrollierten Gebiete als M\u00f6glichkeit f\u00fcr [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-12-02T15:11:24+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/12\/674d9cfb48fbef4da95e28ad.jpg","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Stoltenberg \u00fcber Konfliktl\u00f6sung: Kiew k\u00f6nnte vor\u00fcbergehend Gebiete abtreten","datePublished":"2024-12-02T15:11:24+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\/"},"wordCount":413,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/12\/Stoltenberg-ueber-Konfliktloesung-Kiew-koennte-voruebergehend-Gebiete-abtreten.jpg","keywords":["abtreten","Gebiete","Kiew","Konfliktl\u00f6sung","K\u00f6nnte","Stoltenberg","\u00fcber","vor\u00fcbergehend"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\/","url":"https:\/\/now-news.de\/de\/deutschland\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\/","name":"Stoltenberg \u00fcber Konfliktl\u00f6sung: Kiew k\u00f6nnte vor\u00fcbergehend Gebiete abtreten - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/12\/Stoltenberg-ueber-Konfliktloesung-Kiew-koennte-voruebergehend-Gebiete-abtreten.jpg","datePublished":"2024-12-02T15:11:24+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/12\/Stoltenberg-ueber-Konfliktloesung-Kiew-koennte-voruebergehend-Gebiete-abtreten.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/12\/Stoltenberg-ueber-Konfliktloesung-Kiew-koennte-voruebergehend-Gebiete-abtreten.jpg","width":460,"height":259,"caption":"Stoltenberg \u00fcber Konfliktl\u00f6sung: Kiew k\u00f6nnte vor\u00fcbergehend Gebiete abtreten"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/stoltenberg-ueber-konfliktloesung-kiew-koennte-voruebergehend-gebiete-abtreten\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Stoltenberg \u00fcber Konfliktl\u00f6sung: Kiew k\u00f6nnte vor\u00fcbergehend Gebiete abtreten"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/73680","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=73680"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/73680\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/73681"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=73680"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=73680"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=73680"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}