{"id":73534,"date":"2024-11-29T17:45:48","date_gmt":"2024-11-29T15:45:48","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/"},"modified":"2024-11-29T17:45:48","modified_gmt":"2024-11-29T15:45:48","slug":"ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/","title":{"rendered":"Ex-Habeck-Fl\u00fcsterer Patrick Graichen findet Nebenjob beim ukrainischem Energieunternehmen Ukrenergo"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/6749ab96b480cc1b8f62185b.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Still war es geworden um den medial titulierten &#8220;Graichen-Clan&#8221; im Umfeld von Robert Habeck. Nun informiert das ukrainische Energieunternehmen Ukrenergo mit der Personalie Patrick Graichen \u00fcber ein neues Aufsichtsratsmtglied mit besten Beziehungen zur deutschen Regierung.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Im Mai des Vorjahres wurde Wirtschaftsstaatssekret\u00e4r Patrick Graichen laut <em>ARD<\/em>&#8211;<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.tagesschau.de\/eilmeldung\/graichen-104.html\">Meldung<\/a> wegen des &#8220;Vorwurfs der Vetternwirtschaft&#8221; in den einstweiligen Ruhestand versetzt. Bundesminister Robert Habeck teilte zudem mit, interne Pr\u00fcfungen h\u00e4tten &#8220;weitere Ungereimtheiten ergeben&#8221;, dies bezogen auf ministerielle Jobzusagen seitens des von den Medien als &#8220;Top-Mitarbeiter&#8221; im Wirtschaftsministerium betitelten Ex-Staatssekret\u00e4rs. Zu Wochenbeginn informierte das\u00a0ukrainische Staatsunternehmen Ukrenergo, dass Graichen jetzt eines von &#8220;vier neuen unabh\u00e4ngigen Mitgliedern des Aufsichtsrates&#8221; werden wird.<\/p>\n<p>Der im Jahr 2023 auch als &#8220;umstrittener Vertrauter&#8221; von Wirtschaftsminister Habeck bezeichnete Graichen war final wegen seiner Beteiligung an der Auswahl seines Trauzeugen f\u00fcr den Chefposten der bundeseigenen Deutschen Energie-Agentur (Dena) hinterfragt worden. Nach breiter Kritik seitens Politik und Medien sah sich dann der aktuelle Kanzlerkandidat der Gr\u00fcnen gezwungen, seinen wichtigen Berater zu entlassen. Die Webseite Lobbycontrol <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.lobbycontrol.de\/pressemitteilung\/pressekommentar-zur-entlassung-des-staatssekretaers-patrick-graichen-108849\/\">kommentierte<\/a> die damalige Ereigniskette mit der Feststellung:<\/p>\n<p><em>&#8220;Graichens Beteiligung an einem F\u00f6rderentscheid zugunsten des Landesverbands des BUND, dessen Vorstand seine Schwester angeh\u00f6rt, war ein weiterer Fehler. Sie zeigt, dass der Umgang mit dieser Interessenkonstellation eben nicht korrekt war und die vom Ministerium behauptete sogenannte Brandmauer nicht funktioniert hat.&#8221;<\/em><\/p>\n<p>Kritisch wahrgenommen wurde zudem die Tatsache, dass Graichen gut dotiert in die Zukunft schauen konnte, da ein &#8220;in den einstweiligen Ruhestand versetzter Beamter nach dem Bundesbesoldungsgesetz f\u00fcr den aktuellen und die folgenden drei Monate die Bez\u00fcge weiter erh\u00e4lt, die ihm am Tag vor der Versetzung zustanden&#8221;, so das BMWK-Ministerium nach Presseanfragen <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.tagesspiegel.de\/politik\/habecks-geschasster-staatssekretar-graichen-erhalt-zunachst-weiter-sein-gehalt-von-15000-euro-im-monat-9839420.html\">mitteilend<\/a>. F\u00fcr Graichen bedeutete das mindestens 15.000 Euro pro Monat. Danach st\u00fcnden ihm laut <em><a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.businessinsider.de\/politik\/deutschland\/so-viel-geld-kriegt-graichen-nach-rauswurf-als-staatssekretaer\/\">Business Insider<\/a><\/em> noch rund 11.000 Euro monatlich zu \u2013 f\u00fcr 17 Monate. <\/p>\n<p>Am 27. November wurde nun in einer <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/ua.energy\/general-news\/the-cabinet-of-ministers-of-ukraine-has-approved-the-candidacies-of-four-new-independent-members-of-the-supervisory-board-of-npc-ukrenergo\/\">Pressemitteilung<\/a> des ukrainischen Staatsunternehmens und \u00dcbertragungsnetzbetreibers NPC Ukrenergo dar\u00fcber informiert, dass Graichen neben seiner deutschen Pension zuk\u00fcnftig noch eine neue ukrainische Einkommensquelle erf\u00e4hrt. Dazu hei\u00dft es:<\/p>\n<p><em>&#8220;Das Ministerkabinett der Ukraine hat die Kandidaturen von vier neuen unabh\u00e4ngigen Mitgliedern des Aufsichtsrates der NPC Ukrenergo genehmigt. Es handelt sich um Patrick Roland Graichen, Luigi de Francisci, Jeppe Sebastian Kofod und Jan Henrik Montell. Alle Kandidaten verf\u00fcgen \u00fcber umfangreiche Erfahrung und betr\u00e4chtliche internationale Autorit\u00e4t.<\/em><\/p>\n<p>Die Zusammensetzung des Aufsichtsrates wurde demnach dahingehend ausgew\u00e4hlt, dass &#8220;die erforderlichen Kompetenzen vorhanden sind, um die aktuellen Herausforderungen des Unternehmens zu bew\u00e4ltigen und seine Strategie umzusetzen&#8221;, so die Mitteilung. Die Auswahl nach den &#8220;unabh\u00e4ngigen Aufsichtsratsmitgliedern&#8221; erfolgte laut Mitteilung \u00fcber das Unternehmen <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.kornferry.com\/de\">Korn Ferry<\/a>, &#8220;dem weltweit f\u00fchrenden Unternehmen f\u00fcr die Suche nach F\u00fchrungskr\u00e4ften und die Entwicklung von Corporate Governance&#8221;, unter anderem mit Firmensitz in Berlin.<\/p>\n<p>Zur Begr\u00fcndung von Graichens Nominierung hei\u00dft es:<\/p>\n<p><em>&#8220;Patrick Roland Graichen ist ein bekannter europ\u00e4ischer Experte f\u00fcr Klima- und Energiefragen. Zuvor war er Staatssekret\u00e4r im Bundesministerium f\u00fcr Umwelt und Klimaschutz, wo er eine Schl\u00fcsselrolle bei der Gestaltung der nationalen Energiestrategien spielte.&#8221;<\/em><\/p>\n<p>Zudem wird seine leitende Rolle als Chef des Unternehmens Agora Energiewende erw\u00e4hnt. Zu den Kollegen von Graichen im Aufsichtsrat hei\u00dft es in der Mitteilung:<\/p>\n<ul>\n<li>Luigi de Francisci war bei TERNA, dem gr\u00f6\u00dften italienischen Netzbetreiber in Europa, f\u00fcr Regulierungsfragen zust\u00e4ndig.<\/li>\n<li>Jeppe Sebastian Kofod ist ein bekannter Europapolitiker und Experte f\u00fcr Energie- und Sicherheitsfragen (\u2026) diente von 2018 bis 2022 als Au\u00dfenminister von D\u00e4nemark<\/li>\n<li>Jan Henrik Montell kombinierte erfolgreich seine Erfahrung in der Unternehmensf\u00fchrung mit seinem Hintergrund als Finanzvorstand eines finnischen Strom\u00fcbertragungsnetzbetreibers.<\/li>\n<\/ul>\n<p>Zum Zeitpunkt von Graichens Entlassung im Mai 2023 tauchten dann noch erweiterte Plagiatsvorw\u00fcrfe auf, bezogen auf seine Doktorarbeit mit dem Titel: &#8220;Kommunale Energiepolitik und die Umweltbewegung&#8221;, die mit einer &#8220;R\u00fcge wegen des Versto\u00dfes gegen die gute wissenschaftliche Praxis&#8221; seitens der Universit\u00e4t Heidelberg <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.uni-heidelberg.de\/de\/newsroom\/doktorarbeit-von-patrick-graichen-universitaet-heidelberg-spricht-ruege-aus\">endeten<\/a>.<\/p>\n<p><strong>Mehr zum Thema\u00a0<\/strong>\u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/europa\/227424-medienbericht-gazprom-plant-ab-2025\/\">Medien: Gazprom erwartet, dass ab 2025 kein Gas mehr \u00fcber die Ukraine nach Europa flie\u00dfen wird <\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v5rin48\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/227747-ex-habeck-fluesterer-patrick-graichen\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Still war es geworden um den medial titulierten &#8220;Graichen-Clan&#8221; im Umfeld von Robert Habeck. Nun informiert das ukrainische Energieunternehmen Ukrenergo mit der Personalie Patrick Graichen \u00fcber ein neues Aufsichtsratsmtglied mit besten Beziehungen zur deutschen Regierung. Im Mai des Vorjahres wurde Wirtschaftsstaatssekret\u00e4r Patrick Graichen laut ARD&#8211;Meldung wegen des &#8220;Vorwurfs der Vetternwirtschaft&#8221; in den einstweiligen Ruhestand versetzt. [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":73535,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1732895831"],"wp_automatic_camp":["217"],"bfef5c9eb6f777854bcc0dcb5bcdc8df":["Ex-Habeck-Fl\u00fcsterer Patrick Graichen findet Nebenjob beim ukrainischem Energieunternehmen Ukrenergo"],"original_link":["https:\/\/de.rt.com\/inland\/227747-ex-habeck-fluesterer-patrick-graichen\/"],"_thumbnail_id":["73535"],"jnews_social_counter_last_update":["1784112623"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-11-29 17:58:10\";}"]},"categories":[19,23],"tags":[1814,28516,60659,431,44116,60660,7656,20009,60661],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Ex-Habeck-Fl\u00fcsterer Patrick Graichen findet Nebenjob beim ukrainischem Energieunternehmen Ukrenergo - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ex-Habeck-Fl\u00fcsterer Patrick Graichen findet Nebenjob beim ukrainischem Energieunternehmen Ukrenergo\" \/>\n<meta property=\"og:description\" content=\"Still war es geworden um den medial titulierten &#8220;Graichen-Clan&#8221; im Umfeld von Robert Habeck. Nun informiert das ukrainische Energieunternehmen Ukrenergo mit der Personalie Patrick Graichen \u00fcber ein neues Aufsichtsratsmtglied mit besten Beziehungen zur deutschen Regierung. Im Mai des Vorjahres wurde Wirtschaftsstaatssekret\u00e4r Patrick Graichen laut ARD&#8211;Meldung wegen des &#8220;Vorwurfs der Vetternwirtschaft&#8221; in den einstweiligen Ruhestand versetzt. [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-29T15:45:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/6749ab96b480cc1b8f62185b.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Ex-Habeck-Fl\u00fcsterer Patrick Graichen findet Nebenjob beim ukrainischem Energieunternehmen Ukrenergo\",\"datePublished\":\"2024-11-29T15:45:48+00:00\",\"dateModified\":\"2024-11-29T15:45:48+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/\"},\"wordCount\":663,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Ex-Habeck-Fluesterer-Patrick-Graichen-findet-Nebenjob-beim-ukrainischem-Energieunternehmen-Ukrenergo.jpg\",\"keywords\":[\"beim\",\"Energieunternehmen\",\"ExHabeckFl\u00fcsterer\",\"findet\",\"Graichen\",\"Nebenjob\",\"Patrick\",\"ukrainischem\",\"Ukrenergo\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/\",\"name\":\"Ex-Habeck-Fl\u00fcsterer Patrick Graichen findet Nebenjob beim ukrainischem Energieunternehmen Ukrenergo - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Ex-Habeck-Fluesterer-Patrick-Graichen-findet-Nebenjob-beim-ukrainischem-Energieunternehmen-Ukrenergo.jpg\",\"datePublished\":\"2024-11-29T15:45:48+00:00\",\"dateModified\":\"2024-11-29T15:45:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Ex-Habeck-Fluesterer-Patrick-Graichen-findet-Nebenjob-beim-ukrainischem-Energieunternehmen-Ukrenergo.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Ex-Habeck-Fluesterer-Patrick-Graichen-findet-Nebenjob-beim-ukrainischem-Energieunternehmen-Ukrenergo.jpg\",\"width\":460,\"height\":259,\"caption\":\"Ex-Habeck-Fl\u00fcsterer Patrick Graichen findet Nebenjob beim ukrainischem Energieunternehmen Ukrenergo\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ex-Habeck-Fl\u00fcsterer Patrick Graichen findet Nebenjob beim ukrainischem Energieunternehmen Ukrenergo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Ex-Habeck-Fl\u00fcsterer Patrick Graichen findet Nebenjob beim ukrainischem Energieunternehmen Ukrenergo - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/","og_locale":"de_DE","og_type":"article","og_title":"Ex-Habeck-Fl\u00fcsterer Patrick Graichen findet Nebenjob beim ukrainischem Energieunternehmen Ukrenergo","og_description":"Still war es geworden um den medial titulierten &#8220;Graichen-Clan&#8221; im Umfeld von Robert Habeck. Nun informiert das ukrainische Energieunternehmen Ukrenergo mit der Personalie Patrick Graichen \u00fcber ein neues Aufsichtsratsmtglied mit besten Beziehungen zur deutschen Regierung. Im Mai des Vorjahres wurde Wirtschaftsstaatssekret\u00e4r Patrick Graichen laut ARD&#8211;Meldung wegen des &#8220;Vorwurfs der Vetternwirtschaft&#8221; in den einstweiligen Ruhestand versetzt. [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-11-29T15:45:48+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/6749ab96b480cc1b8f62185b.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Ex-Habeck-Fl\u00fcsterer Patrick Graichen findet Nebenjob beim ukrainischem Energieunternehmen Ukrenergo","datePublished":"2024-11-29T15:45:48+00:00","dateModified":"2024-11-29T15:45:48+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/"},"wordCount":663,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Ex-Habeck-Fluesterer-Patrick-Graichen-findet-Nebenjob-beim-ukrainischem-Energieunternehmen-Ukrenergo.jpg","keywords":["beim","Energieunternehmen","ExHabeckFl\u00fcsterer","findet","Graichen","Nebenjob","Patrick","ukrainischem","Ukrenergo"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/","url":"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/","name":"Ex-Habeck-Fl\u00fcsterer Patrick Graichen findet Nebenjob beim ukrainischem Energieunternehmen Ukrenergo - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Ex-Habeck-Fluesterer-Patrick-Graichen-findet-Nebenjob-beim-ukrainischem-Energieunternehmen-Ukrenergo.jpg","datePublished":"2024-11-29T15:45:48+00:00","dateModified":"2024-11-29T15:45:48+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Ex-Habeck-Fluesterer-Patrick-Graichen-findet-Nebenjob-beim-ukrainischem-Energieunternehmen-Ukrenergo.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Ex-Habeck-Fluesterer-Patrick-Graichen-findet-Nebenjob-beim-ukrainischem-Energieunternehmen-Ukrenergo.jpg","width":460,"height":259,"caption":"Ex-Habeck-Fl\u00fcsterer Patrick Graichen findet Nebenjob beim ukrainischem Energieunternehmen Ukrenergo"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/ex-habeck-fluesterer-patrick-graichen-findet-nebenjob-beim-ukrainischem-energieunternehmen-ukrenergo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Ex-Habeck-Fl\u00fcsterer Patrick Graichen findet Nebenjob beim ukrainischem Energieunternehmen Ukrenergo"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/73534"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=73534"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/73534\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/73535"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=73534"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=73534"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=73534"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}