{"id":73473,"date":"2024-11-28T20:37:12","date_gmt":"2024-11-28T18:37:12","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/"},"modified":"2024-11-28T20:37:12","modified_gmt":"2024-11-28T18:37:12","slug":"oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/","title":{"rendered":"Oleg Zarjow: Solange es Selenskij gibt, sind Friedensverhandlungen aussichtslos"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/674747cf48fbef631d1d3da2.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Oleg Zarjow, langj\u00e4hriger ukrainischer Politiker und seit 2014 im russischen Exil, glaubt nicht, dass Donald Trump die Ukraine zu Friedensverhandlungen zwingen kann. Der ukrainische Machthaber Wladimir Selenskij h\u00e4lt den US-Demokraten die Treue und wird alle L\u00f6sungsans\u00e4tze Trumps sabotieren.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p><em>Von Oleg Zarjow<\/em><\/p>\n<p>Ich verstehe, dass wir gro\u00dfe Hoffnungen hegen, dass Donald Trump nach seinem Amtsantritt einen Friedensschluss mit der Ukraine zu den Bedingungen Russlands erm\u00f6glichen wird. Das ist der Grund, warum Russland jetzt auf die \u00dcberschreitung seiner roten Linien durch die Ukraine und den Westen sehr zur\u00fcckhaltend reagiert und so die von der scheidenden Biden-Administration auferlegte Eskalation einzud\u00e4mmen versucht.<\/p>\n<p>Dennoch glaube ich, dass Trump bei all seinem guten Willen (vorausgesetzt, er hat ihn) nicht in der Lage sein wird, die milit\u00e4rische Auseinandersetzung in der Ukraine zu stoppen. Tatsache ist, dass sich Selenskij anders entschieden hat: Er hatte die M\u00f6glichkeit, auf von Trump ausgesandte Signale zu reagieren, aber er hat sich bewusst f\u00fcr den Weg der Eskalation entschieden, weil er wusste, dass er damit den Demokraten in die H\u00e4nde spielt.<\/p>\n<p>Selenskij hat offenbar alles abgewogen und entschied sich, bis zum Ende auf der Seite der Demokraten zu bleiben. Sowohl vor Trumps Amtsantritt als auch danach. Und Selenskij wei\u00df, dass dies dem gew\u00e4hlten US-Pr\u00e4sidenten nicht entgehen kann. Niemand kommt umhin zu erkennen, dass Selenskij beschlossen hat, in seinem eigenen Interesse und im Interesse der Demokraten zu handeln, die offensichtlich in wichtigen Punkten \u00fcbereinstimmen, und nicht im Interesse der k\u00fcnftigen US-Administration. Auch wenn der Kiewer Machthaber Trump nicht offen widerspricht, wird er den Prozess der Suche nach einer Verhandlungsl\u00f6sung sabotieren, indem er sich auf angebliche Zw\u00e4nge beruft, auf die er keinen Einfluss habe: Die Verfassung lasse es nicht zu, die Opposition sei dagegen&#8230;<\/p>\n<p>Selenskij wird auf Zeit spielen und darauf hoffen, dass Trump bald in inneramerikanische Probleme verwickelt sein wird und dann gezwungen ist, sich nach dem Szenario zu richten, das ihm von den Demokraten und seinen Gegnern unter den Republikanern aufgezwungen wird. Darauf, dass der neue Pr\u00e4sident gezwungen ist, seinen Plan f\u00fcr die Ukraine zu opfern, um seine innenpolitischen Ziele in den Vereinigten Staaten zu erreichen.<\/p>\n<p>Der wichtigste Faktor, der erfolgreiche Friedensverhandlungen verhindern wird, ist Selenskij. Trump kann nicht direkt mit Putin verhandeln, solange es Selenskij gibt und dieser die Ukraine unter seiner Kontrolle h\u00e4lt. Verhandlungen gehen nur mit Beteiligung der Ukraine, es m\u00fcssen also Putin und Selenskij am Verhandlungstisch sitzen. Und das ist ein aussichtsloses Unterfangen, denn der Kiewer Machthaber wird den Verhandlungsprozess sabotieren.<\/p>\n<p>Ich denke, dass der Kreml dies verstanden hat, und deshalb versucht man dort, Selenskij als Verhandlungspartner zu diskreditieren, indem man auf seine erloschenen Machtbefugnisse als Pr\u00e4sident hinweist. Aber der russische Standpunkt wird nirgendwo in der Welt unterst\u00fctzt, Selenskij wird von allen weiterhin als amtierender Pr\u00e4sident der Ukraine akzeptiert.<\/p>\n<p>Auf dieser Grundlage glaube ich nicht, dass eine schnelle Einigung \u00fcber die Ukraine wahrscheinlich ist. Solange es eine unabh\u00e4ngige Ukraine gibt, ist es unwahrscheinlich, dass die Verhandlungen Fr\u00fcchte tragen. Wenn es die Ukraine aber nicht mehr gibt, gibt es auch keinen Verhandlungsgegenstand mit den USA mehr.<\/p>\n<p><em>Der 1970 in Dnjepropetrowsk geborene <strong>Oleg Zarjow<\/strong> studierte von 1987 bis 1992 an der wichtigsten sowjetischen Kaderschmiede f\u00fcr die Atomindustrie und nukleare Waffenherstellung \u2013 dem Moskauer MIFI. Von 1992 bis 2002 baute er als erfolgreicher Gesch\u00e4ftsmann mehrere Unternehmen auf. Von 2002 bis 2014 vertrat er seinen Einzelwahlkreis im ukrainischen Parlament und stieg zu einer der F\u00fchrungspers\u00f6nlichkeiten der ukrainischen Partei der Regionen auf. Nachdem er gewaltsam gezwungen wurde, seine Kandidatur f\u00fcr die Pr\u00e4sidentschaftswahlen im Mai 2014 zur\u00fcckzuziehen, musste er auf die Krim fliehen, engagierte sich f\u00fcr Neurussland und lebt seitdem im russischen Exil. Im Oktober 2023 \u00fcberlebte er nur knapp einen Mordanschlag des ukrainischen Geheimdienstes.<\/em><\/p>\n<p><em>Der vorstehende Text wurde aus dem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/olegtsarov\/19353\">Russischen<\/a> \u00fcbersetzt und im Original auf dem <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/olegtsarov\">Telegram-Kanal von Zarjow<\/a> ver\u00f6ffentlicht.<\/em><\/p>\n<p><strong>Mehr zum Thema<\/strong>\u00a0\u2012 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/international\/223434-kann-ukraine-atomwaffen-herstellen-oleg-zarjow\/\">Kann die Ukraine Atomwaffen herstellen? Oleg Zarjow gibt Antwort<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v5p2198\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/meinung\/227548-oleg-zarjow-solange-es-selenskij-gibt-scheitern-verhandlungen\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Oleg Zarjow, langj\u00e4hriger ukrainischer Politiker und seit 2014 im russischen Exil, glaubt nicht, dass Donald Trump die Ukraine zu Friedensverhandlungen zwingen kann. Der ukrainische Machthaber Wladimir Selenskij h\u00e4lt den US-Demokraten die Treue und wird alle L\u00f6sungsans\u00e4tze Trumps sabotieren. Von Oleg Zarjow Ich verstehe, dass wir gro\u00dfe Hoffnungen hegen, dass Donald Trump nach seinem Amtsantritt einen [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":73474,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1732819685"],"wp_automatic_camp":["217"],"883ca0227e1771bb35261a99e8afdc30":["Oleg Zarjow: Solange es Selenskij gibt, sind Friedensverhandlungen aussichtslos"],"original_link":["https:\/\/de.rt.com\/meinung\/227548-oleg-zarjow-solange-es-selenskij-gibt-scheitern-verhandlungen\/"],"_thumbnail_id":["73474"],"jnews_social_counter_last_update":["1784137592"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-11-28 20:49:06\";}"]},"categories":[19,23],"tags":[60634,19884,1002,41947,6158,1046,17626,21010],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Oleg Zarjow: Solange es Selenskij gibt, sind Friedensverhandlungen aussichtslos - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Oleg Zarjow: Solange es Selenskij gibt, sind Friedensverhandlungen aussichtslos\" \/>\n<meta property=\"og:description\" content=\"Oleg Zarjow, langj\u00e4hriger ukrainischer Politiker und seit 2014 im russischen Exil, glaubt nicht, dass Donald Trump die Ukraine zu Friedensverhandlungen zwingen kann. Der ukrainische Machthaber Wladimir Selenskij h\u00e4lt den US-Demokraten die Treue und wird alle L\u00f6sungsans\u00e4tze Trumps sabotieren. Von Oleg Zarjow Ich verstehe, dass wir gro\u00dfe Hoffnungen hegen, dass Donald Trump nach seinem Amtsantritt einen [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-28T18:37:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/674747cf48fbef631d1d3da2.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Oleg Zarjow: Solange es Selenskij gibt, sind Friedensverhandlungen aussichtslos\",\"datePublished\":\"2024-11-28T18:37:12+00:00\",\"dateModified\":\"2024-11-28T18:37:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/\"},\"wordCount\":665,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Oleg-Zarjow-Solange-es-Selenskij-gibt-sind-Friedensverhandlungen-aussichtslos.jpg\",\"keywords\":[\"aussichtslos\",\"Friedensverhandlungen\",\"gibt\",\"Oleg\",\"Selenskij\",\"sind\",\"solange\",\"Zarjow\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/\",\"name\":\"Oleg Zarjow: Solange es Selenskij gibt, sind Friedensverhandlungen aussichtslos - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Oleg-Zarjow-Solange-es-Selenskij-gibt-sind-Friedensverhandlungen-aussichtslos.jpg\",\"datePublished\":\"2024-11-28T18:37:12+00:00\",\"dateModified\":\"2024-11-28T18:37:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Oleg-Zarjow-Solange-es-Selenskij-gibt-sind-Friedensverhandlungen-aussichtslos.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Oleg-Zarjow-Solange-es-Selenskij-gibt-sind-Friedensverhandlungen-aussichtslos.jpg\",\"width\":460,\"height\":259,\"caption\":\"Oleg Zarjow: Solange es Selenskij gibt, sind Friedensverhandlungen aussichtslos\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Oleg Zarjow: Solange es Selenskij gibt, sind Friedensverhandlungen aussichtslos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Oleg Zarjow: Solange es Selenskij gibt, sind Friedensverhandlungen aussichtslos - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/","og_locale":"de_DE","og_type":"article","og_title":"Oleg Zarjow: Solange es Selenskij gibt, sind Friedensverhandlungen aussichtslos","og_description":"Oleg Zarjow, langj\u00e4hriger ukrainischer Politiker und seit 2014 im russischen Exil, glaubt nicht, dass Donald Trump die Ukraine zu Friedensverhandlungen zwingen kann. Der ukrainische Machthaber Wladimir Selenskij h\u00e4lt den US-Demokraten die Treue und wird alle L\u00f6sungsans\u00e4tze Trumps sabotieren. Von Oleg Zarjow Ich verstehe, dass wir gro\u00dfe Hoffnungen hegen, dass Donald Trump nach seinem Amtsantritt einen [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-11-28T18:37:12+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/674747cf48fbef631d1d3da2.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Oleg Zarjow: Solange es Selenskij gibt, sind Friedensverhandlungen aussichtslos","datePublished":"2024-11-28T18:37:12+00:00","dateModified":"2024-11-28T18:37:12+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/"},"wordCount":665,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Oleg-Zarjow-Solange-es-Selenskij-gibt-sind-Friedensverhandlungen-aussichtslos.jpg","keywords":["aussichtslos","Friedensverhandlungen","gibt","Oleg","Selenskij","sind","solange","Zarjow"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/","url":"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/","name":"Oleg Zarjow: Solange es Selenskij gibt, sind Friedensverhandlungen aussichtslos - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Oleg-Zarjow-Solange-es-Selenskij-gibt-sind-Friedensverhandlungen-aussichtslos.jpg","datePublished":"2024-11-28T18:37:12+00:00","dateModified":"2024-11-28T18:37:12+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Oleg-Zarjow-Solange-es-Selenskij-gibt-sind-Friedensverhandlungen-aussichtslos.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Oleg-Zarjow-Solange-es-Selenskij-gibt-sind-Friedensverhandlungen-aussichtslos.jpg","width":460,"height":259,"caption":"Oleg Zarjow: Solange es Selenskij gibt, sind Friedensverhandlungen aussichtslos"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/oleg-zarjow-solange-es-selenskij-gibt-sind-friedensverhandlungen-aussichtslos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Oleg Zarjow: Solange es Selenskij gibt, sind Friedensverhandlungen aussichtslos"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/73473"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=73473"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/73473\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/73474"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=73473"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=73473"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=73473"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}