{"id":73428,"date":"2024-11-28T10:57:28","date_gmt":"2024-11-28T08:57:28","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/"},"modified":"2024-11-28T10:57:28","modified_gmt":"2024-11-28T08:57:28","slug":"urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/","title":{"rendered":"Urteil: &quot;AfD-Nazis&quot; und Sympathisanten &quot;ins Gesicht kotzen&quot; von Meinungsfreiheit gedeckt"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/67481939b480cc27733fda32.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Das Motto des Jahres lautet weiterhin: &#8220;Gegen Hass und Hetze&#8221;. Ein laut Medienwahrnehmung &#8220;umstrittener&#8221; Anti-AfD-Aufruf stellt seitens der Staatsanwaltschaft K\u00f6ln dabei &#8220;keinen ernst gemeinten Aufruf zu einer Straftat&#8221;. Verbale &#8220;Ohrfeigen&#8221; zu verteilen, sei von Meinungsfreiheit gedeckt.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Peter Fischer, der Ehrenpr\u00e4sident des deutschen Fu\u00dfball-Vereins und Erstligisten Eintracht Frankfurt, beeindruckte im Februar dieses Jahres mit einer beeindruckenden Hasstirade auf die Partei AfD und m\u00f6glichen Sympathisanten (<em>RT<\/em>\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/inland\/195534-zwietracht-frankfurt-ehrenpraesident-spaltet-mit\/\">berichtete<\/a>). Fischer, medial f\u00fcr seine l\u00f6bliche &#8220;Haltung gegen Rechts&#8221; bekannt, echauffierte sich im Rahmen einer gesellschaftlichen Stimmung, dies nach dem mit Unwahrheiten gespickten &#8220;Correctiv&#8221;-Artikel aus dem Januar 2024.<\/p>\n<p>Laut Medienbericht klagten 65 B\u00fcrger dagegen, pauschal als Nazis bezeichnet zu werden, denen man &#8220;T\u00fcre und Tore einrennen&#8221; darf. Ein K\u00f6lner Gericht erkennt demgegen\u00fcber laut aktueller Urteilsfindung nur &#8220;bildhafte&#8221; Sprache, gedeckelt von der &#8220;Meinungsfreiheit&#8221;.<\/p>\n<p>Der &#8220;bodenst\u00e4ndige&#8221; Fischer hatte am 6. Februar in einem\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.youtube.com\/watch?v=TiXON6WXVoU\">Interview<\/a>\u00a0mit dem Sender\u00a0<em>RTL<\/em>\u00a0seine unmissverst\u00e4ndliche Definition gesellschaftlichen Miteinanders formuliert. W\u00f6rtlich gab er zu Protokoll, zum Thema seitens der Politik und Medien eingeforderten Demonstrationen &#8220;gegen rechts&#8221;, ausgehend der fehlerhaften Berichterstattung der &#8220;Correctiv&#8221;-Redaktion zu einer Privatveranstaltung im Jahr 2023:<\/p>\n<p><em>&#8220;Auf der Stra\u00dfe, da m\u00fcsste jetzt viel mehr sein. Rennt denen die T\u00fcren und Tore ein, gebt ihnen Ohrfeigen, kotzt ihnen ins Gesicht. Es ist mir schei\u00dfegal, werdet laut und zeigt euch endlich.&#8221;<\/em><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-twitter\">\n<div class=\"TwitterEmbed\">\n<blockquote class=\"twitter-tweet lazyload\" data-twitter=\"twitter-tweet\" data-media-max-width=\"560\">\n<p lang=\"de\" dir=\"ltr\">\ud83d\uded1F\u00fcr das allgemeine Rechtsverst\u00e4ndnis im Deutschen Rechtsstaat\u203c\ufe0fDer Aufruf gegen <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/hashtag\/AfD?src=hash&amp;ref_src=twsrc%5Etfw\">#AfD<\/a>-W\u00e4hler:&#8221;Rennt ihnen T\u00fcre und Tore ein, gebt ihnen Ohrfeigen, kotzt ihnen ins Gesicht&#8221;, &#8220;Jeder 4. oder 5. ist ein Nazi&#8221;Ist kein Aufruf zur Gewalt, Volksverhetzung oder Beleidigung.\ud83e\uddf5(1\/12) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.co\/xz86Ctz2YA\">pic.twitter.com\/xz86Ctz2YA<\/a><\/p>\n<p>\u2014 Tom B. (@BTom1974) <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/twitter.com\/BTom1974\/status\/1861872751025475608?ref_src=twsrc%5Etfw\">November 27, 2024<\/a><\/p><\/blockquote>\n<\/div>\n<\/div>\n<p>AfD-Erfolge nannte Fischer zudem &#8220;grausame Wahlergebnisse, wenn ich an die Ost-Wahlen denke&#8221;. Damit sei f\u00fcr den Demokraten eindeutig, &#8220;jeder Vierte oder jeder F\u00fcnfte auf der Stra\u00dfe ist dort Nazi&#8221;. Durch die individuelle Wahlentscheidung, dem Wahlkreuz, sei man &#8220;automatisch Nationalsozialist&#8221;, so Fischer weiter ausf\u00fchrend.<\/p>\n<p>Laut\u00a0<a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/www.hessenschau.de\/politik\/peter-fischers-afd-schelte-von-meinungsfreiheit-gedeckt-v1,fischer-afd-100.html\">Artikel<\/a>\u00a0der\u00a0<em>Hessenschau\u00a0<\/em>kam es in K\u00f6ln j\u00fcngst zu einer juristischen Verhandlung, in der die verbale &#8220;AfD-Schelte&#8221; Fischers auf der Tagesliste stand. Dazu hei\u00dft es:<\/p>\n<p><em>&#8220;Ein umstrittener Anti-AfD-Aufruf des fr\u00fcheren Pr\u00e4sidenten von Eintracht Frankfurt wird trotz zahlreicher Strafanzeigen nicht juristisch verfolgt. Die Staatsanwaltschaft K\u00f6ln kam zum Schluss, dass Fischers Appell von der Meinungsfreiheit gedeckt sei.&#8221;<\/em><\/p>\n<p>Die Staatsanwaltschaft argumentierte demnach vor Urteilsspruch, dass die \u00c4u\u00dferungen &#8220;keinen ernst gemeinten Aufruf zu einer Straftat&#8221; darstellen w\u00fcrden. Fischer habe &#8220;offenkundig \u00fcbertrieben&#8221; und sich &#8220;bildhaft ausgedr\u00fcckt&#8221;, teilte die Staatsanwaltschaft auf Anfrage des\u00a0<em>Hessischen Rundfunks<\/em>\u00a0mit. Weiter hei\u00dft es w\u00f6rtlich:<\/p>\n<p><em>&#8220;Im Sinne einer emotionalen Fundamentalkritik an der AfD sei das erlaubt.&#8221;<\/em><\/p>\n<p>Die subjektive Bezeichnung als &#8220;Nationalsozialist&#8221; sei zudem nicht generell als Beleidigung zu verstehen, &#8220;sondern als Pauschalbezeichnung f\u00fcr eine rechtsextrem orientierte Gesinnung&#8221;. Im Falle der AfD basiere die Wahrnehmung daher &#8220;auf Tatsachen&#8221;, so die Staatsanwaltschaft ausf\u00fchrend.<\/p>\n<p>Die Beh\u00f6rde leite deshalb nach eigener Auskunft keine weiteren Ermittlungen gegen Fischer ein. Ein Anfangsverdacht wegen &#8220;einer Straftat wie Volksverhetzung oder Beleidigung&#8221; liege laut der Staatsanwaltschaft K\u00f6ln nicht vor.<\/p>\n<p>Der Vorsitzende der AfD-Fraktion im hessischen Landtag, Robert Lambrou, bezeichnete das Urteil laut Artikel als &#8220;erschreckend&#8221;. Der Politiker kommentierte das Urteil mit der Frage:<\/p>\n<p><em>&#8220;Gewaltaufrufe gegen W\u00e4hler der Opposition sollen durch die Meinungsfreiheit gedeckt sein, aber wenn jemand einen Tweet weiterleitet, in dem Robert Habeck &#8216;Schwachkopf&#8217; genannt wird, kommt die Polizei zur Hausdurchsuchung wegen Volksverhetzung?&#8221;<\/em><\/p>\n<p>Laut Lambrou werde mit solchen Urteilssprechungen &#8220;das Vertrauen in den Rechtsstaat weiter zerst\u00f6rt&#8221;.<\/p>\n<p><strong>Mehr zum Thema\u00a0<\/strong>\u2013 <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/meinung\/226806-habeck-ist-schwachkopf-die-passende-bezeichnung\/\">Habeck: Ist &#8220;Schwachkopf&#8221; die passende Bezeichnung? <\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v5qc0h5\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><script async src=\"https:\/\/platform.twitter.com\/widgets.js\" charset=\"utf-8\"><\/script><br \/>\n<br \/><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/inland\/227584-urteil-afd-nazis-und-sympathisanten\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Motto des Jahres lautet weiterhin: &#8220;Gegen Hass und Hetze&#8221;. Ein laut Medienwahrnehmung &#8220;umstrittener&#8221; Anti-AfD-Aufruf stellt seitens der Staatsanwaltschaft K\u00f6ln dabei &#8220;keinen ernst gemeinten Aufruf zu einer Straftat&#8221;. Verbale &#8220;Ohrfeigen&#8221; zu verteilen, sei von Meinungsfreiheit gedeckt. Peter Fischer, der Ehrenpr\u00e4sident des deutschen Fu\u00dfball-Vereins und Erstligisten Eintracht Frankfurt, beeindruckte im Februar dieses Jahres mit einer beeindruckenden [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":73429,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1732785001"],"wp_automatic_camp":["217"],"90499307b0363190fce4ff26e9061354":["Urteil: &quot;AfD-Nazis&quot; und Sympathisanten &quot;ins Gesicht kotzen&quot; von Meinungsfreiheit gedeckt"],"original_link":["https:\/\/de.rt.com\/inland\/227584-urteil-afd-nazis-und-sympathisanten\/"],"_thumbnail_id":["73429"],"jnews_social_counter_last_update":["1778677435"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-11-28 11:11:08\";}"]},"categories":[19,23],"tags":[39503,18437,46379,7120,60612,53326,60613,140,11769,50],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Urteil: &quot;AfD-Nazis&quot; und Sympathisanten &quot;ins Gesicht kotzen&quot; von Meinungsfreiheit gedeckt - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Urteil: &quot;AfD-Nazis&quot; und Sympathisanten &quot;ins Gesicht kotzen&quot; von Meinungsfreiheit gedeckt\" \/>\n<meta property=\"og:description\" content=\"Das Motto des Jahres lautet weiterhin: &#8220;Gegen Hass und Hetze&#8221;. Ein laut Medienwahrnehmung &#8220;umstrittener&#8221; Anti-AfD-Aufruf stellt seitens der Staatsanwaltschaft K\u00f6ln dabei &#8220;keinen ernst gemeinten Aufruf zu einer Straftat&#8221;. Verbale &#8220;Ohrfeigen&#8221; zu verteilen, sei von Meinungsfreiheit gedeckt. Peter Fischer, der Ehrenpr\u00e4sident des deutschen Fu\u00dfball-Vereins und Erstligisten Eintracht Frankfurt, beeindruckte im Februar dieses Jahres mit einer beeindruckenden [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-28T08:57:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/67481939b480cc27733fda32.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Urteil: &quot;AfD-Nazis&quot; und Sympathisanten &quot;ins Gesicht kotzen&quot; von Meinungsfreiheit gedeckt\",\"datePublished\":\"2024-11-28T08:57:28+00:00\",\"dateModified\":\"2024-11-28T08:57:28+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/\"},\"wordCount\":601,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Urteil-quotAfD-Nazisquot-und-Sympathisanten-quotins-Gesicht-kotzenquot-von-Meinungsfreiheit-gedeckt.jpg\",\"keywords\":[\"gedeckt\",\"Gesicht\",\"Kotzenquot\",\"Meinungsfreiheit\",\"quotAfDNazisquot\",\"quotins\",\"Sympathisanten\",\"und\",\"Urteil\",\"von\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/\",\"name\":\"Urteil: &quot;AfD-Nazis&quot; und Sympathisanten &quot;ins Gesicht kotzen&quot; von Meinungsfreiheit gedeckt - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Urteil-quotAfD-Nazisquot-und-Sympathisanten-quotins-Gesicht-kotzenquot-von-Meinungsfreiheit-gedeckt.jpg\",\"datePublished\":\"2024-11-28T08:57:28+00:00\",\"dateModified\":\"2024-11-28T08:57:28+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Urteil-quotAfD-Nazisquot-und-Sympathisanten-quotins-Gesicht-kotzenquot-von-Meinungsfreiheit-gedeckt.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Urteil-quotAfD-Nazisquot-und-Sympathisanten-quotins-Gesicht-kotzenquot-von-Meinungsfreiheit-gedeckt.jpg\",\"width\":460,\"height\":259,\"caption\":\"Urteil: &quot;AfD-Nazis&quot; und Sympathisanten &quot;ins Gesicht kotzen&quot; von Meinungsfreiheit gedeckt\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Urteil: &quot;AfD-Nazis&quot; und Sympathisanten &quot;ins Gesicht kotzen&quot; von Meinungsfreiheit gedeckt\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Urteil: &quot;AfD-Nazis&quot; und Sympathisanten &quot;ins Gesicht kotzen&quot; von Meinungsfreiheit gedeckt - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/","og_locale":"de_DE","og_type":"article","og_title":"Urteil: &quot;AfD-Nazis&quot; und Sympathisanten &quot;ins Gesicht kotzen&quot; von Meinungsfreiheit gedeckt","og_description":"Das Motto des Jahres lautet weiterhin: &#8220;Gegen Hass und Hetze&#8221;. Ein laut Medienwahrnehmung &#8220;umstrittener&#8221; Anti-AfD-Aufruf stellt seitens der Staatsanwaltschaft K\u00f6ln dabei &#8220;keinen ernst gemeinten Aufruf zu einer Straftat&#8221;. Verbale &#8220;Ohrfeigen&#8221; zu verteilen, sei von Meinungsfreiheit gedeckt. Peter Fischer, der Ehrenpr\u00e4sident des deutschen Fu\u00dfball-Vereins und Erstligisten Eintracht Frankfurt, beeindruckte im Februar dieses Jahres mit einer beeindruckenden [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-11-28T08:57:28+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/67481939b480cc27733fda32.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Urteil: &quot;AfD-Nazis&quot; und Sympathisanten &quot;ins Gesicht kotzen&quot; von Meinungsfreiheit gedeckt","datePublished":"2024-11-28T08:57:28+00:00","dateModified":"2024-11-28T08:57:28+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/"},"wordCount":601,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Urteil-quotAfD-Nazisquot-und-Sympathisanten-quotins-Gesicht-kotzenquot-von-Meinungsfreiheit-gedeckt.jpg","keywords":["gedeckt","Gesicht","Kotzenquot","Meinungsfreiheit","quotAfDNazisquot","quotins","Sympathisanten","und","Urteil","von"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/","url":"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/","name":"Urteil: &quot;AfD-Nazis&quot; und Sympathisanten &quot;ins Gesicht kotzen&quot; von Meinungsfreiheit gedeckt - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Urteil-quotAfD-Nazisquot-und-Sympathisanten-quotins-Gesicht-kotzenquot-von-Meinungsfreiheit-gedeckt.jpg","datePublished":"2024-11-28T08:57:28+00:00","dateModified":"2024-11-28T08:57:28+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Urteil-quotAfD-Nazisquot-und-Sympathisanten-quotins-Gesicht-kotzenquot-von-Meinungsfreiheit-gedeckt.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Urteil-quotAfD-Nazisquot-und-Sympathisanten-quotins-Gesicht-kotzenquot-von-Meinungsfreiheit-gedeckt.jpg","width":460,"height":259,"caption":"Urteil: &quot;AfD-Nazis&quot; und Sympathisanten &quot;ins Gesicht kotzen&quot; von Meinungsfreiheit gedeckt"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/urteil-afd-nazis-und-sympathisanten-ins-gesicht-kotzen-von-meinungsfreiheit-gedeckt\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Urteil: &quot;AfD-Nazis&quot; und Sympathisanten &quot;ins Gesicht kotzen&quot; von Meinungsfreiheit gedeckt"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/73428"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=73428"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/73428\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/73429"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=73428"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=73428"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=73428"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}