{"id":72410,"date":"2024-11-11T19:28:09","date_gmt":"2024-11-11T17:28:09","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/"},"modified":"2024-11-11T19:28:09","modified_gmt":"2024-11-11T17:28:09","slug":"sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/","title":{"rendered":"Sacharowa: Westen will Moldawien an der Seite der Ukraine in den Konflikt hineinziehen"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/6732385548fbef11bf721dff.jpg\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Die \u00c4u\u00dferungen Chi\u0219in\u0103us \u00fcber den Abschuss russischer Drohnen auf moldauischem Territorium sind eine Provokation, so die Sprecherin des russischen Au\u00dfenministeriums. Mit solchen \u00c4u\u00dferungen werde versucht, Moldawien auf der Seite der Ukraine in den Krieg hineinzuziehen.\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die Erkl\u00e4rungen des moldawischen Au\u00dfenministeriums, dass angeblich russische Drohnen auf dem Territorium des Landes abgeschossen worden seien, sind eine Provokation, die darauf abzielt, das Land in den Konflikt an der Seite der Ukraine und des Westens hineinzuziehen. Dies erkl\u00e4rte das russische Au\u00dfenministerium. Die Sprecherin der Beh\u00f6rde, Maria Sacharowa, <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/t.me\/MariaVladimirovnaZakharova\/9218\">schrieb<\/a> auf ihrem Telegram-Kanal:<strong><\/strong><\/p>\n<blockquote>\n<p><em>&#8220;Wir betonen, dass die Streitkr\u00e4fte der Russischen F\u00f6deration w\u00e4hrend der milit\u00e4rischen Sonderoperation keine Drohnen \u00fcber dem Territorium der an die Ukraine angrenzenden Staaten, zu denen auch die Republik Moldau geh\u00f6rt, einsetzen oder steuern.<\/em>\u00a0<em>Die legitimen Ziele der russischen Aktionen sind ausschlie\u00dflich milit\u00e4rische Einrichtungen der ukrainischen Streitkr\u00e4fte und die dazugeh\u00f6rige Infrastruktur.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Die abgeschossenen Drohnen waren am vergangenen Sonntag, dem 10. November, in Moldawien gefunden worden. Der moldauische Au\u00dfenminister Mihail Pop\u0219oi bezeichnete die Drohnen in\u00a0dem sozialen Netz X als russisch und erkl\u00e4rte, dass die Beh\u00f6rden des Landes den Vorfall sowie die Milit\u00e4raktionen in der Ukraine verurteilen w\u00fcrden.<\/p>\n<p>Russlands Verteidigungsministerium erkl\u00e4rte in einem Frontbericht vom 10. November, dass seine Truppen Luft-, Raketen-, Artillerie- und Drohnenangriffe auf ukrainische Milit\u00e4rflugpl\u00e4tze, Energieanlagen sowie Lager- und Ausbildungsst\u00e4tten f\u00fcr Drohnen der ukrainischen Streitkr\u00e4fte durchgef\u00fchrt h\u00e4tten.<\/p>\n<p>Auch die rum\u00e4nischen Beh\u00f6rden hatten im September und Oktober berichtet, dass sie auf ihrem Territorium \u2013 nahe der ukrainischen Grenze \u2013 Drohnentr\u00fcmmer &#8220;russischen Ursprungs&#8221; entdeckt h\u00e4tten. Im Sommer wurden Drohnenwrackteile in dem Dorf Plauru gefunden, das am Ufer der Donau gegen\u00fcber der ukrainischen Stadt Ismail liegt. Das russische Verteidigungsministerium \u00e4u\u00dferte sich damals nicht zu den Berichten der rum\u00e4nischen Seite \u00fcber die Drohnen.<\/p>\n<p>Die rum\u00e4nische Abgeordnete des EU-parlaments Diana Iovanovici \u0218o\u0219oac\u0103 wirft Kiew vor, ihr Land in den Konflikt hineinziehen zu wollen. Auf ihrem Facebook-Account sagte sie: <em>&#8220;Selenskij feuert mit Drohnen, um Rum\u00e4nien in den Krieg hineinzuziehen. Das werde ich ihm nie verzeihen!&#8221; <\/em><\/p>\n<p>Im Oktober hatte sie das h\u00f6chste rum\u00e4nische Gericht wegen ihrer angeblich &#8220;pro-russischen&#8221; Ansichten als Kandidatin von den Pr\u00e4sidentschaftswahlen in Rum\u00e4nien ausgeschlossen.<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/freedert.online\/kurzclips\/video\/223700-ukrainische-drohnen-mit-geschenk-zurueckgeschickt\/\">Ukrainische Drohnen mit &#8220;Geschenk&#8221; zur\u00fcckgeschickt: Feldprogrammierer bei der Arbeit<\/a><\/p>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/225620-sacharowa-westen-will-moldawien-an\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die \u00c4u\u00dferungen Chi\u0219in\u0103us \u00fcber den Abschuss russischer Drohnen auf moldauischem Territorium sind eine Provokation, so die Sprecherin des russischen Au\u00dfenministeriums. Mit solchen \u00c4u\u00dferungen werde versucht, Moldawien auf der Seite der Ukraine in den Krieg hineinzuziehen. Die Erkl\u00e4rungen des moldawischen Au\u00dfenministeriums, dass angeblich russische Drohnen auf dem Territorium des Landes abgeschossen worden seien, sind eine Provokation, [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":72411,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1731346109"],"wp_automatic_camp":["217"],"2d08c0f00d36520d6656f03aa70b1b4f":["Sacharowa: Westen will Moldawien an der Seite der Ukraine in den Konflikt hineinziehen"],"original_link":["https:\/\/de.rt.com\/international\/225620-sacharowa-westen-will-moldawien-an\/"],"_thumbnail_id":["72411"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-11-11 19:29:33\";}"],"jnews_social_counter_last_update":["1778527502"]},"categories":[19,23],"tags":[48,82,35592,1810,25732,942,1934,127,378],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v22.7) - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Sacharowa: Westen will Moldawien an der Seite der Ukraine in den Konflikt hineinziehen - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Sacharowa: Westen will Moldawien an der Seite der Ukraine in den Konflikt hineinziehen\" \/>\n<meta property=\"og:description\" content=\"Die \u00c4u\u00dferungen Chi\u0219in\u0103us \u00fcber den Abschuss russischer Drohnen auf moldauischem Territorium sind eine Provokation, so die Sprecherin des russischen Au\u00dfenministeriums. Mit solchen \u00c4u\u00dferungen werde versucht, Moldawien auf der Seite der Ukraine in den Krieg hineinzuziehen. Die Erkl\u00e4rungen des moldawischen Au\u00dfenministeriums, dass angeblich russische Drohnen auf dem Territorium des Landes abgeschossen worden seien, sind eine Provokation, [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-11-11T17:28:09+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/6732385548fbef11bf721dff.jpg\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Sacharowa: Westen will Moldawien an der Seite der Ukraine in den Konflikt hineinziehen\",\"datePublished\":\"2024-11-11T17:28:09+00:00\",\"dateModified\":\"2024-11-11T17:28:09+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/\"},\"wordCount\":411,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Sacharowa-Westen-will-Moldawien-an-der-Seite-der-Ukraine-in.jpg\",\"keywords\":[\"den\",\"der\",\"hineinziehen\",\"Konflikt\",\"Moldawien\",\"Sacharowa\",\"Seite\",\"ukraine\",\"Westen\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/\",\"url\":\"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/\",\"name\":\"Sacharowa: Westen will Moldawien an der Seite der Ukraine in den Konflikt hineinziehen - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\/\/now-news.de\/de\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Sacharowa-Westen-will-Moldawien-an-der-Seite-der-Ukraine-in.jpg\",\"datePublished\":\"2024-11-11T17:28:09+00:00\",\"dateModified\":\"2024-11-11T17:28:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/#primaryimage\",\"url\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Sacharowa-Westen-will-Moldawien-an-der-Seite-der-Ukraine-in.jpg\",\"contentUrl\":\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Sacharowa-Westen-will-Moldawien-an-der-Seite-der-Ukraine-in.jpg\",\"width\":460,\"height\":259,\"caption\":\"Sacharowa: Westen will Moldawien an der Seite der Ukraine in den Konflikt hineinziehen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/now-news.de\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sacharowa: Westen will Moldawien an der Seite der Ukraine in den Konflikt hineinziehen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/now-news.de\/de\/#website\",\"url\":\"https:\/\/now-news.de\/de\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\/\/now-news.de\/de\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/now-news.de\/de\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/now-news.de\/de\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\/\/now-news.de\/de\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\",\"url\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"contentUrl\":\"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/wirmachenauf\",\"https:\/\/x.com\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\/\/now-news.de\/de\/author\/rnews\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Sacharowa: Westen will Moldawien an der Seite der Ukraine in den Konflikt hineinziehen - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/","og_locale":"de_DE","og_type":"article","og_title":"Sacharowa: Westen will Moldawien an der Seite der Ukraine in den Konflikt hineinziehen","og_description":"Die \u00c4u\u00dferungen Chi\u0219in\u0103us \u00fcber den Abschuss russischer Drohnen auf moldauischem Territorium sind eine Provokation, so die Sprecherin des russischen Au\u00dfenministeriums. Mit solchen \u00c4u\u00dferungen werde versucht, Moldawien auf der Seite der Ukraine in den Krieg hineinzuziehen. Die Erkl\u00e4rungen des moldawischen Au\u00dfenministeriums, dass angeblich russische Drohnen auf dem Territorium des Landes abgeschossen worden seien, sind eine Provokation, [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-11-11T17:28:09+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/6732385548fbef11bf721dff.jpg"}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"2\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Sacharowa: Westen will Moldawien an der Seite der Ukraine in den Konflikt hineinziehen","datePublished":"2024-11-11T17:28:09+00:00","dateModified":"2024-11-11T17:28:09+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/"},"wordCount":411,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Sacharowa-Westen-will-Moldawien-an-der-Seite-der-Ukraine-in.jpg","keywords":["den","der","hineinziehen","Konflikt","Moldawien","Sacharowa","Seite","ukraine","Westen"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/","url":"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/","name":"Sacharowa: Westen will Moldawien an der Seite der Ukraine in den Konflikt hineinziehen - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Sacharowa-Westen-will-Moldawien-an-der-Seite-der-Ukraine-in.jpg","datePublished":"2024-11-11T17:28:09+00:00","dateModified":"2024-11-11T17:28:09+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Sacharowa-Westen-will-Moldawien-an-der-Seite-der-Ukraine-in.jpg","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/11\/Sacharowa-Westen-will-Moldawien-an-der-Seite-der-Ukraine-in.jpg","width":460,"height":259,"caption":"Sacharowa: Westen will Moldawien an der Seite der Ukraine in den Konflikt hineinziehen"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/sacharowa-westen-will-moldawien-an-der-seite-der-ukraine-in-den-konflikt-hineinziehen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Sacharowa: Westen will Moldawien an der Seite der Ukraine in den Konflikt hineinziehen"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/82aafea7d8127119dd649515f56e2117?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/72410"}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=72410"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/72410\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/72411"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=72410"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=72410"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=72410"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}