{"id":71608,"date":"2024-10-29T15:04:50","date_gmt":"2024-10-29T13:04:50","guid":{"rendered":"https:\/\/now-news.de\/de\/deutschland\/washington-neue-drohung-gegen-georgien\/"},"modified":"2024-10-29T15:04:50","modified_gmt":"2024-10-29T13:04:50","slug":"washington-neue-drohung-gegen-georgien","status":"publish","type":"post","link":"https:\/\/now-news.de\/de\/deutschland\/washington-neue-drohung-gegen-georgien\/","title":{"rendered":"Washington: Neue Drohung gegen Georgien"},"content":{"rendered":"<p><img decoding=\"async\" src=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/10\/6720b92d48fbef346d6a9d61.png\" \/><\/p>\n<div class=\"Text-root Text-type_1 \">\n                Das US-Au\u00dfenministerium warnt Georgien davor, sich von der euro-atlantischen Integration zu entfernen. Zudem erkl\u00e4rten 13 EU-Mitgliedstaaten ihre &#8220;tiefe Besorgnis \u00fcber die derzeitige Lage in Georgien&#8221; und forderten &#8220;eine unparteiische Untersuchung der Beschwerden.&#8221;\n            <\/div>\n<p><\/p>\n<div class=\"Text-root Text-type_5 ArticleView-text ViewText-root \">\n<p>Die USA haben Georgien mit &#8220;Konsequenzen&#8221; gedroht, nachdem die politische Pro-NATO-Opposition des Landes die regierende Partei Georgischer Traum beschuldigt hatte, die Parlamentswahlen vom Samstag manipuliert zu haben.<\/p>\n<p>Laut der offiziellen Ausz\u00e4hlung erhielt die Partei Georgischer Traum fast 54 Prozent der Stimmen, w\u00e4hrend verschiedene Oppositionsparteien 3 Prozent bis 11 Prozent erhielten. Mit diesem Sieg d\u00fcrfte die Partei mindestens 90 der 150 Sitze im nationalen Parlament erhalten und damit die n\u00e4chste Regierung des kaukasischen Landes bilden.<\/p>\n<p>Vier prowestliche Oppositionsparteien verweigerten die Anerkennung der Ergebnisse und erkl\u00e4rten, sie w\u00fcrden sich nicht an der Arbeit der neuen Legislative beteiligen. Auch die georgische Pr\u00e4sidentin Salome Surabischwili, eine ehemalige franz\u00f6sische Botschafterin in Georgien, die seit 2004 die georgische Staatsb\u00fcrgerschaft besitzt, lehnte die Anerkennung der Ergebnisse ab und rief zu Protesten auf. Am Montagabend fand eine gro\u00dfe Demonstration vor dem Parlamentsgeb\u00e4ude in Tiflis statt.<\/p>\n<p>W\u00e4hrend Surabischwili die Wahl als &#8220;totalen Betrug&#8221; bezeichnete<em>,<\/em>\u00a0berichtete die Organisation f\u00fcr Sicherheit und Zusammenarbeit in Europa (OSZE), dass sie keine systematischen Unregelm\u00e4\u00dfigkeiten bei der Wahl festgestellt habe. Zwar wolle sie F\u00e4lle von Stimmenkauf und Druck auf Angestellte des \u00f6ffentlichen Dienstes beobachtet haben, doch lobte sie auch die Vielfalt der Wahlm\u00f6glichkeiten auf den Stimmzetteln.<\/p>\n<p>Auf einer Pressekonferenz am Montag erkl\u00e4rte der Sprecher des US-Au\u00dfenministeriums, Matthew Miller, dass die Wahlen in einem &#8220;Umfeld stattfanden, das von der Politik der Regierungspartei gepr\u00e4gt war, einschlie\u00dflich des Missbrauchs \u00f6ffentlicher Mittel, des Stimmenkaufs und der Einsch\u00fcchterung von W\u00e4hlern&#8221;<em>.\u00a0<\/em>Miller forderte Tiflis auf, mit der &#8220;R\u00fccknahme und Aufhebung antidemokratischer Gesetze&#8221; zu beginnen und warnte vor Konsequenzen:<em><br \/><\/em><\/p>\n<blockquote>\n<p><em>&#8220;Wir raten den georgischen Regierungsvertretern, \u00fcber die Beziehungen nachzudenken, die sie mit der euro-atlantischen Gemeinschaft anstreben, anstatt eine Politik zu st\u00e4rken, die von autorit\u00e4ren Kr\u00e4ften gelobt wird.<\/em>&#8220;<\/p>\n<p>&#8220;<em>Wir schlie\u00dfen weitere Konsequenzen nicht aus, wenn sich der Kurs der georgischen Regierung nicht \u00e4ndert.&#8221;<\/em><\/p>\n<\/blockquote>\n<p>Zuvor hatten 13 EU-Mitgliedstaaten am Montag eine Erkl\u00e4rung abgegeben, in der sie ihre &#8220;tiefe Besorgnis \u00fcber die derzeitige Lage in Georgien zum Ausdruck brachten und eine unparteiische Untersuchung der Beschwerden und die Behebung der festgestellten Verst\u00f6\u00dfe&#8221; forderten. Westliche Regierungen haben Georgien demokratische R\u00fcckschritte vorgeworfen und das Land gewarnt, seine j\u00fcngste Politik k\u00f6nne die EU-Beitrittsbestrebungen des Landes behindern. Im Jahr 2024 verabschiedete das georgische Parlament Gesetze, wonach Nichtregierungsorganisationen als &#8220;ausl\u00e4ndische Agenten&#8221; bezeichnet werden k\u00f6nnen und LGBTQ-&#8220;Propaganda&#8221; f\u00fcr Minderj\u00e4hrige verboten ist, was zu Protesten f\u00fchrte.<\/p>\n<p>Die georgische Regierung hat nachdr\u00fccklich bekr\u00e4ftigt, dass sie der EU auf jeden Fall beitreten m\u00f6chte, allerdings zu ihren eigenen Bedingungen. Premierminister Irakli Kobachidse erkl\u00e4rte, die Gesetze dienten der Wahrung der Souver\u00e4nit\u00e4t Georgiens und der Interessen des Volkes. &#8220;Die Opposition kann ihre Wahlniederlage nicht verwinden&#8221;, sagte Kobachidse am Samstag und warf seinen Gegnern vor, das Gesetz zu untergraben. Er f\u00fcgte hinzu: &#8220;Niemand kann das Verfassungssystem unseres Landes untergraben.&#8221;<\/p>\n<p><strong>Mehr zum Thema<\/strong> &#8211; <a rel=\"nofollow noopener\" target=\"_blank\" href=\"https:\/\/dert.online\/meinung\/223886-parlamentswahl-in-georgien-verachtung-westens\/\">Parlamentswahl in Georgien: Die Verachtung des Westens gegen\u00fcber der Demokratie<\/a><\/p>\n<div class=\"EmbedBlock-root EmbedBlock-externalVideo EmbedBlock-rumble\">\n<div class=\"VkEmbed\"><iframe class=\"lazyload\" data-src=\"https:\/\/rumble.com\/embed\/v5i6ywd\" frameborder=\"0\" width=\"853\" height=\"480\" allowfullscreen><\/iframe><\/div>\n<\/div>\n<\/div>\n<p><br \/>\n<br \/><a href=\"https:\/\/de.rt.com\/international\/223957-washington-spricht-neue-drohung-gegen\/\">Source link <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das US-Au\u00dfenministerium warnt Georgien davor, sich von der euro-atlantischen Integration zu entfernen. Zudem erkl\u00e4rten 13 EU-Mitgliedstaaten ihre &#8220;tiefe Besorgnis \u00fcber die derzeitige Lage in Georgien&#8221; und forderten &#8220;eine unparteiische Untersuchung der Beschwerden.&#8221; Die USA haben Georgien mit &#8220;Konsequenzen&#8221; gedroht, nachdem die politische Pro-NATO-Opposition des Landes die regierende Partei Georgischer Traum beschuldigt hatte, die Parlamentswahlen vom [&hellip;]<\/p>\n","protected":false},"author":3,"featured_media":71609,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_yoast_indexnow_last_ping":["1730207397"],"wp_automatic_camp":["217"],"d3f91a1823dc58bc607228d6a91e3d55":["Washington: Neue Drohung gegen Georgien"],"original_link":["https:\/\/de.rt.com\/international\/223957-washington-spricht-neue-drohung-gegen\/"],"_thumbnail_id":["71609"],"_wptgpro_p2tg_sent2tg":["a:1:{i:23737;s:19:\"2024-10-29 15:11:11\";}"],"jnews_social_counter_last_update":["1788342004"]},"categories":[19,23],"tags":[18037,278,20848,1227,1039],"class_list":["post-71608","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deutschland","category-russland","tag-drohung","tag-gegen","tag-georgien","tag-neue","tag-washington"],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v22.7 (Yoast SEO v28.2) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>Washington: Neue Drohung gegen Georgien - just-now.NEWS Deutschland<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/now-news.de\/de\/deutschland\/washington-neue-drohung-gegen-georgien\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Washington: Neue Drohung gegen Georgien\" \/>\n<meta property=\"og:description\" content=\"Das US-Au\u00dfenministerium warnt Georgien davor, sich von der euro-atlantischen Integration zu entfernen. Zudem erkl\u00e4rten 13 EU-Mitgliedstaaten ihre &#8220;tiefe Besorgnis \u00fcber die derzeitige Lage in Georgien&#8221; und forderten &#8220;eine unparteiische Untersuchung der Beschwerden.&#8221; Die USA haben Georgien mit &#8220;Konsequenzen&#8221; gedroht, nachdem die politische Pro-NATO-Opposition des Landes die regierende Partei Georgischer Traum beschuldigt hatte, die Parlamentswahlen vom [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/now-news.de\/de\/deutschland\/washington-neue-drohung-gegen-georgien\/\" \/>\n<meta property=\"og:site_name\" content=\"just-now.NEWS Deutschland\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/wirmachenauf\" \/>\n<meta property=\"article:published_time\" content=\"2024-10-29T13:04:50+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/10\/6720b92d48fbef346d6a9d61.png\" \/>\n<meta name=\"author\" content=\"rtnews\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:site\" content=\"@WirMachenAuf_de\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"rtnews\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"3\u00a0Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/washington-neue-drohung-gegen-georgien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/washington-neue-drohung-gegen-georgien\\\/\"},\"author\":{\"name\":\"rtnews\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\"},\"headline\":\"Washington: Neue Drohung gegen Georgien\",\"datePublished\":\"2024-10-29T13:04:50+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/washington-neue-drohung-gegen-georgien\\\/\"},\"wordCount\":532,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/washington-neue-drohung-gegen-georgien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/10\\\/Washington-Neue-Drohung-gegen-Georgien.png\",\"keywords\":[\"drohung\",\"gegen\",\"Georgien\",\"NEUE\",\"Washington\"],\"articleSection\":[\"Deutschland\",\"Russland\"],\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/washington-neue-drohung-gegen-georgien\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/washington-neue-drohung-gegen-georgien\\\/\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/washington-neue-drohung-gegen-georgien\\\/\",\"name\":\"Washington: Neue Drohung gegen Georgien - just-now.NEWS Deutschland\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/washington-neue-drohung-gegen-georgien\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/washington-neue-drohung-gegen-georgien\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/10\\\/Washington-Neue-Drohung-gegen-Georgien.png\",\"datePublished\":\"2024-10-29T13:04:50+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/washington-neue-drohung-gegen-georgien\\\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/washington-neue-drohung-gegen-georgien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/washington-neue-drohung-gegen-georgien\\\/#primaryimage\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/10\\\/Washington-Neue-Drohung-gegen-Georgien.png\",\"contentUrl\":\"https:\\\/\\\/now-news.de\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2024\\\/10\\\/Washington-Neue-Drohung-gegen-Georgien.png\",\"width\":460,\"height\":259,\"caption\":\"Washington: Neue Drohung gegen Georgien\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/deutschland\\\/washington-neue-drohung-gegen-georgien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/now-news.de\\\/de\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Washington: Neue Drohung gegen Georgien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#website\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"name\":\"just-now.NEWS Deutschland\",\"description\":\"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt\",\"publisher\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/now-news.de\\\/de\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#organization\",\"name\":\"Just Now News\",\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"contentUrl\":\"http:\\\/\\\/just-now.news\\\/de\\\/wp-content\\\/uploads\\\/sites\\\/3\\\/2022\\\/04\\\/logo500x500.jpg\",\"width\":500,\"height\":500,\"caption\":\"Just Now News\"},\"image\":{\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/wirmachenauf\",\"https:\\\/\\\/x.com\\\/WirMachenAuf_de\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/now-news.de\\\/de\\\/#\\\/schema\\\/person\\\/fb534a4e865501d8b3285208df34a9b5\",\"name\":\"rtnews\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g\",\"caption\":\"rtnews\"},\"url\":\"https:\\\/\\\/now-news.de\\\/de\\\/author\\\/rnews\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"Washington: Neue Drohung gegen Georgien - just-now.NEWS Deutschland","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/now-news.de\/de\/deutschland\/washington-neue-drohung-gegen-georgien\/","og_locale":"de_DE","og_type":"article","og_title":"Washington: Neue Drohung gegen Georgien","og_description":"Das US-Au\u00dfenministerium warnt Georgien davor, sich von der euro-atlantischen Integration zu entfernen. Zudem erkl\u00e4rten 13 EU-Mitgliedstaaten ihre &#8220;tiefe Besorgnis \u00fcber die derzeitige Lage in Georgien&#8221; und forderten &#8220;eine unparteiische Untersuchung der Beschwerden.&#8221; Die USA haben Georgien mit &#8220;Konsequenzen&#8221; gedroht, nachdem die politische Pro-NATO-Opposition des Landes die regierende Partei Georgischer Traum beschuldigt hatte, die Parlamentswahlen vom [&hellip;]","og_url":"https:\/\/now-news.de\/de\/deutschland\/washington-neue-drohung-gegen-georgien\/","og_site_name":"just-now.NEWS Deutschland","article_publisher":"https:\/\/www.facebook.com\/wirmachenauf","article_published_time":"2024-10-29T13:04:50+00:00","og_image":[{"url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/10\/6720b92d48fbef346d6a9d61.png","type":"","width":"","height":""}],"author":"rtnews","twitter_card":"summary_large_image","twitter_creator":"@WirMachenAuf_de","twitter_site":"@WirMachenAuf_de","twitter_misc":{"Verfasst von":"rtnews","Gesch\u00e4tzte Lesezeit":"3\u00a0Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/now-news.de\/de\/deutschland\/washington-neue-drohung-gegen-georgien\/#article","isPartOf":{"@id":"https:\/\/now-news.de\/de\/deutschland\/washington-neue-drohung-gegen-georgien\/"},"author":{"name":"rtnews","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5"},"headline":"Washington: Neue Drohung gegen Georgien","datePublished":"2024-10-29T13:04:50+00:00","mainEntityOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/washington-neue-drohung-gegen-georgien\/"},"wordCount":532,"commentCount":0,"publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/washington-neue-drohung-gegen-georgien\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/10\/Washington-Neue-Drohung-gegen-Georgien.png","keywords":["drohung","gegen","Georgien","NEUE","Washington"],"articleSection":["Deutschland","Russland"],"inLanguage":"de","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/now-news.de\/de\/deutschland\/washington-neue-drohung-gegen-georgien\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/now-news.de\/de\/deutschland\/washington-neue-drohung-gegen-georgien\/","url":"https:\/\/now-news.de\/de\/deutschland\/washington-neue-drohung-gegen-georgien\/","name":"Washington: Neue Drohung gegen Georgien - just-now.NEWS Deutschland","isPartOf":{"@id":"https:\/\/now-news.de\/de\/#website"},"primaryImageOfPage":{"@id":"https:\/\/now-news.de\/de\/deutschland\/washington-neue-drohung-gegen-georgien\/#primaryimage"},"image":{"@id":"https:\/\/now-news.de\/de\/deutschland\/washington-neue-drohung-gegen-georgien\/#primaryimage"},"thumbnailUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/10\/Washington-Neue-Drohung-gegen-Georgien.png","datePublished":"2024-10-29T13:04:50+00:00","breadcrumb":{"@id":"https:\/\/now-news.de\/de\/deutschland\/washington-neue-drohung-gegen-georgien\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/now-news.de\/de\/deutschland\/washington-neue-drohung-gegen-georgien\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/deutschland\/washington-neue-drohung-gegen-georgien\/#primaryimage","url":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/10\/Washington-Neue-Drohung-gegen-Georgien.png","contentUrl":"https:\/\/now-news.de\/de\/wp-content\/uploads\/sites\/3\/2024\/10\/Washington-Neue-Drohung-gegen-Georgien.png","width":460,"height":259,"caption":"Washington: Neue Drohung gegen Georgien"},{"@type":"BreadcrumbList","@id":"https:\/\/now-news.de\/de\/deutschland\/washington-neue-drohung-gegen-georgien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/now-news.de\/de\/"},{"@type":"ListItem","position":2,"name":"Washington: Neue Drohung gegen Georgien"}]},{"@type":"WebSite","@id":"https:\/\/now-news.de\/de\/#website","url":"https:\/\/now-news.de\/de\/","name":"just-now.NEWS Deutschland","description":"Das Portal f\u00fcr unzensierte Nachrichten aus der Welt","publisher":{"@id":"https:\/\/now-news.de\/de\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/now-news.de\/de\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"},{"@type":"Organization","@id":"https:\/\/now-news.de\/de\/#organization","name":"Just Now News","url":"https:\/\/now-news.de\/de\/","logo":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/","url":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","contentUrl":"http:\/\/just-now.news\/de\/wp-content\/uploads\/sites\/3\/2022\/04\/logo500x500.jpg","width":500,"height":500,"caption":"Just Now News"},"image":{"@id":"https:\/\/now-news.de\/de\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/wirmachenauf","https:\/\/x.com\/WirMachenAuf_de"]},{"@type":"Person","@id":"https:\/\/now-news.de\/de\/#\/schema\/person\/fb534a4e865501d8b3285208df34a9b5","name":"rtnews","image":{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/358fe31b3ab5769fea05376e1953329834cd9912cf9daf607e2af3076a1b982b?s=96&d=mm&r=g","caption":"rtnews"},"url":"https:\/\/now-news.de\/de\/author\/rnews\/"}]}},"_links":{"self":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/71608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/comments?post=71608"}],"version-history":[{"count":0,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/posts\/71608\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media\/71609"}],"wp:attachment":[{"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/media?parent=71608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/categories?post=71608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/now-news.de\/de\/wp-json\/wp\/v2\/tags?post=71608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}